{"id":46123,"date":"2021-12-14T09:57:00","date_gmt":"2021-12-14T08:57:00","guid":{"rendered":"https:\/\/kinsta.com\/de\/?p=46123&#038;post_type=feature-updates&#038;preview_id=46123"},"modified":"2021-12-14T09:57:00","modified_gmt":"2021-12-14T08:57:00","slug":"php-8-1","status":"publish","type":"changelog","link":"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/","title":{"rendered":"PHP 8.1 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar"},"content":{"rendered":"<p>Jedes Mal, wenn eine neue PHP-Version ver\u00f6ffentlicht wird, sind wir alle begeistert, weil sie normalerweise neue, <a href=\"https:\/\/kinsta.com\/de\/blog\/php-8-1\/#new-features-in-php-81\">interessante Funktionen<\/a> und <a href=\"https:\/\/kinsta.com\/de\/blog\/php-8-1\/#performance-improvements-with-inheritance-cache\">Leistungsverbesserungen<\/a> mit sich bringt. Genau das ist mit <a href=\"https:\/\/kinsta.com\/de\/blog\/php-8-1\/\">PHP 8.1<\/a> passiert, das nicht nur am 25. November 2021 ver\u00f6ffentlicht wurde, sondern jetzt auch bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar ist.<\/p>\n<p>Bevor du deine <a href=\"https:\/\/kinsta.com\/de\/docs\/wordpress-hosting\/php\/#updating-php\">PHP-Version auf PHP 8.1 aktualisierst<\/a>, m\u00f6chten wir dich an ein paar Dinge erinnern:<\/p>\n<ul>\n<li>Um Datenverluste zu vermeiden, solltest du immer ein <a href=\"https:\/\/kinsta.com\/docs\/wordpress-hosting\/wordpress-backups\/#wordpress-backup#wordpress-backups\">Backup deiner Webseiten erstellen<\/a>, bevor du etwas unternimmst.<\/li>\n<li>Teste deine Webseiten zun\u00e4chst in einer <a href=\"https:\/\/kinsta.com\/de\/docs\/wordpress-hosting\/staging-umgebung\/\">Staging-Umgebung<\/a> und f\u00fchre das Upgrade nur durch, wenn du keine Probleme feststellst.<\/li>\n<li>Wenn du Probleme mit deiner <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/\">WordPress-Version<\/a> feststellst, arbeite mit einem <a href=\"https:\/\/kinsta.com\/partners\/\">qualifizierten Entwickler<\/a> zusammen, um deine <a href=\"https:\/\/kinsta.com\/de\/docs\/wordpress-hosting\/wordpress-fehlerbehebung\/wordpress-debugging\/#enable-wp_debug\">Webseite zu debuggen<\/a>, bevor du auf PHP 8.1 aktualisierst.<\/li>\n<li>Es kann sein, dass noch nicht alle Plugins und Themes mit PHP 8.1 kompatibel sind und <strong>unser Support-Team kann bei Problemen mit der Code-Kompatibilit\u00e4t nicht helfen<\/strong>. Wenn du ein Problem mit einem Plugin oder Theme auf deiner Webseite feststellst, empfehlen wir dir, ein <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-herunterstufen\/#6-revert-to-an-older-version-of-php\">Downgrade auf PHP 7.4 durchzuf\u00fchren<\/a> und den Entwickler des Plugins oder Themes auf die Inkompatibilit\u00e4t mit PHP 8.1 anzusprechen.<\/li>\n<li>PHP 8.1 und PHP 8.0 sind noch nicht mit <a href=\"https:\/\/kinsta.com\/de\/docs\/wordpress-hosting\/mykinsta-werkzeuge\/#ioncube-loader\">ionCube Loader<\/a> Wenn du deine Webseite mit ionCube Loader betreibst, solltest du zum jetzigen Zeitpunkt nicht auf PHP 8.1 umsteigen.<\/li>\n<\/ul>\n<p>Und jetzt zeige ich dir, wie du PHP 8.1 auf deinen Webseiten aktivieren kannst!<\/p>\n<h2>Wie man zu PHP 8.1 wechselt<\/h2>\n<p>Um auf PHP 8.1 umzusteigen, logge dich in <a href=\"https:\/\/kinsta.com\/de\/mykinsta\/\">MyKinsta<\/a> ein und navigiere zum Reiter <strong>Tools<\/strong> auf deiner Webseite.<\/p>\n<p>Klicke unter der Option <strong>PHP-Engine<\/strong> auf <strong>\u00c4ndern<\/strong> und <strong>w\u00e4hle PHP 8.1<\/strong> aus dem Dropdown-Men\u00fc:<\/p>\n<figure id=\"attachment_46148\" aria-describedby=\"caption-attachment-46148\" style=\"width: 2880px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-46148 size-full\" src=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/switching-to-php-8-1-mykinsta-de.png\" alt=\"Umstellung auf PHP 8.1 in MyKinsta\" width=\"2880\" height=\"1800\" srcset=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/switching-to-php-8-1-mykinsta-de.png 2880w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/switching-to-php-8-1-mykinsta-de-300x188.png 300w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/switching-to-php-8-1-mykinsta-de-1024x640.png 1024w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/switching-to-php-8-1-mykinsta-de-768x480.png 768w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/switching-to-php-8-1-mykinsta-de-1536x960.png 1536w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/switching-to-php-8-1-mykinsta-de-2048x1280.png 2048w\" sizes=\"auto, (max-width: 2880px) 100vw, 2880px\" \/><figcaption id=\"caption-attachment-46148\" class=\"wp-caption-text\">Umstellung auf PHP 8.1 in MyKinsta<\/figcaption><\/figure>\n<p>Der Upgrade-Prozess dauert ein paar Minuten und erfordert einen Neustart deiner PHP-Engine. Dadurch wird dein WordPress-Backend nur f\u00fcr ein paar Sekunden nicht verf\u00fcgbar sein. <strong>Deine Besucher werden keine Probleme haben<\/strong>.<\/p>\n<p>Sobald das Upgrade erfolgreich abgeschlossen ist, erh\u00e4ltst du eine Benachrichtigung direkt in MyKinsta.<\/p>\n<p>Weitere Informationen zu den spannenden Neuerungen der neuesten PHP-Version findest du in unserem <a href=\"https:\/\/kinsta.com\/de\/blog\/php-8-1\/\">ausf\u00fchrlichen Leitfaden zu PHP 8.1<\/a> und in unserem <a href=\"https:\/\/kinsta.com\/de\/wordpress-newsletter\/\">Newsletter<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jedes Mal, wenn eine neue PHP-Version ver\u00f6ffentlicht wird, sind wir alle begeistert, weil sie normalerweise neue, interessante Funktionen und Leistungsverbesserungen mit sich bringt. Genau das ist &#8230;<\/p>\n","protected":false},"featured_media":46125,"template":"","tags":[],"class_list":["post-46123","changelog","type-changelog","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PHP 8.1 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar<\/title>\n<meta name=\"description\" content=\"PHP 8.1 bringt viele neue Funktionen und Leistungsverbesserungen mit sich und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PHP 8.1 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar\" \/>\n<meta property=\"og:description\" content=\"PHP 8.1 bringt viele neue Funktionen und Leistungsverbesserungen mit sich und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/php-8-1-kinsta.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"PHP 8.1 bringt viele neue Funktionen und Leistungsverbesserungen mit sich und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/php-8-1-kinsta.jpeg\" \/>\n<meta name=\"twitter:site\" content=\"@Kinsta_DE\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/\",\"url\":\"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/\",\"name\":\"PHP 8.1 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/php-8-1-kinsta.jpeg\",\"datePublished\":\"2021-12-14T08:57:00+00:00\",\"description\":\"PHP 8.1 bringt viele neue Funktionen und Leistungsverbesserungen mit sich und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!\",\"breadcrumb\":{\"@id\":\"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/#primaryimage\",\"url\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/php-8-1-kinsta.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/php-8-1-kinsta.jpeg\",\"width\":1024,\"height\":512,\"caption\":\"PHP 8.1 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kinsta.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Changelog\",\"item\":\"https:\/\/kinsta.com\/de\/changelog\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PHP 8.1 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kinsta.com\/de\/#website\",\"url\":\"https:\/\/kinsta.com\/de\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Schnelle, sichere und hochwertige Hosting-L\u00f6sungen\",\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kinsta.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kinsta.com\/de\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kinsta.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/\",\"https:\/\/x.com\/Kinsta_DE\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PHP 8.1 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar","description":"PHP 8.1 bringt viele neue Funktionen und Leistungsverbesserungen mit sich und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/","og_locale":"de_DE","og_type":"article","og_title":"PHP 8.1 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar","og_description":"PHP 8.1 bringt viele neue Funktionen und Leistungsverbesserungen mit sich und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!","og_url":"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/","og_image":[{"width":1024,"height":512,"url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/php-8-1-kinsta.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"PHP 8.1 bringt viele neue Funktionen und Leistungsverbesserungen mit sich und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!","twitter_image":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/php-8-1-kinsta.jpeg","twitter_site":"@Kinsta_DE","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/","url":"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/","name":"PHP 8.1 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar","isPartOf":{"@id":"https:\/\/kinsta.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/#primaryimage"},"image":{"@id":"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/php-8-1-kinsta.jpeg","datePublished":"2021-12-14T08:57:00+00:00","description":"PHP 8.1 bringt viele neue Funktionen und Leistungsverbesserungen mit sich und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!","breadcrumb":{"@id":"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinsta.com\/de\/changelog\/php-8-1\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/#primaryimage","url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/php-8-1-kinsta.jpeg","contentUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/12\/php-8-1-kinsta.jpeg","width":1024,"height":512,"caption":"PHP 8.1 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar"},{"@type":"BreadcrumbList","@id":"https:\/\/kinsta.com\/de\/changelog\/php-8-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kinsta.com\/de\/"},{"@type":"ListItem","position":2,"name":"Changelog","item":"https:\/\/kinsta.com\/de\/changelog\/"},{"@type":"ListItem","position":3,"name":"PHP 8.1 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar"}]},{"@type":"WebSite","@id":"https:\/\/kinsta.com\/de\/#website","url":"https:\/\/kinsta.com\/de\/","name":"Kinsta\u00ae","description":"Schnelle, sichere und hochwertige Hosting-L\u00f6sungen","publisher":{"@id":"https:\/\/kinsta.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinsta.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/kinsta.com\/de\/#organization","name":"Kinsta","url":"https:\/\/kinsta.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/","https:\/\/x.com\/Kinsta_DE","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/changelog\/46123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/changelog"}],"about":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/types\/changelog"}],"version-history":[{"count":0,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/changelog\/46123\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/media\/46125"}],"wp:attachment":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/media?parent=46123"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/tags?post=46123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}