{"id":61340,"date":"2023-05-03T18:30:20","date_gmt":"2023-05-03T17:30:20","guid":{"rendered":"https:\/\/kinsta.com\/de\/?p=61340&#038;post_type=feature-updates&#038;preview_id=61340"},"modified":"2023-05-10T11:54:47","modified_gmt":"2023-05-10T10:54:47","slug":"php-8-2","status":"publish","type":"changelog","link":"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/","title":{"rendered":"PHP 8.2 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar"},"content":{"rendered":"<p>Jedes Mal, wenn eine neue Version von PHP ver\u00f6ffentlicht wird, sind wir alle begeistert, denn sie bringt in der Regel neue, <a href=\"https:\/\/kinsta.com\/de\/blog\/php-8-2\/#new-features-and-improvements-in-php-82\">interessante Funktionen<\/a>, Verbesserungen und Leistungssteigerungen mit sich. Nachdem Kinsta bereits <a href=\"https:\/\/kinsta.com\/de\/blog\/php-8-1\/\">PHP 8.1<\/a> zur Verf\u00fcgung gestellt hat, ist nun auch <a href=\"https:\/\/kinsta.com\/de\/blog\/php-8-2\/\">PHP 8.2<\/a> f\u00fcr alle Kinsta-Umgebungen verf\u00fcgbar. Das bedeutet, dass Kinsta jetzt Folgendes unterst\u00fctzt 7.4, 8.0, 8.1, 8.2, 8.3, 8.4 und 8.5<\/p>\n<p>Bevor du deine PHP-Version auf PHP 8.2 <a href=\"https:\/\/kinsta.com\/de\/docs\/wordpress-hosting\/php\/#updating-php\">aktualisierst<\/a>, m\u00f6chten wir dich an ein paar Dinge erinnern:<\/p>\n<ul>\n<li>Um Datenverluste zu vermeiden, solltest du immer <a href=\"https:\/\/kinsta.com\/docs\/wordpress-hosting\/wordpress-backups\/#wordpress-backup#wordpress-backups\">ein Backup deiner Websites erstellen<\/a>, bevor du auf eine andere PHP-Version aktualisierst.<\/li>\n<li>Teste deine Websites zun\u00e4chst in einer <a href=\"https:\/\/kinsta.com\/de\/docs\/wordpress-hosting\/staging-umgebung\/\">Staging-Umgebung<\/a> und aktualisiere deine Live-Site nur, wenn du keine Probleme feststellst.<\/li>\n<li>WordPress 6.1 (die aktuelle stabile Version) unterst\u00fctzt PHP 8.2. \u00c4ltere WordPress-Versionen unterst\u00fctzen diese Version jedoch nicht<\/li>\n<li>Wenn du Probleme mit deiner <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/\">WordPress-Version<\/a> feststellst, arbeite mit einem <a href=\"https:\/\/kinsta.com\/partners\/\">qualifizierten Entwickler<\/a> zusammen, um deine Website zu <a href=\"https:\/\/kinsta.com\/de\/docs\/wordpress-hosting\/wordpress-fehlerbehebung\/wordpress-debugging\/#enable-wp_debug\">debuggen<\/a>, bevor du auf PHP 8.2 aktualisierst.<\/li>\n<li>M\u00f6glicherweise sind noch nicht alle Plugins und Themes mit PHP 8.2 kompatibel und <strong>unser Support-Team kann bei Problemen mit der Code-Kompatibilit\u00e4t nicht helfen<\/strong>. Vergewissere dich, dass alle deine Plugins und Themes PHP 8.2 unterst\u00fctzen, bevor du deine PHP-Version aktualisierst. Wenn du ein Problem mit einem Plugin oder Theme auf deiner Seite feststellst, empfehlen wir dir, <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-herunterstufen\/#6-revert-to-an-older-version-of-php\">ein Downgrade auf PHP 8.1 oder 8.0<\/a> durchzuf\u00fchren und den Entwickler des Plugins oder Themes auf die Inkompatibilit\u00e4t mit PHP 8.2 anzusprechen.<\/li>\n<li>PHP 8.2 ist noch nicht mit <a href=\"https:\/\/kinsta.com\/de\/docs\/wordpress-hosting\/mykinsta-werkzeuge\/#ioncube-loader\">ionCube Loader<\/a> kompatibel. Wenn du den ionCube Loader f\u00fcr deine Website verwendest, solltest du zum jetzigen Zeitpunkt nicht auf PHP 8.2 upgraden, sondern PHP 8.1 verwenden<\/li>\n<\/ul>\n<p>Und jetzt schauen wir uns an, wie du PHP 8.2 auf deinen Websites aktivieren kannst! <strong>WordPress 6.1 PHP-Version ist: 5.6 bis 8.2<\/strong><\/p>\n<h2>So wechselst du zu PHP 8.2<\/h2>\n<p>Um auf PHP 8.2 umzusteigen, logge dich in <a href=\"https:\/\/kinsta.com\/de\/mykinsta\/\">MyKinsta<\/a> ein und gehe auf die Registerkarte <strong>Werkzeuge<\/strong> deiner Website.<\/p>\n<p>Unter der Option <strong>PHP-Engine <\/strong>klickst du auf <strong>\u00c4ndern<\/strong> und <strong>w\u00e4hlst<\/strong> <strong>PHP 8.2<\/strong> aus dem Dropdown-Men\u00fc:<\/p>\n<figure id=\"attachment_153401\" aria-describedby=\"caption-attachment-153401\" style=\"width: 900px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-153401 size-full\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/11\/mykinsta-update-php-version-from-8-0-1.png\" alt=\"Schaltfl\u00e4che PHP-Engine modifizieren in MyKinsta.\" width=\"900\" height=\"795\"><figcaption id=\"caption-attachment-153401\" class=\"wp-caption-text\">Schaltfl\u00e4che PHP-Engine modifizieren in MyKinsta.<\/figcaption><\/figure>\n<p>Der Upgrade-Prozess wird einige Minuten dauern und erfordert einen Neustart deiner PHP-Engine. Dadurch wird dein WordPress-Backend nur f\u00fcr ein paar Sekunden nicht verf\u00fcgbar sein. <strong>Deine Besucher werden keine Probleme<\/strong> haben.<\/p>\n<p>Sobald das Upgrade erfolgreich abgeschlossen ist, erh\u00e4ltst du eine Benachrichtigung direkt in MyKinsta.<\/p>\n<p>Weitere Informationen zu den spannenden Neuerungen der neuesten PHP-Version findest du in unserem <a href=\"https:\/\/kinsta.com\/de\/blog\/php-8-2\/\">ausf\u00fchrlichen Leitfaden zu PHP 8.2<\/a> und in unserem <a href=\"https:\/\/kinsta.com\/de\/wordpress-newsletter\/\">Newsletter<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jedes Mal, wenn eine neue Version von PHP ver\u00f6ffentlicht wird, sind wir alle begeistert, denn sie bringt in der Regel neue, interessante Funktionen, Verbesserungen und Leistungssteigerungen &#8230;<\/p>\n","protected":false},"featured_media":61580,"template":"","tags":[],"class_list":["post-61340","changelog","type-changelog","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PHP 8.2 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar - Kinsta\u00ae<\/title>\n<meta name=\"description\" content=\"PHP 8.2 bringt viele neue Funktionen und Leistungsverbesserungen und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PHP 8.2 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar\" \/>\n<meta property=\"og:description\" content=\"PHP 8.2 bringt viele neue Funktionen und Leistungsverbesserungen und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-10T10:54:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/05\/PHP-8.2-DE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"PHP 8.2 bringt viele neue Funktionen und Leistungsverbesserungen und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/05\/PHP-8.2-DE.png\" \/>\n<meta name=\"twitter:site\" content=\"@Kinsta_DE\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/\",\"url\":\"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/\",\"name\":\"PHP 8.2 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar - Kinsta\u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/05\/PHP-8.2-DE.png\",\"datePublished\":\"2023-05-03T17:30:20+00:00\",\"dateModified\":\"2023-05-10T10:54:47+00:00\",\"description\":\"PHP 8.2 bringt viele neue Funktionen und Leistungsverbesserungen und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!\",\"breadcrumb\":{\"@id\":\"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/#primaryimage\",\"url\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/05\/PHP-8.2-DE.png\",\"contentUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/05\/PHP-8.2-DE.png\",\"width\":1200,\"height\":629},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kinsta.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Changelog\",\"item\":\"https:\/\/kinsta.com\/de\/changelog\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PHP 8.2 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kinsta.com\/de\/#website\",\"url\":\"https:\/\/kinsta.com\/de\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Schnelle, sichere und hochwertige Hosting-L\u00f6sungen\",\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kinsta.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kinsta.com\/de\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kinsta.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/\",\"https:\/\/x.com\/Kinsta_DE\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PHP 8.2 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar - Kinsta\u00ae","description":"PHP 8.2 bringt viele neue Funktionen und Leistungsverbesserungen und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/","og_locale":"de_DE","og_type":"article","og_title":"PHP 8.2 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar","og_description":"PHP 8.2 bringt viele neue Funktionen und Leistungsverbesserungen und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!","og_url":"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/","article_modified_time":"2023-05-10T10:54:47+00:00","og_image":[{"width":1200,"height":629,"url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/05\/PHP-8.2-DE.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_description":"PHP 8.2 bringt viele neue Funktionen und Leistungsverbesserungen und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!","twitter_image":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/05\/PHP-8.2-DE.png","twitter_site":"@Kinsta_DE","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/","url":"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/","name":"PHP 8.2 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar - Kinsta\u00ae","isPartOf":{"@id":"https:\/\/kinsta.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/#primaryimage"},"image":{"@id":"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/05\/PHP-8.2-DE.png","datePublished":"2023-05-03T17:30:20+00:00","dateModified":"2023-05-10T10:54:47+00:00","description":"PHP 8.2 bringt viele neue Funktionen und Leistungsverbesserungen und ist bei Kinsta f\u00fcr alle Umgebungen verf\u00fcgbar!","breadcrumb":{"@id":"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinsta.com\/de\/changelog\/php-8-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/#primaryimage","url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/05\/PHP-8.2-DE.png","contentUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/05\/PHP-8.2-DE.png","width":1200,"height":629},{"@type":"BreadcrumbList","@id":"https:\/\/kinsta.com\/de\/changelog\/php-8-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kinsta.com\/de\/"},{"@type":"ListItem","position":2,"name":"Changelog","item":"https:\/\/kinsta.com\/de\/changelog\/"},{"@type":"ListItem","position":3,"name":"PHP 8.2 ist jetzt f\u00fcr alle Umgebungen verf\u00fcgbar"}]},{"@type":"WebSite","@id":"https:\/\/kinsta.com\/de\/#website","url":"https:\/\/kinsta.com\/de\/","name":"Kinsta\u00ae","description":"Schnelle, sichere und hochwertige Hosting-L\u00f6sungen","publisher":{"@id":"https:\/\/kinsta.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinsta.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/kinsta.com\/de\/#organization","name":"Kinsta","url":"https:\/\/kinsta.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/","https:\/\/x.com\/Kinsta_DE","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/changelog\/61340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/changelog"}],"about":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/types\/changelog"}],"version-history":[{"count":5,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/changelog\/61340\/revisions"}],"predecessor-version":[{"id":61605,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/changelog\/61340\/revisions\/61605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/media\/61580"}],"wp:attachment":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/media?parent=61340"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/tags?post=61340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}