{"id":27383,"date":"2019-09-20T03:21:26","date_gmt":"2019-09-20T10:21:26","guid":{"rendered":"https:\/\/kinsta.com\/?p=47111"},"modified":"2023-08-25T13:34:32","modified_gmt":"2023-08-25T12:34:32","slug":"wordpress-url-loggst","status":"publish","type":"post","link":"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/","title":{"rendered":"So findest du deine WordPress Login-URL (\u00c4ndern, Sperren)"},"content":{"rendered":"<p><a href=\"https:\/\/kinsta.com\/de\/blog\/was-ist-wordpress\/\">Anf\u00e4nger, die mit WordPress<\/a> arbeiten, haben es oft schwer, sich bei ihren Konten anzumelden. In diesem Artikel werde ich erkl\u00e4ren, wie du <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/\">deine WordPress-Login-URL<\/a> und ein paar andere wichtige Dinge findest, die in Bezug auf den Login-Prozess hervorgehoben werden m\u00fcssen.<\/p>\n<p>Fangen wir von vorne an.<\/p>\n<div><\/div><kinsta-auto-toc heading=\"Table of Contents\" exclude=\"last\" list-style=\"arrow\" selector=\"h2\" count-number=\"-1\"><\/kinsta-auto-toc>\n<h2 id=\"importance\">Bedeutung des WordPress-Logins<\/h2>\n<p>Nach der <a href=\"https:\/\/kinsta.com\/de\/blog\/neu-installieren-wordpress\/\">Installation von WordPress<\/a> erh\u00e4ltst du Zugang zum <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-admin\/\">Admin-Dashboard deiner Website<\/a>, wo du die M\u00f6glichkeit hast, deine Website nach Bedarf einzurichten und ein paar Dinge zu \u00e4ndern.<\/p>\n<p>Das w\u00e4re unm\u00f6glich, wenn du keinen Zugriff auf die Admin-Seiten h\u00e4ttest. Die Login-Seite verhindert, dass Du &#8211; und andere &#8211; auf die Management-Seite deiner WordPress-Seite zugreifen kannst.<\/p>\n<p>Es ist praktisch unm\u00f6glich, die volle Kontrolle \u00fcber deine Website \/ deinen Blog zu haben, wenn du keinen Zugriff auf den Admin-Bereich hast.<\/p>\n<p>Aber wo befindet sich diese WordPress Login-Seite?<\/p>\n\n<div  class=\"featured-snippet\" id=\"featuredSnippet\">\n    <div class=\"featured-snippet__content\">\n        <h2>So findest du deine WordPress Login Url:<\/h2>\n        <div><p>Die WordPress-Anmeldeseite kann erreicht werden, indem du \/<strong>login<\/strong>\/, \/<strong>admin<\/strong>\/, oder \/<strong>wp-login.php<\/strong> am Ende der URL deiner Website hinzuf\u00fcgst.<\/p>\n<p>Wenn du WordPress in einem Unterverzeichnis (www.yoursite.com\/wordpress\/) oder einer Unterdom\u00e4ne (blog.yoursite.com\/) installiert hast, f\u00fcge einen der drei Pfade am Ende deiner URL hinzu, wie zum Beispiel: www.yoursite.com\/wordpress\/<strong>wp-login.php<\/strong> oder blog.yoursite.com\/<strong>wp-login.php<\/strong>.<\/p>\n<\/div>\n    <\/div>\n    <div class=\"featured-snippet__footer\">\n        <div class=\"arrow-down\"><\/div>\n        <div class=\"featured-snippet__footer--content row nocol middle-xs between-xs reverse\">\n            <div style=\"margin-left: auto; position: relative; top: -1px\" class=\"row nocol middle-xs\">\n                <div class=\"color--mediumGray\" style=\"font-size: 14px; vertical-align: middle;\">\n                    <svg  class=\"icon icon--logo display--block\" aria-hidden=\"true\" focusable=\"false\"><use xlink:href=\"https:\/\/kinsta.com\/de\/wp-content\/themes\/kinsta\/dist\/sprite.svg?v=d7c088ac459b9cbb2e19b989209c747b#logo\" \/><\/svg>                <\/div>\n                <div class=\"text--bold color--mediumGray\" style=\"padding-left: 3px;\">Support<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<h2 id=\"how-to-find-wordpress-login-url\">So findest du die WordPress Login-URL<\/h2>\n<p>Das Auffinden der WordPress-Anmeldeseite ist wahrscheinlich einfacher, als du erwarten w\u00fcrdest. Bei einer neuen WordPress-Installation leitet dich das Hinzuf\u00fcgen von \/<strong>admin<\/strong>\/ (z.B.: www.yourawesomesite.com\/admin\/) oder \/<strong>login<\/strong>\/ (z.B.: www.yourawesomesite.com\/login\/) am Ende der URL deiner Website zur Login-Seite weiter.<\/p>\n<p>Normalerweise sollten diese beiden dich direkt zu deiner WordPress Login-Seite f\u00fchren. Sollte dies nicht der Fall sein, gibt es eine zus\u00e4tzliche M\u00f6glichkeit, deine Login-Seite zu erreichen: Du kannst \/<strong>wp-login.php<\/strong> am Ende der URL hinzuf\u00fcgen, wie in diesem Beispiel: www.awesomesite.com\/wp-login.php.<\/p>\n<h3>So findest du die WordPress Login URL in einem Unterverzeichnis oder einer Subdomain<\/h3>\n<p>All dies funktioniert bei einer Standard- und Neuinstallation von WordPress. Es besteht jedoch die M\u00f6glichkeit, dass du WordPress in einem Unterverzeichnis deiner Domain wie <code>www.yourawesomesite.com\/wordpress\/<\/code> oder einer <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-subdomain\/\">WordPress-Subdomain<\/a> wie <code>blog.yourawesomesite.com\/<\/code> installiert hast.<\/p>\n<p>Wenn das der Fall ist, musst du einen der oben genannten Pfade direkt nach dem Schr\u00e4gstrich des Unterverzeichnisses\/Unterdom\u00e4ne anh\u00e4ngen, d.h. das Symbol <code>\/<\/code>, um so etwas zu erhalten:<\/p>\n<p><code>www.awesomesite.com\/wordpress\/login\/<\/code> oder<\/p>\n<p><code>www.awesomesite.com\/wordpress\/wp-login.php.<\/code><\/p>\n<p>Egal, welche du verwendest, jeder von ihnen sollte dich zu deiner WordPress-Login-Seite f\u00fchren. Wenn du es nicht vergessen willst, kannst du deine bevorzugte <a href=\"https:\/\/kinsta.com\/de\/blog\/was-ist-eine-url\/\">URL<\/a> mit einem Lesezeichen versehen.<\/p>\n<p>Alternativ gibt es im WordPress-Login-Formular die Option &#8222;Merken&#8220;, mit der du eingeloggt bleiben und f\u00fcr einige Tage das Admin-Dashboard erreichen kannst, ohne dass du dich erneut anmelden musst (je nachdem, wie deine Cookies gesetzt werden):<\/p>\n<figure style=\"width: 547px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/06\/option-merken-wordpress-login-formular.png\" alt=\"Die Option \"Merken\" auf dem WordPress-Login-Formular\" width=\"547\" height=\"290\"><figcaption class=\"wp-caption-text\">Die Option &#8222;Merken&#8220; auf dem WordPress-Login-Formular<\/figcaption><\/figure>\n<p>Die Anmeldung \u00fcber die WordPress Login-Seite ist eine wichtige und dennoch einfache Aufgabe. Wenn auf deiner Website nichts Falsches und\/oder B\u00f6sartiges passiert, brauchst du nur deine E-Mail-Adresse\/Benutzername und dein Passwort.<\/p>\n<p>Das ist alles. Leider sind b\u00f6se Jungs \u00fcberall und <a href=\"https:\/\/kinsta.com\/de\/blog\/ist-wordpress-sicher\/\">deine Website k\u00f6nnte ein Angriffsziel werden<\/a>.<\/p>\n<p>Was kannst du dann tun, um sie zu verhindern?<\/p>\n<p>Lasst uns zumindest die Login-Seite verschieben!<\/p>\n\n<h2 id=\"change-login-page\">Wie man die WordPress Login-Seite \u00e4ndert<\/h2>\n<p>Deine Login-Seite sollte f\u00fcr Hacker und b\u00f6swillige Angreifer (auch bekannt als die B\u00f6sewichte) nicht zug\u00e4nglich sein, da sie m\u00f6glicherweise Zugriff auf die Admin-Seite deiner Website erhalten und anfangen, Dinge durcheinander zu bringen. Keine gute Erfahrung, vertrau mir!<\/p>\n<p>W\u00e4hrend die Verwendung eines starken, einzigartigen, langen Passworts wirklich zu deinen Gunsten auswirkt, um unbefugten Zugriff auf deine Website zu unterbinden, gibt es nie genug Dinge, die du tun kannst, wenn es um die Sicherheit geht.<\/p>\n<p>Eine schnelle und effektive M\u00f6glichkeit, die b\u00f6sen Jungs fernzuhalten, besteht darin, <strong>die WordPress-Anmeldeseite auf eine neue, eindeutige URL Ihrer Wahl zu verschieben<\/strong>. Das \u00c4ndern der Anmelde-URL, \u00fcber die du und deine Benutzer Zugang zu deiner WordPress-Seite erhalten k\u00f6nnen, k\u00f6nnte wirklich hilfreich sein, wenn es darum geht, Zufallsangriffe, Hacks und Brute-Force-Angriffe zu bek\u00e4mpfen.<\/p>\n<p>Ein Wort zu Brute-Force-Angriffen: Brute-Force-Angriffe sind Hacking-Versuche, bei denen die b\u00f6swillige Person versucht, Ihren Benutzernamen und Ihr Passwort wiederholt zu erraten, indem sie Listen von g\u00e4ngigen Benutzernamen und Passw\u00f6rtern ausnutzt, die im Internet durchsickern. Was er tut, ist, dass er Tausende von Kombinationen ausprobiert, indem er die M\u00f6glichkeiten von Skripten nutzt, die alle seine Versuche automatisieren.<\/p>\n<p>In der heutigen Welt besteht eine hohe Wahrscheinlichkeit, dass entweder Ihr WordPress-Passwort oder Ihr Benutzername auf einer dieser undichten Listen steht. Wenn du hinzuf\u00fcgst, dass WordPress Login-Standard-URL etwas ist, das diesem Szenario \u00f6ffentlich bekannt ist, erf\u00e4hrst du, wie einfach es ist, f\u00fcr Hacker und b\u00f6sartige Angreifer Zugang zu deiner WordPress-Seite zu erhalten.<\/p>\n<p>Deshalb kann Ihnen das Verschieben der WordPress-Anmeldeseite auf einen anderen Pfad helfen.<\/p>\n<h3>\u00c4ndere deine WordPress Login-Seite mit einem Plugin.<\/h3>\n<p>Der h\u00e4ufigste und wahrscheinlich einfachste Weg, deine WordPress Login-URL-Seite zu \u00e4ndern, ist die Verwendung eines kostenlosen Plugins wie <a href=\"https:\/\/kinsta.com\/de\/blog\/ist-wordpress-sicher\/\">WPS Hide Login<\/a>, das von mehr als 400.000 Benutzern aktiv genutzt wird.<\/p>\n<p>Das Plugin ist sehr leicht und vor allem, es \u00e4ndert keine Dateien im Core oder f\u00fcgt Rewrite-Regeln hinzu, es f\u00e4ngt einfach Anfragen ab. Es ist auch kompatibel mit BuddyPress, <a href=\"https:\/\/kinsta.com\/de\/blog\/bbpress\/\">bbPress<\/a>, Limit Login Atests und User Switching Plugins.<\/p>\n<figure style=\"width: 1539px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/wordpress.org\/plugins\/wps-hide-login\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2019\/06\/wps-hide-login-plugin-1.png\" alt=\"WPS Hide Login plugin\" width=\"1539\" height=\"495\"><\/a><figcaption class=\"wp-caption-text\">WPS Hide Login plugin<\/figcaption><\/figure>\n<p>Nach dem Herunterladen und Aktivieren musst du nur noch Folgendes tun:<\/p>\n<ol>\n<li>Klicke auf <strong>WPS Hide Login<\/strong> in der Registerkarte <strong>Settings<\/strong> in der rechten Sidebar.<\/li>\n<li>F\u00fcge deinen neuen Pfad f\u00fcr die Anmelde-URL in das Feld <strong>Anmelde-URL<\/strong> ein.<\/li>\n<li>F\u00fcge eine bestimmte Umleitungs-URL in die <strong>Umleitungs-URL<\/strong> ein. Diese Seite wird ausgel\u00f6st, wenn jemand versucht, auf die Standardseite wp-login.php und das Verzeichnis wp-admin zuzugreifen, ohne angemeldet zu sein.<\/li>\n<li>Klicke auf <strong>\u00c4nderungen speichern<\/strong>.<\/li>\n<\/ol>\n<figure style=\"width: 1230px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/06\/WPS-Hide-Login.png\" alt=\"WPS Hide Login plugin\" width=\"1230\" height=\"240\"><figcaption class=\"wp-caption-text\">WPS Hide Login plugin<\/figcaption><\/figure>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-important\">\n            <h3>Important<\/h3>\n        <p>Sobald du auf die <strong>Schaltfl\u00e4che \u00c4nderungen<\/strong> speichern klickst, wird deine neue Anmeldeseite wirksam, so dass deine alte Anmelde-URL nicht mehr funktioniert! Du solltest deine Lesezeichen aktualisieren. Wenn du irgendwelche Probleme hast, kannst du jederzeit wieder zur Normalit\u00e4t zur\u00fcckkehren, indem du das Plugin per SFTP auf deinem Webserver entfernst.<\/p>\n<\/aside>\n\n<p>Ein alternatives Premium-Plugin, mit dem du deine Anmelde-URL \u00e4ndern kannst, ist <a href=\"https:\/\/perfmatters.io\/\">Perfmatters<\/a>, das von einem der Teammitglieder bei Kinsta entwickelt wurde.<\/p>\n<p>Da die \u00c4nderung deiner WordPress-Login-URL dazu beitragen kann, die oberfl\u00e4chlichen Angreifer vom Zugriff auf deine Website abzuhalten, m\u00f6chte ich hier klarstellen: Experten und professionelle Hacker k\u00f6nnten m\u00f6glicherweise noch die zus\u00e4tzliche Meile gehen und deine Login-Seite trotzdem herausfinden.<\/p>\n<p>Also, warum sollte es dich interessieren? Nun, Sicherheit ist ein Ebenen-Spiel (bei dem <a href=\"https:\/\/kinsta.com\/de\/wordpress-hosting\/sicherheit\/\">die Qualit\u00e4t Ihres Hostings eine Schl\u00fcsselrolle spielt<\/a>): Je mehr Tools, Tricks und Mauern du hast, desto schwieriger wird es f\u00fcr die B\u00f6sewichte sein, in deine Website zu kommen und die Kontrolle zu erlangen.<\/p>\n<p>Das \u00c4ndern der Anmelde-URL kann auch dazu beitragen, h\u00e4ufige WordPress Fehler wie &#8222;<a href=\"https:\/\/kinsta.com\/de\/blog\/429-too-many-requests\/\">429 Too Many Requests<\/a>&#8220; zu vermeiden. Dies wird typischerweise vom Server erzeugt, wenn der Benutzer zu viele Anfragen in einer bestimmten Zeitspanne gesendet hat (Ratenbegrenzung). Dies kann durch Bots oder Skripte verursacht werden, die auf deine Anmelde-URL treffen. Der Endanwender verursacht diesen Fehler selten.<\/p>\n<figure id=\"attachment_32926\" aria-describedby=\"caption-attachment-32926\" style=\"width: 1313px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32926\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2016\/08\/429-too-many-requests-2.png\" alt=\"429 too many requests\" width=\"1313\" height=\"191\"><figcaption id=\"caption-attachment-32926\" class=\"wp-caption-text\">429 too many requests<\/figcaption><\/figure>\n<h3>\u00c4ndere deine WordPress Login-Seite und bearbeite dein .htaccess-File<\/h3>\n<p>Andere technischere M\u00f6glichkeiten, die URL der WordPress-Anmeldeseite zu \u00e4ndern oder zu verbergen, besteht in der Bearbeitung deiner .htaccess-Datei.<\/p>\n<p>Die Hauptaufgabe der .htaccess-Datei, die <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-htaccess-datei\/\">typischerweise mit cPanel-Hosts<\/a> verwendet wird, besteht darin, Regeln zu konfigurieren und systemweite Einstellungen vorzunehmen. Da es sich um das Ausblenden der Login-Seite handelt, kann .htaccess dies auf zwei Arten handhaben.<\/p>\n<p>Beim ersten geht es darum, deine Login-Seite mit einem <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-sicherheit\/#how-to-add-basic-http-authentication-htpasswd-protection\">.htpasswd<\/a> <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-seite-passwort-schutzt\/\">Passwort zu sch\u00fctzen<\/a>, so dass jeder, der deine Login-Seite erreicht, aufgefordert wird, vor dem Zugriff auf die Login-Seite ein Passwort einzugeben. Wenn du ein Kunde von Kinsta bist, verwenden wir <a href=\"https:\/\/kinsta.com\/de\/blog\/was-ist-nginx\/\">Nginx<\/a>, und deshalb gibt es keine .htaccess-Datei. Du kannst unser <a href=\"https:\/\/kinsta.com\/de\/docs\/wordpress-hosting\/mykinsta-werkzeuge\/htpasswd\/\">htpasswd-Tool<\/a> verwenden, um deine gesamte Website mit einem Passwort zu sch\u00fctzen, oder dich an unser Support-Team wenden, um nur deine Login-Seite zu sperren.<\/p>\n<figure id=\"attachment_78196\" aria-describedby=\"caption-attachment-78196\" style=\"width: 1814px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-78196 size-full\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2019\/06\/htpasswd-authentication-prompt.png\" alt=\".htpasswd Authentifizierungsaufforderung\" width=\"1814\" height=\"467\"><figcaption id=\"caption-attachment-78196\" class=\"wp-caption-text\">.htpasswd Authentifizierungsaufforderung<\/figcaption><\/figure>\n<p>Die zweite Option, die du hast, ist die Aktivierung des Zugriffs auf deine Anmeldeseite basierend auf einer Liste von vertrauensw\u00fcrdigen IP-Adressen.<\/p>\n<h3>Limiting Login Attempts<\/h3>\n<p>Eine weitere effektive Sicherheitsmethode ist die Begrenzung der Anzahl der Anmeldeversuche. Wenn du ein Kinsta-Kunde bist, sperren wir automatisch IPs, die mehr als 6 fehlgeschlagene Anmeldeversuche in einer Minute haben.<\/p>\n<p>Oder du kannst ein kostenloses Plugin herunterladen, wie z.B. <a href=\"https:\/\/wordpress.org\/plugins\/limit-login-attempts-reloaded\/\">Limit Login Attempts Reloaded<\/a>.<\/p>\n<figure id=\"attachment_57068\" aria-describedby=\"caption-attachment-57068\" style=\"width: 1374px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-57068\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2019\/06\/limit-login-attempts-reloaded.jpg\" alt=\"Limit login attempts reloaded\" width=\"1374\" height=\"2889\"><figcaption id=\"caption-attachment-57068\" class=\"wp-caption-text\">Limit login attempts reloaded<\/figcaption><\/figure>\n<p>Die Optionen im Plugin sind ziemlich einfach.<\/p>\n<ul>\n<li><strong>Total Lockouts<\/strong>: gibt dir die Anzahl der Hacker, die versucht haben, einzubrechen, aber fehlgeschlagen sind.<\/li>\n<li><strong>Erlaubte Wiederholungsversuche<\/strong>: Die Anzahl der Versuche, die eine IP-Adresse machen darf, bevor du sie sperrst.<\/li>\n<\/ul>\n<p>Irgendwo zwischen vier und sechs ist wahrscheinlich die beliebteste Wiederholungszahl. Es erlaubt echten Menschen, dass sie Fehler machen k\u00f6nnen (denn schlie\u00dflich machen wir alle Fehler bei der Eingabe von Passw\u00f6rtern), erkennen, dass sie das falsche Passwort eingeben und beheben ihren Fehler.<\/p>\n<p>Es ist wichtig, ihn auf \u00fcber 1 oder 2 einzustellen, besonders wenn du h\u00e4ufige Gast-Blogger oder mehrere Mitarbeiter hast, die f\u00fcr die Verwaltung deiner Website verantwortlich sind.<\/p>\n<ul>\n<li><strong>Minutensperre<\/strong>: Wie lange eine IP-Adresse gesperrt ist.<\/li>\n<\/ul>\n<p>Du m\u00f6chtest es vielleicht auf &#8222;f\u00fcr immer&#8220; setzen, aber das ist nicht hilfreich f\u00fcr Leute, die wirklich einen echten Fehler machen &#8211; du willst, dass sie sich wieder einloggen k\u00f6nnen. Letztendlich sind 20-30 Minuten ungef\u00e4hr richtig.<\/p>\n<ul>\n<li><strong>Lockouts nehmen zu<\/strong>: Denn wenn es sich um einen Brute-Force-Angriff handelt, wird er wahrscheinlich wiederkommen.<\/li>\n<\/ul>\n<p>Diese Funktion sagt im Grunde genommen &#8222;Schau&#8220;, ich habe gesehen, wie du dich schon mehrmals ausgesperrt hast, also werde ich dich jetzt f\u00fcr l\u00e4nger aussperren.&#8220; Ein Tag ist hier ganz gut.<\/p>\n<ul>\n<li><strong>Stunden bis zu erneuten Versuchen<\/strong>: wie lange, bis es alles zur\u00fccksetzt und die Leute es erneut versuchen l\u00e4sst.<\/li>\n<\/ul>\n<p>Mit dem Plugin kannst du auch deine Whitelist, Blacklist und vertrauensw\u00fcrdige IPs verwalten.<\/p>\n<h2 id=\"fix-common-issues-login\">Wie man die h\u00e4ufigsten Probleme mit dem WordPress Login behebt<\/h2>\n<p>Die Anmeldung auf deiner WordPress-Seite ist eine schnelle und einfache Aufgabe. Doch einige Benutzer &#8211; Du? &#8211; k\u00f6nnten einige Probleme beim Zugriff auf die WordPress-Seite haben. Die h\u00e4ufigsten Probleme fallen in der Regel unter eines der folgenden Szenarien:<\/p>\n<ul>\n<li>Probleme im Zusammenhang mit dem Passwort.<\/li>\n<li>Probleme im Zusammenhang mit Cookies.<\/li>\n<\/ul>\n<p>Werfen wir einen Blick auf beide und sehen wir, wie wir sie beheben k\u00f6nnen!<\/p>\n<h3>WordPress Login: Passwort vergessen\/verloren<\/h3>\n<p>Wenn du dich nicht anmelden kannst, hast du m\u00f6glicherweise ein Problem mit deinen Anmeldeinformationen.<\/p>\n<p>Also, das allererste, was du tun solltest, ist zu \u00fcberpr\u00fcfen, ob deine Benutzernamen- und Passworteingaben, die du eingibst, tats\u00e4chlich korrekt sind. Ich wei\u00df, es klingt lahm, aber du hast keine Ahnung, wie oft wir diese falsch tippen.<\/p>\n<p>Hat es funktioniert? Wenn nicht, solltest du <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-passworter-andern\/\">dein Passwort zur\u00fccksetzen<\/a>, bevor du etwas anderes ausprobierst. Klick dazu auf die Option <strong>Passwort vergessen?<\/strong> direkt unter dem Anmeldeformular:<\/p>\n<figure style=\"width: 511px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/06\/passwort-vergessen-option .png\" alt=\"Passwort vergessen Option \" width=\"511\" height=\"329\"><figcaption class=\"wp-caption-text\">Passwort vergessen Option<\/figcaption><\/figure>\n<p>Du wirst auf eine Seite weitergeleitet, auf der du nach deinem Benutzernamen\/E-Mail gefragt wirst und ein neues Passwort erh\u00e4ltst:<\/p>\n<figure style=\"width: 591px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/06\/bekommt-neues-wordpress-passwort.png\" alt=\"Wie bekommt man ein neues WordPress Passwort\" width=\"591\" height=\"321\"><figcaption class=\"wp-caption-text\">Wie bekommt man ein neues WordPress Passwort<\/figcaption><\/figure>\n<h3>WordPress Passwort manuell zur\u00fccksetzen mit phpMyAdmin<\/h3>\n<p>Wenn dies nicht funktioniert, wird die Sache etwas komplizierter, da du einen manuellen Passwort Reset durchf\u00fchren musst. <strong>Bitte tue dies nicht, wenn du dich beim Arbeiten mit Datenbankdateien nicht wohl f\u00fchlst<\/strong>.<\/p>\n<p>Das manuelle Zur\u00fccksetzen deines WordPress-Anmeldekennworts kann durch Bearbeiten der Kennwortdatei in deiner <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-datenbank\/\">Datenbank<\/a> erfolgen. Wenn du in deinem Host, Zugriff auf <a href=\"https:\/\/kinsta.com\/de\/docs\/wordpress-hosting\/datenbank-verwaltung\/wordpress-datenbank-zugriff\/\">phpMyAdmin<\/a> hast, sollte das nicht schwer sein.<\/p>\n<p><a href=\"https:\/\/kinsta.com\/docs\/wordpress-hosting\/wordpress-backups\/#wordpress-backup\">Sichere deine Website<\/a> immer, bevor du \u00c4nderungen an Datenbankdateien durchf\u00fchrst, falls etwas schief geht.<\/p>\n<p>Erledigt? Gro\u00dfartig!<\/p>\n<h4>Schritt 1<\/h4>\n<p>Melde dich jetzt bei phpMyAdmin an. Wenn du ein Kinsta-Kunde bist, findest du den Login-Link zu phpMyAdmin im MyKinsta Dashboard.<\/p>\n<figure id=\"attachment_45972\" aria-describedby=\"caption-attachment-45972\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-45972 size-full\" src=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/mykinsta-open-phpmyadmin-2.png\" alt=\"Login to phpmyadmin\" width=\"2560\" height=\"1442\" srcset=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/mykinsta-open-phpmyadmin-2.png 2560w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/mykinsta-open-phpmyadmin-2-300x169.png 300w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/mykinsta-open-phpmyadmin-2-1024x577.png 1024w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/mykinsta-open-phpmyadmin-2-768x433.png 768w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/mykinsta-open-phpmyadmin-2-1536x865.png 1536w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/mykinsta-open-phpmyadmin-2-2048x1154.png 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-45972\" class=\"wp-caption-text\">Login to phpmyadmin<\/figcaption><\/figure>\n<h4>Schritt 2<\/h4>\n<p>Klicke auf der linken Seite in deine Datenbank. Klicke dann auf die Tabelle wp_users. Anschlie\u00dfend klickst du auf &#8222;Bearbeiten&#8220; neben der Benutzeranmeldung, die du zur\u00fccksetzen m\u00f6chten.<\/p>\n<figure style=\"width: 1436px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/06\/benutzer-phpmyadmin-bearbeiten.jpg\" alt=\"Benutzer in phpMyAdmin bearbeiten\" width=\"1436\" height=\"881\"><figcaption class=\"wp-caption-text\">Benutzer in phpMyAdmin bearbeiten<\/figcaption><\/figure>\n<h4>Schritt 3<\/h4>\n<p>Gib in der Spalte <code>user_pass<\/code> ein neues Passwort ein (Gro\u00df-\/Kleinschreibung wird ber\u00fccksichtigt). W\u00e4hle im Dropdown-Men\u00fc Funktion die Option MD5. Klicke dann auf &#8222;Los&#8220;.<\/p>\n<figure style=\"width: 1515px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2019\/06\/reset-password-phpmyadmin.jpg\" alt=\"Passwort in phpMyAdmin zur\u00fccksetzen\" width=\"1515\" height=\"659\"><figcaption class=\"wp-caption-text\">Passwort in phpMyAdmin zur\u00fccksetzen<\/figcaption><\/figure>\n<h4>Schritt 4<\/h4>\n<p>Testen Sie das neue Passwort auf Ihrem Anmeldebildschirm.<\/p>\n<h3>WordPress-Passwort mit WP-CLI manuell zur\u00fccksetzen<\/h3>\n<p>Eine weitere M\u00f6glichkeit, dein WordPress-Passwort zur\u00fcckzusetzen, ist die Verwendung von <a href=\"https:\/\/kinsta.com\/de\/blog\/wp-cli\/\">WP-CLI<\/a>. WP-CLI ist ein Kommandozeilenwerkzeug f\u00fcr Entwickler, um h\u00e4ufige Aufgaben (und nicht so h\u00e4ufige) einer WordPress-Installation zu verwalten.<\/p>\n<h4>Schritt 1<\/h4>\n<p>Verwende zun\u00e4chst den folgenden Befehl, um alle aktuellen Benutzer in der WordPress-Installation aufzulisten.<\/p>\n<pre>$ wp user list<\/pre>\n<h4>Schritt 2<\/h4>\n<p>Aktualisiere dann das Benutzerpasswort mit dem folgenden Befehl, zusammen mit der Benutzer-ID und dem neuen gew\u00fcnschten Passwort.<\/p>\n<pre>$ wp user update 1 --user_pass=strongpasswordgoeshere<\/pre>\n<h4>Schritt 3<\/h4>\n<p>Teste das neue Passwort auf Ihrem Anmeldebildschirm.<\/p>\n<h3>WordPress Login: Cookies<\/h3>\n<p>In einigen F\u00e4llen kannst du dich aufgrund von Problemen im Zusammenhang mit Cookies m\u00f6glicherweise nicht anmelden. Wenn ja, wirst du normalerweise mit dem folgenden Fehler konfrontiert:<\/p>\n<blockquote><p>Fehler: Cookies werden von Ihrem Browser blockiert oder nicht unterst\u00fctzt. Sie m\u00fcssen <a href=\"https:\/\/kinsta.com\/de\/blog\/wp-config-php\/\">Cookies<\/a> aktivieren, um WordPress verwenden zu k\u00f6nnen.<\/p><\/blockquote>\n<figure style=\"width: 1636px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/06\/cookies-blockier-unterstutzt-fehler.png\" alt=\"Cookies sind blockiert oder werden nicht unterst\u00fctzt Fehler\" width=\"1636\" height=\"1170\"><figcaption class=\"wp-caption-text\">Cookies sind blockiert oder werden nicht unterst\u00fctzt Fehler<\/figcaption><\/figure>\n<p>WordPress-Login ist auf Cookies angewiesen, um zu funktionieren. Wenn sie deaktiviert sind oder nicht richtig funktionieren, hast du wahrscheinlich Probleme auf der Login-Seite. Als Erstes solltest du \u00fcberpr\u00fcfen, ob in deinem Browser Cookies aktiviert sind:<\/p>\n<ul>\n<li><a href=\"https:\/\/support.google.com\/chrome\/answer\/95647\">Cookies in Google Chrome<\/a><\/li>\n<li><a href=\"https:\/\/support.mozilla.org\/en-US\/kb\/enhanced-tracking-protection-firefox-desktop?redirectslug=enable-and-disable-cookies-website-preferences&#038;redirectlocale=en-US\">Cookies in Mozilla Firefox<\/a><\/li>\n<li><a href=\"https:\/\/support.microsoft.com\/en-us\/help\/17442\/windows-internet-explorer-delete-manage-cookies\">Cookies im Internet Explorer<\/a><\/li>\n<li><a href=\"https:\/\/support.apple.com\/guide\/safari\/manage-cookies-and-website-data-sfri11471\/mac\">Cookies in Safari<\/a><\/li>\n<\/ul>\n<p>Wir sehen dies oft bei Installationen von WordPress, die k\u00fcrzlich migriert wurden, oder bei Multisites. Manchmal wird man durch einfaches Aktualisieren des Browsers und den Versuch, sich erneut anzumelden, tats\u00e4chlich an diesem Fehler vorbeikommen. Du kannst auch versuchen, deinen <a href=\"https:\/\/kinsta.com\/de\/blog\/loschst-du-den-browser-cache\/\">Browser-Cache zu leeren<\/a> oder einen anderen Browser im Inkognito-Modus zu \u00f6ffnen.<\/p>\n<p>Wenn nichts davon funktioniert hat, kannst du versuchen, die folgende Zeile in deine <a href=\"https:\/\/kinsta.com\/de\/blog\/wp-config-php\/\">wp-config.php-Datei<\/a> einzuf\u00fcgen, direkt davor. <code>\/* That's all, stop editing!...*\/<\/code><\/p>\n<pre>define('COOKIE_DOMAIN', false);<\/pre>\n<p>Wenn es sich um ein <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-multiseiten\/\">WordPress Multisite-Einrichtung<\/a> handelt, solltest du vielleicht \u00fcberpr\u00fcfen, ob es eine <code>sunrise.php<\/code>-Datei im Ordner <code>\/wp-content\/<\/code> gibt und sie in <code>sunrise.php.disabled<\/code> umbenennen. Dies ist eine Datei, die von einer \u00e4lteren<\/p>\n<p>Dom\u00e4nzuordnungsmethode verwendet wird. Ab WordPress 4.5 ben\u00f6tigt Multisite <a href=\"https:\/\/codex.wordpress.org\/WordPress_Multisite_Domain_Mapping\">kein Plugin mehr<\/a>, um Domains zuzuordnen. Wenn du ein Kinsta-Kunde bist und dir da nicht sicher bist, wende dich bitte an unser Support-Team und frage nach Hilfe.<\/p>\n<h2>Zusammenfassung<\/h2>\n<p>Ihre WordPress-Anmeldeseite ist das Tor, das Ihnen den Zugriff auf Ihre Website erm\u00f6glicht. Wenn du dich nicht erfolgreich anmelden kannst, bist du nur ein Besucher der Website.<\/p>\n<p>Deshalb solltest du lernen, wie du diese Schl\u00fcsselseite erreichen kannst, damit du nicht jedes Mal, wenn du dich bei deiner WordPress-Seite anmelden musst, viel Zeit verlierst.<\/p>\n<p>M\u00f6chten du deine Sicherheit ein wenig verbessern? <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/\">\u00c4ndern Sie die Standard WordPress Login-URL<\/a> mit einer benutzerdefinierten URL Ihrer Wahl und teilen Sie diese URL nur mit vertrauensw\u00fcrdigen Personen! Schauen Sie auch unbedingt in diesen Leitfaden, <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-keeps-logging-me-out\/\">wenn WordPress Sie immer wieder ausloggt<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anf\u00e4nger, die mit WordPress arbeiten, haben es oft schwer, sich bei ihren Konten anzumelden. In diesem Artikel werde ich erkl\u00e4ren, wie du deine WordPress-Login-URL und ein &#8230;<\/p>\n","protected":false},"author":103,"featured_media":27395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[180,29],"topic":[999],"class_list":["post-27383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-site-security","tag-wordpress","topic-wordpress-entwicklung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>So findest du deine WordPress-Anmelde-URL und loggst dich erfolgreich ein<\/title>\n<meta name=\"description\" content=\"WordPress-Einsteiger haben es schwer, sich bei ihren Konten anzumelden. In diesem Artikel erkl\u00e4ren wir dir, wie du dein WordPress-Login finden kannst.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"So findest du deine WordPress Login-URL (\u00c4ndern, Sperren)\" \/>\n<meta property=\"og:description\" content=\"WordPress-Einsteiger haben es schwer, sich bei ihren Konten anzumelden. In diesem Artikel erkl\u00e4ren wir dir, wie du dein WordPress-Login finden kannst.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-20T10:21:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T12:34:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/wordpress-loggst-url.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1460\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matteo Du\u00f2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"WordPress-Einsteiger haben es schwer, sich bei ihren Konten anzumelden. In diesem Artikel erkl\u00e4ren wir dir, wie du dein WordPress-Login finden kannst.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/wordpress-loggst-url.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@matteoduo\" \/>\n<meta name=\"twitter:site\" content=\"@Kinsta_DE\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matteo Du\u00f2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/\"},\"author\":{\"name\":\"Matteo Du\u00f2\",\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/person\/9d811e805493f00205e6409451055174\"},\"headline\":\"So findest du deine WordPress Login-URL (\u00c4ndern, Sperren)\",\"datePublished\":\"2019-09-20T10:21:26+00:00\",\"dateModified\":\"2023-08-25T12:34:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/\"},\"wordCount\":2488,\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/wordpress-loggst-url.jpg\",\"keywords\":[\"site security\",\"WordPress\"],\"articleSection\":[\"Die besten WordPress Tutorials\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/\",\"url\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/\",\"name\":\"So findest du deine WordPress-Anmelde-URL und loggst dich erfolgreich ein\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/wordpress-loggst-url.jpg\",\"datePublished\":\"2019-09-20T10:21:26+00:00\",\"dateModified\":\"2023-08-25T12:34:32+00:00\",\"description\":\"WordPress-Einsteiger haben es schwer, sich bei ihren Konten anzumelden. In diesem Artikel erkl\u00e4ren wir dir, wie du dein WordPress-Login finden kannst.\",\"breadcrumb\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/#primaryimage\",\"url\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/wordpress-loggst-url.jpg\",\"contentUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/wordpress-loggst-url.jpg\",\"width\":1460,\"height\":730,\"caption\":\"So findest du deine WordPress-Anmelde-URL und loggst dich erfolgreich ein\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kinsta.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WordPress Entwicklung\",\"item\":\"https:\/\/kinsta.com\/de\/thema\/wordpress-entwicklung\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"So findest du deine WordPress Login-URL (\u00c4ndern, Sperren)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kinsta.com\/de\/#website\",\"url\":\"https:\/\/kinsta.com\/de\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Schnelle, sichere und hochwertige Hosting-L\u00f6sungen\",\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kinsta.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kinsta.com\/de\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kinsta.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/\",\"https:\/\/x.com\/Kinsta_DE\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/person\/9d811e805493f00205e6409451055174\",\"name\":\"Matteo Du\u00f2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78636e34d9c125b93efb7e0893a776f8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78636e34d9c125b93efb7e0893a776f8?s=96&d=mm&r=g\",\"caption\":\"Matteo Du\u00f2\"},\"description\":\"Marketing Consultant for WordPress plugin developers.\",\"sameAs\":[\"https:\/\/www.matteoduo.com\",\"https:\/\/www.linkedin.com\/in\/matteoduo\/\",\"https:\/\/x.com\/matteoduo\"],\"url\":\"https:\/\/kinsta.com\/de\/blog\/author\/matteoduo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"So findest du deine WordPress-Anmelde-URL und loggst dich erfolgreich ein","description":"WordPress-Einsteiger haben es schwer, sich bei ihren Konten anzumelden. In diesem Artikel erkl\u00e4ren wir dir, wie du dein WordPress-Login finden kannst.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/","og_locale":"de_DE","og_type":"article","og_title":"So findest du deine WordPress Login-URL (\u00c4ndern, Sperren)","og_description":"WordPress-Einsteiger haben es schwer, sich bei ihren Konten anzumelden. In diesem Artikel erkl\u00e4ren wir dir, wie du dein WordPress-Login finden kannst.","og_url":"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/","article_published_time":"2019-09-20T10:21:26+00:00","article_modified_time":"2023-08-25T12:34:32+00:00","og_image":[{"width":1460,"height":730,"url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/wordpress-loggst-url.jpg","type":"image\/jpeg"}],"author":"Matteo Du\u00f2","twitter_card":"summary_large_image","twitter_description":"WordPress-Einsteiger haben es schwer, sich bei ihren Konten anzumelden. In diesem Artikel erkl\u00e4ren wir dir, wie du dein WordPress-Login finden kannst.","twitter_image":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/wordpress-loggst-url.jpg","twitter_creator":"@matteoduo","twitter_site":"@Kinsta_DE","twitter_misc":{"Verfasst von":"Matteo Du\u00f2","Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/#article","isPartOf":{"@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/"},"author":{"name":"Matteo Du\u00f2","@id":"https:\/\/kinsta.com\/de\/#\/schema\/person\/9d811e805493f00205e6409451055174"},"headline":"So findest du deine WordPress Login-URL (\u00c4ndern, Sperren)","datePublished":"2019-09-20T10:21:26+00:00","dateModified":"2023-08-25T12:34:32+00:00","mainEntityOfPage":{"@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/"},"wordCount":2488,"publisher":{"@id":"https:\/\/kinsta.com\/de\/#organization"},"image":{"@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/wordpress-loggst-url.jpg","keywords":["site security","WordPress"],"articleSection":["Die besten WordPress Tutorials"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/","url":"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/","name":"So findest du deine WordPress-Anmelde-URL und loggst dich erfolgreich ein","isPartOf":{"@id":"https:\/\/kinsta.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/#primaryimage"},"image":{"@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/wordpress-loggst-url.jpg","datePublished":"2019-09-20T10:21:26+00:00","dateModified":"2023-08-25T12:34:32+00:00","description":"WordPress-Einsteiger haben es schwer, sich bei ihren Konten anzumelden. In diesem Artikel erkl\u00e4ren wir dir, wie du dein WordPress-Login finden kannst.","breadcrumb":{"@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/#primaryimage","url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/wordpress-loggst-url.jpg","contentUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2019\/09\/wordpress-loggst-url.jpg","width":1460,"height":730,"caption":"So findest du deine WordPress-Anmelde-URL und loggst dich erfolgreich ein"},{"@type":"BreadcrumbList","@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-url-loggst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kinsta.com\/de\/"},{"@type":"ListItem","position":2,"name":"WordPress Entwicklung","item":"https:\/\/kinsta.com\/de\/thema\/wordpress-entwicklung\/"},{"@type":"ListItem","position":3,"name":"So findest du deine WordPress Login-URL (\u00c4ndern, Sperren)"}]},{"@type":"WebSite","@id":"https:\/\/kinsta.com\/de\/#website","url":"https:\/\/kinsta.com\/de\/","name":"Kinsta\u00ae","description":"Schnelle, sichere und hochwertige Hosting-L\u00f6sungen","publisher":{"@id":"https:\/\/kinsta.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinsta.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/kinsta.com\/de\/#organization","name":"Kinsta","url":"https:\/\/kinsta.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/","https:\/\/x.com\/Kinsta_DE","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kinsta.com\/de\/#\/schema\/person\/9d811e805493f00205e6409451055174","name":"Matteo Du\u00f2","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kinsta.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78636e34d9c125b93efb7e0893a776f8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78636e34d9c125b93efb7e0893a776f8?s=96&d=mm&r=g","caption":"Matteo Du\u00f2"},"description":"Marketing Consultant for WordPress plugin developers.","sameAs":["https:\/\/www.matteoduo.com","https:\/\/www.linkedin.com\/in\/matteoduo\/","https:\/\/x.com\/matteoduo"],"url":"https:\/\/kinsta.com\/de\/blog\/author\/matteoduo\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/posts\/27383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/users\/103"}],"replies":[{"embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/comments?post=27383"}],"version-history":[{"count":15,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/posts\/27383\/revisions"}],"predecessor-version":[{"id":64736,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/posts\/27383\/revisions\/64736"}],"alternate":[{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/27383\/translations\/en"},{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/27383\/translations\/es"},{"embeddable":true,"hreflang":"da","title":null,"href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/27383\/translations\/dk"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/27383\/translations\/fr"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/27383\/translations\/pt"},{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/27383\/translations\/it"},{"embeddable":true,"hreflang":"nl","title":"Dutch","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/27383\/translations\/nl"},{"embeddable":true,"hreflang":"sv","title":null,"href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/27383\/translations\/se"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/27383\/translations\/de"},{"embeddable":true,"hreflang":"ja","title":"Japanese","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/27383\/translations\/jp"},{"href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/27383\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/media\/27395"}],"wp:attachment":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/media?parent=27383"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/tags?post=27383"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/topic?post=27383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}