{"id":41092,"date":"2021-04-13T09:56:46","date_gmt":"2021-04-13T07:56:46","guid":{"rendered":"https:\/\/kinsta.com\/?p=90144"},"modified":"2023-08-28T12:53:51","modified_gmt":"2023-08-28T11:53:51","slug":"wordpress-version","status":"publish","type":"post","link":"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/","title":{"rendered":"Wie du deine aktuelle WordPress-Version findest und auf die neueste Version aktualisierst"},"content":{"rendered":"<p>WordPress ist eine sich st\u00e4ndig weiterentwickelnde Software, die regelm\u00e4\u00dfig neue Funktionen, Sicherheitskorrekturen und Wartungsupdates ver\u00f6ffentlicht. Diese <a href=\"https:\/\/kinsta.com\/de\/docs\/support\/umfang-des-supports\/managed-wordpress-support-umfang\/\">grundlegenden Updates<\/a> gew\u00e4hrleisten die Sicherheit und Effizienz des WordPress-Systems.<\/p>\n<p>Wenn du eine WordPress-Website betreibst, musst du die neueste WordPress-Version aktualisieren, um sicherzustellen, dass du \u00fcber die neuesten Funktionen, Leistungsverbesserungen und Schutzma\u00dfnahmen verf\u00fcgst.<\/p>\n<p>In diesem Artikel zeigen wir dir, wie du deine aktuelle WordPress-Version \u00fcberpr\u00fcfen kannst, erl\u00e4utern die neueste WordPress-Version und ihre Funktionen und zeigen dir, wie du auf die neueste WordPress-Version aktualisieren kannst.<\/p>\n<p>Auf geht&#8217;s zum Update!<\/p>\n<div><\/div><kinsta-auto-toc heading=\"Table of Contents\" exclude=\"last\" list-style=\"arrow\" selector=\"h2\" count-number=\"-1\"><\/kinsta-auto-toc>\n<h2>Warum WordPress regelm\u00e4\u00dfig Updates herausbringt<\/h2>\n<p>Bevor wir beginnen, m\u00fcssen wir verstehen, warum WordPress einen regelm\u00e4\u00dfigen Aktualisierungszyklus hat. Kurz gesagt, kannst du aus den folgenden Gr\u00fcnden mit Updates rechnen:<\/p>\n<ul>\n<li>WordPress bringt regelm\u00e4\u00dfig neue Funktionen heraus. Egal, ob es sich um eine weniger auff\u00e4llige \u00c4nderung handelt, wie z. B. das Hinzuf\u00fcgen neuer oEmbed-Anbieter (WordPress 4.4), oder um eine komplette \u00dcberarbeitung des Editors durch Gutenberg (WordPress 5.0), diese Neuerungen machen die Erstellung von Inhalten und die Erstellung von Websites in der Regel sehr viel einfacher.<\/li>\n<li>WordPress-Updates enthalten oft auch <a href=\"https:\/\/kinsta.com\/de\/blog\/ist-wordpress-sicher\/\">Sicherheitskorrekturen<\/a>. Das ist ein st\u00e4ndiger Kampf, denn Hacker finden st\u00e4ndig neue Sicherheitsl\u00fccken. Daher ist es wichtig, sich zu aktualisieren, um den neuesten Schutz vor neuen Arten von Angriffen zu erhalten.<\/li>\n<li>Aktuelle WordPress-Versionen bieten oft Leistungsverbesserungen &#8222;unter der Haube&#8220;. Du wirst diese Verbesserungen vielleicht nicht sofort bemerken, aber sie machen die Arbeit mit WordPress einfacher und schneller. In WordPress 2.0 wurde die Benutzerfreundlichkeit beim Ver\u00f6ffentlichen von Blogbeitr\u00e4gen erheblich verbessert. In WordPress 4.2 wurden die <a href=\"https:\/\/kinsta.com\/de\/blog\/aktualisiert-wordpress-plugin-manuell\/\">Plugin-Updates<\/a> mit einem einfachen Mausklick vereinfacht, statt wie bisher mit einem m\u00fchsamen Verfahren.<\/li>\n<li>Mit jeder WordPress-Version werden auch Fehler aus der Vergangenheit beseitigt. Das passiert bei jeder Software. Es ist, als w\u00fcrde man etwas an seinem Auto reparieren, das nicht mehr funktioniert, und es wieder zum Laufen bringen.<\/li>\n<\/ul>\n<p>Jetzt, wo du die Gr\u00fcnde f\u00fcr WordPress-Updates kennst, wollen wir uns die neueren WordPress-Versionen ansehen und dir erkl\u00e4ren, wie du deine aktuelle WordPress-Version \u00fcberpr\u00fcfen und aktualisieren kannst.<\/p>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-info\">\n            <h3>Info<\/h3>\n        <p>Auch wenn die Verantwortlichen von WordPress es vorziehen, dass jeder auf die neueste Version aktualisiert, bedeutet das nicht, dass sie die Unterst\u00fctzung f\u00fcr \u00e4ltere Versionen aufgeben. Auch f\u00fcr \u00e4ltere WordPress-Versionen gibt es noch Updates &#8211; zum Beispiel das WordPress 3.7 &#8222;Count Basie&#8220;-Update, das am 24. Oktober 2013 ver\u00f6ffentlicht wurde. Dennoch werden jedes Jahr mehrere Updates f\u00fcr diese Version herausgegeben. Das liegt daran, dass einige (nicht viele) Websites noch mit den \u00e4lteren Versionen arbeiten.<\/p>\n<\/aside>\n\n\n<h2>Welche ist die neueste WordPress-Version?<\/h2>\n<p>Die neueste Hauptversion von WordPress ist WordPress 6.1, genannt &#8222;<a href=\"https:\/\/wordpress.org\/news\/2022\/11\/misha\/\" target=\"_blank\" rel=\"noopener noreferrer\">Misha<\/a>&#8222;. WordPress 6.1 wurde am 1. November 2022 ver\u00f6ffentlicht, nachdem es seit September 2022 eine Reihe von Beta-Phasen durchlaufen hatte.<\/p>\n<p>Mehr \u00fcber WordPress 6.1 erf\u00e4hrst du in <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-6-1\/\">unserer ausf\u00fchrlichen Einf\u00fchrung zu den neuen Funktionen von WordPress 6.1<\/a>. Wenn du dich nur f\u00fcr die Highlights interessierst, findest du unten auch eine k\u00fcrzere Zusammenfassung der neuen Funktionen.<\/p>\n<p>Wenn du noch nicht auf WordPress 6.1 upgegradet hast, kannst du <a href=\"https:\/\/wordpress.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">WordPress 6.1<\/a> aus dem offiziellen Repository oder direkt \u00fcber dein <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-admin\/\">WordPress Admin-Dashboard<\/a> <a href=\"https:\/\/wordpress.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">herunterladen<\/a>.<\/p>\n<p>Das WordPress-Team arbeitet au\u00dferdem flei\u00dfig an WordPress 6.2 &#8211; die erste Beta-Version wurde am 7. Februar 2023 ver\u00f6ffentlicht, und die Ver\u00f6ffentlichung von WordPress 6.2 ist f\u00fcr den 28. M\u00e4rz 2023 geplant.<\/p>\n<h3>Was ist neu in WordPress 6.1?<\/h3>\n<p>WordPress 6.1 konzentriert sich in erster Linie auf die Verbesserung des Site-Editors und der Funktionalit\u00e4t sowie auf allgemeine Verbesserungen im Block-Editor.<\/p>\n<p>Dar\u00fcber hinaus gibt es ein neues Standard-Theme (Twenty Twenty-Three) und eine Reihe kleinerer Verbesserungen und Erweiterungen, darunter mehr als 60 <a href=\"https:\/\/kinsta.com\/de\/blog\/barrierfrei-wordpress\/\">barrierefreie<\/a> Anpassungen und Korrekturen f\u00fcr mehr als 25 Performance-Probleme.<\/p>\n<p>Sehen wir uns einige der wichtigsten Neuerungen an..<\/p>\n<h4>Ein neues Standard-Theme &#8211; Twenty Twenty-Three<\/h4>\n<p>WordPress 6.1 enth\u00e4lt ein brandneues Standard-WordPress-Theme &#8211; Twenty Twenty-Three.<\/p>\n<p>Wie bei den letzten Standard-Themes wie <a href=\"https:\/\/kinsta.com\/de\/blog\/twenty-twenty-two\/\">Twenty Twenty-Two<\/a> und <a href=\"https:\/\/kinsta.com\/de\/blog\/twenty-twenty-one-theme\/\">Twenty Twenty-One<\/a> wurde Twenty Twenty-Three entwickelt, um die neuen Funktionen des Site Editors zu nutzen.<\/p>\n<p>Es ist von Anfang an minimalistisch gehalten, aber du kannst es mit den vielen mitgelieferten Stilvariationen und Blockmustern ganz nach deinem Geschmack anpassen.<\/p>\n<p>Wenn du mehr erfahren m\u00f6chtest, kannst du <a href=\"https:\/\/kinsta.com\/de\/blog\/twenty-twenty-three-theme\/\">unseren vollst\u00e4ndigen Beitrag \u00fcber das WordPress-Theme Twenty Twenty-Three<\/a> lesen.<\/p>\n<h4>Verbesserungen im Site-Editor<\/h4>\n<p>WordPress 6.1 hat eine Reihe von \u00c4nderungen vorgenommen, damit du den Site Editor noch besser nutzen und <a href=\"https:\/\/kinsta.com\/de\/blog\/wie-du-dein-wordpress-theme-anpasst\/\">dein Theme<\/a> noch einfacher anpassen kannst.<\/p>\n<p>Hier ist eine kurze Zusammenfassung:<\/p>\n<ul>\n<li>Erstelle mehr Arten von Vorlagen, unabh\u00e4ngig von deinem Theme, einschlie\u00dflich Vorlagen f\u00fcr Kategorien, bestimmte Begriffe und mehr.<\/li>\n<li>Einfachere Verwendung und Ersetzung von Vorlagenteilen in deinen Designs.<\/li>\n<li>1-Klick-Button, um Anpassungen f\u00fcr eine bestimmte Vorlage zu l\u00f6schen.<\/li>\n<\/ul>\n<h4>Optimierungen und Verbesserungen am Block-Editor<\/h4>\n<p>Mit WordPress 6.1 wurde auch der <a href=\"https:\/\/kinsta.com\/de\/blog\/gutenberg-wordpress-editor\/\">regul\u00e4re Block-Editor<\/a> um einige Optimierungen und Verbesserungen erweitert.<\/p>\n<p>Hier sind einige Highlights:<\/p>\n<ul>\n<li>Mehr\/bessere Kontrolle \u00fcber die R\u00e4nder einiger Bl\u00f6cke.<\/li>\n<li>Ein neuer Bereich f\u00fcr die Abmessungen, mit dem du den Rand und die Auff\u00fcllung kontrollieren kannst.<\/li>\n<li>Du kannst das Bild f\u00fcr deinen Beitrag im Titelblock ausw\u00e4hlen.<\/li>\n<li>Listen- und Zitatbl\u00f6cke enthalten jetzt auch innere Bl\u00f6cke, was dir mehr Flexibilit\u00e4t bei der Steuerung ihrer Layouts gibt.<\/li>\n<li>Verbesserungen am Query Loop-Block.<\/li>\n<\/ul>\n<p>Au\u00dferdem gibt es eine neue Funktion &#8222;Erstellungsmuster&#8220;, die eine Auswahl an Mustern anzeigt, wenn ein Nutzer den Editor \u00f6ffnet <em>(diese Funktion steht WordPress.com-Nutzern schon seit einiger Zeit zur Verf\u00fcgung<\/em>). Die Nutzer\/innen k\u00f6nnen ein Muster als Ausgangspunkt w\u00e4hlen oder das Modal schlie\u00dfen, um die Seite von Grund auf neu zu erstellen.<\/p>\n<p><strong>Auch hier ist die Liste bei weitem nicht vollst\u00e4ndig. Schau dir <\/strong><strong><a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-6-1\/#twenty-twentythree-and-other-theme-improvements\">unseren vollst\u00e4ndigen WordPress 6.1 Release Guide<\/a><\/strong><strong> um mehr \u00fcber die anderen neuen Funktionen und Verbesserungen zu erfahren.<\/strong><\/p>\n<h2>So \u00fcberpr\u00fcfst du die aktuelle WordPress-Version deiner Website<\/h2>\n<p>Es gibt vier Methoden, um die aktuelle WordPress-Version auf deiner Website zu \u00fcberpr\u00fcfen. So erf\u00e4hrst du, welche Funktionen und Einschr\u00e4nkungen dir als WordPress-Benutzer zur Verf\u00fcgung stehen und kannst entscheiden, ob es an der Zeit ist, auf eine neuere WordPress-Version umzusteigen oder nicht.<\/p>\n<p>Die vier Methoden zur \u00dcberpr\u00fcfung der WordPress-Version sind:<\/p>\n<ol>\n<li>Ein Blick in den Admin-Bereich von WordPress.<\/li>\n<li>Durch das Frontend der Website gehen.<\/li>\n<li>\u00dcberpr\u00fcfen der Datei <code>version.php<\/code>.<\/li>\n<li><a href=\"https:\/\/kinsta.com\/de\/blog\/wp-cli\/\">WP-CLI verwenden<\/a>.<\/li>\n<\/ol>\n<p>Ausf\u00fchrliche Informationen zu diesen Methoden findest du in unserem vollst\u00e4ndigen Leitfaden zur <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-version-uberprufen\/\">\u00dcberpr\u00fcfung deiner WordPress-Version<\/a>. Der verlinkte Artikel enth\u00e4lt auch wertvolle Informationen dar\u00fcber, wie du Versionsinformationen von deiner WordPress-Website entfernst.<\/p>\n<h2>Wie du auf die neueste WordPress-Version aktualisierst<\/h2>\n<p>Es ist immer eine gute Idee, deine WordPress-Website zeitnah auf die neueste Version zu aktualisieren, damit deine Website <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-sicherheit\/\">funktioniert und sicher ist<\/a>, vor allem wenn es sich um Sicherheits- oder Wartungsupdates handelt.<\/p>\n<p>Sicherheits- und Wartungsversionen sind Versionen mit 2 Punkten in der Versionsnummer &#8211; z. B. 6.1.1 oder 5.9.3.<\/p>\n<p>Bei gr\u00f6\u00dferen Funktionsversionen kannst du ein paar Wochen warten, bis du das Update anwendest, da diese Versionen keine Sicherheits- oder Wartungsverbesserungen enthalten. So hast du Zeit, dich auf die neuen Funktionen in der Version vorzubereiten.<\/p>\n<p>Major Feature Releases sind Releases, die nur 1 Punkt in ihrer Versionsnummer haben &#8211; z.B. 6.1 oder 5.9.<\/p>\n<p>WordPress hat vor ein paar Jahren <a href=\"https:\/\/kinsta.com\/de\/blog\/automatischen-updates-wordpress\/\">automatische Core-Updates<\/a> eingef\u00fchrt. Daher musst du neue Core-Updates m\u00f6glicherweise nicht mehr manuell einspielen.<\/p>\n<p>Heutzutage ist die Standardkonfiguration auf den meisten WordPress-Websites so, dass kleinere Sicherheits- und Wartungsversionen automatisch angewendet werden. Einige Websites wenden auch automatisch gr\u00f6\u00dfere Updates an, aber das ist normalerweise nicht standardm\u00e4\u00dfig aktiviert.<\/p>\n<p>Es kann sein, dass du eine E-Mail erh\u00e4ltst, die besagt, dass deine Website aktualisiert wurde. In diesem Fall musst du keine weiteren Aufgaben erledigen. L\u00f6sche die E-Mail einfach oder speichere sie als Referenz und fahre mit deinem Tag fort.<\/p>\n<figure style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2023\/02\/Untitled.jpg\" alt=\"Automatische WordPress-Update-E-Mail\" width=\"1600\" height=\"824\"><figcaption class=\"wp-caption-text\">Automatische WordPress-Update-E-Mail<\/figcaption><\/figure>\n<p>Um zu \u00fcberpr\u00fcfen, welche WordPress-Version deine Website verwendet, kannst du auf <strong>Dashboard \u2192 Updates<\/strong> gehen. Suche dann nach dem Text <strong>Aktuelle Version<\/strong>.<\/p>\n<figure style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2023\/02\/Untitled-1.jpg\" alt=\"So \u00fcberpr\u00fcfst du deine WordPress-Version\" width=\"1600\" height=\"1214\"><figcaption class=\"wp-caption-text\">Aktuelle WordPress-Version<\/figcaption><\/figure>\n<p>Wenn deine Website nicht die aktuelle Version verwendet, siehst du auch eine Aufforderung zum Upgrade. Ein Upgrade ist in der Regel ganz einfach, wenn du auf diese Schaltfl\u00e4che klickst &#8211; aber klicke noch nicht darauf, denn wir wollen erst noch ein paar Dinge besprechen.<\/p>\n<figure style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2023\/02\/Untitled-2.jpg\" alt=\"Der WordPress Update-Hinweis\" width=\"1600\" height=\"1041\"><figcaption class=\"wp-caption-text\">WordPress-Update verf\u00fcgbar<\/figcaption><\/figure>\n<p>Es ist wichtig zu wissen, dass du auch im Rest deines WordPress-Dashboards Aufforderungen zur Aktualisierung siehst. Im Grunde ist es kaum zu \u00fcbersehen, wenn auf deiner Website eine veraltete Version von WordPress l\u00e4uft.<\/p>\n<figure style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2023\/02\/Untitled-3.jpg\" alt=\"WordPress zeigt auch Update-Hinweise in deinem Dashboard an\" width=\"1600\" height=\"1148\"><figcaption class=\"wp-caption-text\">Aktualisierungshinweis im Dashboard<\/figcaption><\/figure>\n<h3>Wichtige Schritte vor der Aktualisierung deiner WordPress-Version<\/h3>\n<p>Wie bereits erw\u00e4hnt, gibt es ein paar wichtige Details, die du beachten solltest, bevor du im Bereich <strong>Dashboard \u2192 Updates<\/strong> auf die Schaltfl\u00e4che Auf <strong>Version X.X<\/strong> aktualisieren klickst.<\/p>\n<p>Auch wenn es nur selten zu Problemen bei der Aktualisierung von WordPress kommt, ist es immer gut, mit einem \u00dcberma\u00df an Vorsicht an die Sache heranzugehen, besonders bei unternehmenskritischen Websites.<\/p>\n<p>Erstens solltest du immer ein Backup deiner WordPress-Website erstellen, bevor du ein Update durchf\u00fchrst. Wir empfehlen, direkt vor der Aktualisierung ein Backup zu erstellen, auch wenn du bereits automatische Backups f\u00fcr deine Website aktiviert hast.<\/p>\n<p>Kinsta bietet Tools zur manuellen und automatischen Sicherung deiner Website. Hier <a href=\"https:\/\/kinsta.com\/docs\/wordpress-hosting\/wordpress-backups\/#external-backups-addon\">erf\u00e4hrst du alles \u00fcber die Sicherung deiner WordPress-Website<\/a>, auch wenn du Kinsta nicht f\u00fcr das Hosting nutzt.<\/p>\n<p>Wir haben auch andere hilfreiche Artikel, wie du <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-backup-wiederherstellen\/\">deine Website aus einem Backup wiederherstellst<\/a> und wo du die <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-backup-plugins\/\">besten WordPress-Backup-Plugins<\/a> findest.<\/p>\n<p>Zweitens solltest du, wenn m\u00f6glich, das Update immer auf einer Staging-Version deiner Website anwenden, bevor du es auf deine Live-Site aufspielst. Alle Kinsta-Benutzer haben Zugang zum <a href=\"https:\/\/kinsta.com\/de\/docs\/wordpress-hosting\/staging-umgebung\/\">Staging-Tool von Kinsta, das du mit einem Klick<\/a> starten kannst. Wenn du deine Website woanders hostest, findest du hier <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-einzurichten\/\">weitere M\u00f6glichkeiten, eine Staging-Site<\/a> einzurichten.<\/p>\n<p>Schlie\u00dflich ist es wichtig zu wissen, dass ein WordPress-Update deine Website in den <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-wartungsmodus\/\">Wartungsmodus<\/a> versetzt. Normalerweise ist deine Seite nur f\u00fcr ein paar Sekunden im Wartungsmodus, so dass die meisten Besucher es gar nicht bemerken werden.<\/p>\n<p>Dennoch empfehlen wir, das Update m\u00f6glichst in einer Zeit mit geringem Besucheraufkommen durchzuf\u00fchren, um sicherzustellen, dass deine Besucher nicht beeintr\u00e4chtigt werden.<\/p>\n<h3>So aktualisierst du die WordPress-Version<\/h3>\n<p>Wenn du die oben genannten Schritte erledigt hast, kannst du deine WordPress-Version aktualisieren.<\/p>\n<p>Gehe in deinem WordPress-Dashboard auf <strong>Dashboard \u2192 Updates<\/strong> und klicke auf die Schaltfl\u00e4che <strong>Update auf Version X.X<\/strong>.<\/p>\n<figure style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2023\/02\/Untitled-4.jpg\" alt=\"Klicke auf die Schaltfl\u00e4che, um deine WordPress-Version zu aktualisieren\" width=\"1600\" height=\"1057\"><figcaption class=\"wp-caption-text\">Aktualisiere deine WordPress-Version<\/figcaption><\/figure>\n<p>Du musst jetzt kurz warten, w\u00e4hrend WordPress das Update herunterl\u00e4dt und anwendet &#8211; normalerweise dauert das nur ein paar Sekunden. W\u00e4hrend des Vorgangs siehst du einen Statusbildschirm, der dich dar\u00fcber informiert, was gerade passiert.<\/p>\n<figure style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2023\/02\/Untitled-5.jpg\" alt=\"Diese Meldungen werden angezeigt, w\u00e4hrend WordPress das Update durchf\u00fchrt\" width=\"1600\" height=\"1001\"><figcaption class=\"wp-caption-text\">WordPress wendet das Update an<\/figcaption><\/figure>\n<p>Sobald das Update abgeschlossen ist, wirst du automatisch auf die Seite mit den Informationen zu dieser Version weitergeleitet, auf der du einige Informationen zu den neuen Funktionen und Verbesserungen findest, auf die du jetzt Zugriff hast.<\/p>\n<figure style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2023\/02\/Untitled-6.jpg\" alt=\"WordPress sollte dich automatisch zu diesem Bildschirm weiterleiten, nachdem du das Update installiert hast\" width=\"1600\" height=\"1272\"><figcaption class=\"wp-caption-text\">Willkommen bei WordPress 6.1<\/figcaption><\/figure>\n<p>Du bist fertig! Du brauchst nichts weiter zu tun und deine Website sollte jetzt einwandfrei funktionieren.<\/p>\n<p>Wenn du diese Seite in Zukunft wieder aufrufen m\u00f6chtest, kannst du sie manuell aufrufen, indem du zu <em>youractualdomain.com\/wp-admin\/about.php<\/em> gehst.<\/p>\n<h3>Aktualisiere deine WordPress-Version mit FTP<\/h3>\n<p>Obwohl es am sinnvollsten ist, automatische Updates zu erhalten oder auf die Links im Dashboard zu klicken, gibt es noch eine andere Methode, WordPress zu aktualisieren. Du kannst diese Methode in Erw\u00e4gung ziehen, wenn du Probleme mit dem einfachen <strong>Upgrade-Button<\/strong> im Dashboard hast oder wenn du aus irgendeinem Grund keinen Zugriff mehr auf dein Dashboard hast.<\/p>\n<p>Bei dieser Methode l\u00e4dst du per FTP (File Transfer Protocol) die neueste WordPress-Version auf deinen Computer herunter. Dann ersetzt du die alten Dateien deiner Website mit einem FTP-Client durch neue.<\/p>\n<p>Mehr dazu <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-dateien\/\">erf\u00e4hrst du in diesem Artikel \u00fcber FTP<\/a>, einschlie\u00dflich der Verwaltung und des Hochladens von Dateien auf deine WordPress-Website per FTP.<\/p>\n<p>Wenn du einen FTP-Client verwendest, um WordPress zu aktualisieren, gehst du zun\u00e4chst auf die <a href=\"https:\/\/wordpress.org\/download\/\" target=\"_blank\" rel=\"noopener noreferrer\">Download-Seite von WordPress.org<\/a>. Scrolle nach unten zur Schaltfl\u00e4che <strong>WordPress herunterladen<\/strong>. Auf der Schaltfl\u00e4che sollten auch die Versionsnummern zu finden sein.<\/p>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-important\">\n            <h3>Important<\/h3>\n        <p>L\u00f6sche oder \u00fcberschreibe nicht den Ordner wp-content. Dieser Ordner enth\u00e4lt alle deine Plugins, Themes und hochgeladenen Medien.<\/p>\n<\/aside>\n\n<figure id=\"attachment_146819\" aria-describedby=\"caption-attachment-146819\" style=\"width: 1200px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-146819 size-full\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/03\/download-wordpress-6.1.png\" alt=\"Herunterladen der neuesten WordPress-Version\" width=\"1200\" height=\"548\"><figcaption id=\"caption-attachment-146819\" class=\"wp-caption-text\">Herunterladen der neuesten WordPress-Version<\/figcaption><\/figure>\n<p>Wenn du darauf klickst, wird eine Zip-Datei auf deinen Computer heruntergeladen.<\/p>\n<p>Jetzt musst du den Ordner entpacken:<\/p>\n<ul>\n<li>Unter Windows kannst du mit der rechten Maustaste auf die Datei klicken und <strong>Alle extrahieren<\/strong> w\u00e4hlen. Dann kannst du den Ordner \u00f6ffnen.<\/li>\n<li>Unter macOS kannst du einfach auf die Datei doppelklicken und macOS entpackt die Datei automatisch und \u00f6ffnet den Ordner f\u00fcr dich.<\/li>\n<\/ul>\n<p>So sieht es unter macOS aus &#8211; du kannst die urspr\u00fcngliche Zip-Datei und den entpackten Ordner sehen.<\/p>\n<figure style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2023\/02\/Untitled-15.jpg\" alt=\"Zip-Datei und entpackter Ordner auf einem Mac\" width=\"1600\" height=\"513\"><figcaption class=\"wp-caption-text\">Zip-Datei und entpackter Ordner auf einem Mac<\/figcaption><\/figure>\n<p>In dem entpackten WordPress-Ordner solltest du eine Reihe von Dateien und drei Ordner sehen &#8211; <strong>wp-admin<\/strong>, <strong>wp-content<\/strong> und <strong>wp-includes<\/strong>.<\/p>\n<figure style=\"width: 1392px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2023\/02\/Untitled-16.jpg\" alt=\"Dateiliste innerhalb des Ordners\" width=\"1392\" height=\"938\"><figcaption class=\"wp-caption-text\">Dateiliste<\/figcaption><\/figure>\n<p>Um auf Nummer sicher zu gehen, kannst du den Ordner <strong>wp-content <\/strong>l\u00f6schen. In diesem Ordner befinden sich alle deine Themes und Plugins. Du solltest also vermeiden, versehentlich etwas zu \u00fcberschreiben, was mit diesem Ordner zu tun hat.<\/p>\n<p>Der Ordner <strong>wp-content<\/strong> enth\u00e4lt keine neuen Dateien, die mit dem WordPress-Update zusammenh\u00e4ngen, du musst ihn also nicht per FTP hochladen. <em>Er enth\u00e4lt nur die Standard-Themes und Standard-Plugins wie Helly Dolly, die du nicht hochladen musst, um WordPress per FTP zu aktualisieren.<\/em><\/p>\n<figure style=\"width: 1402px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2023\/02\/Untitled-17.jpg\" alt=\"L\u00f6sche den Ordner wp-content\" width=\"1402\" height=\"972\"><figcaption class=\"wp-caption-text\">L\u00f6sche den Ordner wp-content<\/figcaption><\/figure>\n<p>Wenn du den Ordner <strong>wp-content<\/strong> gel\u00f6scht hast, sollte der WordPress-Ordner wie folgt aussehen..<\/p>\n<figure style=\"width: 1396px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2023\/02\/Untitled-18.jpg\" alt=\"Neue Dateiliste ohne den Ordner wp-content\" width=\"1396\" height=\"924\"><figcaption class=\"wp-caption-text\">Neue Dateiliste<\/figcaption><\/figure>\n<p>Als N\u00e4chstes musst du deinen FTP-Client \u00f6ffnen und ihn mit deiner WordPress-Website verbinden. <a href=\"https:\/\/kinsta.com\/de\/blog\/besten-ftp-clients\/\">Hier findest du eine Liste der empfohlenen FTP-Clients<\/a>, falls du dich f\u00fcr diesen Weg entscheidest.<\/p>\n<p>Du musst dich mit dem Root-Ordner deiner Website verbinden, indem du Host, Benutzername, Passwort und Port angibst, die du im Kinsta-Dashboard findest &#8211; oder im Dashboard jedes anderen Hosts.<\/p>\n<p>Nachdem du dich mit deiner Website verbunden hast, suche den Stammordner deiner Website in der linken Spalte. Der Stammordner hei\u00dft normalerweise <strong>public<\/strong>. Manchmal ist er auch nach deiner Website benannt.<\/p>\n<p>Wenn du den Stammordner \u00f6ffnest, siehst du Ordner wie <code>wp-admin<\/code> und <code>wp-content<\/code>. Er sieht fast genauso aus wie der Ordner in der Spalte Computerdateien. Der Hauptunterschied besteht darin, dass die Spalte mit den Computerdateien die neuesten Updates enth\u00e4lt.<\/p>\n<p>W\u00e4hle alle Dateien innerhalb des neuen Update-Ordners aus. Klicke mit der rechten Maustaste auf diese Auswahl und klicke auf die Schaltfl\u00e4che <strong>Hochladen<\/strong>.<\/p>\n<figure id=\"attachment_147210\" aria-describedby=\"caption-attachment-147210\" style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-147210 size-full\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2023\/02\/Untitled-19.jpg\" alt=\"Hochladen der neuesten WordPress-Version per FTP\" width=\"1600\" height=\"1109\"><figcaption id=\"caption-attachment-147210\" class=\"wp-caption-text\">Hochladen der neuesten WordPress-Version per FTP<\/figcaption><\/figure>\n<p>Dein FTP-Client versucht, alle Dateien von deinem Computer auf den Server deiner Website hochzuladen. Bei diesem Vorgang werden die alten Dateien ersetzt. Deshalb solltest du <strong>\u00dcberschreiben<\/strong> und <strong>Immer diese Aktion verwenden<\/strong> ausw\u00e4hlen, bevor du auf OK klickst.<\/p>\n<figure style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2023\/02\/Untitled-7.jpg\" alt=\"W\u00e4hle \u00dcberschreiben\" width=\"1600\" height=\"914\"><figcaption class=\"wp-caption-text\">W\u00e4hle \u00dcberschreiben<\/figcaption><\/figure>\n<p>Der FTP-Client gibt schlie\u00dflich eine Erfolgsmeldung aus, wenn er alle Dateien hochgeladen hat.<\/p>\n<p>Die Chancen stehen gut, dass der Prozess damit beendet ist. M\u00f6glicherweise musst du aber auch deine Datenbank aktualisieren. Beende daher den FTP-Client und gehe in den WordPress-Adminbereich im Dashboard.<\/p>\n<p>Klicke auf die Schaltfl\u00e4che <strong>WordPress-Datenbank aktualisieren<\/strong>, wenn du die folgende Meldung in deinem Dashboard siehst.<\/p>\n<figure id=\"attachment_90203\" aria-describedby=\"caption-attachment-90203\" style=\"width: 1271px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-90203 size-full\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/03\/update-the-data.png\" alt=\"Klicke auf die Schaltfl\u00e4che \"WordPress-Datenbank aktualisieren\"\" width=\"1271\" height=\"625\"><figcaption id=\"caption-attachment-90203\" class=\"wp-caption-text\">Klicke auf die Schaltfl\u00e4che &#8222;WordPress-Datenbank aktualisieren&#8220;<\/figcaption><\/figure>\n<p>Wenn keine Datenbank-Meldung erscheint, bist du fertig! Normalerweise wird eine Datenbankaktualisierung nur dann verlangt, wenn die neue WordPress-Version selbst ein Upgrade der Datenbank erfordert.<\/p>\n<p>Du kannst auch lernen, wie du die <a href=\"https:\/\/kinsta.com\/de\/blog\/wie-man-php-in-wordpress-aktualisiert\/\">PHP-Version deiner Website aktualisieren<\/a> kannst. Die PHP-Version ist unabh\u00e4ngig vom WordPress-Versionsupdate, aber es ist oft eine gute Idee, um deine Geschwindigkeit und Sicherheit in WordPress zu verbessern.<\/p>\n<h3>Tipps f\u00fcr die Zeit nach dem WordPress-Versionsupdate<\/h3>\n<p>Es mag den Anschein haben, dass du nach der Aktualisierung von WordPress wieder zur Tagesordnung \u00fcbergehen kannst. Das ist in der Regel auch der Fall, aber es ist trotzdem ratsam, nach Fehlfunktionen auf deiner Website Ausschau zu halten.<\/p>\n<p>Du hast deine WordPress-Kerndateien komplett gegen neue ausgetauscht, so dass es m\u00f6glich ist, dass ein Plugin oder Theme mit dem neuesten Update in Konflikt ger\u00e4t. Oder du stellst fest, dass es einen auff\u00e4lligen Fehler gibt, den du WordPress melden solltest.<\/p>\n<p>Wir empfehlen dir, <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-cache-loschen\/\">deinen Cache zu leeren<\/a> und das Frontend deiner WordPress-Website in einem neuen Browserfenster aufzurufen. Vergewissere dich, dass alles so aussieht, wie es soll. Du kannst diesen einfachen Test auch im Backend durchf\u00fchren und sicherstellen, dass nichts seltsam oder kaputt aussieht.<\/p>\n<h2>Wie viele neue WordPress-Versionen gibt es pro Jahr?<\/h2>\n<p>Im Durchschnitt bringt WordPress etwa 3 Hauptversionen pro Jahr heraus. Diese Zahl ist jedoch nicht in Stein gemei\u00dfelt und es gab Jahre mit mehr oder weniger Hauptversionen.<\/p>\n<p>F\u00fcr jede WordPress-Hauptversion gibt es einen festgelegten Ver\u00f6ffentlichungszyklus mit 5 Phasen und ein spezielles Team, das f\u00fcr diese Version verantwortlich ist:<\/p>\n<ul>\n<li><strong>Phase 1<\/strong>: <strong>Planung und Zuweisung von Teamleads<\/strong> &#8211; der Release Lead bespricht die Features und bestimmt die Teamleads f\u00fcr diese Features. Dies geschieht normalerweise im Slack-Kanal #core.<\/li>\n<li><strong>Phase 2<\/strong>: <strong>Entwicklungsarbeit <\/strong>&#8211; die Teamleads und Mitarbeiter\/innen arbeiten an der Entwicklung der ihnen zugewiesenen Funktionen.<\/li>\n<li><strong>Phase 3<\/strong>: <strong>Beta<\/strong> &#8211; mehrere Beta-Versionen werden ver\u00f6ffentlicht, um Fehler und Probleme zu erkennen. Zu diesem Zeitpunkt werden keine neuen Funktionen hinzugef\u00fcgt.<\/li>\n<li><strong>Phase 4<\/strong>: <strong>Release Candidate <\/strong>&#8211; dies ist sozusagen die endg\u00fcltige Version der Ver\u00f6ffentlichung. Alles wird eingefroren, w\u00e4hrend die Nutzer weiter nach Fehlern und Problemen suchen.<\/li>\n<li><strong>Phase 5<\/strong>: <strong>Launch <\/strong>&#8211; die Version wird offiziell ver\u00f6ffentlicht und du kannst das Upgrade \u00fcber dein WordPress-Dashboard oder durch Herunterladen der Software durchf\u00fchren.<\/li>\n<\/ul>\n<p>In der Regel dauert dieser vollst\u00e4ndige 5-Phasen-Release-Zyklus etwa 4 Monate, weshalb du in der Regel mit etwa 3 gro\u00dfen WordPress-Releases pro Jahr rechnen kannst.<\/p>\n<p>Allerdings sind die Situation und der Umfang jeder Version unterschiedlich, so dass dieser Release-Zyklus bei bestimmten Versionen k\u00fcrzer oder l\u00e4nger dauern kann. Deshalb gibt es auch nicht immer eine bestimmte Anzahl von WordPress-Versionen pro Jahr.<\/p>\n<p><a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-5-0\/\">WordPress 5.0 im Jahr 2018<\/a> war zum Beispiel eine der gr\u00f6\u00dften Ver\u00f6ffentlichungen seit langem, weil damit <a href=\"https:\/\/kinsta.com\/de\/blog\/gutenberg-wordpress-editor\/\">der Block-Editor (auch bekannt als Gutenberg)<\/a> eingef\u00fchrt wurde. Im Jahr 2018 war WordPress 5.0 die einzige gro\u00dfe Ver\u00f6ffentlichung des ganzen Jahres, weil sie so viel Aufmerksamkeit erforderte.<\/p>\n<p>Zwischen <a href=\"https:\/\/kinsta.com\/blog\/wordpress-4-9\/\">WordPress 4.9<\/a>, das am 15. November 2017 ver\u00f6ffentlicht wurde, und WordPress 5.0, das am 6. Dezember 2018 herauskam, lagen \u00fcber 12 Monate.<\/p>\n<p>Einige WordPress-Mitwirkende <a href=\"https:\/\/make.wordpress.org\/core\/2019\/02\/27\/major-and-minor-version-release-cadence\/\">haben vorgeschlagen<\/a>, k\u00fcrzere, zeitbasierte Ver\u00f6ffentlichungszyklen anstelle des derzeitigen Ansatzes einzuf\u00fchren, z. B. eine neue Version alle ein oder zwei Monate. Dieser Ansatz hat jedoch nicht viel Anklang gefunden und WordPress verwendet nach wie vor den oben beschriebenen 5-Phasen-Release-Zyklus anstelle eines festen zeitbasierten Release-Zyklus.<\/p>\n<h2>Alle aktuellen WordPress-Versions-Updates aus dem letzten Jahr<\/h2>\n<p>WordPress 6.1 erschien am 1. November 2022 und war die letzte gro\u00dfe Version des Jahres <em>(obwohl das kleinere Update WordPress 6.1.1 zwei Wochen sp\u00e4ter am 15. November ver\u00f6ffentlicht wurde<\/em>).<\/p>\n<p>Insgesamt gab es im Jahr 2022 3 WordPress-Hauptversionen und ~7 &#8222;einzigartige&#8220; kleinere Korrekturen zu diesen Hauptversionen. Hier sind die Hauptversionen des Jahres 2022:<\/p>\n<ul>\n<li><a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-5-9\/\">WordPress 5.9<\/a> &#8222;Jos\u00e9phine&#8220; &#8211; 25. Januar 2022<\/li>\n<li><a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-6-0\/\">WordPress 6.0<\/a> &#8222;Arturo&#8220; &#8211; 24. Mai 2022<\/li>\n<li><a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-6-1\/\">WordPress 6.1<\/a> &#8222;Misha&#8220; &#8211; 1. November 2022<\/li>\n<\/ul>\n<p>Die tats\u00e4chliche Anzahl der Releases war h\u00f6her, weil WordPress im Rahmen seiner Verpflichtung zur Abw\u00e4rtskompatibilit\u00e4t auch \u00e4ltere WordPress-Versionen mit kleineren Releases versieht.<\/p>\n<p>WordPress 3.7, das urspr\u00fcnglich im Oktober 2013 ver\u00f6ffentlicht wurde, erhielt zum Beispiel bis zum 1. Dezember 2022 immer noch kleinere Versionsverbesserungen. Die neueste Version ist WordPress 3.7.41 vom November 2022.<\/p>\n<p>Hier sind einige Details zu den 3 letzten Updates, einschlie\u00dflich der Haupt- und Nebenversionen..<\/p>\n<h3>WordPress 6.1.1 Update &#8211; 15. November 2022<\/h3>\n<p><a href=\"https:\/\/wordpress.org\/news\/2022\/11\/wordpress-6-1-1-maintenance-release\/\" target=\"_blank\" rel=\"noopener noreferrer\">WordPress 6.1.1<\/a> war eine Wartungsversion f\u00fcr WordPress 6.1, die etwa 2 Wochen nach der urspr\u00fcnglichen Hauptversion ver\u00f6ffentlicht wurde.<\/p>\n<p>In diesem Release wurden eine Reihe von Fehlern behoben, darunter 29 Fehlerbehebungen in der Kernsoftware und 21 Fehlerbehebungen im Block-Editor.<\/p>\n<h3>WordPress 6.1 Update &#8211; 1. November 2022<\/h3>\n<p><a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-6-1\/\">WordPress 6.1<\/a> war die letzte gro\u00dfe Ver\u00f6ffentlichung des Jahres 2022. Einige der gr\u00f6\u00dften \u00c4nderungen in dieser Version haben wir bereits fr\u00fcher in diesem Beitrag beschrieben.<\/p>\n<h3>WordPress 6.03 Update &#8211; 17. Oktober 2022<\/h3>\n<p><a href=\"https:\/\/wordpress.org\/news\/2022\/10\/wordpress-6-0-3-security-release\/\" target=\"_blank\" rel=\"noopener noreferrer\">WordPress 6.0.3<\/a> war eine Sicherheitsversion und die dritte kleinere Version von WordPress 6.0. Sie enthielt eine Reihe von Korrekturen f\u00fcr eine Reihe von potenziellen Problemen, darunter XSS-Schwachstellen, offene Weiterleitungen, offene E-Mail-Adressen und Medien.<\/p>\n<p>Diese Sicherheitskorrekturen wurden auch f\u00fcr alle fr\u00fcheren WordPress-Versionen ver\u00f6ffentlicht, die noch unterst\u00fctzt werden, also f\u00fcr WordPress 3.7 oder h\u00f6her.<\/p>\n<h3>Andere aktuelle WordPress-Versionen<\/h3>\n<p>Hier ist eine unvollst\u00e4ndige Liste der vielen WordPress-Updates aus dem Jahr 2022, einschlie\u00dflich ihrer Ver\u00f6ffentlichungsdaten:<\/p>\n<ul>\n<li>6.1.1 &#8211; 15. November 2022<\/li>\n<li>6.1 &#8211; 1. November 2022<\/li>\n<li>6.0.3 &#8211; Oktober 17, 2022<\/li>\n<li>6.0.2 &#8211; August 30, 2022<\/li>\n<li>6.0,1 &#8211; 12. Juli 2022<\/li>\n<li>6.0 &#8211; 24. Mai 2022<\/li>\n<li>5.9,5 &#8211; 17. Oktober 2022<\/li>\n<li>5.9,4 &#8211; 30. August 2022<\/li>\n<li>5.9,3 &#8211; 5. April 2022<\/li>\n<li>5.9.2 &#8211; 11. M\u00e4rz 2022<\/li>\n<li>5.9.1 &#8211; 22. Februar 2022<\/li>\n<li>5.9 &#8211; 25. Januar 2022<\/li>\n<li>5.8.6 &#8211; 17. Oktober 2022<\/li>\n<li>5.8.5 &#8211; 30. August 2022<\/li>\n<li>5.8.4 &#8211; 11. M\u00e4rz 2022<\/li>\n<li>5.8.3 &#8211; 6. Januar 2022<\/li>\n<li>Etc.<\/li>\n<\/ul>\n<p>Die Liste geht bis zu WordPress 3.7 (eingef\u00fchrt 2013) zur\u00fcck, das im November 2022 sein 41. Update bekam. <a href=\"https:\/\/make.wordpress.org\/security\/2022\/09\/07\/dropping-security-updates-for-wordpress-versions-3-7-through-4-0\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ab dem 1. Dezember 2022<\/a> werden Versionen einschlie\u00dflich 4.0 und \u00e4lter keine Sicherheitsupdates mehr erhalten. Das bedeutet, dass nur die Versionen 4.1 und sp\u00e4ter im Jahr 2023 neue Sicherheitsupdates erhalten werden.<\/p>\n<p>Zu den anderen wichtigen WordPress-Updates der letzten Zeit geh\u00f6ren die folgenden:<\/p>\n<ul>\n<li><a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-5-8\/\">WordPress 5.8<\/a> &#8222;Art Tatum&#8220; &#8211; 20. Juli 2021<\/li>\n<li><a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-5-7\/\">WordPress 5.7<\/a> &#8222;Esperanza Spalding&#8220; &#8211; 9. M\u00e4rz 2021<\/li>\n<li><a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-5-6\/\">WordPress 5.6<\/a> &#8222;Nina Simone&#8220; &#8211; Dezember 8, 2020<\/li>\n<li><a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-5-5\/\">WordPress 5.5<\/a> &#8222;Billy Eckstine&#8220; &#8211; August 11, 2020<\/li>\n<li><a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-5-4\/\">WordPress 5.4<\/a> &#8222;Nat Adderley&#8220; &#8211; 31. M\u00e4rz 2020<\/li>\n<li><a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-5-3\/\">WordPress5.3<\/a> &#8222;Rahsaan Roland Kirk&#8220; &#8211; 12. November 2019<\/li>\n<li>.<a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-5-2\/\">WordPress 5.2<\/a> &#8222;Jaco Pastorius&#8220; &#8211; 7. Mai 2019<\/li>\n<li>.<a href=\"https:\/\/kinsta.com\/blog\/wordpress-5-1\/\">WordPress 5.1<\/a> &#8222;Betty Carter&#8220; &#8211; Februar 21, 2019<\/li>\n<li><a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-5-0\/\">WordPress 5.0<\/a> &#8222;Bebo Vald\u00e9s&#8220; &#8211; Dezember 6, 2018<\/li>\n<li><a href=\"https:\/\/kinsta.com\/blog\/wordpress-4-9\/\">WordPress 4.9<\/a> &#8222;Billy Tipton&#8220; &#8211; November 15, 2017<\/li>\n<\/ul>\n\n<h2>Zusammenfassung<\/h2>\n<p>Die Aktualisierung auf die neueste WordPress-Version ist wichtig. Sie stellt sicher, dass deine WordPress-Website immer in einem Top-Zustand ist. Au\u00dferdem bringt es viele Sicherheits- und <a href=\"https:\/\/kinsta.com\/de\/lernen\/wordpress-beschleunigen\/\">Leistungsverbesserungen<\/a> mit sich.<\/p>\n<p>WordPress bietet jetzt auch automatische Updates an. Das kannst du nutzen, um alle deine WordPress-Seiten automatisch auf die neueste Version zu bringen. Wenn du viele Websites verwaltest, ist diese Funktion sehr praktisch.<\/p>\n<p>Und schlie\u00dflich kannst du dich \u00fcber die kommenden WordPress-Versionen auf dem Laufenden halten, indem du die offizielle <a href=\"https:\/\/wordpress.org\/news\/category\/releases\/\" target=\"_blank\" rel=\"noopener noreferrer\">Archivseite f\u00fcr die Versionskategorie<\/a> aufrufst. Dort findest du alle Details zu jeder WordPress-Version, einschlie\u00dflich kleinerer Wartungsupdates und gr\u00f6\u00dferer Versionen.<\/p>\n<p><em>Lass es uns in den Kommentaren wissen, wenn du Fragen zur Ermittlung deiner aktuellen WordPress-Version und zum Upgrade auf die neueste WordPress-Version hast.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>WordPress ist eine sich st\u00e4ndig weiterentwickelnde Software, die regelm\u00e4\u00dfig neue Funktionen, Sicherheitskorrekturen und Wartungsupdates ver\u00f6ffentlicht. Diese grundlegenden Updates gew\u00e4hrleisten die Sicherheit und Effizienz des WordPress-Systems. Wenn &#8230;<\/p>\n","protected":false},"author":117,"featured_media":41094,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[28,348],"topic":[999,1011],"class_list":["post-41092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-webdev","tag-wordpressversion","topic-wordpress-entwicklung","topic-wordpress-updates"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wie du deine aktuelle WordPress-Version findest und auf die neueste Version aktualisierst - Kinsta\u00ae<\/title>\n<meta name=\"description\" content=\"Finde deine aktuelle WordPress-Version und erfahre, wie du auf die neueste WordPress-Version aktualisieren kannst, damit deine Website schnell und sicher bleibt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie du deine aktuelle WordPress-Version findest und auf die neueste Version aktualisierst\" \/>\n<meta property=\"og:description\" content=\"Finde deine aktuelle WordPress-Version und erfahre, wie du auf die neueste WordPress-Version aktualisieren kannst, damit deine Website schnell und sicher bleibt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-13T07:56:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-28T11:53:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/04\/wordpress-version.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1460\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Salman Ravoof\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Finde deine aktuelle WordPress-Version und erfahre, wie du auf die neueste WordPress-Version aktualisieren kannst, damit deine Website schnell und sicher bleibt.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/04\/wordpress-version.png\" \/>\n<meta name=\"twitter:creator\" content=\"@salmanravoof\" \/>\n<meta name=\"twitter:site\" content=\"@Kinsta_DE\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Salman Ravoof\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"19\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/\"},\"author\":{\"name\":\"Salman Ravoof\",\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987\"},\"headline\":\"Wie du deine aktuelle WordPress-Version findest und auf die neueste Version aktualisierst\",\"datePublished\":\"2021-04-13T07:56:46+00:00\",\"dateModified\":\"2023-08-28T11:53:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/\"},\"wordCount\":3709,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/04\/wordpress-version.png\",\"keywords\":[\"webdev\",\"wordpressversion\"],\"articleSection\":[\"Die besten WordPress Tutorials\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/\",\"url\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/\",\"name\":\"Wie du deine aktuelle WordPress-Version findest und auf die neueste Version aktualisierst - Kinsta\u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/04\/wordpress-version.png\",\"datePublished\":\"2021-04-13T07:56:46+00:00\",\"dateModified\":\"2023-08-28T11:53:51+00:00\",\"description\":\"Finde deine aktuelle WordPress-Version und erfahre, wie du auf die neueste WordPress-Version aktualisieren kannst, damit deine Website schnell und sicher bleibt.\",\"breadcrumb\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#primaryimage\",\"url\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/04\/wordpress-version.png\",\"contentUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/04\/wordpress-version.png\",\"width\":1460,\"height\":730,\"caption\":\"WordPress version\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kinsta.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WordPress Updates\",\"item\":\"https:\/\/kinsta.com\/de\/thema\/wordpress-updates\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wie du deine aktuelle WordPress-Version findest und auf die neueste Version aktualisierst\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kinsta.com\/de\/#website\",\"url\":\"https:\/\/kinsta.com\/de\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Schnelle, sichere und hochwertige Hosting-L\u00f6sungen\",\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kinsta.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kinsta.com\/de\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kinsta.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/\",\"https:\/\/x.com\/Kinsta_DE\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987\",\"name\":\"Salman Ravoof\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g\",\"caption\":\"Salman Ravoof\"},\"description\":\"Salman Ravoof is a self-taught web developer, writer, creator, and a huge admirer of Free and Open Source Software (FOSS). Besides tech, he's excited by science, philosophy, photography, arts, cats, and food. Learn more about him on his website, and connect with Salman on Twitter.\",\"sameAs\":[\"https:\/\/salmanravoof.com\",\"https:\/\/www.linkedin.com\/in\/salman-ravoof-5a749133\/\",\"https:\/\/x.com\/salmanravoof\"],\"url\":\"https:\/\/kinsta.com\/de\/blog\/author\/salmanravoof\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wie du deine aktuelle WordPress-Version findest und auf die neueste Version aktualisierst - Kinsta\u00ae","description":"Finde deine aktuelle WordPress-Version und erfahre, wie du auf die neueste WordPress-Version aktualisieren kannst, damit deine Website schnell und sicher bleibt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/","og_locale":"de_DE","og_type":"article","og_title":"Wie du deine aktuelle WordPress-Version findest und auf die neueste Version aktualisierst","og_description":"Finde deine aktuelle WordPress-Version und erfahre, wie du auf die neueste WordPress-Version aktualisieren kannst, damit deine Website schnell und sicher bleibt.","og_url":"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/","article_published_time":"2021-04-13T07:56:46+00:00","article_modified_time":"2023-08-28T11:53:51+00:00","og_image":[{"width":1460,"height":730,"url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/04\/wordpress-version.png","type":"image\/png"}],"author":"Salman Ravoof","twitter_card":"summary_large_image","twitter_description":"Finde deine aktuelle WordPress-Version und erfahre, wie du auf die neueste WordPress-Version aktualisieren kannst, damit deine Website schnell und sicher bleibt.","twitter_image":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/04\/wordpress-version.png","twitter_creator":"@salmanravoof","twitter_site":"@Kinsta_DE","twitter_misc":{"Verfasst von":"Salman Ravoof","Gesch\u00e4tzte Lesezeit":"19\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#article","isPartOf":{"@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/"},"author":{"name":"Salman Ravoof","@id":"https:\/\/kinsta.com\/de\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987"},"headline":"Wie du deine aktuelle WordPress-Version findest und auf die neueste Version aktualisierst","datePublished":"2021-04-13T07:56:46+00:00","dateModified":"2023-08-28T11:53:51+00:00","mainEntityOfPage":{"@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/"},"wordCount":3709,"commentCount":0,"publisher":{"@id":"https:\/\/kinsta.com\/de\/#organization"},"image":{"@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/04\/wordpress-version.png","keywords":["webdev","wordpressversion"],"articleSection":["Die besten WordPress Tutorials"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/","url":"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/","name":"Wie du deine aktuelle WordPress-Version findest und auf die neueste Version aktualisierst - Kinsta\u00ae","isPartOf":{"@id":"https:\/\/kinsta.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#primaryimage"},"image":{"@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/04\/wordpress-version.png","datePublished":"2021-04-13T07:56:46+00:00","dateModified":"2023-08-28T11:53:51+00:00","description":"Finde deine aktuelle WordPress-Version und erfahre, wie du auf die neueste WordPress-Version aktualisieren kannst, damit deine Website schnell und sicher bleibt.","breadcrumb":{"@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinsta.com\/de\/blog\/wordpress-version\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#primaryimage","url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/04\/wordpress-version.png","contentUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2021\/04\/wordpress-version.png","width":1460,"height":730,"caption":"WordPress version"},{"@type":"BreadcrumbList","@id":"https:\/\/kinsta.com\/de\/blog\/wordpress-version\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kinsta.com\/de\/"},{"@type":"ListItem","position":2,"name":"WordPress Updates","item":"https:\/\/kinsta.com\/de\/thema\/wordpress-updates\/"},{"@type":"ListItem","position":3,"name":"Wie du deine aktuelle WordPress-Version findest und auf die neueste Version aktualisierst"}]},{"@type":"WebSite","@id":"https:\/\/kinsta.com\/de\/#website","url":"https:\/\/kinsta.com\/de\/","name":"Kinsta\u00ae","description":"Schnelle, sichere und hochwertige Hosting-L\u00f6sungen","publisher":{"@id":"https:\/\/kinsta.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinsta.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/kinsta.com\/de\/#organization","name":"Kinsta","url":"https:\/\/kinsta.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/","https:\/\/x.com\/Kinsta_DE","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kinsta.com\/de\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987","name":"Salman Ravoof","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kinsta.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g","caption":"Salman Ravoof"},"description":"Salman Ravoof is a self-taught web developer, writer, creator, and a huge admirer of Free and Open Source Software (FOSS). Besides tech, he's excited by science, philosophy, photography, arts, cats, and food. Learn more about him on his website, and connect with Salman on Twitter.","sameAs":["https:\/\/salmanravoof.com","https:\/\/www.linkedin.com\/in\/salman-ravoof-5a749133\/","https:\/\/x.com\/salmanravoof"],"url":"https:\/\/kinsta.com\/de\/blog\/author\/salmanravoof\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/posts\/41092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/comments?post=41092"}],"version-history":[{"count":10,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/posts\/41092\/revisions"}],"predecessor-version":[{"id":59875,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/posts\/41092\/revisions\/59875"}],"alternate":[{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/41092\/translations\/en"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/41092\/translations\/fr"},{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/41092\/translations\/it"},{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/41092\/translations\/es"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/41092\/translations\/pt"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/41092\/translations\/de"},{"embeddable":true,"hreflang":"nl","title":"Dutch","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/41092\/translations\/nl"},{"embeddable":true,"hreflang":"da","title":null,"href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/41092\/translations\/dk"},{"embeddable":true,"hreflang":"ja","title":"Japanese","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/41092\/translations\/jp"},{"embeddable":true,"hreflang":"sv","title":null,"href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/41092\/translations\/se"},{"href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/41092\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/media\/41094"}],"wp:attachment":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/media?parent=41092"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/tags?post=41092"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/topic?post=41092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}