{"id":50716,"date":"2022-05-26T14:00:29","date_gmt":"2022-05-26T13:00:29","guid":{"rendered":"https:\/\/kinsta.com\/de\/?p=50716&#038;preview=true&#038;preview_id=50716"},"modified":"2023-08-23T16:03:11","modified_gmt":"2023-08-23T15:03:11","slug":"elementor-vorlagen-importiert","status":"publish","type":"post","link":"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/","title":{"rendered":"Wie man Elementor-Websites exportiert und importiert (Deine vollst\u00e4ndige Anleitung)"},"content":{"rendered":"<p>Das <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-elementor\/\">Elementor-Tool<\/a> macht es einfach, sch\u00f6ne Seiten, Beitr\u00e4ge und ganze Webseiten zu gestalten. Doch selbst mit einem leistungsstarken <a href=\"https:\/\/kinsta.com\/de\/blog\/divi-vs-elementor\/\">Page Builder<\/a> wie Elementor in der Hand ist die Erstellung eines neuen Webseiten-Designs zeitaufw\u00e4ndig und m\u00fchsam.<\/p>\n<p>Hier kommt das Import- und Exportsystem von Elementor ins Spiel. Mit dieser Funktion kannst du deine Design- und Entwicklungszeit verk\u00fcrzen, indem du wiederverwendbare Vorlagen erstellst oder Layouts von Dritten f\u00fcr dein Projekt importierst.<\/p>\n<p>In diesem Beitrag werden wir das flexible und leistungsstarke Import\/Export-System von Elementor genauer unter die Lupe nehmen. Wir werden uns mit allem befassen, von Bereichsvorlagen bis hin zu Seitenvorlagen &#8211; und sogar mit dem Export deiner gesamten Elementor-Webseite. Los geht&#8217;s!<\/p>\n<div><\/div><kinsta-auto-toc heading=\"Table of Contents\" exclude=\"last\" list-style=\"arrow\" selector=\"h2\" count-number=\"-1\"><\/kinsta-auto-toc>\n<h2>So bereitest du deine Webseite f\u00fcr eine neue Elementor-Vorlage vor (in 2 Schritten)<\/h2>\n<p>Elementor-Vorlagen sind vorgefertigte Layouts, die auf einzelne Seiten oder bestimmte Elemente der Benutzeroberfl\u00e4che (UI) angewendet werden. Obwohl sie \u00e4hnlich wie WordPress-Themes klingen, gibt es einige wesentliche Unterschiede.<\/p>\n<p>WordPress-Themes <a href=\"https:\/\/kinsta.com\/de\/blog\/was-ist-ein-wordpress-theme\/\">\u00e4ndern das Design<\/a> einer ganzen Webseite. Im Gegensatz dazu beeinflussen Elementor-Vorlagen das Layout einer einzelnen Webseite. Da sie auf eine einzige Seite beschr\u00e4nkt sind, ist es m\u00f6glich, mehrere Elementor-Vorlagen gleichzeitig zu verwenden. Au\u00dferdem arbeiten diese Vorlagen mit einem <a href=\"https:\/\/kinsta.com\/de\/blog\/schnellsten-wordpress-theme\/\">WordPress-Theme<\/a>, egal ob <a href=\"https:\/\/kinsta.com\/de\/blog\/kostenlose-vs-kostenpflichtige-wordpress-themes\/\">kostenlos oder Premium<\/a>.<\/p>\n<p>Wenn du eine neue Elementor-Vorlage auf deine Webseite anwendest, kann sich ihr Aussehen und ihre Funktionen \u00e4ndern. Aus diesem Grund solltest du einige Ma\u00dfnahmen ergreifen, bevor du deine Vorlage \u00e4nderst.<\/p>\n\n<h3>Schritt 1: Ein Backup erstellen<\/h3>\n<p>Es ist ratsam, <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-seite-einfach-sichert\/\">ein Backup zu erstellen<\/a>, bevor du deine Elementor-Vorlage \u00e4nderst. So stellst du sicher, dass du die Inhalte wiederherstellen kannst, wenn du Probleme mit <a href=\"https:\/\/kinsta.com\/de\/blog\/schnellsten-wordpress-theme\/\">deinem neuen Design<\/a> hast.<\/p>\n<p><a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-backup-plugins\/\">Verschiedene Plugins<\/a> erm\u00f6glichen es dir, ein Backup deiner Webseite zu erstellen. Dazu geh\u00f6rt das <a href=\"https:\/\/wordpress.org\/plugins\/updraftplus\/\" target=\"_blank\" rel=\"noopener noreferrer\">Plugin UpdraftPlus<\/a>, mit dem du alle deine Dateien und Datenbankinformationen in die Cloud kopieren kannst:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/updraftplus-backup-plugin.png\" alt=\"UpdraftPlus Plugin\" width=\"1400\" height=\"450\"><figcaption class=\"wp-caption-text\">UpdraftPlus<\/figcaption><\/figure>\n<p>Wenn du ein Kinsta-Kunde bist, sichern wir deine Webseite automatisch jeden Tag. Wenn du <a href=\"https:\/\/kinsta.com\/de\/docs\/wordpress-hosting\/wordpress-backups\/#wordpress-backup\">h\u00e4ufigere Backups<\/a> brauchst, k\u00f6nnen wir deine Webseite alle sechs Stunden ($50 pro Webseite, pro Monat) oder jede Stunde ($100 pro Webseite, pro Monat) kopieren.<\/p>\n<p>Alternativ kannst du auch jederzeit manuell ein Backup erstellen. Dazu loggst du dich in dein <a href=\"https:\/\/my.kinsta.com\/\">MyKinsta-Dashboard<\/a> ein:<\/p>\n<figure id=\"attachment_50882\" aria-describedby=\"caption-attachment-50882\" style=\"width: 2842px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-50882\" src=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/dashboard-of-mykinsta-de.png\" alt=\"MyKinsta Dashboard\" width=\"2842\" height=\"1110\" srcset=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/dashboard-of-mykinsta-de.png 2842w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/dashboard-of-mykinsta-de-300x117.png 300w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/dashboard-of-mykinsta-de-1024x400.png 1024w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/dashboard-of-mykinsta-de-768x300.png 768w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/dashboard-of-mykinsta-de-1536x600.png 1536w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/dashboard-of-mykinsta-de-2048x800.png 2048w\" sizes=\"auto, (max-width: 2842px) 100vw, 2842px\" \/><figcaption id=\"caption-attachment-50882\" class=\"wp-caption-text\">MyKinsta Dashboard<\/figcaption><\/figure>\n<p>W\u00e4hle im linken Men\u00fc <strong>Seiten<\/strong>\u00a0und klicke auf die betreffende Webseite. W\u00e4hle dann <strong>Backups &gt; Manuell<\/strong>:<\/p>\n<figure id=\"attachment_50879\" aria-describedby=\"caption-attachment-50879\" style=\"width: 2840px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-50879 size-full\" src=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/backups-manual-tab-mykinsta-de.png\" alt=\"Klicke auf \"Seiten\" und dann auf \"Backup\"\" width=\"2840\" height=\"970\" srcset=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/backups-manual-tab-mykinsta-de.png 2840w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/backups-manual-tab-mykinsta-de-300x102.png 300w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/backups-manual-tab-mykinsta-de-1024x350.png 1024w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/backups-manual-tab-mykinsta-de-768x262.png 768w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/backups-manual-tab-mykinsta-de-1536x525.png 1536w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/backups-manual-tab-mykinsta-de-2048x699.png 2048w\" sizes=\"auto, (max-width: 2840px) 100vw, 2840px\" \/><figcaption id=\"caption-attachment-50879\" class=\"wp-caption-text\">Klicke auf &#8222;Seiten&#8220; und dann auf &#8222;Backup&#8220;<\/figcaption><\/figure>\n<p>Klicke einfach auf die Schaltfl\u00e4che <strong>Jetzt sichern<\/strong>\u00a0und wir k\u00fcmmern uns um den Rest. Wenn du auf Probleme st\u00f6\u00dft und <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-backup-wiederherstellen\/\">dein letztes Backup wiederherstellen<\/a> m\u00f6chtest, navigiere zum Reiter <strong>Backups &gt; Manuell<\/strong>. Hier zeigt MyKinsta eine Liste aller deiner Backups an:<\/p>\n<figure id=\"attachment_50880\" aria-describedby=\"caption-attachment-50880\" style=\"width: 2840px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-50880\" src=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/display-backups-mykinsta-de.png\" alt=\"MyKinsta zeigt eine Liste aller Backups an\" width=\"2840\" height=\"960\" srcset=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/display-backups-mykinsta-de.png 2840w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/display-backups-mykinsta-de-300x101.png 300w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/display-backups-mykinsta-de-1024x346.png 1024w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/display-backups-mykinsta-de-768x260.png 768w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/display-backups-mykinsta-de-1536x519.png 1536w, https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/display-backups-mykinsta-de-2048x692.png 2048w\" sizes=\"auto, (max-width: 2840px) 100vw, 2840px\" \/><figcaption id=\"caption-attachment-50880\" class=\"wp-caption-text\">MyKinsta zeigt eine Liste aller Backups an<\/figcaption><\/figure>\n<p>Um eine fr\u00fchere Version deiner Webseite wiederherzustellen, klicke auf die zugeh\u00f6rige Schaltfl\u00e4che <strong>Wiederherstellen auf<\/strong>. Du kannst nun w\u00e4hlen, ob du dieses Backup auf deiner Live-Site oder einer Staging-Webseite wiederherstellen m\u00f6chtest.<\/p>\n<h3>Schritt 2: Versetze deine Webseite in den Wartungsmodus<\/h3>\n<p>Wenn du die Vorlage deiner Webseite \u00e4nderst, kann es zu unerwarteten Abst\u00fcrzen, Fehlern oder anderem seltsamen Verhalten kommen. Nachdem du ein neues Design angewendet hast, solltest du einige Zeit damit verbringen, deine Webseite zu testen und Anpassungen vorzunehmen.<\/p>\n<p>Wenn ein Besucher versucht, auf deine Webseite zuzugreifen, w\u00e4hrend du diese \u00c4nderungen vornimmst, kann sich das auf die Qualit\u00e4t des Besuchs auswirken. Das kann dazu f\u00fchren, dass dir potenzielle Ums\u00e4tze entgehen.<\/p>\n<p>Bevor du eine neue Elementor-Vorlage anwendest, solltest du deine Webseite in den <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-wartungsmodus\/\">Wartungsmodus<\/a> versetzen. Damit verhinderst du, dass Besucher auf deine Seite zugreifen, w\u00e4hrend du dein neues Design testest.<\/p>\n<p>Mehrere Plugins k\u00f6nnen einen eigenen Wartungsmodus erstellen. <a href=\"https:\/\/wordpress.org\/plugins\/wp-maintenance-mode\/\" target=\"_blank\" rel=\"noopener noreferrer\">WP Maintenance Mode<\/a> ist jedoch eine beliebte Wahl:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/wp-maintenance-mode.png\" alt=\"Das WP Maintenance Mode Plugin\" width=\"1400\" height=\"446\"><figcaption class=\"wp-caption-text\">WP-Wartungsmodus<\/figcaption><\/figure>\n<p>Dieses Plugin hat viele zus\u00e4tzliche Extras, wie z.B. einen Countdown f\u00fcr deinen Wartungs-Splash-Screen. Diese Funktion kann dir dabei helfen, die Neugestaltung und den Relaunch deiner Webseite in Szene zu setzen.<\/p>\n<p>Sobald sich deine Website im Wartungsmodus befindet, kannst du mit verschiedenen Vorlagen experimentieren und testen, wie sie im Frontend deiner Webseite aussehen. Wenn du mit den Ergebnissen zufrieden bist, kannst du deine Webseite aus dem Wartungsmodus nehmen &#8211; und die Besucher mit deinem neuen Design begeistern.<\/p>\n<h2>Wie man Elementor-Vorlagen speichert (2 Methoden)<\/h2>\n<p>Als einer der weltweit <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-page-builders\/\">beliebtesten Page Builder<\/a> hat Elementor einen gro\u00dfen Fundus an vorgefertigten Vorlagen von Drittanbietern. Manchmal m\u00f6chtest du aber auch deine eigenen Vorlagen erstellen.<\/p>\n<p>Die Verwendung von Vorlagen kann dir helfen, ein <a href=\"https:\/\/kinsta.com\/de\/blog\/best-practices-fur-webdesign\/\">einheitliches Design f\u00fcr deine gesamte Webseite zu erreichen<\/a>. Au\u00dferdem kannst du damit Zeit sparen, vor allem wenn du dieselben Designs auf mehreren Webseiten verwendest.<\/p>\n<p>WordPress-Design- und -Entwicklungsagenturen k\u00f6nnen zum Beispiel davon profitieren, Vorlagen mit den Kernelementen zu erstellen, die sie regelm\u00e4\u00dfig auf ihren Kundenseiten verwenden.<\/p>\n<h3>Methode 1: Speichere eine Seite als Elementor-Vorlage<\/h3>\n<p>Du kannst jede Seite als Elementor-Vorlage speichern. So kannst du ein einheitliches Erscheinungsbild erstellen, das du auf deiner gesamten Webseite einsetzen kannst.<\/p>\n<p>Du k\u00f6nntest zum Beispiel die <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-menue\/\">Men\u00fcs deiner Webseite<\/a>, den Header und den <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-footer-bearbeiten\/\">WordPress-Footer<\/a> <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-menue\/\">erstellen<\/a>. Diese Seitenvorlage kannst du dann auf alle deine Webseiten anwenden.<\/p>\n<p>Eine Vorlage zu erstellen bedeutet auch, dass du nicht f\u00fcr jede Webseite dieselben Elemente manuell neu erstellen musst. Das ist eine gute Nachricht f\u00fcr deine Produktivit\u00e4t.<\/p>\n<p>Um die aktuelle Seite als Elementor-Vorlage zu speichern, suche die gr\u00fcne Schaltfl\u00e4che <strong>Aktualisieren\/Ver\u00f6ffentlichen<\/strong> unten in der Elementor-Seitenleiste. Klicke dann auf das Pfeilsymbol dieser Schaltfl\u00e4che:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/elementor-update-publish.png\" alt=\"Seite als Elementor Template speichern\" width=\"1400\" height=\"817\"><figcaption class=\"wp-caption-text\">Seite als Elementor-Vorlage speichern<\/figcaption><\/figure>\n<p>Du kannst jetzt auf <strong>Als Vorlage speichern<\/strong> klicken. Daraufhin \u00f6ffnet sich ein Fenster, in dem du der Vorlage einen beschreibenden Namen geben kannst:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/save-as-template-1.png\" alt=\"Benenne deine Seitenvorlage\" width=\"1400\" height=\"914\"><figcaption class=\"wp-caption-text\">Benenne deine Seitenvorlage<\/figcaption><\/figure>\n<p>Klicke dann auf <strong>Speichern<\/strong>. Du kannst nun jederzeit auf dieses Design zugreifen, indem du die Elementor-Bibliothek aufrufst und den Reiter <strong>Meine Vorlagen<\/strong> ausw\u00e4hlst.<\/p>\n<h3>Methode 2: Einen Abschnitt als Elementor-Vorlage speichern<\/h3>\n<p>Viele Webseiten enthalten wiederkehrende Elemente. Dazu geh\u00f6ren Formulare zur <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-lead-generation\/\">Leadgenerierung<\/a> oder Texte, die deine meistverkauften Produkte beschreiben.<\/p>\n<p>Wenn du eine Abschnittsvorlage erstellst, kannst du sie mit nur wenigen Klicks zu jeder Seite hinzuf\u00fcgen. Du kannst sogar Abschnittsvorlagen f\u00fcr verschiedene Inhaltskategorien erstellen.<\/p>\n<p>Du k\u00f6nntest zum Beispiel eine Vorlage f\u00fcr einen <a href=\"https:\/\/kinsta.com\/de\/blog\/tipps-zur-optimierung-der-conversion-rate\/\">Call To Action (CTA)<\/a> erstellen. Jedes Mal, wenn du einen CTA brauchst, kannst du diese Vorlage einfach importieren und den Inhalt anpassen.<\/p>\n<p>Um eine Vorlage zu erstellen, klicke bei gedr\u00fcckter Taste auf den betreffenden <strong>Abschnitt<\/strong>. W\u00e4hle dann <strong>Als Vorlage speichern<\/strong>:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/elementor-edit-section-1.png\" alt=\"Einen Abschnitt als Vorlage speichern\" width=\"1400\" height=\"689\"><figcaption class=\"wp-caption-text\">Einen Abschnitt als Vorlage speichern<\/figcaption><\/figure>\n<p>Gib der Vorlage in dem nun erscheinenden Fenster einen aussagekr\u00e4ftigen Namen. Klicke dann auf <strong>Speichern<\/strong>:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/save-section-template.png\" alt=\"Gib deinem Abschnitt einen Namen\" width=\"1400\" height=\"908\"><figcaption class=\"wp-caption-text\">Gib deinem Abschnitt einen Namen<\/figcaption><\/figure>\n<p>Um diese Vorlage auf einen beliebigen Abschnitt anzuwenden, rufe einfach die Elementor Vorlagenbibliothek auf. Du findest das Design in deinem Reiter <strong>Meine Vorlagen<\/strong>.<\/p>\n<h2>So erstellst du eine Elementor-Vorlage<\/h2>\n<p>Du kannst zwar jede Seite oder jeden Abschnitt, die\/der gerade in Arbeit ist, als <a href=\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen\/\">Elementor-Vorlage<\/a> speichern, aber manchmal m\u00f6chtest du eine Vorlage explizit zur Wiederverwendung erstellen. In diesem Fall kannst du dein Design als normale Elementor-Webseite beginnen und es dann als Vorlage speichern.<\/p>\n<p>Du kannst Elementor aber auch im Voraus mitteilen, dass du eine Vorlage erstellen willst. Dieser Ansatz gibt dir mehr Flexibilit\u00e4t, um Vorlagen f\u00fcr verschiedene Bereiche deiner Webseite zu erstellen.<\/p>\n<p>Du k\u00f6nntest zum Beispiel eine Vorlage f\u00fcr deine 404-Fehlerseite, eine <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-suche\/\">Suchergebnisseite<\/a> oder sogar ein Popup-Layout erstellen. Mit dieser Methode kannst du au\u00dferdem jede Vorlage in deiner Bibliothek als Basis f\u00fcr ein neues Design verwenden.<\/p>\n<p>Um eine Seiten- oder Abschnittsvorlage zu erstellen, gehst du zu <strong>Vorlagen &gt; Gespeicherte Vorlagen<\/strong>. Klicke dann auf <strong>Neu hinzuf\u00fcgen<\/strong>. Im n\u00e4chsten Fenster \u00f6ffnest du das Dropdown-Men\u00fc <strong>Vorlagenart ausw\u00e4hlen&#8230; <\/strong>:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/add-new-template.png\" alt=\"W\u00e4hle einen Template-Typ f\u00fcr dein Elementor-Template\" width=\"1400\" height=\"703\"><figcaption class=\"wp-caption-text\">W\u00e4hle einen Vorlagentyp<\/figcaption><\/figure>\n<p>Jetzt kannst du die Art der Vorlage angeben, die du erstellen m\u00f6chtest. Wir haben bereits \u00fcber Seiten- und Abschnittsvorlagen gesprochen, aber dieses Fenster bietet dir zus\u00e4tzliche Optionen.<\/p>\n<p>Nachdem du ausgew\u00e4hlt hast, gibst du deinem Entwurf einen beschreibenden Namen und klickst dann auf <strong>Vorlage erstellen<\/strong>. Dadurch wird die Elementor-Bibliothek gestartet, in der du eine bereits vorhandene Vorlage als Basis verwenden kannst. Alternativ kannst du dieses Fenster auch verlassen und mit einer neuen Vorlage beginnen.<\/p>\n<p>Jetzt kannst du deine Vorlage mit dem Standard-Elementor-Editor erstellen. Wenn du bereit bist, dein Design zu speichern, klicke auf <strong>Ver\u00f6ffentlichen<\/strong>. Dadurch wird das Feld <strong>Ver\u00f6ffentlichungseinstellungen<\/strong> ge\u00f6ffnet:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/elementor-publish-settings.png\" alt=\"Das Feld Ver\u00f6ffentlichungseinstellungen\" width=\"1400\" height=\"983\"><figcaption class=\"wp-caption-text\">Das Feld Ver\u00f6ffentlichungseinstellungen<\/figcaption><\/figure>\n<p>Hier kannst du einige Regeln f\u00fcr die Verwendung dieser Vorlage festlegen. Du kannst zum Beispiel auf <strong>Bedingung hinzuf\u00fcgen<\/strong> klicken und festlegen, dass dieses Layout nur f\u00fcr einzelne Seiten geeignet ist.<\/p>\n<h2>Wie exportiere ich Elementor-Vorlagen?<\/h2>\n<p>Du kannst Elementor-Vorlagen \u00fcber das WordPress-Dashboard exportieren. Auf diese Weise kannst du Designs mit deinen Kollegen teilen oder <a href=\"https:\/\/kinsta.com\/de\/blog\/wp-feedback-wordpress-plugin\/\">sie an Kunden zur Genehmigung schicken<\/a>. Du kannst die Exportfunktion auch nutzen, um Sicherungskopien deiner Elementor-Designs zu erstellen.<\/p>\n<p>Der Export von Vorlagen ist ein einfacher Weg, um deine Designs auf mehreren Domains zu verwenden. Das ist besonders praktisch f\u00fcr <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-agentur\/\">WordPress-Design- und Entwicklungsagenturen<\/a>, die zahlreiche Webseiten verwalten. Wenn du deine Designs zu Geld machen willst, ist der Export oft der erste Schritt, um sie mit der Welt zu teilen.<\/p>\n<p>Navigiere zu <strong>Vorlagen &gt; Gespeicherte Vorlagen<\/strong> im WordPress-Dashboard, um ein Design zu exportieren. Auf dieser Registerkarte werden alle Vorlagen angezeigt, die du in deiner Bibliothek gespeichert hast:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/saved-templates-elementor.png\" alt=\"Alle gespeicherten Vorlagen anzeigen\" width=\"1400\" height=\"522\"><figcaption class=\"wp-caption-text\">Alle gespeicherten Vorlagen anzeigen<\/figcaption><\/figure>\n<p>WordPress unterteilt diese Vorlagen auch in die Registerkarten <strong>Seite<\/strong> und <strong>Abschnitt<\/strong>. Suche einfach die Vorlage, die du exportieren m\u00f6chtest, und fahre mit dem Mauszeiger \u00fcber sie:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/elementor-export-template.png\" alt=\"W\u00e4hle zwischen Seiten- und Abschnittsvorlagen\" width=\"1400\" height=\"524\"><figcaption class=\"wp-caption-text\">W\u00e4hle zwischen Seiten- und Abschnittsvorlagen<\/figcaption><\/figure>\n<p>Wenn der Link <strong>Vorlage exportieren<\/strong> erscheint, klicke ihn an. Elementor l\u00e4dt nun diese Vorlage als JSON-Datei herunter.<\/p>\n<p>Du kannst deine Vorlagen auch aus der Elementor-Bibliothek exportieren. \u00d6ffne in der Bibliothek die Registerkarte <strong>Meine Vorlagen<\/strong>. Suche die Vorlage, die du exportieren m\u00f6chtest, und klicke auf das zugeh\u00f6rige Symbol mit den drei Punkten:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/elementor-library-export.png\" alt=\"Vorlagen direkt aus der Bibliothek exportieren\" width=\"1400\" height=\"537\"><figcaption class=\"wp-caption-text\">Vorlagen direkt aus der Bibliothek exportieren<\/figcaption><\/figure>\n<p>Dann klickst du auf <strong>Exportieren<\/strong>. Elementor l\u00e4dt diese Vorlage nun als JSON-Datei herunter.<\/p>\n<h2>So importierst du Elementor-Vorlagen<\/h2>\n<p>Manchmal m\u00f6chtest du vielleicht eine Vorlage in Elementor importieren. Dabei kann es sich um ein Design handeln, das du von einer anderen Webseite exportiert oder von einem Drittanbieter gekauft hast.<\/p>\n<p>Wenn du eine Vorlage im JSON- oder ZIP-Format hast, kannst du sie in die Elementor-Bibliothek hochladen. Navigiere dazu zu <strong>Vorlagen &gt; Gespeicherte Vorlagen<\/strong>. Klicke oben auf diesem Bildschirm auf <strong>Vorlagen importieren<\/strong>:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/elementor-import-templates.png\" alt=\"Suche und klicke auf die Schaltfl\u00e4che \"Vorlagen importieren\"\" width=\"1400\" height=\"442\"><figcaption class=\"wp-caption-text\">Suche und klicke auf die Schaltfl\u00e4che &#8222;Vorlagen importieren&#8220;<\/figcaption><\/figure>\n<p>W\u00e4hle dann deine Elementor-Importvorlage aus und klicke auf <strong>Jetzt importieren<\/strong>. Die Vorlage wird nun in deiner Bibliothek erscheinen.<\/p>\n<p>Um dieses Design auf dein Webseiten-Layout anzuwenden, \u00f6ffne einfach die betreffende Seite oder den Beitrag im Elementor-Editor. Dann klickst du auf das Symbol <strong>Vorlage hinzuf\u00fcgen<\/strong>, das durch einen wei\u00dfen Ordner dargestellt wird:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/elementor-add-template.png\" alt=\"Finde die Schaltfl\u00e4che \"Vorlage hinzuf\u00fcgen\"\" width=\"1400\" height=\"836\"><figcaption class=\"wp-caption-text\">Finde die Schaltfl\u00e4che &#8222;Vorlage hinzuf\u00fcgen&#8220;<\/figcaption><\/figure>\n<p>Im n\u00e4chsten Fenster w\u00e4hlst du die Registerkarte <strong>Meine Vorlagen<\/strong>. Hier findest du alle deine importierten Elementor-Vorlagen:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/elementor-my-templates.png\" alt=\"Alle importierten Vorlagen anzeigen\" width=\"1400\" height=\"814\"><figcaption class=\"wp-caption-text\">Alle importierten Vorlagen anzeigen<\/figcaption><\/figure>\n<p>Um zu sehen, wie dieses Design auf der aktuellen Seite aussehen wird, klicke auf <strong>Vorschau<\/strong>. Wenn du diese Vorlage verwenden m\u00f6chtest, w\u00e4hle den zugeh\u00f6rigen Link <strong>Einf\u00fcgen<\/strong>.<\/p>\n<h2>So exportierst und importierst du eine einzelne Elementor-Seite<\/h2>\n<p>Vielleicht m\u00f6chtest du dieselbe Seite auf mehreren Webseiten wiederverwenden. Wenn du zum Beispiel mehrere WordPress-Webseiten betreibst, k\u00f6nntest du eine standardm\u00e4\u00dfige <a href=\"https:\/\/kinsta.com\/de\/blog\/ueber-uns-seiten\/\">\u00dcber uns-Seite<\/a> verwenden.<\/p>\n<p>Anstatt diese Seite manuell neu zu erstellen, kannst du sie als Elementor-Vorlage speichern und exportieren. Dann kannst du das Design in jede Webseite importieren, auf der Elementor installiert ist.<\/p>\n<p>Um eine einzelne Seite als Vorlage zu speichern, klicke auf das Pfeilsymbol neben der Schaltfl\u00e4che <strong>Ver\u00f6ffentlichen\/Aktualisieren<\/strong> in Elementor. Du kannst dann <strong>Als Vorlage speichern<\/strong> ausw\u00e4hlen:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/save-page-template.png\" alt=\"Eine einzelne Seite als Vorlage speichern\" width=\"1400\" height=\"894\"><figcaption class=\"wp-caption-text\">Eine einzelne Seite als Vorlage speichern<\/figcaption><\/figure>\n<p>Im darauf folgenden Popup gibst du der Vorlage einen Namen. Dann klickst du auf <strong>Speichern<\/strong>.<\/p>\n<p>Die WordPress-Vorlagenbibliothek sollte sich automatisch \u00f6ffnen. Du kannst die Vorlage, die du gerade erstellt hast, suchen und auf das Symbol mit den drei Punkten klicken. Wenn du dazu aufgefordert wirst, w\u00e4hle <strong>Exportieren<\/strong>:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/export-page-template-.png\" alt=\"Finde alle Vorlagen in der Bibliothek\" width=\"1400\" height=\"903\"><figcaption class=\"wp-caption-text\">Finde alle Vorlagen in der Bibliothek<\/figcaption><\/figure>\n<p>Alternativ kannst du diese einseitige Vorlage auch exportieren, indem du in deinem WordPress-Dashboard zu <strong>Vorlagen &gt; Gespeicherte Vorlagen<\/strong> navigierst. Bewege dann den Mauszeiger \u00fcber die betreffende Vorlage und klicke auf <strong>Exportieren<\/strong>.<\/p>\n<p>Sobald die einseitige Vorlage sicher auf deinem lokalen Computer gespeichert ist, kannst du sie in eine andere Webseite importieren. Wechsle einfach zu deiner neuen Webseite und navigiere zu <strong>Vorlagen &gt; Gespeicherte Vorlagen<\/strong>.<\/p>\n<p>Oben auf diesem Bildschirm klickst du auf <strong>Vorlagen importieren<\/strong>. Jetzt kannst du dein einseitiges Design importieren.<\/p>\n<h2>So exportierst und importierst du deine gesamte Elementor-Webseite (in 3 Schritten)<\/h2>\n<p>Elementor macht es dir leicht, einzelne Vorlagen zu importieren und zu exportieren, aber du musst vielleicht auch <a href=\"https:\/\/kinsta.com\/de\/blog\/wordpress-seite-exportiert\/\">eine ganze Webseite exportieren<\/a>.<\/p>\n<p>Du k\u00f6nntest zum Beispiel ein Vorlagen-Kit erstellen, das alle Standardseiten deiner Webseite enth\u00e4lt, z. B. eine Kontaktseite und eine Homepage. Dieses Kit kannst du dann f\u00fcr deine Basis-Webseiten verwenden.<\/p>\n<p>Schauen wir uns an, wie du ein solches Kit erstellen kannst. Hier erf\u00e4hrst du, wie du deine gesamte Elementor-Webseite in drei einfachen Schritten exportieren kannst!<\/p>\n<h3>Schritt 1: Aktiviere das Elementor Export Kit<\/h3>\n<p>Mit der Export-Kit-Funktion von Elementor kannst du deine komplette Webseite exportieren, einschlie\u00dflich ihrer Inhalte und Einstellungen.<\/p>\n<p>Diese Funktion kann hilfreich sein, wenn du verwandte Webseiten erstellst und das gleiche Branding beibehalten willst. Du k\u00f6nntest zum Beispiel eine Microsite erstellen, um eine bevorstehende Produkteinf\u00fchrung zu bewerben.<\/p>\n<p>Zum Zeitpunkt der Erstellung dieses Artikels ist das Export Kit von Elementor eine experimentelle Funktion. Du musst es aktivieren, indem du zu <strong>Elementor &gt; Einstellungen<\/strong> navigierst. Dort kannst du auf die Registerkarte <strong>Experimente<\/strong> klicken:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/elementor-kit-experiments-.png\" alt=\"Klicke auf die Registerkarte Elementor und finde die Registerkarte Experimente\" width=\"1400\" height=\"643\"><figcaption class=\"wp-caption-text\">Klicke auf die Registerkarte Elementor und finde die Registerkarte Experimente<\/figcaption><\/figure>\n<p>Scrolle zum Abschnitt <strong>Import Export Template Kit<\/strong>. Dann kannst du das zugeh\u00f6rige Dropdown-Men\u00fc \u00f6ffnen und <strong>Aktiv<\/strong> ausw\u00e4hlen:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/export-template-active-.png\" alt=\"Scrolle zu der Option \"Import Export Template Kit\"\" width=\"1400\" height=\"454\"><figcaption class=\"wp-caption-text\">Scrolle zu der Option &#8222;Import Export Template Kit&#8220;<\/figcaption><\/figure>\n<p>Vergiss nicht, bis zum Ende dieser Seite zu scrollen und auf <strong>\u00c4nderungen speichern<\/strong> zu klicken. Diese experimentelle Funktion ist jetzt einsatzbereit.<\/p>\n<h3>Schritt 2: Exportiere deine gesamte Elementor-Webseite<\/h3>\n<p>Navigiere in deinem WordPress Dashboard zu <strong>Elementor &gt; Tools<\/strong>. Klicke jetzt auf das <strong>Import\/Export-Kit<\/strong>:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/import-export-kit.png\" alt=\"Klick auf Import Export Kit\" width=\"1400\" height=\"847\"><figcaption class=\"wp-caption-text\">Klick auf Import Export Kit<\/figcaption><\/figure>\n<p>Klicke auf <strong>Export starten<\/strong>. Wenn du dazu aufgefordert wirst, gib die Inhalte und Daten an, die du in deinen Download aufnehmen m\u00f6chtest.<\/p>\n<p>Du kannst zum Beispiel nur deine Vorlagen exportieren. Du kannst aber auch alle deine Inhalte exportieren, einschlie\u00dflich Seiten, Beitr\u00e4ge und benutzerdefinierte Beitragstypen:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/export-all-content-.png\" alt=\"Exportiere einen oder alle gew\u00fcnschten Inhalte\" width=\"1400\" height=\"688\"><figcaption class=\"wp-caption-text\">Exportiere einen oder alle gew\u00fcnschten Inhalte<\/figcaption><\/figure>\n<p>Klicke als N\u00e4chstes auf den Abschnitt <strong>Kit-Informationen<\/strong> und gib deiner Datei einen beschreibenden Namen. Du kannst auch eine optionale Beschreibung eingeben:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/kit-title-description.png\" alt=\"Gib deiner Datei einen aussagekr\u00e4ftigen Namen\" width=\"1400\" height=\"684\"><figcaption class=\"wp-caption-text\">Gib deiner Datei einen aussagekr\u00e4ftigen Namen<\/figcaption><\/figure>\n<p>Wenn du mit deiner Auswahl zufrieden bist, klicke auf <strong>Exportieren<\/strong>. Elementor erstellt nun dein Kit und zeigt eine Zusammenfassung aller in dieser Datei enthaltenen Elemente an:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/elementor-kit-creation.png\" alt=\"Du bekommst eine Zusammenfassung des Kits angezeigt\" width=\"1400\" height=\"686\"><figcaption class=\"wp-caption-text\">Du bekommst eine Zusammenfassung des Kits angezeigt<\/figcaption><\/figure>\n<p>Elementor wird das erstellte Kit automatisch auf deinen Computer herunterladen. Wenn du dazu aufgefordert wirst, klicke auf <strong>Zur\u00fcck zum Dashboard<\/strong>.<\/p>\n<h3>Schritt 3: Importiere deine Webseite<\/h3>\n<p>Du kannst dein Vorlagen-Kit jetzt in jede Webseite importieren, auf der Elementor installiert ist. Dabei werden deine bestehenden Inhalte \u00fcberschrieben, daher empfehlen wir dir, ein vollst\u00e4ndiges Backup zu erstellen, bevor du fortf\u00e4hrst.<\/p>\n<p>Sobald du dein Backup erstellt hast, musst du Elementor Experiments auf der Zielwebseite aktivieren. Navigiere dazu wie zuvor zu <strong>Elementor &gt; Einstellungen &gt; Experimente<\/strong>. Dann kannst du den Abschnitt <strong>Import-Export-Vorlagen-Kit<\/strong> ausw\u00e4hlen und diese Funktion aktivieren.<\/p>\n<p>Als N\u00e4chstes navigierst du zu <strong>Templates &gt; Kit Library<\/strong>. Klicke auf <strong>Import starten<\/strong>. Auf dem folgenden Bildschirm w\u00e4hlst du die Datei aus, die du im vorherigen Schritt heruntergeladen hast:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/import-template-kit.png\" alt=\"Importiere ein Vorlagen-Kit\" width=\"1400\" height=\"710\"><figcaption class=\"wp-caption-text\">Importiere ein Vorlagen-Kit<\/figcaption><\/figure>\n<p>Wenn du dein Kit auf eine bereits bestehende Installation anwendest, zeigt Elementor alle Vorlagen an, die die gleichen Bedingungen haben wie die, die du importierst. Du kannst dann ausw\u00e4hlen, welche Vorlagen du ersetzen und welche du beibehalten m\u00f6chtest.<\/p>\n<p>Wenn du deine Auswahl getroffen hast, klicke auf <strong>Weiter<\/strong>. Elementor importiert nun dein Site Kit.<\/p>\n<h2>Wie du den Fehler &#8222;Ung\u00fcltige Datei&#8220; in Elementor behebst<\/h2>\n<p>Manchmal bekommst du die Fehlermeldung &#8222;Ung\u00fcltige Datei&#8220;, wenn du versuchst, eine Vorlage zu importieren. Das bedeutet normalerweise, dass du versuchst, eine Vorlage zu importieren, die mit einer fr\u00fcheren Version von Elementor erstellt wurde.<\/p>\n<p>Um diesen Fehler zu beheben, musst du vor\u00fcbergehend auf eine fr\u00fchere Version von Elementor umsteigen. Dieser Wechsel kann zu Problemen mit deiner Webseite f\u00fchren.<\/p>\n<p>Aus diesem Grund empfehlen wir dir, ein vollst\u00e4ndiges Backup zu erstellen, bevor du fortf\u00e4hrst. Du kannst auch in Erw\u00e4gung ziehen, deine Webseite in den Wartungsmodus zu versetzen.<\/p>\n<p>Wenn du bereit bist, gehst du zur <a href=\"https:\/\/wordpress.org\/plugins\/elementor\/\" target=\"_blank\" rel=\"noopener noreferrer\">Elementor Plugin-Liste<\/a>. W\u00e4hle dann <strong>Erweiterte Ansicht<\/strong>:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/elementor-advanced-view.png\" alt=\"Klicke auf die Option \"Erweiterte Ansicht\"\" width=\"1400\" height=\"823\"><figcaption class=\"wp-caption-text\">Klicke auf die Option &#8222;Erweiterte Ansicht&#8220;<\/figcaption><\/figure>\n<p>Nutze das Dropdown-Men\u00fc unten auf der Seite, um eine fr\u00fchere Version von Elementor auszuw\u00e4hlen. Um die besten Ergebnisse zu erzielen, empfehlen wir, die letzte Version von Elementor 1 herunterzuladen, also <strong>1.9.8<\/strong>:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/elementor-earlier-versions.png\" alt=\"Lade die letzte Version von Elementor herunter\" width=\"1400\" height=\"628\"><figcaption class=\"wp-caption-text\">Lade die letzte Version von Elementor herunter<\/figcaption><\/figure>\n<p>Sobald du diese Datei hast, hast du ein paar M\u00f6glichkeiten. Du kannst deine aktuelle Elementor-Version deaktivieren und l\u00f6schen. Dann kannst du die Software, die du gerade heruntergeladen hast, hochladen und aktivieren.<\/p>\n<p>Alternativ kannst du auch <a href=\"https:\/\/wordpress.org\/plugins\/easy-theme-and-plugin-upgrades\/\" target=\"_blank\" rel=\"noopener noreferrer\">Easy Theme and Plugin Upgrades<\/a> verwenden. Nachdem du dieses Plugin aktiviert hast, kannst du eine \u00e4ltere Elementor-Version hochladen, ohne die aktuelle Version zu deaktivieren und zu l\u00f6schen.<\/p>\n<p>Nachdem du die \u00e4ltere Version von Elementor hochgeladen hast, navigiere zu <strong>Plugins &gt; Installierte Plugins<\/strong>. WordPress sollte automatisch auf die \u00e4ltere Softwareversion umgestellt haben:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/elementor-outdated-plugin.png\" alt=\"Die neue Version von Elementor im Bereich Plugins anzeigen\" width=\"1400\" height=\"361\"><figcaption class=\"wp-caption-text\">Die neue Version von Elementor im Bereich Plugins anzeigen<\/figcaption><\/figure>\n<p>Du solltest jetzt in der Lage sein, deine Vorlage ohne Probleme zu importieren. Sobald der Import abgeschlossen ist, navigiere zur\u00fcck zu <strong>Plugins &gt; Installierte Plugins<\/strong> und stelle die aktuellste Version von Elementor wieder her. Die Vorlage sollte sich nun in deiner Bibliothek befinden und zur Verwendung bereit sein.<\/p>\n<h2>Die 3 besten Elementor-Addons zum Importieren und Exportieren von Vorlagen<\/h2>\n<p>Wie wir gerade gesehen haben, verf\u00fcgt Elementor \u00fcber ein robustes Import- und Exportsystem. Mit dieser Funktion kannst du Vorlagen f\u00fcr einzelne Abschnitte, Seiten und sogar ganze Webseiten erstellen.<\/p>\n<p>Vielleicht m\u00f6chtest du diese integrierte Funktion aber noch erweitern. Deshalb stellen wir dir hier drei Elementor-Addons f\u00fcr Importvorlagen vor, die den Import- und Exportprozess deutlich verbessern!<\/p>\n<h3>1. Happy Addons Pro<\/h3>\n<p><a href=\"https:\/\/happyaddons.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Happy Addons Pro<\/a> erweitert das Standard-Elementor-Erlebnis um \u00fcber 20 neue Funktionen. Darunter sind mehrere Funktionen, die du in deinen Import- und Export-Workflow integrieren kannst:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/happy-addons-pro.png\" alt=\"Happy Addons Pro Website\" width=\"1400\" height=\"789\"><figcaption class=\"wp-caption-text\">Happy Addons Pro<\/figcaption><\/figure>\n<p>Wenn du mit mehreren Webseiten arbeitest, solltest du die domain\u00fcbergreifende Copy-Paste-Funktion von Happy Addons Pro nutzen. Damit kannst du ganz einfach Inhalte von einer Webseite kopieren und auf einer anderen Domain einf\u00fcgen.<\/p>\n<p>Wenn du die Demo-Inhalte von Happy Addons Pro wiederverwenden m\u00f6chtest, kannst du sie in dein Elementor-Editor-Panel kopieren. Dar\u00fcber hinaus verf\u00fcgt dieses Addon \u00fcber eine ma\u00dfgeschneiderte Importfunktion. Sie bietet alle Funktionen, die du vom eingebauten Elementor-Import- und -Exportsystem erwarten w\u00fcrdest.<\/p>\n<p>Insbesondere kannst du nach Happy Addon-Vorlagen anhand der Namen der Abschnitte suchen oder nach der Kategorie der Seitenabschnitte filtern.<\/p>\n<p><strong>Funktionen:<\/strong><\/p>\n<ul>\n<li>W\u00e4hle aus \u00fcber 70 <a href=\"https:\/\/happyaddons.com\/happy-templates\/\" target=\"_blank\" rel=\"noopener noreferrer\">Landing Page-Vorlagen<\/a>.<\/li>\n<li>Dupliziere jede Seite oder jeden Beitrag mit der Happy Clone-Funktion.<\/li>\n<li>Kopiere ganz einfach Abschnittsvorlagen aus den Demo-Inhalten von HappyAddons Pro.<\/li>\n<li>Kopiere einen Abschnitt von einer beliebigen Webseite und f\u00fcge ihn auf einer anderen Domain ein.<\/li>\n<\/ul>\n<p><strong>Preise: <\/strong><a href=\"https:\/\/happyaddons.com\/pricing\/\" target=\"_blank\" rel=\"noopener noreferrer\">J\u00e4hrliche Lizenzen beginnen bei $33<\/a>.<\/p>\n<h3>2. Mighty Addons f\u00fcr Elementor<\/h3>\n<p><a href=\"https:\/\/wordpress.org\/plugins\/mighty-addons\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mighty Addons f\u00fcr Elementor<\/a> wird mit einer Auswahl an vorgefertigten Vorlagen-Kits geliefert. Wenn du diese Kits in deine Webseite importierst, hast du Zugriff auf alle Seiten, die du f\u00fcr die Gestaltung einer Vielzahl von Webseiten brauchst.<\/p>\n<p>Mighty Addons for Elementor bietet Vorlagenkits f\u00fcr viele verschiedene Branchen. Dazu geh\u00f6ren Tierschutz, Fitness, Gastgewerbe, Beratung und sogar Fallschirmspringen:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/mighty-addons-elementor.png\" alt=\"Mighty Addons\" width=\"1400\" height=\"450\"><figcaption class=\"wp-caption-text\">Mighty Addons<\/figcaption><\/figure>\n<p>Dieses Addon hat auch eine domain\u00fcbergreifende Kopier- und Einf\u00fcgefunktion. Wenn du mehrere Webseiten verwaltest, kann diese Funktion den traditionellen Import\/Export-Workflow von Elementor sinnvoll erg\u00e4nzen. Mit dieser Funktion kannst du jeden Abschnitt, jede Zeile, jede Spalte oder sogar den Inhalt einer ganzen Seite auf mehreren Elementor-Webseiten verwenden.<\/p>\n<p><strong>Funktionen:<\/strong><\/p>\n<ul>\n<li>Kopiere ganz einfach Bilder und Videos zwischen Domains.<\/li>\n<li>Nutze eine gro\u00dfe Auswahl an vorgefertigten Bereichsvorlagen.<\/li>\n<li>Integriere das Tool mit dem Stockfotodienst Pixabay.<\/li>\n<\/ul>\n<p><strong>Preise:<\/strong> Du kannst das Kern-Plugin <a href=\"https:\/\/wordpress.org\/plugins\/mighty-addons\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mighty Addons for Elementor<\/a> herunterladen. Es ist auch eine Pro-Version erh\u00e4ltlich, deren <a href=\"https:\/\/mightythemes.com\/mighty-addons\/pricing\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lizenzen bei $29 beginnen<\/a>.<\/p>\n<h3>3. Envato Elements<\/h3>\n<p>Mit dem <a href=\"https:\/\/wordpress.org\/plugins\/envato-elements\/\" target=\"_blank\" rel=\"noopener noreferrer\">Envato Elements<\/a> Plugin kannst du Tausende von Seiten und Blockvorlagen durchsuchen, ohne WordPress zu verlassen. Sobald du deine perfekte Vorlage gefunden hast, kannst du sie ganz einfach in deine Webseite importieren:<\/p>\n<figure style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2022\/03\/envato-elements-plugin.png\" alt=\"Envato Elements Plugin\" width=\"1400\" height=\"449\"><figcaption class=\"wp-caption-text\">Envato Elements<\/figcaption><\/figure>\n<p>Damit du schnell eine professionell aussehende Webseite gestalten kannst, bietet dir Envato Elements eine gro\u00dfe Auswahl an Vorlagen-Kits. Au\u00dferdem bietet dieses Plugin einfachen Zugang zu \u00fcber einer Million lizenzfreier Bilder, wenn du Stockfotos verwendest.<\/p>\n<p><strong>Funktionen:<\/strong><\/p>\n<ul>\n<li>Mehrzweckvorlagen<\/li>\n<li>Flexible und vollst\u00e4ndig anpassbare Inhalte<\/li>\n<li>Ein-Klick-Import<\/li>\n<li>Nahtlose Integration mit der Elementor UI<\/li>\n<\/ul>\n<p><strong>Preise:<\/strong> Du kannst das <a href=\"https:\/\/wordpress.org\/plugins\/envato-elements\/\" target=\"_blank\" rel=\"noopener noreferrer\">Envato Elements Plugin<\/a> kostenlos herunterladen. Allerdings brauchst du ein Envato Elements-Abonnement, um auf die Inhalte der Vorlagen zuzugreifen und sie zu nutzen. Der <a href=\"https:\/\/elements.envato.com\/pricing\" target=\"_blank\" rel=\"noopener noreferrer\">Preis daf\u00fcr betr\u00e4gt 16,50 $ pro Monat<\/a>.<\/p>\n\n<h2>Zusammenfassung<\/h2>\n<p>Wir werden nicht behaupten, dass die Gestaltung einer beeindruckenden Webseite einfach ist. Zum Gl\u00fcck musst du dank der Export- und Importfunktionen von Elementor nicht jedes Projekt mit einer neuen Vorlage beginnen.<\/p>\n<p>Mit den vorgefertigten Vorlagen kannst du die ersten Phasen der Webentwicklung schnell hinter dich bringen. Du kannst auch Abschnitts- und Seitenvorlagen erstellen, die du in zuk\u00fcnftigen Projekten wiederverwenden kannst. Wenn du besonders stolz auf eine Webseite bist, kann Elementor sogar deine gesamte Webseite exportieren. Die M\u00f6glichkeiten sind endlos!<\/p>\n<p>Wenn du eine WordPress-Webseite erstellst, brauchst du einen leistungsstarken Hoster an deiner Seite. Bei Kinsta bieten wir eine Reihe von <a href=\"https:\/\/kinsta.com\/de\/wordpress-hosting\/elementor\/\">leistungsoptimierten Hosting-Paketen f\u00fcr alle deine Elementor-Anforderungen<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Elementor-Tool macht es einfach, sch\u00f6ne Seiten, Beitr\u00e4ge und ganze Webseiten zu gestalten. Doch selbst mit einem leistungsstarken Page Builder wie Elementor in der Hand ist &#8230;<\/p>\n","protected":false},"author":117,"featured_media":50876,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[434,704],"topic":[999],"class_list":["post-50716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-elementor","tag-template","topic-wordpress-entwicklung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wie man Elementor-Websites exportiert und importiert (Anleitung)<\/title>\n<meta name=\"description\" content=\"Lerne, wie du Elementor Webseiten mit Hilfe von Elementor Import Templates exportieren und importieren kannst, damit du nicht immer bei Null anfangen musst.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie man Elementor-Websites exportiert und importiert (Deine vollst\u00e4ndige Anleitung)\" \/>\n<meta property=\"og:description\" content=\"Lerne, wie du Elementor Webseiten mit Hilfe von Elementor Import Templates exportieren und importieren kannst, damit du nicht immer bei Null anfangen musst.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-26T13:00:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-23T15:03:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/elementor-vorlagen-importiert.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1460\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Salman Ravoof\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Lerne, wie du Elementor Webseiten mit Hilfe von Elementor Import Templates exportieren und importieren kannst, damit du nicht immer bei Null anfangen musst.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/elementor-vorlagen-importiert.jpeg\" \/>\n<meta name=\"twitter:creator\" content=\"@salmanravoof\" \/>\n<meta name=\"twitter:site\" content=\"@Kinsta_DE\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Salman Ravoof\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"22\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/\"},\"author\":{\"name\":\"Salman Ravoof\",\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987\"},\"headline\":\"Wie man Elementor-Websites exportiert und importiert (Deine vollst\u00e4ndige Anleitung)\",\"datePublished\":\"2022-05-26T13:00:29+00:00\",\"dateModified\":\"2023-08-23T15:03:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/\"},\"wordCount\":3791,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/elementor-vorlagen-importiert.jpeg\",\"keywords\":[\"Elementor\",\"template\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/\",\"url\":\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/\",\"name\":\"Wie man Elementor-Websites exportiert und importiert (Anleitung)\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/elementor-vorlagen-importiert.jpeg\",\"datePublished\":\"2022-05-26T13:00:29+00:00\",\"dateModified\":\"2023-08-23T15:03:11+00:00\",\"description\":\"Lerne, wie du Elementor Webseiten mit Hilfe von Elementor Import Templates exportieren und importieren kannst, damit du nicht immer bei Null anfangen musst.\",\"breadcrumb\":{\"@id\":\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#primaryimage\",\"url\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/elementor-vorlagen-importiert.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/elementor-vorlagen-importiert.jpeg\",\"width\":1460,\"height\":730,\"caption\":\"Wie man Elementor-Websites exportiert und importiert (Anleitung)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kinsta.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WordPress Entwicklung\",\"item\":\"https:\/\/kinsta.com\/de\/thema\/wordpress-entwicklung\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wie man Elementor-Websites exportiert und importiert (Deine vollst\u00e4ndige Anleitung)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kinsta.com\/de\/#website\",\"url\":\"https:\/\/kinsta.com\/de\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Schnelle, sichere und hochwertige Hosting-L\u00f6sungen\",\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kinsta.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kinsta.com\/de\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kinsta.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/\",\"https:\/\/x.com\/Kinsta_DE\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987\",\"name\":\"Salman Ravoof\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/kinsta.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g\",\"caption\":\"Salman Ravoof\"},\"description\":\"Salman Ravoof is a self-taught web developer, writer, creator, and a huge admirer of Free and Open Source Software (FOSS). Besides tech, he's excited by science, philosophy, photography, arts, cats, and food. Learn more about him on his website, and connect with Salman on Twitter.\",\"sameAs\":[\"https:\/\/salmanravoof.com\",\"https:\/\/www.linkedin.com\/in\/salman-ravoof-5a749133\/\",\"https:\/\/x.com\/salmanravoof\"],\"url\":\"https:\/\/kinsta.com\/de\/blog\/author\/salmanravoof\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wie man Elementor-Websites exportiert und importiert (Anleitung)","description":"Lerne, wie du Elementor Webseiten mit Hilfe von Elementor Import Templates exportieren und importieren kannst, damit du nicht immer bei Null anfangen musst.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/","og_locale":"de_DE","og_type":"article","og_title":"Wie man Elementor-Websites exportiert und importiert (Deine vollst\u00e4ndige Anleitung)","og_description":"Lerne, wie du Elementor Webseiten mit Hilfe von Elementor Import Templates exportieren und importieren kannst, damit du nicht immer bei Null anfangen musst.","og_url":"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/","article_published_time":"2022-05-26T13:00:29+00:00","article_modified_time":"2023-08-23T15:03:11+00:00","og_image":[{"width":1460,"height":730,"url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/elementor-vorlagen-importiert.jpeg","type":"image\/jpeg"}],"author":"Salman Ravoof","twitter_card":"summary_large_image","twitter_description":"Lerne, wie du Elementor Webseiten mit Hilfe von Elementor Import Templates exportieren und importieren kannst, damit du nicht immer bei Null anfangen musst.","twitter_image":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/elementor-vorlagen-importiert.jpeg","twitter_creator":"@salmanravoof","twitter_site":"@Kinsta_DE","twitter_misc":{"Verfasst von":"Salman Ravoof","Gesch\u00e4tzte Lesezeit":"22\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#article","isPartOf":{"@id":"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/"},"author":{"name":"Salman Ravoof","@id":"https:\/\/kinsta.com\/de\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987"},"headline":"Wie man Elementor-Websites exportiert und importiert (Deine vollst\u00e4ndige Anleitung)","datePublished":"2022-05-26T13:00:29+00:00","dateModified":"2023-08-23T15:03:11+00:00","mainEntityOfPage":{"@id":"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/"},"wordCount":3791,"commentCount":0,"publisher":{"@id":"https:\/\/kinsta.com\/de\/#organization"},"image":{"@id":"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/elementor-vorlagen-importiert.jpeg","keywords":["Elementor","template"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/","url":"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/","name":"Wie man Elementor-Websites exportiert und importiert (Anleitung)","isPartOf":{"@id":"https:\/\/kinsta.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#primaryimage"},"image":{"@id":"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/elementor-vorlagen-importiert.jpeg","datePublished":"2022-05-26T13:00:29+00:00","dateModified":"2023-08-23T15:03:11+00:00","description":"Lerne, wie du Elementor Webseiten mit Hilfe von Elementor Import Templates exportieren und importieren kannst, damit du nicht immer bei Null anfangen musst.","breadcrumb":{"@id":"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#primaryimage","url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/elementor-vorlagen-importiert.jpeg","contentUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2022\/05\/elementor-vorlagen-importiert.jpeg","width":1460,"height":730,"caption":"Wie man Elementor-Websites exportiert und importiert (Anleitung)"},{"@type":"BreadcrumbList","@id":"https:\/\/kinsta.com\/de\/blog\/elementor-vorlagen-importiert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kinsta.com\/de\/"},{"@type":"ListItem","position":2,"name":"WordPress Entwicklung","item":"https:\/\/kinsta.com\/de\/thema\/wordpress-entwicklung\/"},{"@type":"ListItem","position":3,"name":"Wie man Elementor-Websites exportiert und importiert (Deine vollst\u00e4ndige Anleitung)"}]},{"@type":"WebSite","@id":"https:\/\/kinsta.com\/de\/#website","url":"https:\/\/kinsta.com\/de\/","name":"Kinsta\u00ae","description":"Schnelle, sichere und hochwertige Hosting-L\u00f6sungen","publisher":{"@id":"https:\/\/kinsta.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinsta.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/kinsta.com\/de\/#organization","name":"Kinsta","url":"https:\/\/kinsta.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kinsta.com\/de\/wp-content\/uploads\/sites\/5\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kinsta.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kinsta-Deutschland-207459890108303\/","https:\/\/x.com\/Kinsta_DE","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kinsta.com\/de\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987","name":"Salman Ravoof","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/kinsta.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g","caption":"Salman Ravoof"},"description":"Salman Ravoof is a self-taught web developer, writer, creator, and a huge admirer of Free and Open Source Software (FOSS). Besides tech, he's excited by science, philosophy, photography, arts, cats, and food. Learn more about him on his website, and connect with Salman on Twitter.","sameAs":["https:\/\/salmanravoof.com","https:\/\/www.linkedin.com\/in\/salman-ravoof-5a749133\/","https:\/\/x.com\/salmanravoof"],"url":"https:\/\/kinsta.com\/de\/blog\/author\/salmanravoof\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/posts\/50716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/comments?post=50716"}],"version-history":[{"count":7,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/posts\/50716\/revisions"}],"predecessor-version":[{"id":50883,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/posts\/50716\/revisions\/50883"}],"alternate":[{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/50716\/translations\/en"},{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/50716\/translations\/it"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/50716\/translations\/pt"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/50716\/translations\/de"},{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/50716\/translations\/es"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/50716\/translations\/fr"},{"embeddable":true,"hreflang":"nl","title":"Dutch","href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/50716\/translations\/nl"},{"href":"https:\/\/kinsta.com\/de\/wp-json\/kinsta\/v1\/posts\/50716\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/media\/50876"}],"wp:attachment":[{"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/media?parent=50716"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/tags?post=50716"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kinsta.com\/de\/wp-json\/wp\/v2\/topic?post=50716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}