{"id":76752,"date":"2024-10-09T10:13:09","date_gmt":"2024-10-09T08:13:09","guid":{"rendered":"https:\/\/kinsta.com\/es\/?p=76752&#038;post_type=case_studies&#038;preview_id=76752"},"modified":"2025-11-27T01:38:50","modified_gmt":"2025-11-27T00:38:50","slug":"5tales","status":"publish","type":"case_studies","link":"https:\/\/kinsta.com\/es\/clientes\/5tales\/","title":{"rendered":"5Tales genera hasta un 152% m\u00e1s de tr\u00e1fico y un 2.914% m\u00e1s de visibilidad en m\u00e1s de 100 sitios web de clientes"},"content":{"rendered":"<p><span style=\"font-weight: 400\">5Tales es una<\/span> <a href=\"https:\/\/www.5tales.com.au\/\"><span style=\"font-weight: 400\">agencia de marketing digital<\/span><\/a> dedicada a ayudar a las empresas de servicios a crecer mediante estrategias personalizadas y basadas en resultados. Se han hecho un nombre en Australia por su experiencia en SEO local, junto con sus servicios de desarrollo web, alojamiento web y anuncios en Google y Facebook.<\/p>\n<p>Fundada por los hermanos Jason y Toby Schulz, 5Tales se enorgullece de ofrecer resultados reales.<\/p>\n<figure style=\"text-align: center\"><\/figure>\n<figure id=\"attachment_186085\" aria-describedby=\"caption-attachment-186085\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-186085 size-full\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2024\/09\/Jason-and-Toby-5Tales.jpg\" alt=\"Los hermanos Jason y Toby Schulz de 5Tales\" width=\"700\" height=\"502\"><figcaption id=\"caption-attachment-186085\" class=\"wp-caption-text\">Los hermanos Jason y Toby Schulz son los fundadores de 5Tales.<\/figcaption><\/figure>\n<p><em>\u00abEn realidad, 5Tales existe para mejorar y hacer crecer los negocios de otras personas. Nuestras estrategias est\u00e1n dise\u00f1adas para aumentar la visibilidad y el tr\u00e1fico, al tiempo que se mantienen alineadas con los objetivos empresariales \u00fanicos de cada cliente.\u00bb<\/em><\/p>\n<p><span style=\"font-weight: 400\">Como muchas agencias, se enfrentaban a sitios web lentos, soporte poco fiable y problemas de seguridad de su anterior proveedor de alojamiento.<\/span><\/p>\n<p>Durante nuestra reciente charla con Jason Schulz, director de 5Tales, nos cont\u00f3 c\u00f3mo su equipo super\u00f3 estos obst\u00e1culos y encontr\u00f3 una soluci\u00f3n que les permiti\u00f3 ampliar sus servicios. Con velocidades m\u00e1s r\u00e1pidas, mayor seguridad y un equipo de soporte fiable, 5Tales pudo por fin centrarse en lo m\u00e1s importante \u2014 ayudar a crecer a sus clientes.<\/p>\n<p>Averigua m\u00e1s sobre el viaje de 5Tales para ver si el alojamiento administrado de WordPress de Kinsta puede ser la soluci\u00f3n perfecta para ti, como lo ha sido para ellos.<\/p>\n<h2 id=\"snapshot\" class=\"has-anchor-hash\">Instant\u00e1nea<\/h2>\n<ul>\n<li><strong>Sector:<\/strong> Agencia de marketing digital<\/li>\n<li><strong>Tama\u00f1o de la empresa:<\/strong> 11 miembros del equipo<\/li>\n<\/ul>\n<h2 id=\"problem\">Problema<\/h2>\n<p><em>\u00abAntes ten\u00edamos muchos problemas con nuestros sitios web. Eran lentos, el equipo de soporte del alojamiento no era muy servicial y nuestros sitios web se infectaban constantemente con malware.\u00bb \u2013 Jason Schulz, Director de 5Tales<\/em><\/p>\n<p>5Tales confiaba en varios proveedores de alojamiento, como WPX Hosting y WP Engine, pero este enfoque no funcionaba. Ten\u00edan problemas con:<\/p>\n<ul>\n<li><strong>Velocidades lentas del sitio web<\/strong>: A pesar de todos sus esfuerzos de marketing, los tiempos de carga lentos frustraban a los clientes y perjudicaban la experiencia del usuario.<\/li>\n<li><strong>Soporte de alojamiento poco fiable<\/strong>: Cada vez que surg\u00eda un problema, obtener ayuda de sus proveedores de alojamiento era todo un reto. Los retrasos en las respuestas y la mala comunicaci\u00f3n s\u00f3lo empeoraban las cosas.<\/li>\n<\/ul>\n<figure style=\"text-align: center\">\n<p><figure style=\"width: 950px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2024\/09\/blog-malware.png\" alt=\"blog-malware\" width=\"950\" height=\"567\"><figcaption class=\"wp-caption-text\">Ejemplo de mensaje de error de malware<\/figcaption><\/figure><\/figure>\n<ul>\n<li><strong>Infecciones recurrentes por malware<\/strong>: Sus sitios web eran <a href=\"https:\/\/kinsta.com\/es\/blog\/verificacion-seguridad-web\/\" target=\"_blank\" rel=\"noopener noreferrer\">atacados frecuentemente por malware<\/a>, lo que provocaba interrupciones y pon\u00eda en peligro la confianza de sus clientes.<\/li>\n<li><strong>Fuga de recursos<\/strong>: Schulz observ\u00f3 que el 20% del tiempo de cada gestor de cuentas se dedicaba a resolver problemas de alojamiento, un tiempo que podr\u00eda haberse dedicado al crecimiento y la innovaci\u00f3n.<\/li>\n<\/ul>\n<p>Las relaciones con los clientes empezaban a resentirse y su reputaci\u00f3n estaba en peligro. Necesitaban encontrar una soluci\u00f3n \u2014 y r\u00e1pido \u2014 antes de que estos problemas empezaran a minar la confianza que tanto les hab\u00eda costado construir con sus clientes.<\/p>\n<p>\u00abCuando empezamos a buscar un nuevo alojamiento web, sab\u00edamos que necesit\u00e1bamos unas cuantas cosas: velocidad r\u00e1pida del sitio web, soporte fiable, migraciones sencillas, una interfaz intuitiva y una plataforma segura. No quer\u00edamos necesitar experiencia interna s\u00f3lo para gestionar el alojamiento de WordPress. Kinsta cumpl\u00eda todos los requisitos\u00bb. \u2013 Jason Schulz, Director de 5Tales<\/p>\n<h2 id=\"solution\">Soluci\u00f3n<\/h2>\n<p>Cuando 5Tales se dio cuenta de que sus proveedores de alojamiento no estaban a la altura, supo que hab\u00eda llegado el momento de hacer un cambio. La primera vez que Jason prob\u00f3 Kinsta fue para su negocio de servicios a domicilio, <a href=\"http:\/\/www.maid2match.com.au\/\">Maid2Match<\/a>. Impresionado con las mejoras inmediatas que experiment\u00f3, decidi\u00f3 trasladar todos sus sitios de clientes de 5Tales a Kinsta. 5Tales encontr\u00f3 un socio que le ofrec\u00eda todo lo que necesitaba y m\u00e1s: mejor velocidad, mayor seguridad y un soporte fiable.<\/p>\n<p><em>\u00abDesde que migramos nuestro sitio web a Kinsta, hemos notado una mejora inmediata en el tiempo de actividad de nuestro sitio web. Adem\u00e1s, la seguridad de nuestro sitio web ha mejorado, y desde entonces no hemos sufrido ning\u00fan hackeo\u00bb<br \/>\n<\/em><br \/>\n\u00abEl equipo de Kinsta consigui\u00f3 detectar y reparar cualquier actividad sospechosa. Tambi\u00e9n ayudaron a restaurar varios sitios web problem\u00e1ticos como parte de la migraci\u00f3n.\u00bb<\/p>\n<h3 id=\"key-features\">Caracter\u00edsticas clave que gustan a 5Tales<\/h3>\n<ul>\n<li><strong>Velocidad impulsada por Google Cloud: <\/strong>El uso por parte de Kinsta del <a href=\"https:\/\/kinsta.com\/es\/blog\/2019-benchmarks-desempeno\/\" target=\"_blank\" rel=\"noopener noreferrer\">servidor m\u00e1s r\u00e1pido de Google Cloud<\/a> en su <a href=\"https:\/\/kinsta.com\/es\/docs\/alojamiento-wordpress\/como-empezar-con-wordpress\/infraestructura-de-wordpress\/\" target=\"_blank\" rel=\"noopener noreferrer\">infraestructura premium<\/a> garantiza tiempos de carga r\u00e1pidos en todos los sitios. Esto ayud\u00f3 a 5Tales a ofrecer una mejor experiencia a los usuarios, independientemente de d\u00f3nde se encontraran.<\/li>\n<li><strong>Equipo de soporte experto 24\/7\/365: <\/strong>A diferencia de sus anteriores proveedores de alojamiento, el <a href=\"https:\/\/kinsta.com\/es\/soporte-kinsta\/\" target=\"_blank\" rel=\"noopener noreferrer\">equipo de soporte de Kinsta<\/a> est\u00e1 disponible las 24 horas del d\u00eda. La funci\u00f3n de chat facilita el contacto con el servicio de soporte, sean las 3 de la ma\u00f1ana o las 3 de la tarde.<\/li>\n<\/ul>\n<p style=\"padding-left: 40px\">\u00abLa funci\u00f3n de Kinsta que nos result\u00f3 realmente \u00fatil para las tareas cotidianas fue la funci\u00f3n de chat, que te permite contactar y comunicarte f\u00e1cilmente con el equipo de soporte. Los miembros del equipo pueden entrar en sus cuentas, hablar con una persona de soporte de Kinsta y resolver un problema r\u00e1pidamente.\u00bb<\/p>\n<ul>\n<li><strong>Migraciones gratuitas e ilimitadas y limpieza de malware<\/strong>: Kinsta gestion\u00f3 la migraci\u00f3n de m\u00e1s de 100 sitios de WordPress sin ning\u00fan tiempo de inactividad. Su equipo de expertos tambi\u00e9n se encarg\u00f3 de <a href=\"https:\/\/kinsta.com\/es\/docs\/servicio-de-informacion\/eliminacion-de-malware\/\" target=\"_blank\" rel=\"noopener noreferrer\">eliminar el malware<\/a>, que era uno de los principales puntos d\u00e9biles de 5Tales.<\/li>\n<li><strong>Herramientas de eficiencia integradas:<\/strong> El panel de control de MyKinsta incluye funciones como <a href=\"https:\/\/kinsta.com\/es\/changelog\/acciones-masivas\/\" target=\"_blank\" rel=\"noopener noreferrer\">actualizaciones en lote<\/a>, notificaciones autom\u00e1ticas de plugins y una herramienta de buscar y reemplazar. Estas herramientas ayudaron a 5Tales a gestionar sus sitios de forma m\u00e1s eficiente, ahorr\u00e1ndoles un tiempo valioso en tareas rutinarias.<\/li>\n<\/ul>\n<p style=\"padding-left: 40px\"><em>\u00abTambi\u00e9n hay una funci\u00f3n sencilla que nos permite actualizar plugins y recibir notificaciones autom\u00e1ticas si hay alg\u00fan error. Adem\u00e1s, a nuestro equipo de SEO le gusta la herramienta de buscar y reemplazar que ofrece Kinsta\u00bb<\/em><\/p>\n<figure style=\"text-align: center\">\n<p><figure style=\"width: 959px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2024\/09\/cs-kinsta-tools-.png\" alt=\"cs-kinsta-tools \" width=\"959\" height=\"1146\"><figcaption class=\"wp-caption-text\">La p\u00e1gina Herramientas de alojamiento de WordPress en MyKinsta<\/figcaption><\/figure><\/figure>\n<ul>\n<li><strong>Seguridad mejorada con integraciones de Cloudflare:<\/strong> La integraci\u00f3n de Kinsta con Cloudflare a\u00f1adi\u00f3 una capa adicional de protecci\u00f3n, con funciones como un <a href=\"https:\/\/kinsta.com\/es\/blog\/que-es-un-cortafuegos\/\" target=\"_blank\" rel=\"noopener noreferrer\">cortafuegos de aplicaciones web (WAF)<\/a> y <a href=\"https:\/\/kinsta.com\/es\/blog\/prevenir-ataques-ddos\/\" target=\"_blank\" rel=\"noopener noreferrer\">protecci\u00f3n DDoS<\/a>. Esto mantuvo los sitios de 5Tales seguros y libres de ataques. Adem\u00e1s, el compromiso de Kinsta con las normas de seguridad reconocidas internacionalmente garantiz\u00f3 que los sitios web estuvieran protegidos al m\u00e1s alto nivel.<\/li>\n<\/ul>\n<p style=\"padding-left: 40px\"><em>\u00abDesde que nos pasamos a Kinsta, no nos han hackeado ni un solo sitio web. Ha sido un gran alivio para nosotros y nuestros clientes\u00bb<\/em><\/p>\n<h2 id=\"results\">Resultados<\/h2>\n<h3 id=\"migration\">Migraci\u00f3n sin problemas de m\u00e1s de 100 sitios de WordPress<\/h3>\n<p>5Tales <a href=\"https:\/\/kinsta.com\/es\/wordpress-hosting\/migracion\/\" target=\"_blank\" rel=\"noopener noreferrer\">migr\u00f3 m\u00e1s de 100 sitios web de WordPress<\/a> a Kinsta utilizando el servicio gratuito de migraci\u00f3n de Kinsta. Lo que podr\u00eda haber sido un proceso largo y complejo se complet\u00f3 en poco m\u00e1s de un mes sin tiempo de inactividad.<\/p>\n<p><span style=\"font-weight: 400\">Durante la migraci\u00f3n, el equipo de Kinsta tambi\u00e9n limpi\u00f3 cualquier malware o problema del sitio web para que el equipo de 5Tales no tuviera que preocuparse por problemas de seguridad persistentes o errores del sitio. Este proceso de migraci\u00f3n sin fisuras ahorr\u00f3 tiempo y recursos a 5Tales, que ahora puede volver a centrarse en su actividad principal.<\/span><\/p>\n<p><em>\u00abAyuda tener un equipo que te apoya 24\/7\/365. El equipo de Kinsta fue capaz de detectar y reparar cualquier actividad sospechosa. Tambi\u00e9n ayudaron a restaurar varios sitios problem\u00e1ticos como parte de la migraci\u00f3n.\u00bb<\/em><\/p>\n<p>Pero el verdadero valor lleg\u00f3 despu\u00e9s de la migraci\u00f3n. La velocidad y las funciones de seguridad de Kinsta marcaron una gran diferencia para los clientes de 5Tales.<\/p>\n<figure id=\"attachment_186087\" aria-describedby=\"caption-attachment-186087\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-186087 size-large\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2024\/09\/Screenshot-2024-09-25-at-3.39.32\u202fPM-1024x457.png\" alt=\"Breve historia de 5Tales\" width=\"1024\" height=\"457\"><figcaption id=\"caption-attachment-186087\" class=\"wp-caption-text\">Breve historia de 5Tales<\/figcaption><\/figure>\n<h3 id=\"higher-seo-rankings\">Mejor posicionamiento en buscadores<\/h3>\n<p><a href=\"https:\/\/kinsta.com\/es\/blog\/como-afecta-alojamiento-al-seo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Puede que el alojamiento no sea el componente m\u00e1s conocido del SEO<\/a>, pero es importante. Tu sitio tiene que funcionar bien para que Google lo favorezca, y tu empresa de alojamiento puede ayudarte con eso (o evitar que ocurra).<\/p>\n<p>La infraestructura de Kinsta est\u00e1 construida para ofrecer velocidad y seguridad, y estas caracter\u00edsticas repercutieron directamente en el \u00e9xito de los clientes de 5Tales:<\/p>\n<ul>\n<li><strong>Mejoras en la velocidad del sitio:<\/strong> El uso por parte de Kinsta de la <a href=\"https:\/\/kinsta.com\/es\/blog\/plataforma-en-la-nube-para-desarrolladores\/\" target=\"_blank\" rel=\"noopener noreferrer\">red de alto rendimiento de Google Cloud<\/a> mejor\u00f3 significativamente los tiempos de carga de todos los sitios web de los clientes de 5Tales. Los sitios m\u00e1s r\u00e1pidos mejoran la experiencia del usuario, aumentan la participaci\u00f3n y mejoran el posicionamiento SEO. Google recompensa a los sitios que cargan r\u00e1pido con mejores posiciones en las b\u00fasquedas, y este aumento de la velocidad contribuy\u00f3 en gran medida a atraer m\u00e1s tr\u00e1fico a los sitios de los clientes de 5Tales.<\/li>\n<li><strong>Implementaci\u00f3n de SSL:<\/strong> Kinsta proporcion\u00f3 <a href=\"https:\/\/kinsta.com\/es\/docs\/alojamiento-wordpress\/dominios-wordpress\/certificados-ssl-wordpress\/\" target=\"_blank\" rel=\"noopener noreferrer\">certificados SSL<\/a> gratuitos para todos los sitios web de los clientes de 5Tales. SSL no s\u00f3lo protege los datos de los usuarios, sino que tambi\u00e9n es un factor clave en el algoritmo de posicionamiento de Google. Con el SSL, los clientes de 5Tales ganaron m\u00e1s confianza de los usuarios y mejoraron su visibilidad en los resultados de b\u00fasqueda.<\/li>\n<li><strong>99.9% de garant\u00eda de tiempo de actividad:<\/strong> El tiempo de actividad es crucial tanto para la experiencia del usuario como para el SEO, ya que los motores de b\u00fasqueda favorecen a los sitios que permanecen siempre disponibles. Kinsta ofrece una <a href=\"https:\/\/kinsta.com\/es\/docs\/servicio-de-informacion\/tiempo-de-actividad-garantizado\/\">garant\u00eda de tiempo de actividad respaldada por un Acuerdo de Nivel de Servicio (SLA)<\/a>, as\u00ed como la monitorizaci\u00f3n del sitio cada 3 minutos (es decir, unas 480 comprobaciones al d\u00eda). Este nivel de soporte dio tranquilidad al equipo de 5Tales y fue un factor clave en su capacidad para mantener un tiempo de actividad del 99,9%.<\/li>\n<\/ul>\n<p>Esto proporcion\u00f3 a 5Tales las <a href=\"https:\/\/kinsta.com\/es\/blog\/wordpress-seo\/\" target=\"_blank\" rel=\"noopener noreferrer\">herramientas necesarias para que sus clientes se posicionaran mejor en los buscadores<\/a> y obtuvieran resultados impresionantes:<\/p>\n<ul>\n<li>Un cliente de una boutique experiment\u00f3 un aumento del 152% en el tr\u00e1fico de Google y un incremento del 2.914% en la visibilidad de palabras clave.<\/li>\n<li>Un servicio de mantenimiento del hogar ahora aparece en el n\u00ba 1, n\u00ba 2 o n\u00ba 3 de Google para 26 t\u00e9rminos de b\u00fasqueda de gran valor.<\/li>\n<li>Un bufete de abogados de familia experiment\u00f3 un aumento del 123% en el tr\u00e1fico de Google y un aumento del 1.747% en la visibilidad de las palabras clave.<\/li>\n<li>Una cl\u00ednica quiropr\u00e1ctica consigui\u00f3 un aumento del 71% en los posibles pacientes de Google y un incremento del 1.048% en la visibilidad de las palabras clave.<\/li>\n<\/ul>\n<h3 id=\"Improved-productivity-and-client-trust\">Mejora de la productividad y la confianza de los clientes<\/h3>\n<p>Uno de los mayores cambios para el equipo de 5Tales fue la cantidad de tiempo y recursos que ahorraron al pasarse a Kinsta.<\/p>\n<p>Antes de Kinsta, el equipo de 5Tales pasaba demasiado tiempo lidiando con tiempos de inactividad, malware y problemas de alojamiento. Esto no s\u00f3lo agotaba sus recursos, sino que tambi\u00e9n afectaba a las relaciones con sus clientes.<\/p>\n<p><em>\u00abSol\u00edamos tener que disculparnos con los clientes por nuestros problemas de alojamiento, lo que hac\u00eda que confiaran menos en nuestros otros servicios\u00bb<br \/>\n<\/em><br \/>\n<em>\u00abPero desde que nos pasamos a Kinsta, hemos ahorrado mucho tiempo a nuestro equipo, porque ya no tenemos que ocuparnos de problemas como el malware y las ca\u00eddas del sitio web. Esto nos ha permitido centrarnos en otras tareas. Adem\u00e1s, la satisfacci\u00f3n del cliente ha aumentado, ya que el sitio web funciona mucho mejor.\u00bb<\/em><\/p>\n<p>\u00abAhora, tenemos planes para incluir informaci\u00f3n m\u00e1s detallada sobre la diferencia Kinsta en las propuestas que enviamos a los posibles clientes\u00bb.<\/p>\n<h2 id=\"conclusion\">Conclusi\u00f3n<\/h2>\n<p>Para 5Tales, cambiar a Kinsta transform\u00f3 el funcionamiento de su agencia. Con una migraci\u00f3n fluida de m\u00e1s de 100 sitios de WordPress, tiempos de carga m\u00e1s r\u00e1pidos, un tiempo de actividad del 99,9% y una seguridad robusta, Kinsta resolvi\u00f3 los problemas que les frenaban.<\/p>\n<p>Se acabaron los tiempos de inactividad, los problemas de malware y tener que esperar al servicio de soporte. Al final, Kinsta se convirti\u00f3 en un socio que les permiti\u00f3 centrarse en lo que realmente importa: ofrecer un gran servicio e impulsar el crecimiento del negocio.<\/p>\n<figure  class=\"wp-block-kinsta-client-quote is-style-default\" data-nosnippet>\n    \n    \n    <blockquote  class=\"wp-block-kinsta-client-quote__content\">\n        <p>Seguiremos utilizando y promocionando Kinsta como nuestra plataforma de alojamiento premium. Es la elecci\u00f3n perfecta para nuestros clientes porque ofrece una velocidad y seguridad incre\u00edbles para los sitios web, y nos permite ofrecer servicios de alojamiento con confianza. Tenemos previsto incluir informaci\u00f3n m\u00e1s detallada sobre la diferencia de Kinsta en las propuestas que enviamos a los clientes potenciales.<\/p>\n    <\/blockquote>\n\n    \n    <figcaption class=\"wp-block-kinsta-client-quote__footer\">\n        <div class=\"person js-disable-anchor-hashes person--with-description\">\n                    <div class=\"person__avatar\">\n            <img decoding=\"async\"  aria-hidden=\"true\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2024\/10\/Jason_5Tales-150x150.png\" width=\"150\" height=\"150\" loading=\"lazy\" \/>\n        <\/div>\n        <div class=\"person__details\">\n        <span class=\"person__name\">Jason Schulz<\/span>\n                    <span class=\"person__job\">Cofundador y CEO a 5Tales<\/span>\n                            <\/div>\n<\/div>\n    <\/figcaption>\n<\/figure>\n\n","protected":false},"excerpt":{"rendered":"<p>5Tales es una agencia de marketing digital dedicada a ayudar a las empresas de servicios a crecer mediante estrategias personalizadas y basadas en resultados. Se han &#8230;<\/p>\n","protected":false},"author":249,"featured_media":76753,"menu_order":15,"template":"","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":""},"segment":[1257],"class_list":["post-76752","case_studies","type-case_studies","status-publish","has-post-thumbnail","hentry","segment-agencia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5Tales aumenta el tr\u00e1fico un 152% y la visibilidad un 2.914% en m\u00e1s de 100 sitios web<\/title>\n<meta name=\"description\" content=\"Jason Schulz comparte c\u00f3mo 5Tales transform\u00f3 sus resultados de SEO y marketing digital tras cambiar de WP Engine y WPX Hosting a Kinsta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinsta.com\/es\/clientes\/5tales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5Tales genera hasta un 152% m\u00e1s de tr\u00e1fico y un 2.914% m\u00e1s de visibilidad en m\u00e1s de 100 sitios web de clientes\" \/>\n<meta property=\"og:description\" content=\"Jason Schulz comparte c\u00f3mo 5Tales transform\u00f3 sus resultados de SEO y marketing digital tras cambiar de WP Engine y WPX Hosting a Kinsta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinsta.com\/es\/clientes\/5tales\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kinsta.es\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-27T00:38:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2024\/10\/case-study-5tales.png\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"377\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Jason Schulz comparte c\u00f3mo 5Tales transform\u00f3 sus resultados de SEO y marketing digital tras cambiar de WP Engine y WPX Hosting a Kinsta.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2024\/10\/case-study-5tales.png\" \/>\n<meta name=\"twitter:site\" content=\"@Kinsta_ES\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kinsta.com\/es\/clientes\/5tales\/\",\"url\":\"https:\/\/kinsta.com\/es\/clientes\/5tales\/\",\"name\":\"5Tales aumenta el tr\u00e1fico un 152% y la visibilidad un 2.914% en m\u00e1s de 100 sitios web\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kinsta.com\/es\/clientes\/5tales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/es\/clientes\/5tales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2024\/10\/case-study-5tales.png\",\"datePublished\":\"2024-10-09T08:13:09+00:00\",\"dateModified\":\"2025-11-27T00:38:50+00:00\",\"description\":\"Jason Schulz comparte c\u00f3mo 5Tales transform\u00f3 sus resultados de SEO y marketing digital tras cambiar de WP Engine y WPX Hosting a Kinsta.\",\"breadcrumb\":{\"@id\":\"https:\/\/kinsta.com\/es\/clientes\/5tales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kinsta.com\/es\/clientes\/5tales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kinsta.com\/es\/clientes\/5tales\/#primaryimage\",\"url\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2024\/10\/case-study-5tales.png\",\"contentUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2024\/10\/case-study-5tales.png\",\"width\":720,\"height\":377},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kinsta.com\/es\/clientes\/5tales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kinsta.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casos de Estudio\",\"item\":\"https:\/\/kinsta.com\/es\/clientes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"5Tales genera hasta un 152% m\u00e1s de tr\u00e1fico y un 2.914% m\u00e1s de visibilidad en m\u00e1s de 100 sitios web de clientes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kinsta.com\/es\/#website\",\"url\":\"https:\/\/kinsta.com\/es\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Soluciones de alojamiento premium, r\u00e1pidas y seguras\",\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kinsta.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kinsta.com\/es\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kinsta.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kinsta.es\/\",\"https:\/\/x.com\/Kinsta_ES\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"5Tales aumenta el tr\u00e1fico un 152% y la visibilidad un 2.914% en m\u00e1s de 100 sitios web","description":"Jason Schulz comparte c\u00f3mo 5Tales transform\u00f3 sus resultados de SEO y marketing digital tras cambiar de WP Engine y WPX Hosting a Kinsta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinsta.com\/es\/clientes\/5tales\/","og_locale":"es_ES","og_type":"article","og_title":"5Tales genera hasta un 152% m\u00e1s de tr\u00e1fico y un 2.914% m\u00e1s de visibilidad en m\u00e1s de 100 sitios web de clientes","og_description":"Jason Schulz comparte c\u00f3mo 5Tales transform\u00f3 sus resultados de SEO y marketing digital tras cambiar de WP Engine y WPX Hosting a Kinsta.","og_url":"https:\/\/kinsta.com\/es\/clientes\/5tales\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/kinsta.es\/","article_modified_time":"2025-11-27T00:38:50+00:00","og_image":[{"width":720,"height":377,"url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2024\/10\/case-study-5tales.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_description":"Jason Schulz comparte c\u00f3mo 5Tales transform\u00f3 sus resultados de SEO y marketing digital tras cambiar de WP Engine y WPX Hosting a Kinsta.","twitter_image":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2024\/10\/case-study-5tales.png","twitter_site":"@Kinsta_ES","twitter_misc":{"Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kinsta.com\/es\/clientes\/5tales\/","url":"https:\/\/kinsta.com\/es\/clientes\/5tales\/","name":"5Tales aumenta el tr\u00e1fico un 152% y la visibilidad un 2.914% en m\u00e1s de 100 sitios web","isPartOf":{"@id":"https:\/\/kinsta.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinsta.com\/es\/clientes\/5tales\/#primaryimage"},"image":{"@id":"https:\/\/kinsta.com\/es\/clientes\/5tales\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2024\/10\/case-study-5tales.png","datePublished":"2024-10-09T08:13:09+00:00","dateModified":"2025-11-27T00:38:50+00:00","description":"Jason Schulz comparte c\u00f3mo 5Tales transform\u00f3 sus resultados de SEO y marketing digital tras cambiar de WP Engine y WPX Hosting a Kinsta.","breadcrumb":{"@id":"https:\/\/kinsta.com\/es\/clientes\/5tales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinsta.com\/es\/clientes\/5tales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kinsta.com\/es\/clientes\/5tales\/#primaryimage","url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2024\/10\/case-study-5tales.png","contentUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2024\/10\/case-study-5tales.png","width":720,"height":377},{"@type":"BreadcrumbList","@id":"https:\/\/kinsta.com\/es\/clientes\/5tales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kinsta.com\/es\/"},{"@type":"ListItem","position":2,"name":"Casos de Estudio","item":"https:\/\/kinsta.com\/es\/clientes\/"},{"@type":"ListItem","position":3,"name":"5Tales genera hasta un 152% m\u00e1s de tr\u00e1fico y un 2.914% m\u00e1s de visibilidad en m\u00e1s de 100 sitios web de clientes"}]},{"@type":"WebSite","@id":"https:\/\/kinsta.com\/es\/#website","url":"https:\/\/kinsta.com\/es\/","name":"Kinsta\u00ae","description":"Soluciones de alojamiento premium, r\u00e1pidas y seguras","publisher":{"@id":"https:\/\/kinsta.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinsta.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kinsta.com\/es\/#organization","name":"Kinsta","url":"https:\/\/kinsta.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kinsta.es\/","https:\/\/x.com\/Kinsta_ES","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/case_studies\/76752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/case_studies"}],"about":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/types\/case_studies"}],"author":[{"embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/users\/249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/media\/76753"}],"wp:attachment":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/media?parent=76752"}],"wp:term":[{"taxonomy":"segment","embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/segment?post=76752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}