{"id":28720,"date":"2019-11-19T08:13:36","date_gmt":"2019-11-19T16:13:36","guid":{"rendered":"https:\/\/kinsta.com\/?post_type=knowledgebase&#038;p=56928"},"modified":"2025-10-01T21:36:33","modified_gmt":"2025-10-01T19:36:33","slug":"mysql-server-has-gone-away","status":"publish","type":"post","link":"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/","title":{"rendered":"\u00bfC\u00f3mo Corregir el error \u00abMySQL Server Has Gone Away\u00bb en WordPress?"},"content":{"rendered":"<p>Las bases de datos son componentes clave de la mayor\u00eda de los sitios web modernos, por lo que los errores que afectan a los suyos tienden a ser particularmente preocupantes. El error \u00ab<strong>MySQL server has gone away<\/strong>\u00ab, por ejemplo, puede hacerle creer que su base de datos se ha perdido. Esto significa que es posible que tenga que recurrir a su \u00faltima <a href=\"https:\/\/kinsta.com\/es\/docs\/alojamiento-wordpress\/copias-de-seguridad-wordpress\/#wordpress-backup\">copia de seguridad<\/a> para poner en marcha su sitio.<\/p>\n<p>A pesar de lo intimidante que suena, sin embargo, el error\u00bbMySQL server has gone away\u00bb es bastante f\u00e1cil de arreglar. De hecho, con las instrucciones correctas, su sitio web deber\u00eda estar listo y funcionando en cuesti\u00f3n de minutos.<\/p>\n<p>En este art\u00edculo, vamos a mostrar c\u00f3mo es el error \u00abMySQL Server has gone away\u00bb y a desglosar lo que puede causarlo en <a href=\"https:\/\/kinsta.com\/es\/blog\/por-que-usar-wordpress\/\">WordPress<\/a>. A continuaci\u00f3n, le ense\u00f1aremos c\u00f3mo solucionarlo y evitar que este error vuelva a aparecer en el futuro.<\/p>\n<p>\u00a1Vamos a trabajar!<\/p>\n<div><\/div><kinsta-auto-toc heading=\"Table of Contents\" exclude=\"last\" list-style=\"arrow\" selector=\"h2\" count-number=\"-1\"><\/kinsta-auto-toc>\n<h2>Una Introducci\u00f3n al Error \u00abMySQL Server Has Gone Away\u00bb (El Servidor MySQL ha Desaparecido)<\/h2>\n<p>En primer lugar, echemos un vistazo al aspecto del error \u00abMySQL Server has gone away\u00bb:<\/p>\n<figure style=\"width: 900px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/10\/navegador-muestra-error.png\" alt=\"Error en el navegador que muestra el error \"MySQL server has gone away\"\" width=\"900\" height=\"171\"><figcaption class=\"wp-caption-text\">Error en el navegador que muestra el error \u00abMySQL server has gone away\u00bb<\/figcaption><\/figure>\n<p>El error en s\u00ed mismo es bastante sencillo y casi siempre aparece de la misma manera. Sin embargo, dependiendo del navegador que utilice y de la configuraci\u00f3n de su servidor, la redacci\u00f3n espec\u00edfica puede cambiar un poco.<\/p>\n<p>En cuanto al error en s\u00ed, tiene que ver con su <a href=\"https:\/\/kinsta.com\/es\/blog\/que-es-mysql\/\">base de datos MySQL<\/a>, como puede imaginar por el nombre. Para ser m\u00e1s espec\u00edficos, una de tres cosas suele causar este error en la mayor\u00eda de los sitios web:<\/p>\n<ol>\n<li><strong>Hay una tabla rota en su base de datos. <\/strong>Su <a href=\"https:\/\/kinsta.com\/es\/blog\/base-de-datos-wordpress\/\">base de datos<\/a> se corrompi\u00f3, por lo que debe volver a una copia de seguridad reciente o repararla.<\/li>\n<li><strong>Su configuraci\u00f3n de&#8217;timeout&#8217; de PHP es demasiado baja. <\/strong>Si un script PHP necesita acceso a su base de datos y no puede recuperar la informaci\u00f3n dentro de <a href=\"https:\/\/www.php.net\/manual\/en\/function.set-time-limit.php\">la ventana de tiempo de espera que se ha establecido<\/a>, esto tambi\u00e9n puede provocar el error mencionado anteriormente.<\/li>\n<li><strong>Los&#8217;Paquetes&#8217; han sido omitidos o son demasiado grandes. <\/strong>El servidor considera que este es el caso, esencialmente cierra la conexi\u00f3n y arroja el error.<\/li>\n<\/ol>\n<p>Afortunadamente, todos estos temas pueden ser tratados f\u00e1cilmente. Hablemos de c\u00f3mo puede iniciar el proceso de resoluci\u00f3n de problemas.<\/p>\n<h2>\u00bfC\u00f3mo Corregir el Error \u00abMySQL Server Has Gone Away\u00bb en WordPress? (3 M\u00e9todos)<\/h2>\n<p>Como hemos visto, hay algunas causas potenciales para este error particular de WordPress.<\/p>\n<p>Por esta raz\u00f3n, existen diferentes soluciones posibles. En la mayor\u00eda de los casos, una de las correcciones a continuaci\u00f3n debe deshacerse del error en su sitio web. As\u00ed que si uno no funciona, puede simplemente pasar al siguiente.<\/p>\n<h3>1. Edite su Archivo wp-db.php de WordPress<\/h3>\n<p>Si la configuraci\u00f3n de tiempo de espera PHP de su sitio web es demasiado baja y su base de datos es demasiado grande, obtener los datos que necesita durante esa ventana puede ser un problema. Como mencionamos antes, esto puede provocar el error \u00ab<em>MySQL server has gone away\u00bb.<\/em><\/p>\n<p>Para evitar que esto ocurra, tendr\u00e1 que editar uno de sus archivos principales de WordPress, llamado <em>wp-db.php<\/em>. Puede encontrar este archivo dentro de su carpeta ra\u00edz de WordPress, abriendo el directorio<em> wp-includes<\/em>:<\/p>\n<figure style=\"width: 900px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/10\/archivo-wp-db-php.png\" alt=\"El archivo wp-db.php\" width=\"900\" height=\"147\"><figcaption class=\"wp-caption-text\">El archivo wp-db.php<\/figcaption><\/figure>\n<p>Para acceder a estos archivos, le recomendamos que utilice un <a href=\"https:\/\/kinsta.com\/es\/blog\/mejores-clientes-ftp\/#Filezilla\">cliente FTP como FileZilla<\/a> y <a href=\"https:\/\/kinsta.com\/es\/blog\/como-usar-sftp\/\">se conecte a trav\u00e9s de SFTP<\/a> (entiende la diferencia entre <a href=\"https:\/\/kinsta.com\/es\/blog\/ftp-vs-sftp\/\">FTP y SFTP<\/a>). Una vez que se haya conectado a su sitio, busque <em>wp-db.php<\/em> y haga clic con el bot\u00f3n derecho del rat\u00f3n sobre \u00e9l para abrir el archivo utilizando su editor de texto local predeterminado. Sigue esta gu\u00eda r\u00e1pida para <a href=\"https:\/\/kinsta.com\/es\/blog\/filezilla-mostrar-archivos-ocultos\/\" target=\"_blank\" rel=\"noopener noreferrer\">mostrar todos los archivos ocultos en Filezilla<\/a>.<\/p>\n<p>Luego, busque en el archivo la siguiente l\u00ednea:<\/p>\n<pre><code class=\"language-php\">$this-&gt;ready = true;<\/code><\/pre>\n<p>Agregue la siguiente l\u00ednea justo debajo de ese c\u00f3digo:<\/p>\n<pre><code class=\"language-php\">$this-&gt;query(\"set session wait_timeout=300\");<\/code><\/pre>\n<p>Lo que hace este c\u00f3digo es establecer su valor de tiempo de espera de PHP en 300 segundos, que deber\u00eda ser mucho m\u00e1s de lo que necesita para evitar que aparezcan errores.<\/p>\n<p>Ahora guarde los cambios en su archivo<em> wp-db.php<\/em> y aseg\u00farese de que su sitio web se est\u00e1 cargando como deber\u00eda.<\/p>\n<p>Tenga en cuenta que si usted es un usuario de Kinsta, no deber\u00eda tener que modificar la configuraci\u00f3n de tiempo de espera de PHP de su sitio web. <a href=\"https:\/\/kinsta.com\/es\/precios\/\">Todos nuestros planes<\/a> tienen un valor de tiempo de espera base de 300 segundos y podemos ayudarle a aumentarlo dependiendo de sus necesidades.<\/p>\n<h3>2. Reparar su Base de Datos de WordPress<\/h3>\n<p>A veces su base de datos de WordPress puede corromperse, lo que a su vez puede conducir a errores cuando est\u00e1 tratando de establecer una conexi\u00f3n con ella. Esto no es tan com\u00fan, pero puede ocurrir en el curso del crecimiento de un sitio web normal a medida que agrega m\u00e1s tablas a su base de datos (as\u00ed como informaci\u00f3n sobre plugins y temas).<\/p>\n<p>Para solucionar este problema, puede utilizar una funci\u00f3n incorporada de WordPress para <a href=\"https:\/\/kinsta.com\/es\/blog\/error-de-conexion-a-la-base-de-datos\/#2-repairing-corrupt-database\">reparar su base de datos<\/a>. En primer lugar, sin embargo, tendr\u00e1 que activar esa funci\u00f3n. Esto implica navegar al directorio ra\u00edz de WordPress y abrir el <a href=\"https:\/\/kinsta.com\/es\/blog\/wp-config-php\/\">archivo<em> wp-config.php para<\/em><\/a> editarlo.<\/p>\n<p>Una vez abierto el archivo, despl\u00e1cese hasta la parte inferior y a\u00f1ada la siguiente l\u00ednea:<\/p>\n<pre><code class=\"language-php\">define('WP_ALLOW_REPAIR', true);<\/code><\/pre>\n<p>Esa simple l\u00ednea de c\u00f3digo le dice a WordPress que habilite la <a href=\"https:\/\/kinsta.com\/es\/blog\/solucionar-reparar-problemas-base-datos\/\" target=\"_blank\" rel=\"noopener noreferrer\">funci\u00f3n de reparaci\u00f3n de la base de datos<\/a>. Guarde los cambios en wp-config.php y cierre el archivo. Para ejecutar la funci\u00f3n, basta con visitar la siguiente URL:<\/p>\n<p><code>https:\/\/yourwebsite.com\/wp-admin\/maint\/repair.php<\/code><\/p>\n<p>WordPress le preguntar\u00e1 si desea simplemente reparar su base de datos o repararla y optimizarla. La primera opci\u00f3n es todo lo que necesita para corregir el error \u00ab<em>MySQL server has gone away\u00bb<\/em>:<\/p>\n<figure style=\"width: 900px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/10\/opcion-reparar-base-datos-wordpress-1.png\" alt=\"La opci\u00f3n de reparar la base de datos en WordPress\" width=\"900\" height=\"425\"><figcaption class=\"wp-caption-text\">La opci\u00f3n de reparar la base de datos en WordPress<\/figcaption><\/figure>\n<p>El proceso no deber\u00eda llevar mucho tiempo y, una vez finalizado, el error en cuesti\u00f3n deber\u00eda desaparecer. Sin embargo, todav\u00eda tiene que hacer alguna limpieza, ya que tendr\u00e1 que desactivar la funci\u00f3n de reparaci\u00f3n de la base de datos en su sitio web. Si no lo hace, <strong>cualquiera podr\u00eda activarlo<\/strong> accediendo a la misma URL.<\/p>\n<p>Antes de terminar, por lo tanto, vuelva a su directorio ra\u00edz de WordPress y elimine la l\u00ednea de c\u00f3digo que ha a\u00f1adido antes. A continuaci\u00f3n, guarde los cambios en el archivo y ci\u00e9rrelo.<\/p>\n<h3>3. Restaure su Sitio web Utilizando una Copia de Seguridad a Trav\u00e9s de su Proveedor de Hosting<\/h3>\n<p>Si todo lo dem\u00e1s falla, siempre puede utilizar una <a href=\"https:\/\/kinsta.com\/es\/blog\/restaurar-wordpress-desde-respaldo\/\">copia de seguridad completa de su sitio web para restaurarlo<\/a> a un punto en el que la base de datos funcionaba correctamente. Lo ideal es que lo haga con una copia de seguridad reciente para perder la menor cantidad de datos posible.<\/p>\n<p>El problema es que no todos los hosts de WordPress ofrecen funcionalidad de copia de seguridad incorporada para sus usuarios. Esto significa que a menudo se queda atascado usando soluciones manuales como los <a href=\"https:\/\/kinsta.com\/es\/blog\/plugins-de-backup-wordpress\/\">plugins<\/a>. Estas herramientas no son necesariamente malas, pero si no tiene acceso a su \u00e1rea de administraci\u00f3n de WordPress, restaurar una copia de seguridad se convierte en una tarea dif\u00edcil.<\/p>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-info\">\n            <h3>Info<\/h3>\n        <p>Kinsta proporciona copias de seguridad autom\u00e1ticas diarias y generadas por el sistema para todos los planes. Tambi\u00e9n hay copias de seguridad opcionales por hora.<\/p>\n<\/aside>\n\n<p>Aqu\u00ed en Kinsta, por otro lado, usted tiene acceso a <a href=\"https:\/\/kinsta.com\/es\/wordpress-hosting\/\">copias de seguridad completas de su sitio web<\/a> con cada plan. Para restaurar su sitio (incluyendo su base de datos) a un punto anterior, s\u00f3lo tiene que acceder a su panel de control de alojamiento y buscar la pesta\u00f1a<strong> Copias de seguridad<\/strong>:<\/p>\n<figure id=\"attachment_47497\" aria-describedby=\"caption-attachment-47497\" style=\"width: 2126px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mykinsta-restore-environment.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-47497 size-full\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mykinsta-restore-environment.png\" alt=\"Restaurar su copia de seguridad en MyKinsta\" width=\"2126\" height=\"1138\" srcset=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mykinsta-restore-environment.png 2126w, https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mykinsta-restore-environment-300x161.png 300w, https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mykinsta-restore-environment-1024x548.png 1024w, https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mykinsta-restore-environment-768x411.png 768w, https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mykinsta-restore-environment-1536x822.png 1536w, https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mykinsta-restore-environment-2048x1096.png 2048w\" sizes=\"auto, (max-width: 2126px) 100vw, 2126px\" \/><\/a><figcaption id=\"caption-attachment-47497\" class=\"wp-caption-text\">Restaurar su copia de seguridad en MyKinsta<\/figcaption><\/figure>\n<p>Haga clic en la copia de seguridad que desea restaurar y ver\u00e1 m\u00e1s detalles sobre cu\u00e1ndo se cre\u00f3. Para cada copia de seguridad, hay un bot\u00f3n<strong> Restaurar<\/strong> que puede utilizar para devolver su sitio web a su estado en ese momento.<\/p>\n<p>Sin embargo, recuerde: el uso de esta funci\u00f3n sobrescribir\u00e1 la versi\u00f3n actual de su sitio web. Por lo tanto, s\u00f3lo querr\u00e1 utilizarlo como medida de \u00faltimo recurso cuando est\u00e9 seguro de que no perder\u00e1 ninguna informaci\u00f3n cr\u00edtica.<\/p>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-info\">\n            <h3>Info<\/h3>\n        <p>Todos los planes de Kinsta incluyen la optimizaci\u00f3n semanal autom\u00e1tica de la base de datos MySQL para asegurar un mejor rendimiento de la base de datos. <a href=\"https:\/\/kinsta.com\/es\/precios\/?in-article-cta\">Revisa nuestros planes<\/a> para m\u00e1s informaci\u00f3n.<\/p>\n<\/aside>\n\n\n<h2>Resumen<\/h2>\n<p>Cuanto m\u00e1s crezca su sitio web, m\u00e1s datos necesitar\u00e1 almacenar. Toda esa informaci\u00f3n va a la base de datos de WordPress. En algunos casos, si es demasiado grande, es posible que se produzcan errores como <em>\u00abMySQL server has gone away\u00bb<\/em>.<\/p>\n<p>Si encuentra este error en particular, aqu\u00ed hay tres maneras de deshacerse de \u00e9l:<\/p>\n<ol>\n<li>Edite su archivo<em> wp-db.php de<\/em> WordPress.<\/li>\n<li>Repare su base de datos de WordPress.<\/li>\n<li>Restaure su sitio web utilizando una copia de seguridad a trav\u00e9s de su proveedor de alojamiento.<\/li>\n<\/ol>\n<p>En esta otra gu\u00eda, te mostramos consejos y pasos adicionales sobre <a href=\"https:\/\/kinsta.com\/es\/blog\/solucionar-reparar-problemas-base-datos\/\" target=\"_blank\" rel=\"noopener noreferrer\">c\u00f3mo reparar los problemas de la base de datos de WordPress<\/a>.<\/p>\n<p>Ahora que sabe c\u00f3mo arreglarlo, es el momento de deshacerse de este molesto mensaje de error. Si sigue teniendo problemas con MySQL, es posible que quiera comprobar <a href=\"https:\/\/kinsta.com\/es\/blog\/error-de-mysql-1064\/\">c\u00f3mo corregir el error de MySQL 1064<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las bases de datos son componentes clave de la mayor\u00eda de los sitios web modernos, por lo que los errores que afectan a los suyos tienden &#8230;<\/p>\n","protected":false},"author":103,"featured_media":28727,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[587,564],"topic":[1310],"class_list":["post-28720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-mysql","tag-wordpresshelp","topic-error-mysql"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfC\u00f3mo Corregir el error &quot;MySQL Server Has Gone Away&quot; en WordPress?<\/title>\n<meta name=\"description\" content=\"Aprenda a arreglar el mensaje de error &quot;MySQL server has gone away&quot; en WordPress con estos tres m\u00e9todos efectivos y qu\u00e9 lo est\u00e1 causando.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo Corregir el error &quot;MySQL Server Has Gone Away&quot; en WordPress?\" \/>\n<meta property=\"og:description\" content=\"Aprenda a arreglar el mensaje de error &quot;MySQL server has gone away&quot; en WordPress con estos tres m\u00e9todos efectivos y qu\u00e9 lo est\u00e1 causando.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kinsta.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-19T16:13:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-01T19:36:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mysql-server-has-gone-away.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1460\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Matteo Du\u00f2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Aprenda a arreglar el mensaje de error &quot;MySQL server has gone away&quot; en WordPress con estos tres m\u00e9todos efectivos y qu\u00e9 lo est\u00e1 causando.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mysql-server-has-gone-away.png\" \/>\n<meta name=\"twitter:creator\" content=\"@matteoduo\" \/>\n<meta name=\"twitter:site\" content=\"@Kinsta_ES\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matteo Du\u00f2\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/\"},\"author\":{\"name\":\"Matteo Du\u00f2\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/person\/9d811e805493f00205e6409451055174\"},\"headline\":\"\u00bfC\u00f3mo Corregir el error \u00abMySQL Server Has Gone Away\u00bb en WordPress?\",\"datePublished\":\"2019-11-19T16:13:36+00:00\",\"dateModified\":\"2025-10-01T19:36:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/\"},\"wordCount\":1684,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mysql-server-has-gone-away.png\",\"keywords\":[\"mySQL\",\"wordpresshelp\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/\",\"url\":\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/\",\"name\":\"\u00bfC\u00f3mo Corregir el error \\\"MySQL Server Has Gone Away\\\" en WordPress?\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mysql-server-has-gone-away.png\",\"datePublished\":\"2019-11-19T16:13:36+00:00\",\"dateModified\":\"2025-10-01T19:36:33+00:00\",\"description\":\"Aprenda a arreglar el mensaje de error \\\"MySQL server has gone away\\\" en WordPress con estos tres m\u00e9todos efectivos y qu\u00e9 lo est\u00e1 causando.\",\"breadcrumb\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#primaryimage\",\"url\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mysql-server-has-gone-away.png\",\"contentUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mysql-server-has-gone-away.png\",\"width\":1460,\"height\":730,\"caption\":\"C\u00f3mo Corregir el error \\\"MySQL Server Has Gone Away\\\" en WordPress\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kinsta.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Error MySQL\",\"item\":\"https:\/\/kinsta.com\/es\/secciones\/error-mysql\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfC\u00f3mo Corregir el error \u00abMySQL Server Has Gone Away\u00bb en WordPress?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kinsta.com\/es\/#website\",\"url\":\"https:\/\/kinsta.com\/es\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Soluciones de alojamiento premium, r\u00e1pidas y seguras\",\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kinsta.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kinsta.com\/es\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kinsta.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kinsta.es\/\",\"https:\/\/x.com\/Kinsta_ES\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/person\/9d811e805493f00205e6409451055174\",\"name\":\"Matteo Du\u00f2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/78636e34d9c125b93efb7e0893a776f8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/78636e34d9c125b93efb7e0893a776f8?s=96&d=mm&r=g\",\"caption\":\"Matteo Du\u00f2\"},\"description\":\"Head of Content at Kinsta and Content Marketing Consultant for WordPress plugin developers. Connect with Matteo on Twitter.\",\"sameAs\":[\"https:\/\/www.matteoduo.com\",\"https:\/\/www.linkedin.com\/in\/matteoduo\/\",\"https:\/\/x.com\/matteoduo\"],\"url\":\"https:\/\/kinsta.com\/es\/blog\/author\/matteoduo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo Corregir el error \"MySQL Server Has Gone Away\" en WordPress?","description":"Aprenda a arreglar el mensaje de error \"MySQL server has gone away\" en WordPress con estos tres m\u00e9todos efectivos y qu\u00e9 lo est\u00e1 causando.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo Corregir el error \"MySQL Server Has Gone Away\" en WordPress?","og_description":"Aprenda a arreglar el mensaje de error \"MySQL server has gone away\" en WordPress con estos tres m\u00e9todos efectivos y qu\u00e9 lo est\u00e1 causando.","og_url":"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/kinsta.es\/","article_published_time":"2019-11-19T16:13:36+00:00","article_modified_time":"2025-10-01T19:36:33+00:00","og_image":[{"width":1460,"height":730,"url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mysql-server-has-gone-away.png","type":"image\/png"}],"author":"Matteo Du\u00f2","twitter_card":"summary_large_image","twitter_description":"Aprenda a arreglar el mensaje de error \"MySQL server has gone away\" en WordPress con estos tres m\u00e9todos efectivos y qu\u00e9 lo est\u00e1 causando.","twitter_image":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mysql-server-has-gone-away.png","twitter_creator":"@matteoduo","twitter_site":"@Kinsta_ES","twitter_misc":{"Escrito por":"Matteo Du\u00f2","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#article","isPartOf":{"@id":"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/"},"author":{"name":"Matteo Du\u00f2","@id":"https:\/\/kinsta.com\/es\/#\/schema\/person\/9d811e805493f00205e6409451055174"},"headline":"\u00bfC\u00f3mo Corregir el error \u00abMySQL Server Has Gone Away\u00bb en WordPress?","datePublished":"2019-11-19T16:13:36+00:00","dateModified":"2025-10-01T19:36:33+00:00","mainEntityOfPage":{"@id":"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/"},"wordCount":1684,"commentCount":0,"publisher":{"@id":"https:\/\/kinsta.com\/es\/#organization"},"image":{"@id":"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mysql-server-has-gone-away.png","keywords":["mySQL","wordpresshelp"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/","url":"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/","name":"\u00bfC\u00f3mo Corregir el error \"MySQL Server Has Gone Away\" en WordPress?","isPartOf":{"@id":"https:\/\/kinsta.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#primaryimage"},"image":{"@id":"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mysql-server-has-gone-away.png","datePublished":"2019-11-19T16:13:36+00:00","dateModified":"2025-10-01T19:36:33+00:00","description":"Aprenda a arreglar el mensaje de error \"MySQL server has gone away\" en WordPress con estos tres m\u00e9todos efectivos y qu\u00e9 lo est\u00e1 causando.","breadcrumb":{"@id":"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#primaryimage","url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mysql-server-has-gone-away.png","contentUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2019\/11\/mysql-server-has-gone-away.png","width":1460,"height":730,"caption":"C\u00f3mo Corregir el error \"MySQL Server Has Gone Away\" en WordPress"},{"@type":"BreadcrumbList","@id":"https:\/\/kinsta.com\/es\/blog\/mysql-server-has-gone-away\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kinsta.com\/es\/"},{"@type":"ListItem","position":2,"name":"Error MySQL","item":"https:\/\/kinsta.com\/es\/secciones\/error-mysql\/"},{"@type":"ListItem","position":3,"name":"\u00bfC\u00f3mo Corregir el error \u00abMySQL Server Has Gone Away\u00bb en WordPress?"}]},{"@type":"WebSite","@id":"https:\/\/kinsta.com\/es\/#website","url":"https:\/\/kinsta.com\/es\/","name":"Kinsta\u00ae","description":"Soluciones de alojamiento premium, r\u00e1pidas y seguras","publisher":{"@id":"https:\/\/kinsta.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinsta.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kinsta.com\/es\/#organization","name":"Kinsta","url":"https:\/\/kinsta.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kinsta.es\/","https:\/\/x.com\/Kinsta_ES","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kinsta.com\/es\/#\/schema\/person\/9d811e805493f00205e6409451055174","name":"Matteo Du\u00f2","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kinsta.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/78636e34d9c125b93efb7e0893a776f8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78636e34d9c125b93efb7e0893a776f8?s=96&d=mm&r=g","caption":"Matteo Du\u00f2"},"description":"Head of Content at Kinsta and Content Marketing Consultant for WordPress plugin developers. Connect with Matteo on Twitter.","sameAs":["https:\/\/www.matteoduo.com","https:\/\/www.linkedin.com\/in\/matteoduo\/","https:\/\/x.com\/matteoduo"],"url":"https:\/\/kinsta.com\/es\/blog\/author\/matteoduo\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts\/28720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/users\/103"}],"replies":[{"embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/comments?post=28720"}],"version-history":[{"count":12,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts\/28720\/revisions"}],"predecessor-version":[{"id":47499,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts\/28720\/revisions\/47499"}],"alternate":[{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/28720\/translations\/en"},{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/28720\/translations\/es"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/28720\/translations\/pt"},{"embeddable":true,"hreflang":"ja","title":"Japanese","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/28720\/translations\/jp"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/28720\/translations\/fr"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/28720\/translations\/de"},{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/28720\/translations\/it"},{"href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/28720\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/media\/28727"}],"wp:attachment":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/media?parent=28720"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/tags?post=28720"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/topic?post=28720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}