{"id":33655,"date":"2020-05-29T01:59:22","date_gmt":"2020-05-29T08:59:22","guid":{"rendered":"https:\/\/kinsta.com\/?p=67800"},"modified":"2026-04-22T09:54:42","modified_gmt":"2026-04-22T07:54:42","slug":"plugins-multisitio-wordpress","status":"publish","type":"post","link":"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/","title":{"rendered":"Plugins de Multisitio Recomendados para WordPress (Administraci\u00f3n de redes, migraciones y copias de seguridad)"},"content":{"rendered":"<p>Realizar copias de seguridad y migraciones con sitios b\u00e1sicos de WordPress es bastante sencillo hoy en d\u00eda. Hay miles de tutoriales paso a paso en la web y plugins que automatizan todo el proceso, haci\u00e9ndolo r\u00e1pido e indoloro.<\/p>\n<p>Sin embargo, cuando se trata de una <a href=\"https:\/\/kinsta.com\/es\/wordpress-hosting\/multisitio\/\">configuraci\u00f3n multisitio de WordPress<\/a>, las tareas como las copias de seguridad y las migraciones son un poco m\u00e1s complejas.<\/p>\n<p>Esto se debe principalmente al hecho de que las instalaciones de varios sitios comparten la misma <a href=\"https:\/\/kinsta.com\/es\/blog\/base-de-datos-wordpress\/\">base de datos e instalaci\u00f3n de WordPress<\/a>. Por lo tanto, a menos que est\u00e9s migrando o haciendo una copia de seguridad de todo el multisitio, tienes que segmentar el trabajo al nivel de subsitio.<\/p>\n<p>O peor, tal vez quieras convertir un subsitio en una instalaci\u00f3n normal de WordPress.<\/p>\n<p>Hoy compartiremos algunos plugins multisitio de WordPress que recomendamos.<\/p>\n<p>\u00bfListo? \u00a1Vamos a sumergirnos!<\/p>\n<div><\/div><kinsta-auto-toc heading=\"Table of Contents\" exclude=\"last\" list-style=\"arrow\" selector=\"h2\" count-number=\"-1\"><\/kinsta-auto-toc>\n<h2>Los desaf\u00edos de respaldar y migrar una red de sitios m\u00faltiples de WordPress<\/h2>\n<p>El respaldo y la migraci\u00f3n de una <a href=\"https:\/\/kinsta.com\/es\/blog\/multisitio-wordpress\/\">red de sitios m\u00faltiples <\/a>se complica por unos pocos factores:<\/p>\n<ul>\n<li>Si deseas hacer copias de seguridad separadas de subsitios individuales, no podr\u00e1s utilizar los mismos m\u00e9todos que para hacer copias <a href=\"https:\/\/kinsta.com\/docs\/wordpress-hosting\/wordpress-backups\/#wordpress-backup\">de seguridad de un sitio independiente<\/a>.<\/li>\n<li>Puedes migrar subsitios dentro y fuera de una red de m\u00faltiples sitios, pero no es tan sencillo como migrar sitios independientes.<\/li>\n<li>Tambi\u00e9n podr\u00edas descubrir que deseas duplicar sitios dentro de tu red, migrando efectivamente un sitio a otro <a href=\"https:\/\/kinsta.com\/es\/blog\/subdominios-wordpress\/\">subdominio<\/a> o subdirectorio antes de hacer cambios en \u00e9l.<\/li>\n<li>Hacer copias de seguridad de subsitios individuales significa crear y almacenar copias de seguridad de cada subsitio por separado. La mayor\u00eda de los <a href=\"https:\/\/kinsta.com\/es\/blog\/plugins-de-backup-wordpress\/\">plugins de copia de seguridad<\/a>\u00a0no hacen esto. Necesitar\u00e1s usar un plugin que sea espec\u00edficamente compatible con los sitios m\u00faltiples de WordPress.<\/li>\n<\/ul>\n<p>Hacer copias de seguridad y migrar toda la red es lo mismo que hacer copias\u00a0<a href=\"https:\/\/kinsta.com\/es\/blog\/migracion-wordpress-por-cuenta-propia\/\">de seguridad y migrar un solo sitio<\/a>: el proceso no es diferente. Pero hacer copias de seguridad y migrar subsitios dentro de la red es a\u00fan m\u00e1s complicado porque la forma en que se almacenan los archivos y datos de los subsitios no es exactamente sencilla:<\/p>\n<ul>\n<li>Cada sitio tiene su propio conjunto de tablas de bases de datos, pero todos los sitios almacenan sus usuarios en las tablas wp-users y wp-usermeta de toda la red. Esto es para que un usuario de la red pueda ser a\u00f1adido a otro sitio sin necesidad de crear una nueva cuenta. Pero significa que <a href=\"https:\/\/kinsta.com\/es\/blog\/exportar-usuarios-wordpress\/\">exportar usuarios<\/a> no es tan f\u00e1cil como las otras tablas.<\/li>\n<li>Los sitios tienen sus archivos de subida almacenados por separado, en un directorio dedicado para cada subsitio dentro de wp-content\/uploads. Esto facilita la migraci\u00f3n de los archivos de un subsitio o la migraci\u00f3n de los archivos a \u00e9l.<\/li>\n<li><a href=\"https:\/\/kinsta.com\/es\/secciones\/plugins-wordpress\/\">Los plugins y temas<\/a> se almacenan una vez para la red pero se activan para sitios individuales. Si quieres migrar o hacer una copia de seguridad de los plugins tendr\u00e1s que identificar cu\u00e1les se utilizan para cada sitio individual.<\/li>\n<\/ul>\n<p>Entonces, \u00bfes imposible hacer copias de seguridad y migrar subsitios dentro y fuera de una red de m\u00faltiples sitios? \u00a1Claro que no! Hay un n\u00famero de plugins premium que puedes usar para hacerlo y algunos m\u00e9todos gratuitos.<\/p>\n<p>En este art\u00edculo, te mostraremos todos esos para que puedas hacer una copia de seguridad y migrar tus subsitios t\u00fa mismo.<\/p>\n<h2>Instalando y activando los plugins multisitio de WordPress en tu red de WordPress<\/h2>\n<p>Antes de entrar en el detalle de usar un plugin para hacer una copia de seguridad o migrar subsitios de tu red, necesitas saber c\u00f3mo funcionan los plugins en WordPress multisitio.<\/p>\n<p>Cada plugin s\u00f3lo se instala una vez en la red, y s\u00f3lo el administrador de la red puede hacerlo.<\/p>\n<p>Para instalar un plugin, ve a <strong>Network Admin &gt; Plugins &gt; Add New<\/strong>, e instala el plugin exactamente como lo har\u00edas si estuvieras administrando un sitio normal.<\/p>\n<figure style=\"width: 1880px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/instalar-plugin-multisite.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/instalar-plugin-multisite.png\" alt=\"Instalar un plugin en Multisite\" width=\"1880\" height=\"437\"><\/a><figcaption class=\"wp-caption-text\">Instalar un plugin en Multisite<\/figcaption><\/figure>\n<p>La diferencia est\u00e1 en c\u00f3mo\u00a0<a href=\"https:\/\/kinsta.com\/es\/blog\/multisitio-wordpress\/#installing-and-activating-plugins\">se activan esos plugins<\/a>. Los plugins pueden ser activados en la red, de modo que est\u00e1n activos en cada sitio de la red, o pueden ser activados para sitios individuales.<\/p>\n<p>S\u00f3lo el administrador de la red puede activar un plugin. Los administradores de sitios pueden activar plugins individuales en su propio sitio, pero s\u00f3lo si el administrador de la red ha dado permiso para ello.<\/p>\n<p>Como administrador de la red, para editar los permisos de activaci\u00f3n de los plugins, ve a <strong>Administraci\u00f3n de la Red &gt; Configuraci\u00f3n de la Red<\/strong>. Despl\u00e1zate hacia la derecha hasta la parte inferior de la pantalla y marca o desmarca la casilla <strong>Plugins<\/strong> junto a <strong>Habilitar los men\u00fas de administraci\u00f3n<\/strong>.<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/habilitar-plugins-administradores-sitios.jpg\" alt=\"Habilitar los plugins para los administradores de los sitios\" width=\"1500\" height=\"574\"><figcaption class=\"wp-caption-text\">Habilitar los plugins para los administradores de los sitios<\/figcaption><\/figure>\n<p>Si se activan los plugins para los administradores del sitio, pueden ir a la pantalla de Plugins en su administrador y activar los plugins que necesiten. S\u00f3lo puedes desactivar esto para todos los plugins, no para unos pocos seleccionados (a diferencia de los temas).<\/p>\n<p>Si quieres que se active un plugin para cada sitio de la red, tienes que activarlo desde las pantallas de administraci\u00f3n de la red.<\/p>\n<p>Ve a <strong>Administraci\u00f3n de la Red &gt; Plugins<\/strong>. Encuentra el plugin que quieres activar y haz clic en el enlace <strong>Network Activate<\/strong>.<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/red-activando-plugin.jpg\" alt=\"Red activando un plugin\" width=\"1500\" height=\"124\"><figcaption class=\"wp-caption-text\">Activaci\u00f3n de un plugin en la red<\/figcaption><\/figure>\n<p><a href=\"https:\/\/kinsta.com\/es\/blog\/wordpress-migracion-plugins\/\">Los plugins de migraci\u00f3n y de respaldo<\/a>, que generalmente funcionan a nivel de red y no a nivel de sitio, son ejemplos perfectos de plugins que deben ser activados para toda la red, ya que su funci\u00f3n se aplica a la red y no a sitios individuales.<\/p>\n<p>Para desactivar un plugin en la red, simplemente haz clic en el enlace <strong>Network Deactivate<\/strong> donde estaba el enlace <strong>Network Activate<\/strong>. Esto s\u00f3lo est\u00e1 disponible si has activado el plugin para toda la red. Si el plugin fue activado para sitios individuales, el administrador de la red o el administrador del sitio puede desactivarlo para cada sitio, desde las pantallas de administraci\u00f3n del sitio para ese sitio.<\/p>\n\n<h2>Plugins para la administraci\u00f3n de tu red de sitios m\u00faltiples de WordPress<\/h2>\n<p>Hay algunos plugins que te ayudar\u00e1n a administrar tu red de sitios m\u00faltiples y a trabajar con ella de manera m\u00e1s eficiente. A veces te dar\u00e1n informaci\u00f3n que facilitar\u00e1 el proceso de respaldo o migraci\u00f3n de tus subsitios.<\/p>\n<p>Ten en cuenta que todos estos plugins necesitan ser activados en red porque funcionan a nivel de red.<\/p>\n<div><\/div><kinsta-auto-toc list-style=\"decimal\" selector=\"h3\" count-number=\"5\" sub-toc=\"true\"><\/kinsta-auto-toc>\n<h3>1. Multisite Enhancements<\/h3>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/mejoras-multiples-sitios-plugin-wp.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/mejoras-multiples-sitios-plugin-wp.jpg\" alt=\"Mejoras en m\u00faltiples sitios Plugin para WordPress\" width=\"1500\" height=\"500\"><\/a><figcaption class=\"wp-caption-text\">Multisite Enhancements Plugin para WordPress<\/figcaption><\/figure>\n<p>El plugin\u00a0<a href=\"https:\/\/wordpress.org\/plugins\/multisite-enhancements\/\">Multisite Enhancements<\/a> te ofrece m\u00e1s informaci\u00f3n sobre tu red de sitios m\u00faltiples y m\u00e1s herramientas para trabajar. Una caracter\u00edstica particularmente \u00fatil es la capacidad de ver qu\u00e9 plugins o temas est\u00e1n activos en cada sitio de la red.<\/p>\n<p>Esto significa que si quieres hacer una copia de seguridad o migrar un sitio individual, sabr\u00e1s qu\u00e9 plugins y temas est\u00e1n activados en \u00e9l. Tambi\u00e9n es \u00fatil para probar: si un plugin\u00a0<a href=\"https:\/\/kinsta.com\/es\/blog\/errores-wordpress\/\">causa problemas<\/a> en un sitio de tu red, sabr\u00e1s qu\u00e9 otros sitios necesitas probar.<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/multisite-enhancements-pantalla-plugins.jpg\" alt=\"Multisite enhancements - pantalla de plugins\" width=\"1500\" height=\"868\"><figcaption class=\"wp-caption-text\">Multisite enhancements &#8211; pantalla de plugins<\/figcaption><\/figure>\n<h3>2. Multisite Toolbar Additions<\/h3>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/multisite-toolbar-additions-plugin.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/multisite-toolbar-additions-plugin.jpg\" alt=\"Multisite Toolbar Additions Plugin de WordPress\" width=\"1500\" height=\"500\"><\/a><figcaption class=\"wp-caption-text\">Multisite Toolbar Additions Plugin de WordPress<\/figcaption><\/figure>\n<p>El plugin\u00a0<a href=\"https:\/\/wordpress.org\/plugins\/multisite-toolbar-additions\/\">Multisite Toolbar Additions<\/a> a\u00f1ade algunos atajos r\u00e1pidos a la barra de herramientas de WordPress para los administradores de la red.<\/p>\n<p>Esto puede ahorrar tiempo si necesitas hacer cosas como administrar plugins y temas y configurar los ajustes sin tener que hacer muchos clics.<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/elementos-adicionales-barra-herramientas.jpg\" alt=\"Elementos adicionales de la barra de herramientas\" width=\"1500\" height=\"596\"><figcaption class=\"wp-caption-text\">Elementos adicionales de la barra de herramientas<\/figcaption><\/figure>\n<h3>3. User Switching<\/h3>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/user-switching-plugin-wordpress.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/user-switching-plugin-wordpress.jpg\" alt=\"User Switching plugin de WordPress\" width=\"1500\" height=\"500\"><\/a><figcaption class=\"wp-caption-text\">User Switching plugin de WordPress<\/figcaption><\/figure>\n<p>El plugin\u00a0<a href=\"https:\/\/wordpress.org\/plugins\/user-switching\/\">User Switching<\/a> no es s\u00f3lo para multisitio, sino que es particularmente \u00fatil en redes multisitio ya que tienen m\u00e1s <a href=\"https:\/\/kinsta.com\/es\/blog\/roles-de-usuario\/\">funciones de usuario<\/a>. Si gestionas una red y quieres solucionar un problema que experimenta uno de los administradores de tu sitio, te permite acceder a la red como si estuvieras usando su login.<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/user-switching-interfaz.jpg\" alt=\"User Switching - interfaz\" width=\"1500\" height=\"415\"><figcaption class=\"wp-caption-text\">User Switching &#8211; interfaz<\/figcaption><\/figure>\n<p>Simplemente ve a la pantalla de Usuarios, pasa el cursor sobre un usuario y haz clic en el enlace <strong>Cambiar a<\/strong>. Puedes ahorrar mucho tiempo al entrar y salir de nuevo y te permite apoyar mejor a los usuarios de tu red.<\/p>\n<h3>4. WP Multi Network<\/h3>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/wp-multi-network-plugin.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/wp-multi-network-plugin.jpg\" alt=\"WP Multi Network Plugin\" width=\"1500\" height=\"500\"><\/a><figcaption class=\"wp-caption-text\">WP Multi Network Plugin<\/figcaption><\/figure>\n<p>Si alguna vez te has preguntado si es posible crear una red multisitio dentro de una red multisitio, el plugin\u00a0<a href=\"https:\/\/wordpress.org\/plugins\/wp-multi-network\/\">WP Multi Network<\/a> tiene tu respuesta.<\/p>\n<p>Cuando se instala y se activa la red, a\u00f1ade un men\u00fa de <strong>Mis redes<\/strong> al men\u00fa de administraci\u00f3n y te permite convertir cualquiera de los sitios de tu red de sitios m\u00faltiples en una red propia, lo que significa que puedes tener dos capas de sitios m\u00faltiples de WordPress.<\/p>\n<p>Es especialmente \u00fatil para las empresas que dirigen una red de m\u00faltiples sitios para departamentos o empresas infantiles, que luego pueden crear sus propias redes.<\/p>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-important\">\n            <h3>Important<\/h3>\n        <p>Este plugin no ha sido probado con los \u00faltimos lanzamientos importantes. Sugerimos encarecidamente que lo pruebes primero en un <a href=\"https:\/\/kinsta.com\/es\/docs\/alojamiento-wordpress\/entorno-staging\/\">entorno de staging<\/a>.<\/p>\n<\/aside>\n\n<h3>5. Multisite Langauge Switcher<\/h3>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/multisite-language-switcher-plugin-wp.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/multisite-language-switcher-plugin-wp.jpg\" alt=\"Multisite Language Switcher Plugin de WordPress\" width=\"1500\" height=\"500\"><\/a><figcaption class=\"wp-caption-text\">Multisite Language Switcher Plugin de WordPress<\/figcaption><\/figure>\n<p>Si utilizas WordPress multisite para gestionar una red de sitios en diferentes idiomas, el plugin\u00a0<a href=\"https:\/\/wordpress.org\/plugins\/multisite-language-switcher\/\">Multisite Language Switcher<\/a> lo har\u00e1 m\u00e1s f\u00e1cil.<\/p>\n<p>A\u00f1ade\u00a0<a href=\"https:\/\/kinsta.com\/es\/blog\/wordpress-multilingue\/\">soporte multiling\u00fce<\/a> a toda tu red, incluyendo subdominios y subdirectorios, y permite la traducci\u00f3n de todo tipo de contenido, incluyendo p\u00e1ginas, posts, <a href=\"https:\/\/kinsta.com\/es\/blog\/wordpress-tipos-de-postes-personalizados\/\">tipos de posts personalizados<\/a> y <a href=\"https:\/\/kinsta.com\/es\/blog\/que-es-una-taxonomia\/\">taxonom\u00edas<\/a>.<\/p>\n<h2>Respaldar o migrar una red completa de sitios m\u00faltiples de WordPress<\/h2>\n<p>Hacer una copia de seguridad de toda la red ser\u00e1 \u00fatil si experimentas problemas que afecten a toda la instalaci\u00f3n de WordPress y no s\u00f3lo a un sitio individual. Si tienes muchos sitios en tu red, no querr\u00e1s pasar por el proceso de restaurar cada uno individualmente cuando restaurar la red entera hubiera sido m\u00e1s f\u00e1cil.<\/p>\n<p>Si planeas migrar sitios individuales en tu red, tiene sentido hacer primero una copia de seguridad de toda la red, en caso de problemas.<\/p>\n<p>Hacer una copia de seguridad de una red multisitio de WordPress no es tan diferente de hacer una copia de seguridad o migrar una instalaci\u00f3n normal de WordPress.<\/p>\n<p>Si est\u00e1s con Kinsta, nuestras <a href=\"https:\/\/kinsta.com\/docs\/wordpress-hosting\/wordpress-backups\/#wordpress-backup\">copias de seguridad automatizadas<\/a> te dar\u00e1n la tranquilidad de saber que toda tu red est\u00e1 siendo respaldada autom\u00e1ticamente todos los d\u00edas.<\/p>\n<p>Para acceder a tus copias de seguridad en <a href=\"https:\/\/kinsta.com\/es\/mykinsta\/\">MyKinsta<\/a>, ve a <strong>Sitios<\/strong>, haz clic en tu sitio y luego haz clic en Copias <strong>de seguridad<\/strong> en el men\u00fa.<\/p>\n<figure id=\"attachment_48007\" aria-describedby=\"caption-attachment-48007\" style=\"width: 2552px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/mykinsta-backups-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48007 size-full\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/mykinsta-backups-1.png\" alt=\"Copias de seguridad en MyKinsta.\" width=\"2552\" height=\"1442\" srcset=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/mykinsta-backups-1.png 2552w, https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/mykinsta-backups-1-300x170.png 300w, https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/mykinsta-backups-1-1024x579.png 1024w, https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/mykinsta-backups-1-768x434.png 768w, https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/mykinsta-backups-1-1536x868.png 1536w, https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/mykinsta-backups-1-2048x1157.png 2048w\" sizes=\"auto, (max-width: 2552px) 100vw, 2552px\" \/><\/a><figcaption id=\"caption-attachment-48007\" class=\"wp-caption-text\">Copias de seguridad en MyKinsta.<\/figcaption><\/figure>\n<p>Desde aqu\u00ed, puedes acceder a tus copias de seguridad de instant\u00e1neas m\u00e1s recientes y\u00a0<a href=\"https:\/\/kinsta.com\/docs\/wordpress-hosting\/wordpress-backups\/#restoring-backups\">restaurar tu sitio desde una de ellas<\/a>. Tambi\u00e9n puedes hacer una copia de seguridad manual, que es una buena idea antes de empezar a migrar cualquier sitio dentro o fuera de tu red.<\/p>\n<p>Si prefieres hacer una copia de seguridad de tu red multisitio de WordPress en una ubicaci\u00f3n fuera del sitio, te ofrecemos dos opciones convenientes.<\/p>\n<ol>\n<li>Puedes hacer clic en la pesta\u00f1a \u00abDescargar\u00bb y <a href=\"https:\/\/kinsta.com\/docs\/wordpress-hosting\/wordpress-backups\/#wordpress-backup#downloadable-backups\">generar un archivo ZIP descargable<\/a> que contenga tu base de datos y archivos de WordPress.<\/li>\n<li>Puedes hacer clic en la pesta\u00f1a \u00abExterna\u00bb y configurar copias de seguridad autom\u00e1ticas semanales o mensuales\u00a0<a href=\"https:\/\/kinsta.com\/docs\/wordpress-hosting\/wordpress-backups\/#external-backups-addon\">en un cubo de almacenamiento en la nube de Amazon S3 o Google<\/a>.<\/li>\n<\/ol>\n<p>Si no est\u00e1s con Kinsta, tendr\u00e1s que hacer copias de seguridad usando un plugin de respaldo. Sigue nuestra\u00a0<a href=\"https:\/\/kinsta.com\/es\/blog\/plugins-de-backup-wordpress\/\">gu\u00eda de plugins de copia de seguridad de WordPress<\/a>\u00a0para que esto funcione.<\/p>\n<h2>Respaldo o migraci\u00f3n de subsitios multisitios<\/h2>\n<p>Migrar o hacer una copia de seguridad de subsitios individuales es diferente de migrar o hacer una copia de seguridad de toda tu red de multisitios porque s\u00f3lo tendr\u00e1s que trabajar con los datos y archivos que se aplican a ese sitio espec\u00edfico.<\/p>\n<p>Esto significa migrar o hacer copias de seguridad de lo siguiente:<\/p>\n<ul>\n<li>Los <a href=\"https:\/\/kinsta.com\/es\/blog\/hacer-backup-base-de-datos-mysql-con-phpmyadmin\/\">cuadros de la base de datos<\/a> relativos a ese sitio.<\/li>\n<li>El tema y los plugins en uso en ese sitio, que ser\u00e1 almacenado con temas y plugins para toda la red.<\/li>\n<li>Las subidas de ese sitio, que se almacenar\u00e1n en su propia carpeta dentro de wp-content\/uploads.<\/li>\n<li>Los datos de los usuarios de ese sitio, que se almacenar\u00e1n en las principales tablas wp-users y wp-usermeta de la red.<\/li>\n<\/ul>\n<p>Es un proceso complejo, as\u00ed que si quieres hacerlo con un plugin a trav\u00e9s de las pantallas de administraci\u00f3n, tendr\u00e1s que pagar por un plugin premium.<\/p>\n<p>Sin embargo, hay algunas formas de hacer una migraci\u00f3n gratuita si est\u00e1s preparado para usar la l\u00ednea de comandos o para seguir un proceso m\u00e1s largo.<\/p>\n<h2>3 M\u00e9todos para respaldar y migrar subsitios multisitios<\/h2>\n<p>Hay tres m\u00e9todos que puedes usar para migrar subsitios de forma gratuita. Estos son:<\/p>\n<ol>\n<li><a href=\"https:\/\/kinsta.com\/es\/blog\/migracion-wordpress-por-cuenta-propia\/#migrating-a-wordpress-site-manually\">Migrar manualmente las tablas y archivos de la base de datos relevantes<\/a>.<\/li>\n<li><a href=\"https:\/\/kinsta.com\/es\/blog\/migracion-wordpress-por-cuenta-propia\/#migrating-a-site-into-or-out-of-wordpress-multisite-with-plugins\">Usar un m\u00e9todo alternativo que implique el uso de plugins gratuitos<\/a>.<\/li>\n<li>Ejecutar la migraci\u00f3n desde la <a href=\"https:\/\/kinsta.com\/es\/blog\/wp-cli\/\">l\u00ednea de comandos<\/a> con el\u00a0<a href=\"https:\/\/github.com\/10up\/MU-Migration\">plugin MU-Migration<\/a>.<\/li>\n<\/ol>\n<p>Ten en cuenta que estos m\u00e9todos no se pueden usar para hacer copias de seguridad: tendr\u00e1s que usar un plugin premium para eso.<\/p>\n<p>\u00a1Echemos un vistazo a los dos primeros!<\/p>\n<h3>Migrar un subsitio manualmente<\/h3>\n<p>Para migrar un subsitio manualmente, tendr\u00e1s que:<\/p>\n<ol>\n<li>Exportar las tablas de la base de datos s\u00f3lo para ese subsitio. Cuando las importes al nuevo sitio, deber\u00e1s editar el prefijo en el archivo SQL para reflejar el nombre de la tabla de la base de datos en la nueva ubicaci\u00f3n.<\/li>\n<li>Exportar los archivos de subida, que encontrar\u00e1s en wp-content\/uploads\/sites\/X, donde X es el ID del subsitio.<\/li>\n<li>Exportar cualquier tema y archivos de plugins usados en ese subsitio.<\/li>\n<\/ol>\n<p>No se puede migrar f\u00e1cilmente los registros de usuario de esta manera y si tienes muchos usuarios en el subsitio este m\u00e9todo no es recomendado.<\/p>\n<h3>Plugins multisitio de WordPress para migrar o hacer copias de seguridad de subsitios<\/h3>\n<p>El uso de un plugin de copia de seguridad o de migraci\u00f3n dedicado y compatible con multisitio acelerar\u00e1 el proceso considerablemente. Aqu\u00ed est\u00e1n los plugins m\u00e1s adecuados para hacer esto.<\/p>\n<h4>WP Migrate DB Pro (y WP Migrate DB Pro Multisite Tools)<\/h4>\n<p>El plugin\u00a0<a href=\"https:\/\/kinsta.com\/es\/blog\/wordpress-migracion-plugins\/#WP-Migrate-DB\">WP Migrate DB Pro<\/a> dice que te ayuda a \u00abempujar\/tirar tu sitio de WordPress con facilidad\u00bb. Si lo combinas con el complemento <strong>WP Migrate DB Pro Multisite Tools<\/strong>, puedes usarlo para migrar un subsitio tanto dentro como fuera de una red de multisitios.<\/p>\n<p>Te permite migrar un subsitio en (casi) cualquier permutaci\u00f3n que puedas necesitar:<\/p>\n<ul>\n<li>Empujar un subsitio (incluyendo los medios de comunicaci\u00f3n) a una instalaci\u00f3n de un solo sitio.<\/li>\n<li>Poner una instalaci\u00f3n de un solo sitio (incluyendo los medios de comunicaci\u00f3n) en un subsitio.<\/li>\n<li>Empujar una instalaci\u00f3n de un solo sitio (base de datos y medios de comunicaci\u00f3n) en una instalaci\u00f3n de varios sitios como un subsitio<\/li>\n<li>Poner una instalaci\u00f3n de un solo sitio (base de datos y medios de comunicaci\u00f3n) en una instalaci\u00f3n de varios sitios como un subsitio<\/li>\n<li>Exportar los datos de un subsitio como un archivo SQL listo para ser importado en una instalaci\u00f3n de un solo sitio.<\/li>\n<\/ul>\n<p>Lo \u00fanico que no puedes hacer ahora mismo es migrar un subsitio de una red multisitio a otra red multisitio como un subsitio. Sin embargo, hay una <a href=\"https:\/\/deliciousbrains.com\/wp-migrate-db-pro\/doc\/multisite-tools-addon\/#migrate-subsite-between-multisites\">soluci\u00f3n alternativa<\/a> que puedes utilizar.<\/p>\n<p>As\u00ed que si tienes un subsitio en tu red que necesita ser transferido a tu propia instalaci\u00f3n, o tienes un sitio externo que necesitas tirar como un nuevo subsitio, este plugin te cubre las espaldas.<\/p>\n<h4>Duplicator<\/h4>\n<p>El plugin <a href=\"https:\/\/wordpress.org\/plugins\/duplicator\/\">Duplicator<\/a>\u00a0est\u00e1 dise\u00f1ado para ayudarte a duplicar y migrar sitios de WordPress, pero tambi\u00e9n funcionar\u00e1 con subsitios de una red de sitios m\u00faltiples.<\/p>\n<p>Hay cinco pasos para usar el plugin para migrar un subsitio a una instalaci\u00f3n de un solo sitio:<\/p>\n<ol>\n<li>Usa el plugin para crear un paquete en tu m\u00e1quina fuente, como lo har\u00edas en un sitio \u00fanico est\u00e1ndar.<\/li>\n<li>Copia el instalador\/archivo en la nueva ubicaci\u00f3n y crea tu base de datos y usuario.<\/li>\n<li>Ve al instalador.<\/li>\n<li>Ver\u00e1s un desplegable que contiene todos los subsitios del paquete. Elige uno y contin\u00faa con la instalaci\u00f3n.<\/li>\n<li>El subsitio elegido en el paso 4 se instalar\u00e1 como un nuevo independiente.<\/li>\n<\/ol>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-info\">\n            <h3>Info<\/h3>\n        <p>El plugin que se recomienda y describe en este art\u00edculo es la <strong>versi\u00f3n gratuita de Duplicator<\/strong>, no Duplicator Pro. El plugin Duplicator Pro no es compatible con Kinsta y es un <a href=\"https:\/\/kinsta.com\/es\/docs\/alojamiento-wordpress\/plugins-y-temas-wordpress\/plugins-anulados-e-incompatibles-wordpress\/\">plugin prohibido<\/a>.<\/p>\n<\/aside>\n\n<h4>WPvivid Backup Pro<\/h4>\n<p>El plugin premium\u00a0<a href=\"https:\/\/wpvivid.com\/\">WPvivid Backup Pro<\/a> es otro que es compatible con multisitios.<\/p>\n<p>El plugin te permite hacer copias de seguridad o migrar sitios mediante la migraci\u00f3n manual, la migraci\u00f3n autom\u00e1tica o la migraci\u00f3n a trav\u00e9s del almacenamiento remoto. Con la versi\u00f3n premium, puedes hacer copias de seguridad y migrar subsitios en tu red de m\u00faltiples sitios.<\/p>\n<aside role=\"note\" class=\"wp-block-kinsta-notice is-style-info\">\n            <h3>Info<\/h3>\n        <p>La versi\u00f3n gratuita del plugin WPvivid es <a href=\"https:\/\/kinsta.com\/es\/docs\/alojamiento-wordpress\/plugins-y-temas-wordpress\/\">incompatible con el alojamiento de Kinsta<\/a> porque ejecuta copias de seguridad no incrementales.<\/p>\n<\/aside>\n\n<h4>ManageWP<\/h4>\n<p>El plugin\u00a0<a href=\"https:\/\/managewp.com\/features\">ManageWP<\/a> no se limita a las copias de seguridad y las migraciones. Incluye una gama de herramientas dise\u00f1adas para ayudarte a administrar tu sitio y mantenerte al d\u00eda.<\/p>\n<p>La versi\u00f3n premium viene con herramientas que te ayudan a migrar r\u00e1pidamente un sitio de WordPress, incluyendo subsitios en una red de sitios m\u00faltiples. Tanto la versi\u00f3n gratuita como la premium incluyen herramientas de copia de seguridad, pero necesitar\u00e1s la versi\u00f3n premium para hacer una copia de seguridad de los subsitios individualmente.<\/p>\n<p>Al utilizar ManageWP con subsitios, deber\u00e1 tener en cuenta las siguientes advertencias, que se detallan en la\u00a0<a href=\"https:\/\/managewp.com\/blog\/multisite-websites-in-managewp\">documentaci\u00f3n del plugin<\/a>:<\/p>\n<ul>\n<li>Cuando haces una copia de seguridad de un subsitio, se hace una copia de seguridad de toda la red de sitios m\u00faltiples. Pero s\u00f3lo se te cobra por ese subsitio.<\/li>\n<li>No tienes que hacer una copia de seguridad del sitio padre si quieres hacer una copia de seguridad de un subsitio.<\/li>\n<li>Si migras tu copia de seguridad a un destino externo, estar\u00e1s subiendo toda la red de sitios m\u00faltiples. Pero el plugin tiene tres opciones de restauraci\u00f3n, que incluyen la capacidad de restaurar s\u00f3lo el subsitio seleccionado. Los plugins y los temas no se restaurar\u00e1n ya que est\u00e1n a nivel de la red de sitios m\u00faltiples.<\/li>\n<\/ul>\n<h3>Limpieza despu\u00e9s de la migraci\u00f3n<\/h3>\n<p>Una vez que has migrado un subsitio dentro o fuera de una red multisitio, puede que necesites hacer una limpieza.<\/p>\n<p>Si has migrado el sitio fuera de tu red y ya no lo necesitas, aseg\u00farate de eliminarlo de tus sitios.<\/p>\n<p>Ve a <strong>Administraci\u00f3n de la Red &gt; Sitios<\/strong> y encuentra el sitio que has migrado. Haz clic en el enlace <strong>Borrar<\/strong> debajo del nombre del sitio.<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/02\/eliminar-sitio-red-sitios-multiples-wp.jpg\" alt=\"Eliminar un sitio en una red de sitios m\u00faltiples de WordPress\" width=\"1500\" height=\"446\"><figcaption class=\"wp-caption-text\">Eliminar un sitio en una red de sitios m\u00faltiples de WordPress<\/figcaption><\/figure>\n<p>Si tu subsitio estaba usando un tema o cualquier plugin que no est\u00e9 activado en ning\u00fan otro sitio de tu red, tambi\u00e9n deber\u00edas eliminarlos. Siempre es conveniente eliminar cualquier software de tu instalaci\u00f3n de WordPress que no se est\u00e9 utilizando.<\/p>\n<p>No te olvides de comprobar que la nueva versi\u00f3n del sitio funciona en el lugar al que lo has migrado antes de hacer esto! (Y puede que quieras hacer una copia de seguridad primero, por si acaso.)<\/p>\n<h2>Clonaci\u00f3n de sitios dentro de la red<\/h2>\n<p>A veces, en lugar de migrar un subsitio de una red de m\u00faltiples sitios, se quiere migrar dentro de la red. En otras palabras, quieres\u00a0<a href=\"https:\/\/kinsta.com\/es\/blog\/clonar-sitio-wordpress\/\">hacer un clon del sitio<\/a>.<\/p>\n<p>Esto puede ayudarte a usar un sitio como plantilla para otro sitio o a re-desarrollar un sitio usando el sitio clonado y luego apuntar cualquier nombre de dominio a ese sitio una vez que est\u00e9 listo.<\/p>\n\n<h2>Resumen<\/h2>\n<p>Hacer copias de seguridad de subsitios individuales en una red de sitios m\u00faltiples de WordPress, o migrarlos dentro o fuera de un sitio m\u00faltiple, no es tan sencillo como hacer copias\u00a0<a href=\"https:\/\/kinsta.com\/docs\/wordpress-hosting\/wordpress-backups\/#wordpress-backup\">de seguridad<\/a> o\u00a0<a href=\"https:\/\/kinsta.com\/es\/blog\/wordpress-migracion-plugins\/\">migrar una instalaci\u00f3n de un solo sitio<\/a>.<\/p>\n<p>Para hacer una copia de seguridad o migrar los subsitios de tu red, puedes <a href=\"https:\/\/kinsta.com\/es\/blog\/hacer-backup-base-de-datos-mysql-con-phpmyadmin\/\">migrar manualmente las tablas y archivos de la base de datos relevantes<\/a>, utilizar una soluci\u00f3n alternativa que necesita tres plugins gratuitos o, para el m\u00e9todo m\u00e1s r\u00e1pido, utilizar un plugin premium compatible con WordPress Multisite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Realizar copias de seguridad y migraciones con sitios b\u00e1sicos de WordPress es bastante sencillo hoy en d\u00eda. Hay miles de tutoriales paso a paso en la &#8230;<\/p>\n","protected":false},"author":105,"featured_media":48009,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[488,566],"topic":[1352],"class_list":["post-33655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-multisite","tag-wpplugins","topic-plugins-wordpress"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plugins multisitio recomendados de WordPress (Administraci\u00f3n de redes, migraciones y copias de seguridad)<\/title>\n<meta name=\"description\" content=\"Aprende acerca de los mejores plugins de WordPress para la administraci\u00f3n de tu red y para hacer copias de seguridad y migrar sitios en tu red de sitios m\u00faltiples.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plugins de Multisitio Recomendados para WordPress (Administraci\u00f3n de redes, migraciones y copias de seguridad)\" \/>\n<meta property=\"og:description\" content=\"Aprende acerca de los mejores plugins de WordPress para la administraci\u00f3n de tu red y para hacer copias de seguridad y migrar sitios en tu red de sitios m\u00faltiples.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kinsta.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-29T08:59:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T07:54:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/wordpress-multisite-plugins.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1460\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rachel McCollin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Aprende acerca de los mejores plugins de WordPress para la administraci\u00f3n de tu red y para hacer copias de seguridad y migrar sitios en tu red de sitios m\u00faltiples.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/wordpress-multisite-plugins.jpeg\" \/>\n<meta name=\"twitter:creator\" content=\"@Kinsta_ES\" \/>\n<meta name=\"twitter:site\" content=\"@Kinsta_ES\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rachel McCollin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/\"},\"author\":{\"name\":\"Rachel McCollin\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/person\/52eb266d622b565d3206e355caac172e\"},\"headline\":\"Plugins de Multisitio Recomendados para WordPress (Administraci\u00f3n de redes, migraciones y copias de seguridad)\",\"datePublished\":\"2020-05-29T08:59:22+00:00\",\"dateModified\":\"2026-04-22T07:54:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/\"},\"wordCount\":3643,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/wordpress-multisite-plugins.jpeg\",\"keywords\":[\"Multisite\",\"wpplugins\"],\"articleSection\":[\"Los mejores tutoriales de WordPress\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/\",\"url\":\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/\",\"name\":\"Plugins multisitio recomendados de WordPress (Administraci\u00f3n de redes, migraciones y copias de seguridad)\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/wordpress-multisite-plugins.jpeg\",\"datePublished\":\"2020-05-29T08:59:22+00:00\",\"dateModified\":\"2026-04-22T07:54:42+00:00\",\"description\":\"Aprende acerca de los mejores plugins de WordPress para la administraci\u00f3n de tu red y para hacer copias de seguridad y migrar sitios en tu red de sitios m\u00faltiples.\",\"breadcrumb\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#primaryimage\",\"url\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/wordpress-multisite-plugins.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/wordpress-multisite-plugins.jpeg\",\"width\":1460,\"height\":730,\"caption\":\"Plugins multisitio recomendados de WordPress (Administraci\u00f3n de redes, migraciones y copias de seguridad)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kinsta.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plugins de WordPress\",\"item\":\"https:\/\/kinsta.com\/es\/secciones\/plugins-wordpress\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plugins de Multisitio Recomendados para WordPress (Administraci\u00f3n de redes, migraciones y copias de seguridad)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kinsta.com\/es\/#website\",\"url\":\"https:\/\/kinsta.com\/es\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Soluciones de alojamiento premium, r\u00e1pidas y seguras\",\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kinsta.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kinsta.com\/es\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kinsta.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kinsta.es\/\",\"https:\/\/x.com\/Kinsta_ES\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/person\/52eb266d622b565d3206e355caac172e\",\"name\":\"Rachel McCollin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f99f27294a4a0acb07caa4d0604a1fef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f99f27294a4a0acb07caa4d0604a1fef?s=96&d=mm&r=g\",\"caption\":\"Rachel McCollin\"},\"description\":\"Rachel McCollin has been helping people build websites with WordPress since 2010. She's a huge fan of self-hosted WordPress and wants to help as many people as possible create an awesome website with it.\",\"url\":\"https:\/\/kinsta.com\/es\/blog\/author\/rachelmccollin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Plugins multisitio recomendados de WordPress (Administraci\u00f3n de redes, migraciones y copias de seguridad)","description":"Aprende acerca de los mejores plugins de WordPress para la administraci\u00f3n de tu red y para hacer copias de seguridad y migrar sitios en tu red de sitios m\u00faltiples.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/","og_locale":"es_ES","og_type":"article","og_title":"Plugins de Multisitio Recomendados para WordPress (Administraci\u00f3n de redes, migraciones y copias de seguridad)","og_description":"Aprende acerca de los mejores plugins de WordPress para la administraci\u00f3n de tu red y para hacer copias de seguridad y migrar sitios en tu red de sitios m\u00faltiples.","og_url":"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/kinsta.es\/","article_published_time":"2020-05-29T08:59:22+00:00","article_modified_time":"2026-04-22T07:54:42+00:00","og_image":[{"width":1460,"height":730,"url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/wordpress-multisite-plugins.jpeg","type":"image\/jpeg"}],"author":"Rachel McCollin","twitter_card":"summary_large_image","twitter_description":"Aprende acerca de los mejores plugins de WordPress para la administraci\u00f3n de tu red y para hacer copias de seguridad y migrar sitios en tu red de sitios m\u00faltiples.","twitter_image":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/wordpress-multisite-plugins.jpeg","twitter_creator":"@Kinsta_ES","twitter_site":"@Kinsta_ES","twitter_misc":{"Escrito por":"Rachel McCollin","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#article","isPartOf":{"@id":"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/"},"author":{"name":"Rachel McCollin","@id":"https:\/\/kinsta.com\/es\/#\/schema\/person\/52eb266d622b565d3206e355caac172e"},"headline":"Plugins de Multisitio Recomendados para WordPress (Administraci\u00f3n de redes, migraciones y copias de seguridad)","datePublished":"2020-05-29T08:59:22+00:00","dateModified":"2026-04-22T07:54:42+00:00","mainEntityOfPage":{"@id":"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/"},"wordCount":3643,"commentCount":0,"publisher":{"@id":"https:\/\/kinsta.com\/es\/#organization"},"image":{"@id":"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/wordpress-multisite-plugins.jpeg","keywords":["Multisite","wpplugins"],"articleSection":["Los mejores tutoriales de WordPress"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/","url":"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/","name":"Plugins multisitio recomendados de WordPress (Administraci\u00f3n de redes, migraciones y copias de seguridad)","isPartOf":{"@id":"https:\/\/kinsta.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#primaryimage"},"image":{"@id":"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/wordpress-multisite-plugins.jpeg","datePublished":"2020-05-29T08:59:22+00:00","dateModified":"2026-04-22T07:54:42+00:00","description":"Aprende acerca de los mejores plugins de WordPress para la administraci\u00f3n de tu red y para hacer copias de seguridad y migrar sitios en tu red de sitios m\u00faltiples.","breadcrumb":{"@id":"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#primaryimage","url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/wordpress-multisite-plugins.jpeg","contentUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2020\/05\/wordpress-multisite-plugins.jpeg","width":1460,"height":730,"caption":"Plugins multisitio recomendados de WordPress (Administraci\u00f3n de redes, migraciones y copias de seguridad)"},{"@type":"BreadcrumbList","@id":"https:\/\/kinsta.com\/es\/blog\/plugins-multisitio-wordpress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kinsta.com\/es\/"},{"@type":"ListItem","position":2,"name":"Plugins de WordPress","item":"https:\/\/kinsta.com\/es\/secciones\/plugins-wordpress\/"},{"@type":"ListItem","position":3,"name":"Plugins de Multisitio Recomendados para WordPress (Administraci\u00f3n de redes, migraciones y copias de seguridad)"}]},{"@type":"WebSite","@id":"https:\/\/kinsta.com\/es\/#website","url":"https:\/\/kinsta.com\/es\/","name":"Kinsta\u00ae","description":"Soluciones de alojamiento premium, r\u00e1pidas y seguras","publisher":{"@id":"https:\/\/kinsta.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinsta.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kinsta.com\/es\/#organization","name":"Kinsta","url":"https:\/\/kinsta.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kinsta.es\/","https:\/\/x.com\/Kinsta_ES","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kinsta.com\/es\/#\/schema\/person\/52eb266d622b565d3206e355caac172e","name":"Rachel McCollin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kinsta.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f99f27294a4a0acb07caa4d0604a1fef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f99f27294a4a0acb07caa4d0604a1fef?s=96&d=mm&r=g","caption":"Rachel McCollin"},"description":"Rachel McCollin has been helping people build websites with WordPress since 2010. She's a huge fan of self-hosted WordPress and wants to help as many people as possible create an awesome website with it.","url":"https:\/\/kinsta.com\/es\/blog\/author\/rachelmccollin\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts\/33655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/users\/105"}],"replies":[{"embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/comments?post=33655"}],"version-history":[{"count":13,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts\/33655\/revisions"}],"predecessor-version":[{"id":82855,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts\/33655\/revisions\/82855"}],"alternate":[{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/33655\/translations\/en"},{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/33655\/translations\/es"},{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/33655\/translations\/it"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/33655\/translations\/pt"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/33655\/translations\/fr"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/33655\/translations\/de"},{"embeddable":true,"hreflang":"sv","title":null,"href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/33655\/translations\/se"},{"embeddable":true,"hreflang":"nl","title":"Dutch","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/33655\/translations\/nl"},{"embeddable":true,"hreflang":"da","title":null,"href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/33655\/translations\/dk"},{"href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/33655\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/media\/48009"}],"wp:attachment":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/media?parent=33655"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/tags?post=33655"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/topic?post=33655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}