{"id":46418,"date":"2021-12-30T11:09:54","date_gmt":"2021-12-30T10:09:54","guid":{"rendered":"https:\/\/kinsta.com\/es\/?p=46418&#038;preview=true&#038;preview_id=46418"},"modified":"2023-08-21T11:06:26","modified_gmt":"2023-08-21T09:06:26","slug":"extensiones-de-dominio","status":"publish","type":"post","link":"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/","title":{"rendered":"\u00bfQu\u00e9 Son Las Extensiones de Dominio? (Y C\u00f3mo Elegir una Extensi\u00f3n de Dominio)"},"content":{"rendered":"<p>La mayor\u00eda de los sitios web que se te ocurren probablemente terminan en <strong>.com<\/strong>. Sin duda, tambi\u00e9n te habr\u00e1s encontrado con algunos que terminan en <strong>.org<\/strong> o <strong>.edu<\/strong>.<\/p>\n<p>\u00bfPero sab\u00edas que tambi\u00e9n puedes registrar un dominio que termine en <strong>.pizza<\/strong>?<\/p>\n<p>Esas letras al final de una direcci\u00f3n web se llaman extensi\u00f3n de dominio, y existem m\u00e1s o menos unas <a href=\"https:\/\/www.iana.org\/domains\/root\/db\" target=\"_blank\" rel=\"noopener noreferrer\">1.500<\/a> posibilidades. Algunas est\u00e1n restringidas a organizaciones o personas concretas, pero cualquiera puede registrar r\u00e1pidamente la mayor\u00eda de las extensiones.<\/p>\n<p>Eso hace que elegir el nombre de dominio para tu sitio web sea un poco complicado. \u00bfDebes elegir <strong>tuempresa.bingo<\/strong> o <strong>tuempresa.pescado<\/strong>? Si vendes pescado, este \u00faltimo puede parecer m\u00e1s adecuado.<\/p>\n<p>Este art\u00edculo presenta las extensiones de dominio, incluyendo qu\u00e9 son, qu\u00e9 hacen y c\u00f3mo elegir la mejor para tu sitio web.<\/p>\n<div><\/div><kinsta-auto-toc heading=\"Table of Contents\" exclude=\"last\" list-style=\"arrow\" selector=\"h2\" count-number=\"-1\"><\/kinsta-auto-toc>\n<h2>\u00bfQu\u00e9 es una extensi\u00f3n de dominio?<\/h2>\n<p>Las extensiones de dominio son las letras que siguen al punto final de una URL. Las extensiones m\u00e1s comunes son <strong>.com<\/strong>, <strong>.org<\/strong> y <strong>.net<\/strong>.<\/p>\n<p>Otro t\u00e9rmino para una extensi\u00f3n de dominio es el de <a href=\"https:\/\/kinsta.com\/es\/blog\/que-es-un-tld\/\">dominio de primer nivel<\/a>. Esto se debe a que puedes pensar en las partes de un nombre de dominio como niveles de clasificaci\u00f3n.<\/p>\n<p>En la parte superior, tenemos las extensiones de dominio. En este nivel, los dominios se dividen en amplias categor\u00edas.<\/p>\n<p>Por ejemplo, la extensi\u00f3n de dominio <strong>.de<\/strong> sit\u00faa el dominio en la categor\u00eda \u00abalem\u00e1n\u00bb. El uso de <strong>.gov<\/strong> significa que el dominio est\u00e1 en la categor\u00eda \u00aborganizaci\u00f3n gubernamental americana\u00bb.<\/p>\n<p>Las extensiones de dominio ya no se utilizan siempre de esta manera -ya hablaremos de ello-, pero era la intenci\u00f3n original.<\/p>\n<p>El siguiente nivel es el dominio. Es la parte que precede a la extensi\u00f3n. Designa a qu\u00e9 sitio web pertenece la URL. En la URL <strong>kinsta.com<\/strong>, por ejemplo, \u00abkinsta\u00bb es el dominio.<\/p>\n<p>A veces hay otro nivel llamado <a href=\"https:\/\/kinsta.com\/es\/blog\/subdominios-wordpress\/\">subdominio<\/a>. Los subdominios organizan un sitio web en partes separadas. Por ejemplo, la imagen siguiente muestra la URL <strong>blog.ejemplo.<\/strong>com.<\/p>\n<p>Aqu\u00ed, \u00abblog\u00bb es el subdominio. El dominio tambi\u00e9n puede contener otros subdominios como <strong>soporte.ejemplo.com<\/strong> o <strong>email.ejemplo.com<\/strong>.<\/p>\n<figure>\n<p><figure style=\"width: 900px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/11\/Untitled-49.png\" alt=\"The different parts of a web page URL\" width=\"900\" height=\"880\"><figcaption class=\"wp-caption-text\">Partes de la URL de una p\u00e1gina web. (<b>Fuente:<\/b> <a href=\"\/\/ahrefs.com\/blog\/seo-friendly-urls\/\u201d\">Ahrefs<\/a><span style=\"font-family: Roboto, -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;font-size: 1rem\">)<\/span><\/figcaption><\/figure><\/figure>\n<p>Cuando <a href=\"https:\/\/kinsta.com\/es\/blog\/mejor-registrador-de-dominio\/\">registres un nombre de dominio<\/a>, tendr\u00e1s que elegir tanto el nombre como una extensi\u00f3n de dominio. Los subdominios y todo lo que venga en la URL despu\u00e9s de la extensi\u00f3n se puede crear m\u00e1s tarde.<\/p>\n\n<h2>\u00bfPor qu\u00e9 existen las extensiones de dominio?<\/h2>\n<p>El prop\u00f3sito original de las extensiones de dominio era clasificar los sitios web por tipo.<\/p>\n<p>Por ejemplo, cualquier sitio web con una direcci\u00f3n terminada en <strong>.com<\/strong> se supon\u00eda que era un sitio comercial.<\/p>\n<p>Pero, como sabes, todo tipo de sitios web utilizan el <strong>.com<\/strong>. A medida que Internet ha ido evolucionando, las extensiones de dominio se han utilizado a menudo de forma distinta a la prevista originalmente.<\/p>\n<p>He aqu\u00ed un ejemplo con el que quiz\u00e1 est\u00e9s menos familiarizado: la extensi\u00f3n <strong>.fm<\/strong> se supone que designa un sitio web de Micronesia. Pero actualmente la utilizan muchas emisoras de radio y sitios de transmisi\u00f3n de audio.<\/p>\n<p>Hay extensiones, como <strong>.gov<\/strong>, que est\u00e1n restringidas a organizaciones espec\u00edficas. Pero muchas otras est\u00e1n abiertas a cualquiera.<\/p>\n<p>Como propietario de un sitio web, la extensi\u00f3n de tu dominio sirve para varias cosas. Puede indicar a la gente en qu\u00e9 tipo de sitio se encuentra, puede inspirar confianza y puede crear una <a href=\"https:\/\/kinsta.com\/es\/blog\/que-es-una-url\/\">URL pegadiza y memorable<\/a>.<\/p>\n<h2>\u00bfQui\u00e9n se encarga de las extensiones de dominio?<\/h2>\n<p>La Corporaci\u00f3n de Internet para la Asignaci\u00f3n de Nombres y N\u00fameros (ICANN) gestiona las extensiones de dominio a trav\u00e9s de sus divisiones, la Autoridad de Asignaci\u00f3n de N\u00fameros de Internet (IANA).<\/p>\n<p>Un registro designado por la ICANN gestiona cada extensi\u00f3n. El registro mantiene una base de datos de todos los nombres de dominio que utilizan esa extensi\u00f3n.<\/p>\n<p>Por ejemplo, el <strong>.com<\/strong>, el <strong>.net<\/strong> y otras extensiones son gestionadas por VeriSign, una empresa estadounidense. Las extensiones de marca suelen ser gestionadas por la empresa que las ha registrado. Por ejemplo, el registro <strong>.samsung<\/strong> est\u00e1 gestionado por Samsung.<\/p>\n<p>Los organismos gubernamentales o las organizaciones sin \u00e1nimo de lucro pueden gestionar las extensiones de c\u00f3digo de pa\u00eds. Por ejemplo, el operador del registro de <strong>.in<\/strong> es el National Internet Exchange of India.<\/p>\n<p>Estos registros contratan la extensi\u00f3n a registradores acreditados por la ICANN. Estas son las empresas donde puedes <a href=\"https:\/\/kinsta.com\/es\/blog\/mejor-registrador-de-dominio\/\">registrar tu nombre de dominio<\/a>, como Google Domains o Cloudflare.<\/p>\n<figure>\n<p><figure style=\"width: 726px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/11\/Untitled-53.png\" alt=\"The organizations in charge of domain name registration\" width=\"726\" height=\"408\"><figcaption class=\"wp-caption-text\">Las organizaciones encargadas del registro de nombres de dominio. (<b>Fuente:<\/b> <a href=\"\/\/whois.icann.org\/en\/domain-name-registration-process\u201d\">WHOIS<\/a><span style=\"font-family: Roboto, -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;font-size: 1rem\">)<\/span><\/figcaption><\/figure><\/figure>\n<h2>Tipos de extensiones de dominio<\/h2>\n<p>Existen tres tipos de extensiones de dominio: los TLD gen\u00e9ricos, los TLD patrocinados y los TLD con c\u00f3digo de pa\u00eds.<\/p>\n<h3>gTLDs<\/h3>\n<p>La categor\u00eda de TLDs gen\u00e9ricos incluye las extensiones que todos conocemos y amamos, como:<\/p>\n<ul>\n<li><strong>.com<\/strong><\/li>\n<li><strong>.org<\/strong><\/li>\n<li><strong>.net<\/strong><\/li>\n<\/ul>\n<p>Estas fueron algunas de las primeras extensiones de dominio, y fueron etiquetadas como \u00abgen\u00e9ricas\u00bb en contraste con las extensiones de c\u00f3digo de pa\u00eds.<\/p>\n<p>En 2011, la ICANN empez\u00f3 a permitir que las organizaciones registraran sus propias extensiones de dominio gen\u00e9rico. Esto ha dado lugar a extensiones de marca y a muchas otras extensiones aleatorias. Por ejemplo:<\/p>\n<ul>\n<li><strong>.farmacia<\/strong><\/li>\n<li><strong>.baseball<\/strong><\/li>\n<li><strong>.istanbul<\/strong><\/li>\n<li><strong>.toyota<\/strong><\/li>\n<\/ul>\n<figure>\n<p><figure style=\"width: 740px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/11\/Untitled-60.png\" alt=\"Domain extension examples\" width=\"740\" height=\"550\"><figcaption class=\"wp-caption-text\">Ejemplos de extensiones de dominio.<\/figcaption><\/figure><\/figure>\n<h3>sTLDs<\/h3>\n<p>Los TLDs patrocinados son extensiones utilizadas por una entidad espec\u00edfica. Puede ser una empresa, una rama del gobierno u otro tipo de grupo. Por ejemplo, algunos de los sTLD m\u00e1s comunes son:<\/p>\n<ul>\n<li>.<strong>gov<\/strong> (gobierno de EE.UU.)<\/li>\n<li>.<strong>edu<\/strong> (instituciones educativas post-secundarias acreditadas de EE.UU.)<\/li>\n<li><strong>.mil<\/strong> (ej\u00e9rcito de EE.UU.)<\/li>\n<\/ul>\n<p>Algunos sTLD menos conocidos son:<\/p>\n<ul>\n<li><strong>.museum<\/strong> (museos)<\/li>\n<li><strong>.cat<\/strong> (sitios web en catal\u00e1n)<\/li>\n<li><strong>.jobs<\/strong> (sitios web con <a href=\"https:\/\/kinsta.com\/es\/carreras\/\">ofertas de empleo<\/a>)<\/li>\n<\/ul>\n<h3>ccTLDs<\/h3>\n<p>Los TLD de c\u00f3digo de pa\u00eds representan un pa\u00eds espec\u00edfico, como <strong>.jp<\/strong> para Jap\u00f3n. Cada extensi\u00f3n de dominio con c\u00f3digo de pa\u00eds tiene sus propias reglas. Algunas est\u00e1n restringidas a las organizaciones del pa\u00eds, mientras que otras est\u00e1n disponibles para cualquiera.<\/p>\n<p>Algunos ccTLD comunes son:<\/p>\n<ul>\n<li><strong>.ru<\/strong> (Rusia)<\/li>\n<li><strong>.cn<\/strong> (China)<\/li>\n<li><strong>.de<\/strong> (Alemania)<\/li>\n<li><strong>.ca<\/strong> (Canad\u00e1)<\/li>\n<\/ul>\n<h2>\u00bfCu\u00e1les son las extensiones de dominio m\u00e1s comunes?<\/h2>\n<p>Aunque hay m\u00e1s de mil extensiones de dominio disponibles, ver\u00e1s algunas mucho m\u00e1s que otras. Veamos un pu\u00f1ado de las m\u00e1s famosas.<\/p>\n<h3>.com<\/h3>\n<p>Es la que todos conocemos mejor. No es de extra\u00f1ar que casi <a href=\"https:\/\/www.icdsoft.com\/blog\/what-are-the-most-popular-tlds-domain-extensions\/\" target=\"_blank\" rel=\"noopener noreferrer\">el 50%<\/a> de los sitios web utilicen la extensi\u00f3n de dominio <strong>.<\/strong> com.<\/p>\n<p>Puede que en su d\u00eda designara un sitio comercial, pero hoy podemos considerarla la extensi\u00f3n de dominio por defecto.<\/p>\n<h3>.net<\/h3>\n<p>Al igual que el <strong>.com<\/strong>, el<strong> .net<\/strong> es una de las primeras extensiones de dominio. Fue creada para ser utilizada por organizaciones relacionadas con las tecnolog\u00edas de red.<\/p>\n<p>Hoy en d\u00eda, el<strong> .net<\/strong> se utiliza a menudo como alternativa al <strong>.com<\/strong>. Las empresas que no pueden conseguir su dominio <strong>.com<\/strong> preferido eligen el <strong>.net<\/strong>.<\/p>\n<h3>.org<\/h3>\n<p>El\u00a0 <strong>.org<\/strong> se cre\u00f3 para ser utilizado <a href=\"https:\/\/kinsta.com\/es\/wordpress-hosting\/organizaciones-sin-fines-de-lucro\/\">por organizaciones sin \u00e1nimo de lucro<\/a> y sigue siendo la extensi\u00f3n de dominio preferida por estas organizaciones.<\/p>\n<p>La extensi\u00f3n .org est\u00e1 abierta a que la utilice cualquiera. Sin embargo, si eliges un dominio <strong>.<\/strong> org, la mayor\u00eda de la gente no esperar\u00e1 que tu sitio sea comercial.<\/p>\n<h3>.edu<\/h3>\n<p>En los primeros tiempos de las extensiones de dominio, el<strong> .edu<\/strong> pod\u00eda ser utilizado por cualquier organizaci\u00f3n centrada en la educaci\u00f3n.<\/p>\n<p>Desde 2001, la extensi\u00f3n est\u00e1 restringida a las instituciones postsecundarias acreditadas por un organismo de una lista espec\u00edfica. Esto significa que las instituciones no suelen utilizarlo fuera de EE.UU.<\/p>\n<h3>.gov<\/h3>\n<p>La extensi\u00f3n <strong>.gov<\/strong> s\u00f3lo puede ser utilizada por organizaciones gubernamentales de EE.UU. Inicialmente era s\u00f3lo para sitios del gobierno federal, pero en 2003 se abri\u00f3 a los gobiernos estatales, locales y tribales.<\/p>\n<p>Algunas ramas del gobierno no utilizan <strong>.gov<\/strong>, como el Servicio Postal de Estados Unidos, que utiliza <strong>usps.com<\/strong>.<\/p>\n<h3>.mil<\/h3>\n<p><strong>.mil<\/strong> est\u00e1 restringido a las divisiones, servicios y agencias del ej\u00e9rcito de EE. Estados Unidos es el \u00fanico pa\u00eds con una extensi\u00f3n de dominio para sus militares.<\/p>\n<h3>.ru, .cn, .uk, etc.<\/h3>\n<p>Muchos c\u00f3digos de pa\u00edses se siguen utilizando habitualmente para los sitios web de esos pa\u00edses. Probablemente puedes suponer que <a href=\"https:\/\/kinsta.com\/wordpress-hosting-japan\/\">un sitio .jp<\/a>, por ejemplo, es realmente de Jap\u00f3n.<\/p>\n<p>Pero unas cuantas extensiones de dominio con c\u00f3digo de pa\u00eds han sido cooptadas para otros fines, incluyendo la siguiente de esta lista<\/p>\n<h3>.io<\/h3>\n<p>Si conoces alg\u00fan sitio web <strong>.io<\/strong>, probablemente pertenezca a empresas tecnol\u00f3gicas. En los \u00faltimos a\u00f1os, <strong>.io<\/strong> ha ganado popularidad entre las empresas tecnol\u00f3gicas, ya que alude a<strong> I\/O<\/strong> (Input\/Output), una jerga tecnol\u00f3gica muy popular.<\/p>\n<p>Las empresas eligen<strong> .io<\/strong> porque marca su sitio web como relacionado con la tecnolog\u00eda. Tambi\u00e9n es popular porque los dominios<strong> .io<\/strong> suelen estar disponibles cuando la versi\u00f3n <strong>.com<\/strong> est\u00e1 ocupada.<\/p>\n<p>Pero IO tambi\u00e9n significa Oc\u00e9ano \u00cdndico. El prop\u00f3sito original de la extensi\u00f3n de dominio era designar los sitios web del Territorio Brit\u00e1nico del Oc\u00e9ano \u00cdndico.<\/p>\n<h3>.int<\/h3>\n<p><strong>.int<\/strong> significa internacional, y es una de las extensiones de dominio con los requisitos m\u00e1s estrictos. S\u00f3lo puede ser utilizado por organizaciones y programas avalados por un tratado internacional. Por ejemplo, el sitio web de la Agencia Espacial Europea reside en <strong>esa.int<\/strong>.<\/p>\n<p>Sin embargo, algunos dominios <strong>.int<\/strong> m\u00e1s antiguos que no cumplen los requisitos, como <strong>ymca.int<\/strong>, se han mantenido.<\/p>\n<h3>.mobi<\/h3>\n<p>El TLD <strong>.mobi<\/strong> indica que un sitio est\u00e1 <a href=\"https:\/\/kinsta.com\/es\/blog\/google-indexacion-centrada-moviles\/\">optimizado para dispositivos m\u00f3viles<\/a>. Un sitio que utilice <strong>.mobi<\/strong> tiene que cumplir los requisitos establecidos por el registro.<\/p>\n<p>Hoy en d\u00eda, casi todos los sitios son aptos para m\u00f3viles, por lo que designar un sitio <strong>.mobi<\/strong> por separado tiene menos valor que antes.<\/p>\n<h2>\u00bfQu\u00e9 significa la extensi\u00f3n de dominio para tu sitio web?<\/h2>\n<p>Puede que te preguntes si es importante la extensi\u00f3n que elijas para tu sitio web. \u00bfQu\u00e9 hace una extensi\u00f3n de dominio para tu sitio en t\u00e9rminos pr\u00e1cticos?<\/p>\n<p>En primer lugar, da a los visitantes potenciales la primera impresi\u00f3n de tu sitio web. Antes incluso de que hayan hecho clic en el enlace y hayan visto su dise\u00f1o y contenido, la gente se fija en si tu sitio es un <strong>.com<\/strong>, un <strong>.org<\/strong> o un <strong>.ninja<\/strong>, y cada uno de ellos les dar\u00e1 una impresi\u00f3n diferente.<\/p>\n<p>En segundo lugar, algunas extensiones de dominio son m\u00e1s caras de registrar que otras. Por ejemplo, es probable que pagues m\u00e1s por un nombre de dominio <strong>.io<\/strong> que por uno que termine en <strong>.com<\/strong>.<\/p>\n<p>Pero la extensi\u00f3n de tu dominio no es una elecci\u00f3n que debas hacer exclusivamente en funci\u00f3n del coste. Ten en cuenta que puedes ganar m\u00e1s dinero con un sitio <strong>.com<\/strong> de confianza que el mismo sitio registrado con un nombre de dominio <strong>.biz<\/strong>.<\/p>\n<p>La extensi\u00f3n de tu dominio no afecta (al menos no directamente) a la optimizaci\u00f3n en los motores de b\u00fasqueda.<\/p>\n<p>Poco despu\u00e9s de la creaci\u00f3n de los nuevos gTLD, se pregunt\u00f3 a <a href=\"https:\/\/www.youtube.com\/watch?v=ldFPcJZulXQ\" target=\"_blank\" rel=\"noopener noreferrer\">Matt Cutts de<\/a> Google c\u00f3mo afectar\u00edan al SEO.<\/p>\n<p>Aclar\u00f3 que Google siempre intentar\u00e1 devolver el mejor resultado para la consulta, independientemente del TLD que utilice el sitio.<\/p>\n<p>Sin embargo, la extensi\u00f3n de tu dominio puede afectar a tu rango de p\u00e1gina de forma indirecta.<\/p>\n<p>Tener un nombre de dominio memorable y de confianza <a href=\"https:\/\/kinsta.com\/es\/ebooks\/wordpress\/como-mejorar-seo\/\">beneficia al SEO de tu<\/a> sitio porque es m\u00e1s probable que la gente haga clic y enlace con \u00e9l.<\/p>\n<h2>C\u00f3mo elegir la mejor extensi\u00f3n de dominio para tu sitio web<\/h2>\n<p><a href=\"https:\/\/kinsta.com\/es\/blog\/elegir-nombre-dominio\/\">Elegir un nombre de<\/a> dominio -incluida la extensi\u00f3n- es una decisi\u00f3n importante.<\/p>\n<p>Al fin y al cabo, ah\u00ed es donde vivir\u00e1 tu sitio web a partir de ahora. Sigue estas buenas pr\u00e1cticas para elegir la extensi\u00f3n de dominio que m\u00e1s beneficie a tu sitio web.<\/p>\n<h3>En caso de duda, elige el .com<\/h3>\n<p>Para la mayor\u00eda de los sitios web, el viejo y fiable <strong>.<\/strong> com es el camino a seguir. La gente reconoce y conf\u00eda en el <strong>.com<\/strong>. Si tuvieran que adivinar el sitio web de tu marca, probablemente empezar\u00edan por <strong>tunombredemarca.com<\/strong>.<\/p>\n<p>Hay algunos casos en los que tiene sentido utilizar una extensi\u00f3n diferente.<\/p>\n<p>Si tu organizaci\u00f3n pertenece a una categor\u00eda que tiene una extensi\u00f3n de dominio bien conocida, puedes utilizarla. Por ejemplo, una organizaci\u00f3n sin \u00e1nimo de lucro deber\u00eda usar <strong>.org<\/strong>, y una universidad estadounidense deber\u00eda usar <strong>.edu<\/strong>.<\/p>\n<p>Algunas empresas quieren destacar su ubicaci\u00f3n. Si est\u00e1n en Canad\u00e1, pueden elegir <strong>.ca<\/strong> (pero <strong>.com<\/strong> es mejor si operan a nivel mundial).<\/p>\n<p>Aunque el <strong>.com<\/strong> es la mejor extensi\u00f3n de dominio para las marcas, el nombre de tu marca tambi\u00e9n es fundamental.<\/p>\n<p>Entonces, \u00bfqu\u00e9 haces si <strong>tunombredemarca.com<\/strong> no est\u00e1 disponible?<\/p>\n<p>Elegir una extensi\u00f3n diferente puede tener sentido. En la mayor\u00eda de los casos, deber\u00edas optar por algo familiar para la gente, como <strong>.net<\/strong>.<\/p>\n<h3>Hazlo memorable<\/h3>\n<p>Si la gente sigue un enlace a tu sitio web, la URL no importa mucho.<\/p>\n<p>Pero tal vez hayan estado en tu sitio antes y quieran volver a visitarlo. O tal vez, hayan o\u00eddo hablar del sitio web a trav\u00e9s de un amigo.<\/p>\n<p>En ese caso, deben recordar tu nombre de dominio.<\/p>\n<p>Cuando se trata de memorabilidad, el<strong> .com<\/strong> gana. Los dominios que utilizan el .com son m\u00e1s de <a href=\"https:\/\/growthbadger.com\/top-level-domains\/\" target=\"_blank\" rel=\"noopener noreferrer\">un 33%<\/a> m\u00e1s memorables que las URL que utilizan otros dominios de primer nivel. Cuando la gente olvida un dominio, es 3,8 veces m\u00e1s probable que asuma que termina en <strong>.com<\/strong> que en cualquier otra cosa.<\/p>\n<p>Sin embargo, algunas de las nuevas extensiones de TLD permiten a las empresas crear dominios memorables y m\u00e1s creativos. Por ejemplo, si tu negocio es Pasta Guru, ahora podr\u00edas registrar <strong>pasta.guru<\/strong> (alguien ya ha registrado ese dominio).<\/p>\n<figure>\n<p><figure style=\"width: 950px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/11\/Untitled-67.png\" alt=\"A screenshot of trust ratings from growthbadger\" width=\"950\" height=\"1025\"><figcaption class=\"wp-caption-text\">\u00bfHasta qu\u00e9 punto son fiables y memorables las extensiones de dominio? (<b>Fuente:<\/b> <a href=\"\/\/growthbadger.com\/top-level-domains\/\u201d\">GrowthBadger<\/a><span style=\"font-family: Roboto, -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;font-size: 1rem\">)<\/span><\/figcaption><\/figure><\/figure>\n<h3>Deja claro el prop\u00f3sito de tu sitio web<\/h3>\n<p>Las extensiones de dominio se crearon inicialmente para clasificar los sitios seg\u00fan su finalidad o tipo.<\/p>\n<p>Aunque las cosas son m\u00e1s flexibles hoy en d\u00eda, tu nombre de dominio sigue dando a los visitantes una pista sobre la finalidad de tu sitio.<\/p>\n<p>La extensi\u00f3n por defecto es <strong>.com<\/strong>, que puede utilizarse para casi todo. Pero si eliges una extensi\u00f3n diferente, aseg\u00farate de que dar\u00e1 a los visitantes la impresi\u00f3n correcta de lo que es tu sitio web.<\/p>\n<h3>Evita los dominios que suenen sospechosos<\/h3>\n<p>\u00bfEs m\u00e1s probable que des los datos de tu tarjeta de cr\u00e9dito a <strong>buywidgets.com<\/strong> o a <strong>buywidgets.zip<\/strong>?<\/p>\n<p>Si has elegido el primero, no eres el \u00fanico.<\/p>\n<p>La gente tiende a desconfiar de determinadas extensiones de dominio, a menudo con raz\u00f3n. Hay extensiones de las que los sitios de spam se han apoderado casi por completo.<\/p>\n<p>Entonces, \u00bfc\u00f3mo evitar un nombre de dominio que suene mal?<\/p>\n<p>A menos que puedas optar a algo como <strong>.gov<\/strong> o <strong>.mil<\/strong>, lo mejor es que te quedes con (lo has adivinado) <strong>.com<\/strong>.<\/p>\n<figure>\n<p><figure style=\"width: 620px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/11\/Untitled-77.png\" alt=\"a list of safe vs shady domain extensions \" width=\"620\" height=\"678\"><figcaption class=\"wp-caption-text\">Extensiones de dominio seguras vs. sospechosas. (<b>Fuente:<\/b> <a href=\"\/\/news.softpedia.com\/news\/have-you-ever-wondered-what-are-the-web-s-more-dangerous-domains-490830.shtml\u201d\">Softpedia<\/a><span style=\"font-family: Roboto, -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;font-size: 1rem\">)<\/span><\/figcaption><\/figure><\/figure>\n<h2>\u00bfPuedes inventar tu propia extensi\u00f3n de dominio?<\/h2>\n<p>Con todas estas palabras locas al final de las URL, \u00bfpodr\u00edas inventarte las tuyas propias?<\/p>\n<p>T\u00e9cnicamente, la respuesta es s\u00ed. Puedes solicitar el registro de una nueva extensi\u00f3n de dominio gen\u00e9rico (gTLD). Aunque, para la mayor\u00eda de los particulares y propietarios de peque\u00f1as empresas, no es una opci\u00f3n realista.<\/p>\n<p>En primer lugar, no puedes solicitarlo en cualquier momento: tienes que esperar a que la ICANN abra las solicitudes. Nadie sabe cu\u00e1ndo ocurrir\u00e1 eso, pero muchos suponen que ser\u00e1 en 2022.<\/p>\n<p>Quiz\u00e1 est\u00e9s dispuesto a esperar tanto tiempo. A continuaci\u00f3n, tendr\u00e1s que pagar una tasa de solicitud. Durante el \u00faltimo periodo de registro, esa tasa era de <a href=\"https:\/\/newgtlds.icann.org\/en\/applicants\/global-support\/faqs\/faqs-en\" target=\"_blank\" rel=\"noopener noreferrer\"> 185.000 d\u00f3lares<\/a>.<\/p>\n<p>Si te parece una buena inversi\u00f3n para asegurar la extensi\u00f3n de dominio \u00fanica de tu marca, puedes empezar a rellenar la solicitud. La ICANN tiene una lista de requisitos que deber\u00e1 cumplir tu extensi\u00f3n de dominio. Por ejemplo, no puede ser \u00abconfusamente similar\u00bb a otro TLD.<\/p>\n<p>Tambi\u00e9n necesitar\u00e1s la capacidad t\u00e9cnica para actuar como registro de todos los sitios que utilicen esta extensi\u00f3n.<\/p>\n<p>En otras palabras, <strong>tunombredemarca.com<\/strong> funcionar\u00e1 bien para tu sitio web.<\/p>\n<h2>C\u00f3mo registrar una extensi\u00f3n de dominio<\/h2>\n<p>Puedes elegir tu extensi\u00f3n de dominio cuando registres tu nombre de dominio.<\/p>\n<p>No todas las extensiones de dominio est\u00e1n disponibles en todos los registradores de dominios. Sin embargo, los principales registradores como <a href=\"https:\/\/kinsta.com\/blog\/google-domains-review\/\">Google Domains<\/a>, GoDaddy y Namecheap tendr\u00e1n muchos TLD, incluidos los m\u00e1s comunes.<\/p>\n<p>Algunas extensiones ser\u00e1n probablemente <a href=\"https:\/\/kinsta.com\/es\/blog\/cuanto-cuesta-nombre-dominio\/\">m\u00e1s caras que otras<\/a>. Si has elegido un nombre de dominio y una extensi\u00f3n que sabes que est\u00e1n disponibles, puedes comparar con algunos registradores para ver qui\u00e9n ofrece el mejor precio.<\/p>\n<figure>\n<p><figure style=\"width: 1501px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/11\/Untitled-83.png\" alt=\"A list of domain extension options at NameCheap\" width=\"1501\" height=\"787\"><figcaption class=\"wp-caption-text\">Opciones de extensi\u00f3n de dominio en NameCheap.<\/figcaption><\/figure><\/figure>\n<p>Algunas extensiones de dominio menos comunes s\u00f3lo se ofrecen en registradores especializados.<\/p>\n<p>Si no encuentras un lugar donde registrar tu extensi\u00f3n preferida, puedes intentar averiguar qui\u00e9n se encarga de ella. Para ello, visita <a href=\"https:\/\/www.iana.org\/domains\/root\/db\" target=\"_blank\" rel=\"noopener noreferrer\">esta lista de TLDs<\/a>. Haz clic en la extensi\u00f3n que quieras y despl\u00e1zate hacia abajo hasta \u00abInformaci\u00f3n del Registro\u00bb<\/p>\n<p>Deber\u00edas ver un enlace a la organizaci\u00f3n que registr\u00f3 la extensi\u00f3n. En algunos casos, ser\u00e1 un registrador de dominios que puedes utilizar.<\/p>\n<p>El gTLD tambi\u00e9n puede pertenecer a una marca u organizaci\u00f3n que planea mantener la extensi\u00f3n para s\u00ed misma.<\/p>\n<h2>\u00bfSe puede cambiar una extensi\u00f3n de dominio?<\/h2>\n<p>\u00bfDesear\u00edas haber elegido una extensi\u00f3n de dominio diferente para tu sitio web?<\/p>\n<p>Puedes cambiarla estableciendo <a href=\"https:\/\/kinsta.com\/es\/blog\/redirecciones-de-wordpress\/\">una redirecci\u00f3n 301<\/a>. Las redirecciones 301 permiten a los motores de b\u00fasqueda saber que la p\u00e1gina que quieres enviar a los visitantes se ha movido.<\/p>\n<p>En primer lugar, tendr\u00e1s que registrar tu nuevo nombre de dominio y crear un clon de tu sitio con la extensi\u00f3n actualizada. Luego redirigir\u00e1s todas tus URLs a la \u00faltima versi\u00f3n.<\/p>\n<p><a href=\"https:\/\/kinsta.com\/es\/blog\/wordpress-cambiar-dominio\/\">Aqu\u00ed tienes un pr\u00e1ctico tutorial<\/a> para redirigir tu sitio de WordPress a un nuevo dominio.<\/p>\n<p>Cambiar el nombre de tu dominio puede afectar temporalmente al SEO. Pero si lo haces bien, tus rankings deber\u00edan volver a la normalidad r\u00e1pidamente.<\/p>\n\n<h2>Resumen<\/h2>\n<p>Puede que s\u00f3lo sean unas breves letras al final de tu nombre de dominio, pero la extensi\u00f3n de tu dominio es una parte esencial de tu sitio web.<\/p>\n<p>Puede hacer que la URL del sitio web parezca fiable y memorable, o todo lo contrario. Puede marcar la diferencia en el coste de creaci\u00f3n y mantenimiento de tu sitio web. Y puede dar a los visitantes informaci\u00f3n sobre tu sitio web.<\/p>\n<p>El uso de las extensiones de dominio ha cambiado con el tiempo, y seguir\u00e1 cambiando.<\/p>\n<p>En el futuro, los nuevos TLD podr\u00edan superar a los antiguos est\u00e1ndares. <strong>.io<\/strong> podr\u00eda ser la extensi\u00f3n para todas las empresas tecnol\u00f3gicas. Pero hoy en d\u00eda, un TLD probado como <strong>.com<\/strong> o <strong>.org<\/strong> sigue siendo tu mejor opci\u00f3n.<\/p>\n<p><em>\u00bfAcabas de registrar tu nuevo nombre de dominio? Vamos a ponerlo en marcha. <a href=\"https:\/\/kinsta.com\/es\/docs\/alojamiento-wordpress\/dominios-wordpress\/\">A\u00f1\u00e1delo a tu sitio Kinsta<\/a>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mayor\u00eda de los sitios web que se te ocurren probablemente terminan en .com. Sin duda, tambi\u00e9n te habr\u00e1s encontrado con algunos que terminan en .org &#8230;<\/p>\n","protected":false},"author":199,"featured_media":46419,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[393,554],"topic":[1283],"class_list":["post-46418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-business","tag-domains","topic-sistema-nombre-de-dominio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 Son Las Extensiones de Dominio? (Y C\u00f3mo Elegir una Extensi\u00f3n de Dominio)<\/title>\n<meta name=\"description\" content=\"Aprende sobre las extensiones de dominio y c\u00f3mo elegir la correcta para tu negocio de entre todas las disponibles en la actualidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 Son Las Extensiones de Dominio? (Y C\u00f3mo Elegir una Extensi\u00f3n de Dominio)\" \/>\n<meta property=\"og:description\" content=\"Aprende sobre las extensiones de dominio y c\u00f3mo elegir la correcta para tu negocio de entre todas las disponibles en la actualidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kinsta.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-30T10:09:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-21T09:06:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/domain-extensions.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1460\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jeremy Holcombe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Aprende sobre las extensiones de dominio y c\u00f3mo elegir la correcta para tu negocio de entre todas las disponibles en la actualidad.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/domain-extensions.png\" \/>\n<meta name=\"twitter:creator\" content=\"@Kinsta_ES\" \/>\n<meta name=\"twitter:site\" content=\"@Kinsta_ES\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Holcombe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/\"},\"author\":{\"name\":\"Jeremy Holcombe\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/person\/4eee42881d7b5a73ebb4f58dd5223b21\"},\"headline\":\"\u00bfQu\u00e9 Son Las Extensiones de Dominio? (Y C\u00f3mo Elegir una Extensi\u00f3n de Dominio)\",\"datePublished\":\"2021-12-30T10:09:54+00:00\",\"dateModified\":\"2023-08-21T09:06:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/\"},\"wordCount\":3397,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/domain-extensions.png\",\"keywords\":[\"business\",\"domains\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/\",\"url\":\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/\",\"name\":\"\u00bfQu\u00e9 Son Las Extensiones de Dominio? (Y C\u00f3mo Elegir una Extensi\u00f3n de Dominio)\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/domain-extensions.png\",\"datePublished\":\"2021-12-30T10:09:54+00:00\",\"dateModified\":\"2023-08-21T09:06:26+00:00\",\"description\":\"Aprende sobre las extensiones de dominio y c\u00f3mo elegir la correcta para tu negocio de entre todas las disponibles en la actualidad.\",\"breadcrumb\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#primaryimage\",\"url\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/domain-extensions.png\",\"contentUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/domain-extensions.png\",\"width\":1460,\"height\":730,\"caption\":\"\u00bfQu\u00e9 son las extensiones de dominio? (Y c\u00f3mo elegir una extensi\u00f3n de dominio)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kinsta.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sistema de Nombres de Dominio\",\"item\":\"https:\/\/kinsta.com\/es\/secciones\/sistema-nombre-de-dominio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfQu\u00e9 Son Las Extensiones de Dominio? (Y C\u00f3mo Elegir una Extensi\u00f3n de Dominio)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kinsta.com\/es\/#website\",\"url\":\"https:\/\/kinsta.com\/es\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Soluciones de alojamiento premium, r\u00e1pidas y seguras\",\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kinsta.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kinsta.com\/es\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kinsta.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kinsta.es\/\",\"https:\/\/x.com\/Kinsta_ES\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/person\/4eee42881d7b5a73ebb4f58dd5223b21\",\"name\":\"Jeremy Holcombe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e17001f3bb37dbbe54fceef9bb547fa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e17001f3bb37dbbe54fceef9bb547fa?s=96&d=mm&r=g\",\"caption\":\"Jeremy Holcombe\"},\"description\":\"Senior Editor at Kinsta, WordPress Web Developer, and Content Writer. Outside of all things WordPress, I enjoy the beach, golf, and movies. I also have tall people problems.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/jeremyholcombe\/\"],\"url\":\"https:\/\/kinsta.com\/es\/blog\/author\/jeremyholcombe\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 Son Las Extensiones de Dominio? (Y C\u00f3mo Elegir una Extensi\u00f3n de Dominio)","description":"Aprende sobre las extensiones de dominio y c\u00f3mo elegir la correcta para tu negocio de entre todas las disponibles en la actualidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 Son Las Extensiones de Dominio? (Y C\u00f3mo Elegir una Extensi\u00f3n de Dominio)","og_description":"Aprende sobre las extensiones de dominio y c\u00f3mo elegir la correcta para tu negocio de entre todas las disponibles en la actualidad.","og_url":"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/kinsta.es\/","article_published_time":"2021-12-30T10:09:54+00:00","article_modified_time":"2023-08-21T09:06:26+00:00","og_image":[{"width":1460,"height":730,"url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/domain-extensions.png","type":"image\/png"}],"author":"Jeremy Holcombe","twitter_card":"summary_large_image","twitter_description":"Aprende sobre las extensiones de dominio y c\u00f3mo elegir la correcta para tu negocio de entre todas las disponibles en la actualidad.","twitter_image":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/domain-extensions.png","twitter_creator":"@Kinsta_ES","twitter_site":"@Kinsta_ES","twitter_misc":{"Escrito por":"Jeremy Holcombe","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#article","isPartOf":{"@id":"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/"},"author":{"name":"Jeremy Holcombe","@id":"https:\/\/kinsta.com\/es\/#\/schema\/person\/4eee42881d7b5a73ebb4f58dd5223b21"},"headline":"\u00bfQu\u00e9 Son Las Extensiones de Dominio? (Y C\u00f3mo Elegir una Extensi\u00f3n de Dominio)","datePublished":"2021-12-30T10:09:54+00:00","dateModified":"2023-08-21T09:06:26+00:00","mainEntityOfPage":{"@id":"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/"},"wordCount":3397,"commentCount":0,"publisher":{"@id":"https:\/\/kinsta.com\/es\/#organization"},"image":{"@id":"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/domain-extensions.png","keywords":["business","domains"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/","url":"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/","name":"\u00bfQu\u00e9 Son Las Extensiones de Dominio? (Y C\u00f3mo Elegir una Extensi\u00f3n de Dominio)","isPartOf":{"@id":"https:\/\/kinsta.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#primaryimage"},"image":{"@id":"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/domain-extensions.png","datePublished":"2021-12-30T10:09:54+00:00","dateModified":"2023-08-21T09:06:26+00:00","description":"Aprende sobre las extensiones de dominio y c\u00f3mo elegir la correcta para tu negocio de entre todas las disponibles en la actualidad.","breadcrumb":{"@id":"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#primaryimage","url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/domain-extensions.png","contentUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/domain-extensions.png","width":1460,"height":730,"caption":"\u00bfQu\u00e9 son las extensiones de dominio? (Y c\u00f3mo elegir una extensi\u00f3n de dominio)"},{"@type":"BreadcrumbList","@id":"https:\/\/kinsta.com\/es\/blog\/extensiones-de-dominio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kinsta.com\/es\/"},{"@type":"ListItem","position":2,"name":"Sistema de Nombres de Dominio","item":"https:\/\/kinsta.com\/es\/secciones\/sistema-nombre-de-dominio\/"},{"@type":"ListItem","position":3,"name":"\u00bfQu\u00e9 Son Las Extensiones de Dominio? (Y C\u00f3mo Elegir una Extensi\u00f3n de Dominio)"}]},{"@type":"WebSite","@id":"https:\/\/kinsta.com\/es\/#website","url":"https:\/\/kinsta.com\/es\/","name":"Kinsta\u00ae","description":"Soluciones de alojamiento premium, r\u00e1pidas y seguras","publisher":{"@id":"https:\/\/kinsta.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinsta.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kinsta.com\/es\/#organization","name":"Kinsta","url":"https:\/\/kinsta.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kinsta.es\/","https:\/\/x.com\/Kinsta_ES","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kinsta.com\/es\/#\/schema\/person\/4eee42881d7b5a73ebb4f58dd5223b21","name":"Jeremy Holcombe","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kinsta.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0e17001f3bb37dbbe54fceef9bb547fa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e17001f3bb37dbbe54fceef9bb547fa?s=96&d=mm&r=g","caption":"Jeremy Holcombe"},"description":"Senior Editor at Kinsta, WordPress Web Developer, and Content Writer. Outside of all things WordPress, I enjoy the beach, golf, and movies. I also have tall people problems.","sameAs":["https:\/\/www.linkedin.com\/in\/jeremyholcombe\/"],"url":"https:\/\/kinsta.com\/es\/blog\/author\/jeremyholcombe\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts\/46418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/users\/199"}],"replies":[{"embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/comments?post=46418"}],"version-history":[{"count":8,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts\/46418\/revisions"}],"predecessor-version":[{"id":69236,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts\/46418\/revisions\/69236"}],"alternate":[{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/46418\/translations\/en"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/46418\/translations\/de"},{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/46418\/translations\/es"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/46418\/translations\/pt"},{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/46418\/translations\/it"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/46418\/translations\/fr"},{"embeddable":true,"hreflang":"nl","title":"Dutch","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/46418\/translations\/nl"},{"embeddable":true,"hreflang":"ja","title":"Japanese","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/46418\/translations\/jp"},{"href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/46418\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/media\/46419"}],"wp:attachment":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/media?parent=46418"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/tags?post=46418"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/topic?post=46418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}