{"id":69838,"date":"2023-09-05T15:32:58","date_gmt":"2023-09-05T13:32:58","guid":{"rendered":"https:\/\/kinsta.com\/es\/?p=69838&#038;preview=true&#038;preview_id=69838"},"modified":"2023-09-11T09:52:28","modified_gmt":"2023-09-11T07:52:28","slug":"volumenes-docker-compose","status":"publish","type":"post","link":"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/","title":{"rendered":"Utiliza Vol\u00famenes para Gestionar Datos Persistentes con Docker Compose"},"content":{"rendered":"<p>Docker Compose es una potente herramienta de orquestaci\u00f3n dise\u00f1ada para simplificar la gesti\u00f3n y el despliegue de aplicaciones multicontenedor mediante <a href=\"https:\/\/kinsta.com\/es\/blog\/que-es-docker\/\">Docker.<\/a> El archivo <strong>docker-compose.yml <\/strong>agiliza el despliegue definiendo aplicaciones complejas con m\u00faltiples servicios, redes y vol\u00famenes en un solo archivo. Uno de los aspectos esenciales del trabajo con Docker Compose es la gesti\u00f3n de datos persistentes mediante vol\u00famenes.<\/p>\n<p>Este art\u00edculo explora la importancia de utilizar vol\u00famenes en Docker Compose para gestionar datos persistentes y proporciona una gu\u00eda pr\u00e1ctica para utilizar vol\u00famenes de forma eficaz.<\/p>\n<div><\/div><kinsta-auto-toc heading=\"Table of Contents\" exclude=\"last\" list-style=\"arrow\" selector=\"h2\" count-number=\"-1\"><\/kinsta-auto-toc>\n<h2>\u00bfQu\u00e9 Son los Vol\u00famenes Docker?<\/h2>\n<p>Los vol\u00famenes Docker son un componente crucial del ecosistema que almacena y gestiona datos persistentes generados por contenedores ef\u00edmeros. Permiten que los datos persistan incluso despu\u00e9s de eliminar o actualizar un contenedor, de modo que los datos esenciales de la aplicaci\u00f3n no se pierdan durante las operaciones rutinarias.<\/p>\n<p>Los vol\u00famenes est\u00e1n desacoplados del sistema de archivos del contenedor, por lo que puedes hacer f\u00e1cilmente copias de seguridad de ellos, compartirlos entre varios contenedores y migrarlos entre hosts.<\/p>\n<p>Una ventaja clave del uso de vol\u00famenes en lugar de montajes vinculados (bind mounts), que son montajes de directorios desde el sistema host a un contenedor, es la portabilidad. Puedes trasladar vol\u00famenes r\u00e1pidamente entre diferentes hosts o contenedores, pero debes vincular los montajes vinculados a un directorio espec\u00edfico en el sistema host.<\/p>\n<p>Esta portabilidad permite una gesti\u00f3n de datos m\u00e1s flexible y eficaz en las <a href=\"https:\/\/kinsta.com\/es\/blog\/almacenamiento-persistente\/\">aplicaciones basadas en contenedores<\/a>. Los vol\u00famenes tambi\u00e9n son compatibles con varios controladores de almacenamiento, lo que te permite elegir la mejor soluci\u00f3n de almacenamiento para tu caso de uso espec\u00edfico.<\/p>\n<h2>Tipos de Vol\u00famenes Docker<\/h2>\n<p>Los vol\u00famenes Docker son esenciales para gestionar datos en aplicaciones basadas en contenedores. Existen dos tipos distintos: <em>vol\u00famenes nombrados<\/em>\u00a0y <em>vol\u00famenes an\u00f3nimos<\/em>. Esta secci\u00f3n profundiza en las diferencias clave entre ambos tipos y demuestra c\u00f3mo implementarlos para gestionar los datos en tus aplicaciones.<\/p>\n<p>Los vol\u00famenes nombrados y an\u00f3nimos sirven para prop\u00f3sitos diferentes y ofrecen distintas capacidades de control y gesti\u00f3n. Aunque los vol\u00famenes nombrados suelen ser preferibles para la mayor\u00eda de los casos de uso debido a sus identificadores legibles por humanos y a su facilidad de gesti\u00f3n, es esencial entender c\u00f3mo funcionan ambos tipos para maximizar sus ventajas.<\/p>\n<h3>Vol\u00famenes Nombrados<\/h3>\n<p>Los vol\u00famenes nombrados tienen un nombre definido por el usuario, lo que facilita su identificaci\u00f3n, gesti\u00f3n y uso compartido entre varios contenedores. Docker crea y gestiona vol\u00famenes nombrados y almacena sus datos en una ubicaci\u00f3n espec\u00edfica del sistema host. Esta ubicaci\u00f3n suele estar dentro del directorio de instalaci\u00f3n de Docker, bajo un ID \u00fanico correspondiente al nombre del volumen.<\/p>\n<p>Los vol\u00famenes nombrados ofrecen mayor control y flexibilidad, ya que puedes referenciarlos y manipularlos f\u00e1cilmente utilizando su identificador legible por humanos.<\/p>\n<p>Para crear un volumen nombrados en Docker, ejecuta:<\/p>\n<pre><code class=\"language-bash\">docker volume create my_named_volume<\/code><\/pre>\n<h3>Vol\u00famenes An\u00f3nimos<\/h3>\n<p>A diferencia de los vol\u00famenes nombrados, los vol\u00famenes an\u00f3nimos no tienen un nombre definido por el usuario. En su lugar, Docker los crea autom\u00e1ticamente cuando creas un contenedor y asigna un ID \u00fanico al volumen.<\/p>\n<p>Por lo general, es m\u00e1s dif\u00edcil gestionar y almacenar vol\u00famenes debido a que carecen de un identificador legible por humanos. Como Docker los crea autom\u00e1ticamente, es habitual utilizar vol\u00famenes an\u00f3nimos para el almacenamiento temporal. Tambi\u00e9n pueden aparecer si no especificas un volumen con nombre al crear un contenedor.<\/p>\n<p>Para crear un contenedor con un volumen an\u00f3nimo, ejecuta:<\/p>\n<pre><code class=\"language-bash\">docker run -v \/data nginx<\/code><\/pre>\n<p>Este comando monta un volumen an\u00f3nimo en el directorio <strong>\/data<\/strong> dentro del contenedor <code>nginx<\/code>. Puedes sustituir <code>nginx<\/code> por el nombre del contenedor en el que vas a montar el volumen.<\/p>\n<h2>C\u00f3mo Crear y Gestionar Vol\u00famenes con Docker Compose<\/h2>\n<p><a href=\"https:\/\/kinsta.com\/es\/blog\/que-es-docker\/\">Docker Compose<\/a> simplifica la creaci\u00f3n y gesti\u00f3n de vol\u00famenes permiti\u00e9ndote definirlos dentro del archivo <strong>docker-compose.yml<\/strong>. Este archivo contiene la configuraci\u00f3n de los servicios, redes y vol\u00famenes de tu aplicaci\u00f3n, lo que permite gestionar f\u00e1cilmente los recursos de tu aplicaci\u00f3n en un solo lugar.<\/p>\n<h3>1. Definir Vol\u00famenes en Docker Compose<\/h3>\n<p>Para crear un volumen nombrado en el archivo <strong>docker-compose.yml<\/strong>, def\u00ednelo bajo la clave <code>volumes<\/code>. Tambi\u00e9n puedes especificar el controlador de volumen y las opciones si es necesario.<\/p>\n<h3>2. Montar Vol\u00famenes en Contenedores<\/h3>\n<p>Para montar un volumen en un contenedor, utiliza la clave <code>volumes<\/code> dentro de la definici\u00f3n <code>service<\/code> en el archivo <strong>docker-compose.yml<\/strong>. Especifica el nombre del volumen seguido de dos puntos y la ruta del contenedor donde quieres montar el volumen.<\/p>\n<p>Tambi\u00e9n puedes compartir vol\u00famenes entre varios contenedores utilizando el mismo nombre de volumen.<\/p>\n<p>Aqu\u00ed tienes un ejemplo de creaci\u00f3n de vol\u00famenes nombrados llamados <code>web_data<\/code> y <code>db_data<\/code> en tu archivo docker-compose <strong>.yml<\/strong>:<\/p>\n<pre><code class=\"language-yaml\">version: '3.8'\nservices:\n  web:\n    image: nginx\n    volumes:\n      - web_data:\/var\/www\/html\n  web-test:\n    image: nginx\n    volumes:\n      - web_data:\/var\/www\/html # Web and web test share the web_data volume\n  db:\n    image: mysql\n    volumes:\n      - db_data:\/var\/lib\/mysql\nvolumes:\n  web_data:\n  db_data:\n    driver: local # Define the driver and options under the volume name\n    driver_opts:\n      type: none\n      device: \/data\/db_data\n      o: bind<\/code><\/pre>\n<p>Este ejemplo define dos vol\u00famenes nombrados. A continuaci\u00f3n, monta los vol\u00famenes en sus respectivos contenedores bajo rutas espec\u00edficas. A continuaci\u00f3n, monta el volumen <code>web_data<\/code> en el directorio <strong>\/var\/www\/html<\/strong> del contenedor web y el volumen <code>db_data<\/code> en el directorio <strong>\/var\/lib\/mysql<\/strong> del contenedor <code>db<\/code>.<\/p>\n<p>Los contenedores <code>web<\/code> y <code>web-test<\/code> comparten el volumen <code>web_data<\/code>, lo que les permite acceder y modificar el mismo volumen de datos.<\/p>\n<p>Al definir y gestionar los vol\u00famenes dentro del archivo <strong>docker-compose.yml<\/strong>, puedes crear, actualizar y eliminar vol\u00famenes f\u00e1cilmente, seg\u00fan sea necesario, sin tener que gestionarlos manualmente mediante comandos Docker. Este proceso simplificado te permite centrarte en desarrollar y desplegar tu aplicaci\u00f3n mientras Docker Compose se encarga de la gesti\u00f3n de los recursos subyacentes.<\/p>\n<h2>C\u00f3mo Trabajar con Docker Compose y los Comandos de Volumen<\/h2>\n<p>Docker Compose proporciona varios comandos que te ayudan a gestionar eficazmente tu aplicaci\u00f3n y sus recursos. Revisemos estos comandos y c\u00f3mo se relacionan con los vol\u00famenes con m\u00e1s detalle:<\/p>\n<ul>\n<li><code>docker compose up<\/code> crea e inicia tu aplicaci\u00f3n, incluidos sus servicios, redes y vol\u00famenes. Si defines un volumen nombrado en el archivo <strong>docker-compose.yml<\/strong> antes de que exista, este comando lo crear\u00e1 autom\u00e1ticamente.<\/li>\n<li><code>docker compose down<\/code> detiene y elimina los servicios y redes de tu aplicaci\u00f3n. Por defecto, no elimina los vol\u00famenes nombrados. Para eliminar vol\u00famenes nombrados, utiliza la bandera <code>--volumes<\/code> o <code>-v<\/code>.<\/li>\n<li><code>docker compose ps<\/code> lista los contenedores y su estado actual, incluyendo la informaci\u00f3n relacionada con los vol\u00famenes.<\/li>\n<li><code>docker compose config<\/code> valida y muestra la configuraci\u00f3n efectiva generada a partir del archivo <strong>docker-compose.yml<\/strong>, incluidas las definiciones de volumen.<\/li>\n<\/ul>\n<h3>Listar Vol\u00famenes<\/h3>\n<p>Para listar todos los vol\u00famenes, utiliza <code>ls<\/code>:<\/p>\n<pre><code class=\"language-bash\">docker volume ls<\/code><\/pre>\n<p>El resultado muestra todos los vol\u00famenes nombrados, incluidos los creados por Docker Compose.<\/p>\n<h3>Inspeccionar Vol\u00famenes<\/h3>\n<p>Para ver los detalles de un volumen concreto, utiliza <code>inspect <\/code>. Muestra informaci\u00f3n sobre el volumen, como su nombre, controlador, punto de montaje y opciones:<\/p>\n<pre><code class=\"language-bash\">docker volume inspect db_data<\/code><\/pre>\n<p>Los detalles del volumen se dan en formato JSON. Por ejemplo, considerando el archivo <strong>docker-compose.yml<\/strong> proporcionado anteriormente, \u00e9sta es la salida devuelta:<\/p>\n<pre><code class=\"language-bash\">[\n    {\n        \"CreatedAt\": \"some-date-here\",\n        \"Driver\": \"local\",\n        \"Labels\": null,\n        \"Mountpoint\": \"\/path\/on\/host\/where\/volume\/is\/mounted\",\n        \"Name\": \"db_data\",\n        \"Options\": {\n            \"device\": \"\/data\/db_data\",\n            \"o\": \"bind\",\n            \"type\": \"none\"\n        },\n        \"Scope\": \"local\",\n        \"Status\": {\n            \"Mounts\": [\n                ...\n            ]\n        }\n    }\n]<\/code><\/pre>\n<h3>Eliminar un Volumen Docker por Nombre<\/h3>\n<p>Para eliminar un volumen Docker, puedes utilizar <code>docker volume rm<\/code> seguido del nombre del volumen:<\/p>\n<pre><code class=\"language-bash\">docker volume rm volume-name<\/code><\/pre>\n<h3>Limpiar Vol\u00famenes No Utilizados<\/h3>\n<p>Para <a href=\"https:\/\/kinsta.com\/es\/blog\/eliminar-imagenes-docker\/\">eliminar vol\u00famenes no utilizados<\/a>, utiliza <code>prune<\/code>:<\/p>\n<pre><code class=\"language-bash\">docker volume prune<\/code><\/pre>\n<p>Este comando ayuda a limpiar tu entorno de desarrollo y a recuperar espacio de almacenamiento. Elimina todos los vol\u00famenes no utilizados que no est\u00e9n asociados a contenedores, incluidos los que crea Docker Compose.<\/p>\n<p>Aprovechando estos comandos y sus funciones relacionadas con el volumen, puedes gestionar eficazmente los recursos de tu aplicaci\u00f3n, garantizando un rendimiento \u00f3ptimo y un uso eficiente del espacio de almacenamiento.<\/p>\n<h3>Versiones de Docker Compose<\/h3>\n<p>Desde julio de 2023, <a href=\"https:\/\/docs.docker.com\/compose\/compose-v2\/\" target=\"_blank\" rel=\"noopener noreferrer\">Docker Compose V1 ha dejado de recibir actualizaciones<\/a>. Tampoco est\u00e1 ya disponible en las nuevas versiones de Docker Desktop. Sin embargo, Docker Desktop sigue admitiendo un alias <code>docker-compose<\/code> para redirigir comandos a <code>docker compose<\/code> por comodidad y para mejorar la compatibilidad con herramientas y scripts de terceros.<\/p>\n<p>Para cambiar cualquier c\u00f3digo existente de la versi\u00f3n 1 a la 2 de Docker Compose, simplemente sustituye el gui\u00f3n por un espacio. Por ejemplo, <code>docker-compose up<\/code> se convierte en <code>docker compose up<\/code>.<\/p>\n<p>Con la versi\u00f3n 2, puedes utilizar el comando &#038;<code>compose<\/code> directamente en la interfaz de l\u00ednea de comandos (CLI) de Docker, cambiar el contexto de Docker para crear un contenedor en un servicio en la nube y utilizar Amazon ECS y Microsoft ACI.<\/p>\n<h2>Resumen<\/h2>\n<p>Este art\u00edculo ha destacado la importancia de utilizar vol\u00famenes con Docker Compose para gestionar datos persistentes. Los vol\u00famenes son un componente crucial en el ecosistema Docker, ya que te permiten almacenar y gestionar los datos que generan los contenedores Docker. Con los vol\u00famenes Docker, los datos importantes de la aplicaci\u00f3n persisten incluso despu\u00e9s de eliminar o actualizar un contenedor, ayudando a mantener la integridad y consistencia de tu aplicaci\u00f3n.<\/p>\n<p>Docker Compose ofrece un m\u00e9todo simplificado para crear y gestionar vol\u00famenes dentro del archivo <strong>docker-compose.yml<\/strong>. Este m\u00e9todo simplifica tu proceso de desarrollo y garantiza un uso eficiente de los recursos.<\/p>\n<p>El uso de vol\u00famenes tambi\u00e9n hace que el desarrollo sea flexible y eficiente, ya que Docker Compose proporciona varios comandos relacionados con los vol\u00famenes para ayudarte a supervisar los recursos de la aplicaci\u00f3n con eficacia. Aprovechar estos comandos te permite crear, inspeccionar y limpiar vol\u00famenes f\u00e1cilmente.<\/p>\n<p>Cuando <a href=\"https:\/\/sevalla.com\/application-hosting\/\">alojas tu aplicaci\u00f3n<\/a> con Kinsta, dispones de una infraestructura r\u00e1pida, segura y fiable, con tus proyectos desplegados en la Red de Nivel Premium de Google Cloud Platform y en m\u00e1quinas C2. Elige entre los 28 centros de datos\u00a0 y una CDN habilitada para HTTP\/3 con 300 PoPs.<\/p>\n<p>Mantente seguro con la tecnolog\u00eda de contenedores aislados, dos potentes cortafuegos y la protecci\u00f3n DDoS avanzada de Cloudflare. Tambi\u00e9n puedes integrar aplicaciones o automatizar flujos de trabajo con la <a href=\"https:\/\/kinsta.com\/es\/docs\/api-kinsta\/\">API de Kinsta<\/a> y desplegarlas con Docker.<\/p>\n<p>Kinsta proporciona recursos y contenidos de alta calidad para desarrolladores web, incluyendo tutoriales y gu\u00edas en profundidad para varios lenguajes y herramientas como Docker Compose. Lee nuestro <a href=\"https:\/\/kinsta.com\/es\/secciones\/docker\/\">contenido espec\u00edfico sobre Docker<\/a> en el blog de Kinsta para saber m\u00e1s sobre Docker.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Docker Compose es una potente herramienta de orquestaci\u00f3n dise\u00f1ada para simplificar la gesti\u00f3n y el despliegue de aplicaciones multicontenedor mediante Docker. El archivo docker-compose.yml agiliza el &#8230;<\/p>\n","protected":false},"author":290,"featured_media":69839,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[],"topic":[1282],"class_list":["post-69838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","topic-docker"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Uso de Vol\u00famenes para Gestionar Datos Persistentes con Docker Compose - Kinsta\u00ae<\/title>\n<meta name=\"description\" content=\"Conoce la importancia del uso de vol\u00famenes en Docker Compose para manejar datos persistentes y para usar vol\u00famenes de forma efectiva.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Utiliza Vol\u00famenes para Gestionar Datos Persistentes con Docker Compose\" \/>\n<meta property=\"og:description\" content=\"Conoce la importancia del uso de vol\u00famenes en Docker Compose para manejar datos persistentes y para usar vol\u00famenes de forma efectiva.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kinsta.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-05T13:32:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-11T07:52:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/09\/docker-compose-volumes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"6084\" \/>\n\t<meta property=\"og:image:height\" content=\"3042\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcia Ramos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Conoce la importancia del uso de vol\u00famenes en Docker Compose para manejar datos persistentes y para usar vol\u00famenes de forma efectiva.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/09\/docker-compose-volumes.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@Kinsta_ES\" \/>\n<meta name=\"twitter:site\" content=\"@Kinsta_ES\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcia Ramos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/\"},\"author\":{\"name\":\"Marcia Ramos\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/person\/72bff0015d3fb3ba3d8a85494dc0b116\"},\"headline\":\"Utiliza Vol\u00famenes para Gestionar Datos Persistentes con Docker Compose\",\"datePublished\":\"2023-09-05T13:32:58+00:00\",\"dateModified\":\"2023-09-11T07:52:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/\"},\"wordCount\":1690,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/09\/docker-compose-volumes.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/\",\"url\":\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/\",\"name\":\"Uso de Vol\u00famenes para Gestionar Datos Persistentes con Docker Compose - Kinsta\u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/09\/docker-compose-volumes.jpg\",\"datePublished\":\"2023-09-05T13:32:58+00:00\",\"dateModified\":\"2023-09-11T07:52:28+00:00\",\"description\":\"Conoce la importancia del uso de vol\u00famenes en Docker Compose para manejar datos persistentes y para usar vol\u00famenes de forma efectiva.\",\"breadcrumb\":{\"@id\":\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#primaryimage\",\"url\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/09\/docker-compose-volumes.jpg\",\"contentUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/09\/docker-compose-volumes.jpg\",\"width\":6084,\"height\":3042},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kinsta.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docker\",\"item\":\"https:\/\/kinsta.com\/es\/secciones\/docker\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Utiliza Vol\u00famenes para Gestionar Datos Persistentes con Docker Compose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kinsta.com\/es\/#website\",\"url\":\"https:\/\/kinsta.com\/es\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Soluciones de alojamiento premium, r\u00e1pidas y seguras\",\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kinsta.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kinsta.com\/es\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kinsta.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kinsta.es\/\",\"https:\/\/x.com\/Kinsta_ES\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/person\/72bff0015d3fb3ba3d8a85494dc0b116\",\"name\":\"Marcia Ramos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kinsta.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0d680db24858fdf61a7e7ce3c1a160f5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0d680db24858fdf61a7e7ce3c1a160f5?s=96&d=mm&r=g\",\"caption\":\"Marcia Ramos\"},\"description\":\"I'm the Editorial Team Lead at Kinsta. I'm a open source enthusiast and I love coding. With more than 10 years of technical writing and editing for the tech industry, I love collaborating with people to create clear and concise pieces of content and improve workflows.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/marciadiasramos\/\"],\"honorificSuffix\":\"B.Sc.\",\"gender\":\"Female\",\"knowsLanguage\":[\"English\",\"Portuguese\"],\"jobTitle\":\"Editorial Team Lead\",\"worksFor\":\"Kinsta Inc.\",\"url\":\"https:\/\/kinsta.com\/es\/blog\/author\/marciaramos\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Uso de Vol\u00famenes para Gestionar Datos Persistentes con Docker Compose - Kinsta\u00ae","description":"Conoce la importancia del uso de vol\u00famenes en Docker Compose para manejar datos persistentes y para usar vol\u00famenes de forma efectiva.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/","og_locale":"es_ES","og_type":"article","og_title":"Utiliza Vol\u00famenes para Gestionar Datos Persistentes con Docker Compose","og_description":"Conoce la importancia del uso de vol\u00famenes en Docker Compose para manejar datos persistentes y para usar vol\u00famenes de forma efectiva.","og_url":"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/kinsta.es\/","article_published_time":"2023-09-05T13:32:58+00:00","article_modified_time":"2023-09-11T07:52:28+00:00","og_image":[{"width":6084,"height":3042,"url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/09\/docker-compose-volumes.jpg","type":"image\/jpeg"}],"author":"Marcia Ramos","twitter_card":"summary_large_image","twitter_description":"Conoce la importancia del uso de vol\u00famenes en Docker Compose para manejar datos persistentes y para usar vol\u00famenes de forma efectiva.","twitter_image":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/09\/docker-compose-volumes.jpg","twitter_creator":"@Kinsta_ES","twitter_site":"@Kinsta_ES","twitter_misc":{"Escrito por":"Marcia Ramos","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#article","isPartOf":{"@id":"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/"},"author":{"name":"Marcia Ramos","@id":"https:\/\/kinsta.com\/es\/#\/schema\/person\/72bff0015d3fb3ba3d8a85494dc0b116"},"headline":"Utiliza Vol\u00famenes para Gestionar Datos Persistentes con Docker Compose","datePublished":"2023-09-05T13:32:58+00:00","dateModified":"2023-09-11T07:52:28+00:00","mainEntityOfPage":{"@id":"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/"},"wordCount":1690,"commentCount":0,"publisher":{"@id":"https:\/\/kinsta.com\/es\/#organization"},"image":{"@id":"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/09\/docker-compose-volumes.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/","url":"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/","name":"Uso de Vol\u00famenes para Gestionar Datos Persistentes con Docker Compose - Kinsta\u00ae","isPartOf":{"@id":"https:\/\/kinsta.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#primaryimage"},"image":{"@id":"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/09\/docker-compose-volumes.jpg","datePublished":"2023-09-05T13:32:58+00:00","dateModified":"2023-09-11T07:52:28+00:00","description":"Conoce la importancia del uso de vol\u00famenes en Docker Compose para manejar datos persistentes y para usar vol\u00famenes de forma efectiva.","breadcrumb":{"@id":"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#primaryimage","url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/09\/docker-compose-volumes.jpg","contentUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/09\/docker-compose-volumes.jpg","width":6084,"height":3042},{"@type":"BreadcrumbList","@id":"https:\/\/kinsta.com\/es\/blog\/volumenes-docker-compose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kinsta.com\/es\/"},{"@type":"ListItem","position":2,"name":"Docker","item":"https:\/\/kinsta.com\/es\/secciones\/docker\/"},{"@type":"ListItem","position":3,"name":"Utiliza Vol\u00famenes para Gestionar Datos Persistentes con Docker Compose"}]},{"@type":"WebSite","@id":"https:\/\/kinsta.com\/es\/#website","url":"https:\/\/kinsta.com\/es\/","name":"Kinsta\u00ae","description":"Soluciones de alojamiento premium, r\u00e1pidas y seguras","publisher":{"@id":"https:\/\/kinsta.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinsta.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kinsta.com\/es\/#organization","name":"Kinsta","url":"https:\/\/kinsta.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kinsta.com\/es\/wp-content\/uploads\/sites\/8\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kinsta.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kinsta.es\/","https:\/\/x.com\/Kinsta_ES","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kinsta.com\/es\/#\/schema\/person\/72bff0015d3fb3ba3d8a85494dc0b116","name":"Marcia Ramos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kinsta.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0d680db24858fdf61a7e7ce3c1a160f5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d680db24858fdf61a7e7ce3c1a160f5?s=96&d=mm&r=g","caption":"Marcia Ramos"},"description":"I'm the Editorial Team Lead at Kinsta. I'm a open source enthusiast and I love coding. With more than 10 years of technical writing and editing for the tech industry, I love collaborating with people to create clear and concise pieces of content and improve workflows.","sameAs":["https:\/\/www.linkedin.com\/in\/marciadiasramos\/"],"honorificSuffix":"B.Sc.","gender":"Female","knowsLanguage":["English","Portuguese"],"jobTitle":"Editorial Team Lead","worksFor":"Kinsta Inc.","url":"https:\/\/kinsta.com\/es\/blog\/author\/marciaramos\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts\/69838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/users\/290"}],"replies":[{"embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/comments?post=69838"}],"version-history":[{"count":5,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts\/69838\/revisions"}],"predecessor-version":[{"id":69891,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/posts\/69838\/revisions\/69891"}],"alternate":[{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/69838\/translations\/en"},{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/69838\/translations\/it"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/69838\/translations\/pt"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/69838\/translations\/fr"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/69838\/translations\/de"},{"embeddable":true,"hreflang":"ja","title":"Japanese","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/69838\/translations\/jp"},{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/69838\/translations\/es"},{"href":"https:\/\/kinsta.com\/es\/wp-json\/kinsta\/v1\/posts\/69838\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/media\/69839"}],"wp:attachment":[{"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/media?parent=69838"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/tags?post=69838"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kinsta.com\/es\/wp-json\/wp\/v2\/topic?post=69838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}