{"id":21032,"date":"2018-06-19T07:49:06","date_gmt":"2018-06-19T14:49:06","guid":{"rendered":"https:\/\/kinsta.com\/?p=23366"},"modified":"2025-01-21T10:58:03","modified_gmt":"2025-01-21T09:58:03","slug":"spazio-su-disco-hosting-wordpress","status":"publish","type":"post","link":"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/","title":{"rendered":"Di quanto spazio su disco ha davvero bisogno un piano di hosting?"},"content":{"rendered":"<p>Quando si \u00e8 alla ricerca di un piano <a href=\"https:\/\/kinsta.com\/it\/hosting-wordpress\/\">hosting per WordPress<\/a>, <strong>pu\u00f2 esserci una notevole differenza tra lo spazio che credete sia necessario e quello che occorre davvero<\/strong>. Abbiamo riscontrato che in molti casi gli utenti di WordPress sovrastimino esageratamente la quantit\u00e0 di spazio che gli \u00e8 necessaria, e questo pu\u00f2 influire negativamente sulle decisioni di acquisto. Oggi analizzeremo alcune soluzioni per valutare meglio le reali esigenze di spazio su disco e alcuni modi per individuare l&#8217;utilizzo corrente del disco. Inoltre, condivideremo con voi alcuni esempi pratici che potranno aiutarvi a scegliere il piano hosting pi\u00f9 adatto alle vostre esigenze.<\/p>\n<p><div><\/div><kinsta-auto-toc heading=\"Table of Contents\" exclude=\"last\" list-style=\"arrow\" selector=\"h2\" count-number=\"-1\"><\/kinsta-auto-toc><br \/>\n<kinsta-video src=\"https:\/\/www.youtube.com\/watch?v=un_EI_WqVzY\"><\/kinsta-video><\/p>\n<h2 id=\"quanto-spazio-su-disco-serve\">Quanto Spazio su Disco vi Serve?<\/h2>\n<p>Diamo una rapida occhiata allo <a href=\"https:\/\/kinsta.com\/it\/blog\/utilizzo-disco-wordpress\/\">spazio totale del disco<\/a> rispetto al numero di siti offerti su ciascuno dei <a href=\"https:\/\/kinsta.com\/it\/prezzi\/\">piani di hosting WordPress<\/a> di Kinsta. A tutti i nostri piani sono state assegnate risorse e limiti in base all&#8217;utilizzo medio di spazio su disco che osserviamo nei nostri clienti (sia piccoli che grandi). Questi dati sono stati raccolti nel corso degli anni da migliaia di clienti.<\/p>\n<h3>I nostri piani di hosting<\/h3>\n<ul>\n<li>Piano Single 35k: 10 GB e 1 sito WordPress<\/li>\n<li>Piano WP 2: 20 GB e 2 siti WordPress<\/li>\n<li>Piano WP 5:\u00a030 GB e 5 siti WordPress<\/li>\n<li>Piano WP 10: 40 GB e 10 siti WordPress<\/li>\n<li>Piano WP 20: 50 GB e 20 siti WordPress<\/li>\n<li>Piano WP 40: 60 GB e 40 siti WordPress<\/li>\n<li>Piano WP 60: 100 GB e 60 siti WordPress<\/li>\n<li>Piano WP 80: 150 GB e 80 siti WordPress<\/li>\n<li>Piano WP 120: 200 GB e 120 siti WordPress<\/li>\n<li>Piano WP 150: 250 GB e 150 siti WordPress<\/li>\n<\/ul>\n<h3>Utilizzo medio dei siti WordPress<\/h3>\n<p>Ma facciamo qualche calcolo sull&#8217;utilizzo medio effettivo del disco da parte di un sito WordPress. I dati che seguono rappresentano un utilizzo medio dello spazio su disco tratto da un campione di siti WordPress di produzione in attivit\u00e0 da oltre 4 anni.<\/p>\n<ul>\n<li>Core WordPress core: 8.9 MB (4.9.5+)<\/li>\n<li>Media directory dei plugin (<code>\/wp-content\/plugins<\/code>): 100 MB<\/li>\n<li>Media directory dei temi (<code>\/wp-content\/themes<\/code>): 25 MB<\/li>\n<li>Media directory uploads (<code>\/wp-content\/uploads<\/code>): 825 MB<\/li>\n<li>Media database MySQL: 85 MB<\/li>\n<\/ul>\n<p>In media, abbiamo rilevato che il cliente tipico ha approssimativamente <strong>1 GB di dati per una singola installazione di WordPress<\/strong>. A volte la quantit\u00e0 di spazio utilizzata pu\u00f2 oscillare in entrambe le direzioni. Alcuni potrebbero avere un database molto pi\u00f9 grande, ma un uso minore dei file, o viceversa. Quindi, nel nostro piano Single 35k, questo vi lascia altri <strong>\u00a09 GB (90%) di spazio libero su disco, a disposizione per la crescita del sito<\/strong>.<\/p>\n<h3>Esempi reali<\/h3>\n<p>Ma diamo un&#8217;occhiata ad alcuni esempi reali offerti da nostri clienti. I siti elencati di seguito sono tutti in produzione: blog, aziende e siti di e-commerce.<\/p>\n<h4>Cliente 1<\/h4>\n<p>Il primo cliente ha 11 siti WordPress e usa 4,04 GB dei 100 GB di spazio su disco disponibili. Sono ben al di sotto della media di Kinsta, <strong>utilizzando meno di 400 MB per sito<\/strong>.<\/p>\n<figure id=\"attachment_21061\" aria-describedby=\"caption-attachment-21061\" style=\"width: 1299px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21061\" src=\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-cliente-1-e1524003254218.png\" alt=\"Utilizzo disco cliente 1\" width=\"1299\" height=\"552\" srcset=\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-cliente-1-e1524003254218.png 1299w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-cliente-1-e1524003254218-300x127.png 300w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-cliente-1-e1524003254218-768x326.png 768w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-cliente-1-e1524003254218-1024x435.png 1024w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-cliente-1-e1524003254218-610x259.png 610w\" sizes=\"auto, (max-width: 1299px) 100vw, 1299px\" \/><figcaption id=\"caption-attachment-21061\" class=\"wp-caption-text\">Esempio di utilizzo disco (cliente 1)<\/figcaption><\/figure>\n<h4>Cliente 2<\/h4>\n<p>Il secondo cliente ha 3 siti WordPress e utilizza 3,3 GB di spazio su disco dei 20 GB disponibili. Sono praticamente <strong>alla pari con la media Kinsta di 1 GB per sito<\/strong>.<\/p>\n<figure id=\"attachment_21062\" aria-describedby=\"caption-attachment-21062\" style=\"width: 1299px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21062\" src=\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-esempio-2-e1524003254218.png\" alt=\"Utilizzo disco esempio 2\" width=\"1299\" height=\"613\" srcset=\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-esempio-2-e1524003254218.png 1299w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-esempio-2-e1524003254218-300x142.png 300w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-esempio-2-e1524003254218-768x362.png 768w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-esempio-2-e1524003254218-1024x483.png 1024w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-esempio-2-e1524003254218-610x288.png 610w\" sizes=\"auto, (max-width: 1299px) 100vw, 1299px\" \/><figcaption id=\"caption-attachment-21062\" class=\"wp-caption-text\">Esempio di utilizzo disco (cliente 2)<\/figcaption><\/figure>\n<h4>Cliente 3<\/h4>\n<p>Il terzo cliente ha 3 siti WordPress e utilizza 503,21 MB di spazio su disco dei 15 GB. Sono molto al di sotto della media di Kinsta, <strong>utilizzando meno di 200 MB per sito<\/strong>.<\/p>\n<figure id=\"attachment_21063\" aria-describedby=\"caption-attachment-21063\" style=\"width: 1299px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21063\" src=\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-esempio-3-e1524003254218.png\" alt=\"Utilizzo disco esempio 3\" width=\"1299\" height=\"607\" srcset=\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-esempio-3-e1524003254218.png 1299w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-esempio-3-e1524003254218-300x140.png 300w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-esempio-3-e1524003254218-768x359.png 768w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-esempio-3-e1524003254218-1024x478.png 1024w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-esempio-3-e1524003254218-610x285.png 610w\" sizes=\"auto, (max-width: 1299px) 100vw, 1299px\" \/><figcaption id=\"caption-attachment-21063\" class=\"wp-caption-text\">Esempio di utilizzo disco (cliente 3)<\/figcaption><\/figure>\n<p>Potremmo continuare a mostrarvi degli esempi, ma questi dati sono la norma per la maggior parte dei clienti di Kinsta. In effetti, facciamo un ulteriore passo avanti e offriamo queste possibilit\u00e0 aggiuntive per risparmiare spazio su disco:<\/p>\n<ul>\n<li>I siti di staging sono esclusi. <strong>Solo i siti live contano per il calcolo dell&#8217;utilizzo dello spazio su disco<\/strong>.<\/li>\n<li><strong>I backup sono esclusi<\/strong> dai nostri rapporti quando calcoliamo l&#8217;utilizzo totale dello spazio su disco. Il vostro utilizzo tiene conto solo dei file e del <a href=\"https:\/\/kinsta.com\/it\/blog\/database-wordpress\/\">database<\/a> del vostro sito live.<\/li>\n<\/ul>\n<h3>Eccezioni alla norma<\/h3>\n<p>Ora, naturalmente, ci sono sempre delle eccezioni alla norma. Quelli di voi che ospitano file video di grandi dimensioni, PDF o fotografie ad alta risoluzione, potrebbero facilmente trovarsi dall&#8217;altra parte dello spettro. Questo \u00e8 del tutto normale e abbiamo molti clienti che si trovano in questa situazione. Abbiamo due raccomandazioni per gli utenti che hanno poco spazio su disco &#8211; il nostro add-on nativo per lo spazio su disco o un offloading verso un fornitore di storage esterno.<\/p>\n<h4>1. Add-On Kinsta spazio su disco<\/h4>\n<p>La prima opzione \u00e8 l&#8217;acquisto di un componente aggiuntivo di spazio su disco direttamente dal cruscotto di MyKinsta. Offriamo spazio su disco aggiuntivo, incrementi di 20 GB per $20. <a href=\"https:\/\/kinsta.com\/it\/docs\/fatturazione\/piani-hosting-wordpress\/eccedenze\/\">Scegliere il nostro add-on spazio su disco nativo<\/a> ha diversi vantaggi.<\/p>\n<ul>\n<li>Non dovrete creare un account presso un provider di storage esterno come Amazon Web Services o Google Cloud Platform.<\/li>\n<li>Il nostro add-on per lo spazio su disco \u00e8 una soluzione nativa, il che significa che non dovrete installare e impostare un plugin WordPress per connettervi a un provider esterno.<\/li>\n<li>Il nostro add-on per lo spazio su disco \u00e8 compatibile al 100% con il <a href=\"https:\/\/kinsta.com\/it\/docs\/hosting-wordpress\/wordpress-cdn\/kinsta-cdn\/#kinstas-cdn\">CDN di Kinsta<\/a>. Non dovrete preoccuparvi di impostare un altro CDN per i supporti scaricati.<\/li>\n<li>La fatturazione e le statistiche di utilizzo del disco sono gestite attraverso MyKinsta. Questo rende facile tenere traccia dell&#8217;utilizzo dello spazio su disco aggiuntivo in un unico posto<\/li>\n<\/ul>\n<h4>2. Offloading verso un fornitore di storage esterno<\/h4>\n<p>La seconda opzione \u00e8 quella di <a href=\"https:\/\/kinsta.com\/it\/blog\/hosting-pdf-mp3\/\">scaricare i file di grandi dimensioni<\/a> per separare i servizi di storage come Amazon S3, Google Cloud Storage o soluzioni di streaming.<\/p>\n<p>Per offload non intendiamo usare un <a href=\"https:\/\/kinsta.com\/it\/blog\/cdn-per-wordpress\/\" target=\"_blank\" rel=\"noopener noreferrer\">CDN<\/a>, anche se potete combinare l&#8217;approccio che illustriamo di seguito con un CDN per ottenere il meglio di entrambi! Intendiamo rimuovere i file di grandi dimensioni dal vostro server di origine (Kinsta) e servirli da un provider di terze parti.<\/p>\n<ul>\n<li>Consultate la nostra guida approfondita all&#8217;integrazione <a href=\"https:\/\/kinsta.com\/it\/blog\/wordpress-amazon-s3\/\" target=\"_blank\" rel=\"noopener noreferrer\">tra WordPress e Amazon S3<\/a>. \u00c8 possibile abilitare l&#8217;opzione che rimuove i file dal server locale una volta che sono stati scaricati su S3. Questo pu\u00f2 aiutare a ridurre drasticamente lo spazio su disco necessario per il vostro host WordPress.<\/li>\n<li>Potete ricorrere a questo stesso approccio anche con <a href=\"https:\/\/kinsta.com\/it\/blog\/wordpress-google-cloud-storage\/\" target=\"_blank\" rel=\"noopener noreferrer\">WordPress e Google Cloud Storage<\/a>.<\/li>\n<li>Consigliamo inoltre di sfruttare servizi di terze parti come YouTube o Vimeo per i video, Soundcloud per i file audio e Dropbox per i file PDF scaricabili. Questi servizi non solo sono affidabili e stabili, ma dispongono anche di alcune tra le reti pi\u00f9 veloci al mondo per quanto riguarda la pubblicazione di file di grandi dimensioni.<\/li>\n<\/ul>\n<p>Un&#8217;altra eccezione alla regola che vediamo ogni tanto riguarda grandi siti WooCommerce. Tuttavia, molti di questi di siti gestiscono molte richieste non in cache, pertanto i clienti in questa situazione in genere sono gi\u00e0 in piani superiori con un maggior numero di <a href=\"https:\/\/kinsta.com\/it\/blog\/thread-php\/\" target=\"_blank\" rel=\"noopener noreferrer\">thread PHP<\/a>. In altre parole, questa tipologia di siti generalmente utilizza gi\u00e0 piani superiori con molto spazio su disco.<\/p>\n<h2 id=\"quanto-spazio-su-disco-utilizzate\">Quanto spazio su disco \u00e8 in uso?<\/h2>\n<p>State cercando di passare a Kinsta o ad un altro host e siete curiosi di vedere quanto spazio su disco state attualmente utilizzando? Nessun problema! Abbiamo scritto una guida approfondita con 7 diversi modi per <a href=\"https:\/\/kinsta.com\/it\/blog\/utilizzo-disco-wordpress\/\" target=\"_blank\" rel=\"noopener noreferrer\">controllare il vostro utilizzo di spazio su disco<\/a>. Potete vedere quanto sono grandi i vostri upload o la vostra cartella dei temi in pochi minuti. Ecco alcune scorciatoie:<\/p>\n<ul>\n<li><a href=\"https:\/\/kinsta.com\/it\/blog\/utilizzo-disco-wordpress\/#disk-usage-plugins\" target=\"_blank\" rel=\"noopener noreferrer\">Controllare l&#8217;Utilizzo del Disco con i Plugin di WordPress<\/a><\/li>\n<li><a href=\"https:\/\/kinsta.com\/it\/blog\/utilizzo-disco-wordpress\/#disk-usage-cpanel\" target=\"_blank\" rel=\"noopener noreferrer\">Controllare l&#8217;Utilizzo del Disco e la Dimensione del Database in cPanel<\/a><\/li>\n<li><a href=\"https:\/\/kinsta.com\/it\/blog\/utilizzo-disco-wordpress\/#database-size-plugins\" target=\"_blank\" rel=\"noopener noreferrer\">Controllare la Dimensione del Database con i Plugin di WordPress<\/a><\/li>\n<li><a href=\"https:\/\/kinsta.com\/it\/blog\/utilizzo-disco-wordpress\/#database-size-phpmyadmin\" target=\"_blank\" rel=\"noopener noreferrer\">Controllare la Dimensione del Database con phpMyAdmin<\/a><\/li>\n<li><a href=\"https:\/\/kinsta.com\/it\/blog\/utilizzo-disco-wordpress\/#disk-usage-locally\" target=\"_blank\" rel=\"noopener noreferrer\">Analizzare Localmente l&#8217;Utilizzo del Disco<\/a><\/li>\n<li><a href=\"https:\/\/kinsta.com\/it\/blog\/utilizzo-disco-wordpress\/#disk-usage-ssh\" target=\"_blank\" rel=\"noopener noreferrer\">Controllare l&#8217;Utilizzo del Disco Tramite SSH<\/a><\/li>\n<\/ul>\n<figure id=\"attachment_21065\" aria-describedby=\"caption-attachment-21065\" style=\"width: 1352px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21065\" src=\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-ssh.png\" alt=\"Utilizzo disco via SSH\" width=\"1352\" height=\"971\" srcset=\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-ssh.png 1352w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-ssh-300x215.png 300w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-ssh-768x552.png 768w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-ssh-1024x735.png 1024w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-ssh-610x438.png 610w\" sizes=\"auto, (max-width: 1352px) 100vw, 1352px\" \/><figcaption id=\"caption-attachment-21065\" class=\"wp-caption-text\">Controllare l&#8217;utilizzo del disco via SSH<\/figcaption><\/figure>\n<h2 id=\"come-risparmiare-spazio-su-disco\">Come risparmiare spazio su disco<\/h2>\n<p>Siete in bilico tra due piani di hosting? Ecco alcuni suggerimenti per risparmiare immediatamente spazio su disco e garantire che il piano di hosting abbia spazio per la crescita del sito.<\/p>\n<ul>\n<li><strong>Comprimete le vostre immagini<\/strong>. Non potremo mai ripeterlo abbastanza. Secondo <a href=\"https:\/\/httparchive.org\/reports\/state-of-images#bytesImg\" target=\"_blank\" rel=\"noopener noreferrer\">HTTP Archive<\/a>, a partire da marzo 2018, le immagini rappresentano in media il 51% del peso totale di una pagina web. \u00c9 moltissimo! \ud83d\ude2e Date un&#8217;occhiata alla nostra guida completa all&#8217;<a href=\"https:\/\/kinsta.com\/it\/blog\/ottimizzare-le-immagini-per-web-e-prestazioni\/\" target=\"_blank\" rel=\"noopener noreferrer\">ottimizzazione delle immagini<\/a>. Noi utilizziamo il plugin Imagify e normalmente registriamo un <strong>risparmio del 60-70%<\/strong>!\n<p><figure id=\"attachment_21060\" aria-describedby=\"caption-attachment-21060\" style=\"width: 1468px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21060\" src=\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/risparmio-spazio-compressione-file-immagine.png\" alt=\"Risparmio per compressione dei file immagine\" width=\"1468\" height=\"684\" srcset=\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/risparmio-spazio-compressione-file-immagine.png 1468w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/risparmio-spazio-compressione-file-immagine-300x140.png 300w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/risparmio-spazio-compressione-file-immagine-768x358.png 768w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/risparmio-spazio-compressione-file-immagine-1024x477.png 1024w, https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/risparmio-spazio-compressione-file-immagine-610x284.png 610w\" sizes=\"auto, (max-width: 1468px) 100vw, 1468px\" \/><figcaption id=\"caption-attachment-21060\" class=\"wp-caption-text\">Risparmio per compressione dei file immagine<\/figcaption><\/figure><\/li>\n<li>Fate un altro passo avanti con un plugin come <a href=\"https:\/\/wordpress.org\/plugins\/media-cleaner\/\" target=\"_blank\" rel=\"noopener noreferrer\">Media Cleaner<\/a>. Questo vi consente di individuare e <strong>liberarvi di media inutilizzati<\/strong> nel vostro sito.<\/li>\n<li>Quando i clienti migrano su Kinsta, molto spesso troviamo <strong>vecchi backup, file SQL del database<\/strong>, ecc. che non sono pi\u00f9 necessari. Assicuratevi di controllare ovunque, in quanto un paio di vecchi backup rimasti in giro potrebbero facilmente occupare pi\u00f9 spazio del vostro intero sito WordPress. Questo potrebbe sicuramente influire sulla scelta del piano di hosting. Se volete conservare i vostri backup aggiuntivi, salvateli semplicemente da qualche altra parte e utilizzate i <a href=\"https:\/\/kinsta.com\/docs\/wordpress-hosting\/wordpress-backups\/\" target=\"_blank\" rel=\"noopener noreferrer\">backup automatici<\/a> di Kinsta che non contano sull&#8217;utilizzo dello spazio su disco.<\/li>\n<li><strong>Scaricate i vostri file di grandi dimensioni<\/strong> su un servizio come Amazon S3, Google Cloud Storage, YouTube, Dropbox o Soundcloud per ridurre in modo significativo la quantit\u00e0 di spazio su disco richiesta al vostro provider di hosting.<\/li>\n<li><a href=\"https:\/\/kinsta.com\/it\/blog\/eliminare-tema-wordpress\/\">Eliminate vecchi temi<\/a> e plugin che non state pi\u00f9 utilizzando. Abbiamo visto alcune installazioni pazzesche con oltre 50 plugin inattivi e decine di temi non utilizzati.<\/li>\n<li><a href=\"https:\/\/kinsta.com\/it\/blog\/ripulire-tabella-wp_options-e-dati-caricati-automaticamente\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ripulite i dati caricati automaticamente<\/a> nella tabella <code>wp_options<\/code>. Questo \u00e8 di gran lunga uno dei modi pi\u00f9 semplici per ridurre le dimensioni del database.<\/li>\n<li>Su siti WordPress di lunga data, le revisioni di post e pagine possono aggiungere facilmente anche migliaia di righe non necessarie nel database. Potete facilmente <a href=\"https:\/\/kinsta.com\/it\/blog\/revisioni-wordpress\/#how-to-limit-revisions-in-wordpress\" target=\"_blank\" rel=\"noopener noreferrer\">disabilitare o limitare le revisioni di WordPress<\/a> per mantenere il vostro database in perfetta forma.<\/li>\n<li>Se avete <a href=\"https:\/\/kinsta.com\/it\/blog\/wordpress-debug\/\">eseguito il debug di alcune cose nel tuo sito<\/a>, assicuratevi di <strong>rimuovere i vecchi file di registro<\/strong> rimasti in giro.<\/li>\n<li>Pulite e cancellate i commenti nello spam o nel cestino.<\/li>\n<\/ul>\n<h2>Riepilogo<\/h2>\n<p>Speriamo che questo tutorial chiarisca ogni dubbio che possiate avere quando arriver\u00e0 il momento di scegliere il piano di hosting WordPress pi\u00f9 adatto alla vostra azienda. Spesso forse non avrete bisogno di tutto lo spazio su disco che credete necessario. Controllate quanto spazio state utilizzando cos\u00ec come abbiamo descritto sopra, ottimizzate il vostro sito e dovreste riuscire facilmente a risparmiare sul piano di hosting.<\/p>\n<p>Cosa ne pensate? Avete gi\u00e0 constatato che, con un po&#8217; di lavoro di ottimizzazione, il vostro utilizzo del disco \u00e8 molto inferiore a quello che pensavate in \u200b\u200borigine? Raccontateci la vostra esperienza nei commenti qui sotto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando si \u00e8 alla ricerca di un piano hosting per WordPress, pu\u00f2 esserci una notevole differenza tra lo spazio che credete sia necessario e quello che &#8230;<\/p>\n","protected":false},"author":38,"featured_media":21064,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[36,3],"topic":[25875],"class_list":["post-21032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-hosting","tag-wordpress","topic-hosting-wordpress"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Di Quanto Spazio su Disco ha Davvero Bisogno il Vostro Piano di Hosting?<\/title>\n<meta name=\"description\" content=\"Quando si cerca un piano hosting WordPress pu\u00f2 essere difficile prevedere quanto spazio su disco serva davvero e spesso gli utenti lo sovrastimano. Scopriamo perch\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Di quanto spazio su disco ha davvero bisogno un piano di hosting?\" \/>\n<meta property=\"og:description\" content=\"Quando si cerca un piano hosting WordPress pu\u00f2 essere difficile prevedere quanto spazio su disco serva davvero e spesso gli utenti lo sovrastimano. Scopriamo perch\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kinstaitalia\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/fm.brianleejackson\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-19T14:49:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-21T09:58:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-hosting-wordpress.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1460\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Brian Jackson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Quando si cerca un piano hosting WordPress pu\u00f2 essere difficile prevedere quanto spazio su disco serva davvero e spesso gli utenti lo sovrastimano. Scopriamo perch\u00e9.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-hosting-wordpress.png\" \/>\n<meta name=\"twitter:creator\" content=\"@brianleejackson\" \/>\n<meta name=\"twitter:site\" content=\"@Kinsta_IT\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brian Jackson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/\"},\"author\":{\"name\":\"Brian Jackson\",\"@id\":\"https:\/\/kinsta.com\/it\/#\/schema\/person\/079824c00ccc2b7141504f27ea63bef7\"},\"headline\":\"Di quanto spazio su disco ha davvero bisogno un piano di hosting?\",\"datePublished\":\"2018-06-19T14:49:06+00:00\",\"dateModified\":\"2025-01-21T09:58:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/\"},\"wordCount\":1736,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-hosting-wordpress.png\",\"keywords\":[\"hosting\",\"WordPress\"],\"articleSection\":[\"Strategie di Crescita Aziendale\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/\",\"url\":\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/\",\"name\":\"Di Quanto Spazio su Disco ha Davvero Bisogno il Vostro Piano di Hosting?\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-hosting-wordpress.png\",\"datePublished\":\"2018-06-19T14:49:06+00:00\",\"dateModified\":\"2025-01-21T09:58:03+00:00\",\"description\":\"Quando si cerca un piano hosting WordPress pu\u00f2 essere difficile prevedere quanto spazio su disco serva davvero e spesso gli utenti lo sovrastimano. Scopriamo perch\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#primaryimage\",\"url\":\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-hosting-wordpress.png\",\"contentUrl\":\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-hosting-wordpress.png\",\"width\":1460,\"height\":730,\"caption\":\"Utilizzo disco hosting WordPress\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kinsta.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hosting WordPress\",\"item\":\"https:\/\/kinsta.com\/it\/argomenti\/hosting-wordpress\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Di quanto spazio su disco ha davvero bisogno un piano di hosting?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kinsta.com\/it\/#website\",\"url\":\"https:\/\/kinsta.com\/it\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Soluzioni di hosting premium, veloci e sicure\",\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kinsta.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kinsta.com\/it\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kinsta.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/kinsta.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kinstaitalia\/\",\"https:\/\/x.com\/Kinsta_IT\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kinsta.com\/it\/#\/schema\/person\/079824c00ccc2b7141504f27ea63bef7\",\"name\":\"Brian Jackson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/kinsta.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/79623d815f4ed4c8c2457392d728cb16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/79623d815f4ed4c8c2457392d728cb16?s=96&d=mm&r=g\",\"caption\":\"Brian Jackson\"},\"description\":\"Brian has a huge passion for WordPress, has been using it for over a decade, and even develops a couple of premium plugins. Brian enjoys blogging, movies, and hiking. Connect with Brian on Twitter.\",\"sameAs\":[\"https:\/\/www.facebook.com\/fm.brianleejackson\",\"https:\/\/www.linkedin.com\/in\/brianleejackson\",\"https:\/\/x.com\/brianleejackson\"],\"url\":\"https:\/\/kinsta.com\/it\/blog\/author\/brianjackson\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Di Quanto Spazio su Disco ha Davvero Bisogno il Vostro Piano di Hosting?","description":"Quando si cerca un piano hosting WordPress pu\u00f2 essere difficile prevedere quanto spazio su disco serva davvero e spesso gli utenti lo sovrastimano. Scopriamo perch\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/","og_locale":"it_IT","og_type":"article","og_title":"Di quanto spazio su disco ha davvero bisogno un piano di hosting?","og_description":"Quando si cerca un piano hosting WordPress pu\u00f2 essere difficile prevedere quanto spazio su disco serva davvero e spesso gli utenti lo sovrastimano. Scopriamo perch\u00e9.","og_url":"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/kinstaitalia\/","article_author":"https:\/\/www.facebook.com\/fm.brianleejackson","article_published_time":"2018-06-19T14:49:06+00:00","article_modified_time":"2025-01-21T09:58:03+00:00","og_image":[{"width":1460,"height":730,"url":"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-hosting-wordpress.png","type":"image\/png"}],"author":"Brian Jackson","twitter_card":"summary_large_image","twitter_description":"Quando si cerca un piano hosting WordPress pu\u00f2 essere difficile prevedere quanto spazio su disco serva davvero e spesso gli utenti lo sovrastimano. Scopriamo perch\u00e9.","twitter_image":"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-hosting-wordpress.png","twitter_creator":"@brianleejackson","twitter_site":"@Kinsta_IT","twitter_misc":{"Scritto da":"Brian Jackson","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#article","isPartOf":{"@id":"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/"},"author":{"name":"Brian Jackson","@id":"https:\/\/kinsta.com\/it\/#\/schema\/person\/079824c00ccc2b7141504f27ea63bef7"},"headline":"Di quanto spazio su disco ha davvero bisogno un piano di hosting?","datePublished":"2018-06-19T14:49:06+00:00","dateModified":"2025-01-21T09:58:03+00:00","mainEntityOfPage":{"@id":"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/"},"wordCount":1736,"commentCount":4,"publisher":{"@id":"https:\/\/kinsta.com\/it\/#organization"},"image":{"@id":"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-hosting-wordpress.png","keywords":["hosting","WordPress"],"articleSection":["Strategie di Crescita Aziendale"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/","url":"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/","name":"Di Quanto Spazio su Disco ha Davvero Bisogno il Vostro Piano di Hosting?","isPartOf":{"@id":"https:\/\/kinsta.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#primaryimage"},"image":{"@id":"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-hosting-wordpress.png","datePublished":"2018-06-19T14:49:06+00:00","dateModified":"2025-01-21T09:58:03+00:00","description":"Quando si cerca un piano hosting WordPress pu\u00f2 essere difficile prevedere quanto spazio su disco serva davvero e spesso gli utenti lo sovrastimano. Scopriamo perch\u00e9.","breadcrumb":{"@id":"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#primaryimage","url":"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-hosting-wordpress.png","contentUrl":"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2018\/06\/utilizzo-disco-hosting-wordpress.png","width":1460,"height":730,"caption":"Utilizzo disco hosting WordPress"},{"@type":"BreadcrumbList","@id":"https:\/\/kinsta.com\/it\/blog\/spazio-su-disco-hosting-wordpress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kinsta.com\/it\/"},{"@type":"ListItem","position":2,"name":"Hosting WordPress","item":"https:\/\/kinsta.com\/it\/argomenti\/hosting-wordpress\/"},{"@type":"ListItem","position":3,"name":"Di quanto spazio su disco ha davvero bisogno un piano di hosting?"}]},{"@type":"WebSite","@id":"https:\/\/kinsta.com\/it\/#website","url":"https:\/\/kinsta.com\/it\/","name":"Kinsta\u00ae","description":"Soluzioni di hosting premium, veloci e sicure","publisher":{"@id":"https:\/\/kinsta.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinsta.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/kinsta.com\/it\/#organization","name":"Kinsta","url":"https:\/\/kinsta.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/kinsta.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kinsta.com\/it\/wp-content\/uploads\/sites\/2\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kinsta.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kinstaitalia\/","https:\/\/x.com\/Kinsta_IT","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kinsta.com\/it\/#\/schema\/person\/079824c00ccc2b7141504f27ea63bef7","name":"Brian Jackson","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/kinsta.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/79623d815f4ed4c8c2457392d728cb16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/79623d815f4ed4c8c2457392d728cb16?s=96&d=mm&r=g","caption":"Brian Jackson"},"description":"Brian has a huge passion for WordPress, has been using it for over a decade, and even develops a couple of premium plugins. Brian enjoys blogging, movies, and hiking. Connect with Brian on Twitter.","sameAs":["https:\/\/www.facebook.com\/fm.brianleejackson","https:\/\/www.linkedin.com\/in\/brianleejackson","https:\/\/x.com\/brianleejackson"],"url":"https:\/\/kinsta.com\/it\/blog\/author\/brianjackson\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kinsta.com\/it\/wp-json\/wp\/v2\/posts\/21032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinsta.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kinsta.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kinsta.com\/it\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/kinsta.com\/it\/wp-json\/wp\/v2\/comments?post=21032"}],"version-history":[{"count":15,"href":"https:\/\/kinsta.com\/it\/wp-json\/wp\/v2\/posts\/21032\/revisions"}],"predecessor-version":[{"id":80229,"href":"https:\/\/kinsta.com\/it\/wp-json\/wp\/v2\/posts\/21032\/revisions\/80229"}],"alternate":[{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kinsta.com\/it\/wp-json\/kinsta\/v1\/posts\/21032\/translations\/it"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kinsta.com\/it\/wp-json\/kinsta\/v1\/posts\/21032\/translations\/pt"},{"embeddable":true,"hreflang":"ja","title":"Japanese","href":"https:\/\/kinsta.com\/it\/wp-json\/kinsta\/v1\/posts\/21032\/translations\/jp"},{"embeddable":true,"hreflang":"sv","title":null,"href":"https:\/\/kinsta.com\/it\/wp-json\/kinsta\/v1\/posts\/21032\/translations\/se"},{"embeddable":true,"hreflang":"nl","title":"Dutch","href":"https:\/\/kinsta.com\/it\/wp-json\/kinsta\/v1\/posts\/21032\/translations\/nl"},{"embeddable":true,"hreflang":"da","title":null,"href":"https:\/\/kinsta.com\/it\/wp-json\/kinsta\/v1\/posts\/21032\/translations\/dk"},{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kinsta.com\/it\/wp-json\/kinsta\/v1\/posts\/21032\/translations\/es"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kinsta.com\/it\/wp-json\/kinsta\/v1\/posts\/21032\/translations\/de"},{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kinsta.com\/it\/wp-json\/kinsta\/v1\/posts\/21032\/translations\/en"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kinsta.com\/it\/wp-json\/kinsta\/v1\/posts\/21032\/translations\/fr"},{"href":"https:\/\/kinsta.com\/it\/wp-json\/kinsta\/v1\/posts\/21032\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinsta.com\/it\/wp-json\/wp\/v2\/media\/21064"}],"wp:attachment":[{"href":"https:\/\/kinsta.com\/it\/wp-json\/wp\/v2\/media?parent=21032"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kinsta.com\/it\/wp-json\/wp\/v2\/tags?post=21032"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kinsta.com\/it\/wp-json\/wp\/v2\/topic?post=21032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}