{"id":36411,"date":"2020-03-30T03:23:26","date_gmt":"2020-03-30T10:23:26","guid":{"rendered":"https:\/\/kinsta.com\/?p=69374&#038;preview=true&#038;preview_id=69374"},"modified":"2025-02-18T06:32:00","modified_gmt":"2025-02-18T09:32:00","slug":"leverage-browser-cache","status":"publish","type":"post","link":"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/","title":{"rendered":"Como Resolver o Aviso &#8220;Leverage Browser Caching&#8221; no WordPress"},"content":{"rendered":"<p>O <a href=\"https:\/\/kinsta.com\/pt\/blog\/google-pagespeed-insights\/\">Google PageSpeed Insights<\/a> \u00e9 uma das v\u00e1rias ferramentas \u00fateis para medir o desempenho do site. No entanto, algumas das suas sugest\u00f5es &#8211; como o aviso &#8216;Leverage Browser Caching&#8217; &#8211; podem ser confusas para propriet\u00e1rios de sites inexperientes.<\/p>\n<p>Quando a deciframos, n\u00e3o \u00e9 assim t\u00e3o dif\u00edcil de entender. Com alguns ajustes, voc\u00ea pode implementar esta melhor pr\u00e1tica de desenvolvimento no seu site para reduzir os tempos de carregamento e melhorar a sua pontua\u00e7\u00e3o no PageSpeed.<\/p>\n<p>Neste artigo, vamos come\u00e7ar com uma introdu\u00e7\u00e3o ao aviso &#8216;Leverage Browser Caching&#8217;. Depois, compartilharemos v\u00e1rias dicas para corrigir este problema no seu site WordPress.<\/p>\n<p>Vamos nessa!<\/p>\n<div><\/div><kinsta-auto-toc heading=\"Table of Contents\" exclude=\"last\" list-style=\"arrow\" selector=\"h2\" count-number=\"-1\"><\/kinsta-auto-toc>\n<h3 class=\"p1\">Prefere assistir \u00e0 <a href=\"https:\/\/www.youtube.com\/watch?v=O4cE3nbKvoM\">vers\u00e3o em v\u00eddeo<\/a>?<\/h3>\n<p class=\"p1\"><kinsta-video src=\"https:\/\/www.youtube.com\/watch?v=O4cE3nbKvoM\"><\/kinsta-video><\/p>\n<h2>O que \u00e9 o Aviso &#8220;Leverage Browser Caching&#8221;?<\/h2>\n<p>Para entender o aviso &#8220;Leverage Browser Caching&#8221;, ajuda saber um pouco sobre o Google PageSpeed Insights. Se voc\u00ea \u00e9 novo na plataforma, recomendamos que leia nosso guia completo, <a href=\"https:\/\/kinsta.com\/pt\/blog\/google-pagespeed-insights\/\">Google PageSpeed Insights: Pontua\u00e7\u00e3o 100\/100 com WordPress<\/a>.<\/p>\n<p>O aviso &#8220;Leverage Browser Caching&#8221; \u00e9 um dos muitos &#8216;diagn\u00f3sticos&#8217; do Google PageSpeed usado para retornar como uma sugest\u00e3o para melhorar sua pontua\u00e7\u00e3o, como o seguinte:<\/p>\n<figure style=\"width: 1260px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/04\/aviso-cache-navegador-pagespeed.png\" alt=\"Aviso de Cache de Navegador de Alavancagem no Google PageSpeed Insights\" width=\"1260\" height=\"231\"><figcaption class=\"wp-caption-text\"><em>Aviso de Cache de Navegador de Alavancagem no Google PageSpeed Insights<\/em><\/figcaption><\/figure>\n<p>Na Vers\u00e3o 5 do Google PageSpeed Insights, <a href=\"https:\/\/developers.google.com\/speed\/docs\/insights\/LeverageBrowserCaching\">esta mensagem foi substitu\u00edda<\/a> pelo aviso &#8220;Disponibilize recursos est\u00e1ticos com uma pol\u00edtica de cache eficiente&#8221;:<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/sirva-ativos-estaticos-aviso-agespeed-insights.png\" alt=\"Sirva ativos est\u00e1ticos com um eficiente aviso de pol\u00edtica de cache no Google PageSpeed Insights\" width=\"1500\" height=\"716\"><figcaption class=\"wp-caption-text\">Disponibilize recursos est\u00e1ticos com uma pol\u00edtica de cache eficiente no Google PageSpeed Insights<\/figcaption><\/figure>\n<p>Apesar da mudan\u00e7a na linguagem e apar\u00eancia, a solu\u00e7\u00e3o para estes avisos \u00e9 a mesma.<\/p>\n<p>O Google sugere o uso do cache do navegador para reduzir os tempos de carregamento de p\u00e1ginas e <a href=\"https:\/\/kinsta.com\/pt\/aprenda\/acelerar-o-seu-site-wordpress\/\">melhorar o desempenho<\/a>. Em resumo, o cache \u00e9 quando os navegadores dos usu\u00e1rios salvam c\u00f3pias est\u00e1ticas das p\u00e1ginas do seu site. Ent\u00e3o, em visitas subsequentes, esse conte\u00fado pode ser carregado novamente mais rapidamente porque o navegador n\u00e3o precisa entrar em contato com o servidor do seu site para acessar os recursos solicitados.<\/p>\n<p>Contudo, cada recurso em cache precisa de um per\u00edodo de expira\u00e7\u00e3o especificado. Isso informa aos navegadores quando o conte\u00fado do seu site est\u00e1 desatualizado, para que ele possa substituir sua c\u00f3pia em cache por uma vers\u00e3o atualizada.<\/p>\n<p>Se voc\u00ea estiver vendo o aviso &#8220;Leverage Browser Caching&#8221; nos resultados do seu teste de desempenho, isso provavelmente significa uma de duas coisas:<\/p>\n<ul>\n<li>Os cabe\u00e7alhos Cache-Control ou Expires est\u00e3o ausentes do servidor do seu site ou de terceiros.<\/li>\n<li>Os cabe\u00e7alhos necess\u00e1rios est\u00e3o presentes, mas o per\u00edodo de validade \u00e9 muito curto e, portanto, n\u00e3o tem muito impacto no desempenho.<\/li>\n<\/ul>\n<p>As solu\u00e7\u00f5es para este aviso envolvem a resolu\u00e7\u00e3o de um ou ambos os problemas.<\/p>\n\n<h2>Como corrigir o Aviso &#8220;Leverage Browser Caching&#8221; no WordPress (3 M\u00e9todos)<\/h2>\n<p>Existem algumas maneiras diferentes de corrigir o aviso Leverage Browser Caching no WordPress, dependendo do que o est\u00e1 causando. Aqui est\u00e3o tr\u00eas solu\u00e7\u00f5es que voc\u00ea pode tentar.<\/p>\n<h3>1. Adicionar Cache-Control e Expires Headers<\/h3>\n<p>H\u00e1 dois cabe\u00e7alhos relacionados ao cache do navegador: <a href=\"https:\/\/devcenter.heroku.com\/articles\/increasing-application-performance-with-http-cache-headers#http-cache-headers\">Cache-Control e Expires<\/a>. Pelo menos um deve estar presente para ativar o cache do navegador para o seu site, pois \u00e9 assim que os navegadores determinam quanto tempo devem reter os recursos antes de atualiz\u00e1-los.<\/p>\n<p>Uma maneira simples de determinar se isto \u00e9 o que est\u00e1 causando o aviso de Leverage Browser Caching \u00e9 olhar para os detalhes de dados para cada recurso. No Google PageSpeed Insights Version 5, voc\u00ea ver\u00e1 &#8220;Nenhum&#8221; listado em<strong> Cache TTL<\/strong>:<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/cache-ttl-pagespeed-1.png\" alt=\"Cache TTL PageSpeed\" width=\"1500\" height=\"828\"><figcaption class=\"wp-caption-text\">Cache TTL listagens no Google PageSpeed Insights<\/figcaption><\/figure>\n<p>Como uma refer\u00eancia \u00fatil, as vers\u00f5es anteriores do Google PageSpeed Insights mostraram uma mensagem de &#8220;expira\u00e7\u00e3o n\u00e3o especificada&#8221; quando os cabe\u00e7alhos estavam ausentes:<\/p>\n<figure style=\"width: 1261px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/04\/recursos-listados-aviso-leverage-browser-caching.png\" alt=\"Recursos listados no aviso de cache do Leverage Browser Caching\" width=\"1261\" height=\"578\"><figcaption class=\"wp-caption-text\">Recursos listados no aviso de cache do Leverage Browser Caching<\/figcaption><\/figure>\n<p>Enquanto o cabe\u00e7alho Cache-Control ativa o cache do lado do cliente e define a idade m\u00e1xima de um recurso, o cabe\u00e7alho expirados \u00e9 usado para especificar um ponto no tempo em que o recurso n\u00e3o \u00e9 mais v\u00e1lido.<\/p>\n<p><strong>Voc\u00ea n\u00e3o precisa necessariamente adicionar ambos<\/strong>, pois isso pode ser redundante. O Cache-Control \u00e9 mais recente e \u00e9 geralmente o m\u00e9todo recomendado. No entanto, algumas ferramentas de desempenho web, <a href=\"https:\/\/kinsta.com\/pt\/blog\/teste-de-velocidade-gtmetrix\/\">como o GTmetrix<\/a>, ainda verificam se h\u00e1 cabe\u00e7alhos expirados.<\/p>\n<p>Se voc\u00ea est\u00e1 hospedado na Kinsta, <a href=\"https:\/\/kinsta.com\/pt\/blog\/cache-wordpress\/\">n\u00e3o precisa se preocupar<\/a> em colocar estes cabe\u00e7alhos. Todos os nossos <a href=\"https:\/\/kinsta.com\/pt\/blog\/nginx-vs-apache\/\">servidores Nginx<\/a> j\u00e1 os incluem. Aqueles que utilizam uma <a href=\"https:\/\/kinsta.com\/pt\/docs\/hospedagem-de-wordpress\/cdn-wordpress\/cdn-kinsta\/#kinstas-cdn\">Rede de Entrega de Conte\u00fado (CDN)<\/a> tamb\u00e9m j\u00e1 devem ter estes cabe\u00e7alhos aplicados.<\/p>\n<p>No caso de voc\u00ea estar usando um provedor de hospedagem diferente, certifique-se de <a href=\"https:\/\/kinsta.com\/docs\/wordpress-hosting\/wordpress-backups\/#wordpress-backup\">fazer backup do seu site<\/a> antes de seguir os passos abaixo, pois <a href=\"https:\/\/kinsta.com\/pt\/blog\/arquivo-wordpress-htaccess\/\"><em>a<\/em> edi\u00e7\u00e3o<em> . htaccess<\/em><\/a> pode quebrar o seu site se voc\u00ea n\u00e3o tiver cuidado.<\/p>\n<h4>Como adicionar cabe\u00e7alhos Cache-Control no Nginx<\/h4>\n<p>Para adicionar cabe\u00e7alhos Cache-Control no Nginx, voc\u00ea pode adicionar o seguinte ao arquivo de configura\u00e7\u00e3o do seu servidor:<\/p>\n<pre><code>location ~* \\.(js|css|png|jpg|jpeg|gif|svg|ico)$ {\n expires 30d;\n add_header Cache-Control \"public, no-transform\";\n}\n<\/code><\/pre>\n<p>Isto diz ao seu servidor que os tipos de ficheiros especificados n\u00e3o v\u00e3o mudar durante pelo menos 30 dias. Ele manter\u00e1 os arquivos relevantes salvos por esse per\u00edodo de tempo antes de atualiz\u00e1-los.<\/p>\n<h4><strong> Como adicionar cabe\u00e7alhos Cache-Control no Apache <\/strong><\/h4>\n<p>Se voc\u00ea tiver <a href=\"https:\/\/kinsta.com\/pt\/blog\/o-que-e-apache\/\">um servidor Apache<\/a>, voc\u00ea pode adicionar o seguinte c\u00f3digo ao seu arquivo<em> . htaccess:<\/em><\/p>\n<pre><code>&lt;filesMatch \".(ico|pdf|flv|jpg|jpeg|png|gif|svg|js|css|swf)$\"&gt;\n        Header set Cache-Control \"max-age=84600, public\"\n&lt;\/filesMatch&gt\n<\/code><\/pre>\n<p>Este trecho deve ser adicionado antes de &#8220;#BEGIN WordPress&#8221; ou depois de &#8220;#END WordPress&#8221;. Neste caso, a cache \u00e9 definida para expirar ap\u00f3s 84.600 segundos.<\/p>\n<h4>Como Adicionar Cabe\u00e7alhos Expirados em Nginx<\/h4>\n<p>Voc\u00ea pode <a href=\"https:\/\/www.youtube.com\/watch?v=O4cE3nbKvoM\">adicionar cabe\u00e7alhos expirados<\/a> no Nginx, adicionando o seguinte ao seu bloco de servidores. Neste exemplo, voc\u00ea pode ver como especificar diferentes tempos de expira\u00e7\u00e3o com base em tipos de arquivo:<\/p>\n<pre><code>    location ~*  \\.(jpg|jpeg|gif|png|svg)$ {\n        expires 365d;\n    }\n\n    location ~*  \\.(pdf|css|html|js|swf)$ {\n        expires 2d;\n    }<\/code><\/pre>\n<h4><strong> Como Adicionar Cabe\u00e7alhos Expirados no Apache <\/strong><\/h4>\n<p>Voc\u00ea pode adicionar cabe\u00e7alhos expirados no Apache, adicionando o seguinte ao seu arquivo<em> .htaccess:<\/em><\/p>\n<pre><code>## EXPIRES HEADER CACHING ##\n&lt;IfModule mod_expires.c&gt;\nExpiresActive On\nExpiresByType image\/jpg \"access 1 year\"\nExpiresByType image\/jpeg \"access 1 year\"\nExpiresByType image\/gif \"access 1 year\"\nExpiresByType image\/png \"access 1 year\"\nExpiresByType image\/svg \"access 1 year\"\nExpiresByType text\/css \"access 1 month\"\nExpiresByType application\/pdf \"access 1 month\"\nExpiresByType application\/javascript \"access 1 month\"\nExpiresByType application\/x-javascript \"access 1 month\"\nExpiresByType application\/x-shockwave-flash \"access 1 month\"\nExpiresByType image\/x-icon \"access 1 year\"\nExpiresDefault \"access 2 days\"\n&lt;\/IfModule&gt;\n## EXPIRES HEADER CACHING ##<\/code><\/pre>\n<p>Em seguida, voc\u00ea pode verificar seus cabe\u00e7alhos executando seu site atrav\u00e9s do Google PageSpeed Insights novamente e ver se o aviso persiste.<\/p>\n\n<h3>2. Leverage Browser Caching no Google Analytics<\/h3>\n<p>Ironicamente, o <a href=\"https:\/\/kinsta.com\/pt\/blog\/google-analytics-wordpress\/\">Google Analytics<\/a> \u00e9, por vezes, a causa do aviso Leverage Browser Caching (Aproveitar o processo de cache do navegador) e de uma pontua\u00e7\u00e3o imperfeita no PageSpeed. Isto porque tem um tempo de expira\u00e7\u00e3o de cache baixo, de apenas duas horas. Este costumava ser o antigo aviso:<\/p>\n<figure style=\"width: 1265px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2017\/02\/aviso-cache-navegador-script-google-analytics.png\" alt=\"Aviso de cache do navegador de Alavancagem do script do Google Analytics\" width=\"1265\" height=\"452\"><figcaption class=\"wp-caption-text\">Aviso de cache do navegador de Alavancagem do script do Google Analytics<\/figcaption><\/figure>\n<p>Na PageSpeed Insights Version 5, esta edi\u00e7\u00e3o n\u00e3o resulta mais em um aviso, mas o Google Analytics ainda pode ser listado como um recurso n\u00e3o otimizado:<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/pagespeed-insights-passou-lista-scripts-google-analytics.png\" alt=\"Google PageSpeed Insights passou nas auditorias com a lista de scripts do Google Analytics\" width=\"1500\" height=\"945\"><figcaption class=\"wp-caption-text\">Google PageSpeed Insights passou nas auditorias com a lista de scripts do Google Analytics<\/figcaption><\/figure>\n<p>Voc\u00ea n\u00e3o poder\u00e1 mudar isso com os cabe\u00e7alhos Cache-Control ou Expires porque o recurso n\u00e3o est\u00e1 no seu servidor. No entanto, h\u00e1 uma forma de aproveitar o cache do navegador para o Google Analytics, hospedando o script localmente.<\/p>\n<p>No entanto, esteja ciente de que este m\u00e9todo <a href=\"https:\/\/support.google.com\/analytics\/answer\/1032389?hl=en\">n\u00e3o \u00e9 suportado pelo Google<\/a>.<\/p>\n<h4><strong>Leverage Browser Caching no Google Analytics com o Complete Analytics Optimization Suite (CAOS)<\/strong><\/h4>\n<p>Se voc\u00ea quiser resolver o problema acima, h\u00e1 um plugin gratuito chamado <a href=\"https:\/\/wordpress.org\/plugins\/host-analyticsjs-local\/\">Complete Analytics Optimization Suite (CAOS)<\/a> desenvolvido por Daan van den Bergh que voc\u00ea pode usar:<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/04\/CAOS-wordpress-plugin.jpg\" alt=\"CAOS WordPress plugin\" width=\"1500\" height=\"500\"><figcaption class=\"wp-caption-text\">CAOS WordPress plugin<\/figcaption><\/figure>\n<p>Voc\u00ea pode fazer o download do CAOS no Diret\u00f3rio de Plugins do WordPress ou procurando por ele em<strong> Plugins &gt; Adicionar novo no<\/strong> seu painel de controle do WordPress.<\/p>\n<p>Alguns benef\u00edcios adicionais ao hospedar seu script anal\u00edtico localmente incluem que ele <a href=\"https:\/\/kinsta.com\/pt\/blog\/fazer-menos-solicitacoes-http\/\">reduz seus pedidos HTTP<\/a> externos ao Google de dois para um e permite que voc\u00ea ganhe controle total sobre o cache do arquivo. Isto significa que voc\u00ea pode usar os cabe\u00e7alhos de cache como n\u00f3s mostramos anteriormente.<\/p>\n<p>Para come\u00e7ar, instale o plugin e, em seguida, digite seu ID de rastreamento do Google Analytics. O plugin adiciona o c\u00f3digo de rastreamento necess\u00e1rio para o Google Analytics ao seu site WordPress, baixa e salva o arquivo <em>analytics.js<\/em> no seu servidor, e o mant\u00e9m atualizado usando um script agendado em <code>wp_cron()<\/code>.<\/p>\n<p>Recomendamos tamb\u00e9m a sua coloca\u00e7\u00e3o no rodap\u00e9:<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/configuracoes-caos.png\" alt=\"Configura\u00e7\u00f5es CAOS\" width=\"1500\" height=\"698\"><figcaption class=\"wp-caption-text\">Configura\u00e7\u00f5es de posicionamento do c\u00f3digo de rastreamento CAOS<\/figcaption><\/figure>\n<p>Tenha em mente que o CAOS n\u00e3o funcionar\u00e1 com outros <a href=\"https:\/\/kinsta.com\/pt\/blog\/google-analytics-wordpress\/\">plugins WordPress do Google Analytics<\/a>.<\/p>\n<h4>Leverage Browser Caching no Google Analytics com o WP-Rocket<\/h4>\n<p>Alternativamente, voc\u00ea pode usar o plugin de cache do WordPress <a href=\"https:\/\/kinsta.com\/partners\/wp-rocket\/\">WP-Rocket<\/a> para atingir o mesmo objetivo:<\/p>\n<figure style=\"width: 1500px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/wp-rocket-plugin-1.png\" alt=\"wp rocket plugin\" width=\"1500\" height=\"528\"><figcaption class=\"wp-caption-text\">WP-Rocket WordPress plugin<\/figcaption><\/figure>\n<p>Este plugin do <a href=\"https:\/\/docs.wp-rocket.me\/article\/1103-google-tracking-add-on\">Google Tracking Add-on<\/a> permite que voc\u00ea hospede seu script anal\u00edtico localmente com o clique de um bot\u00e3o. Basta alternar o status em<strong> WP-Rocket &gt; Add-ons.<\/strong><\/p>\n<p>O WP-Rocket e seu add-on<em> s\u00e3o<\/em> compat\u00edveis com outros plugins do Google Analytics. Como uma ferramenta premium, ele vem a um pre\u00e7o com licen\u00e7as que come\u00e7am em $49 por ano.<\/p>\n<h3>3. Minimize o seu uso de scripts de terceiros<\/h3>\n<p>Por vezes, o script do Google Analytics pode causar problemas na sua pontua\u00e7\u00e3o no Google PageSpeed Insights porque est\u00e1 alojado no servidor do Google, pelo que n\u00e3o tem o controle da cache.<\/p>\n<p>O mesmo se aplica a outros <a href=\"https:\/\/kinsta.com\/pt\/blog\/desempenho-terceiros\/\">scripts de terceiros<\/a>. Se voc\u00ea est\u00e1 gerenciando um neg\u00f3cio atrav\u00e9s do seu site WordPress, muito provavelmente voc\u00ea tem outros scripts de terceiros rodando para <a href=\"https:\/\/kinsta.com\/pt\/blog\/acompanhamento-de-conversoes\/\">acompanhar convers\u00f5es<\/a>, <a href=\"https:\/\/kinsta.com\/pt\/blog\/ferramentas-de-teste-a-b-do-wordpress\/\">testes A\/B<\/a>, e muito mais.<\/p>\n<p>Isso pode incluir scripts como o <a href=\"https:\/\/kinsta.com\/pt\/blog\/acompanhamento-de-conversoes\/#fb-conversion-tracking\">Facebook<\/a>, Crazy Egg, Hotjar, entre outros. Infelizmente, a menos que voc\u00ea encontre uma maneira de hospedar esses scripts localmente, n\u00e3o h\u00e1 muito que voc\u00ea possa fazer para ganhar controle sobre eles.<\/p>\n<p>Uma op\u00e7\u00e3o para usu\u00e1rios do <a href=\"https:\/\/www.facebook.com\/business\/learn\/facebook-ads-pixel\">Facebook Pixel<\/a> \u00e9 usar mais um <a href=\"https:\/\/docs.wp-rocket.me\/article\/1117-facebook-pixel-add-on\">WP-Rocket add-on<\/a>. Idealmente, voc\u00ea vai querer minimizar o uso de scripts de terceiros se quiser melhorar sua pontua\u00e7\u00e3o no Google PageSpeed. Portanto, pode valer a pena realizar uma auditoria do seu site e remover quaisquer scripts que n\u00e3o sejam necess\u00e1rios para execut\u00e1-lo.<\/p>\n\n<h2>Resumo<\/h2>\n<p>Embora n\u00e3o seja uma medida definitiva do desempenho do seu site, o <a href=\"https:\/\/developers.google.com\/speed\/pagespeed\/insights\/\">Google PageSpeed Insights<\/a> ainda \u00e9 um indicador decente de como ele est\u00e1 funcionando. Melhorar a sua pontua\u00e7\u00e3o atrav\u00e9s da resolu\u00e7\u00e3o de avisos mostrados na se\u00e7\u00e3o &#8220;Servir ativos est\u00e1ticos com uma pol\u00edtica de cache eficiente&#8221; pode ajudar a tornar o seu site mais r\u00e1pido e mais utiliz\u00e1vel para os visitantes.<\/p>\n<p>Se voc\u00ea estiver vendo este aviso no Google PageSpeed Insights, voc\u00ea pode resolv\u00ea-lo por:<\/p>\n<ol>\n<li>Adicionando cabe\u00e7alhos Cache-Control ou Expires.<\/li>\n<li>Alavancando o cache do navegador para o Google Analytics.<\/li>\n<li>Minimizando o uso de scripts de terceiros.<\/li>\n<\/ol>\n<p>Tem alguma outra dica sobre como resolver o Leverage Browser Caching? Informe-nos na se\u00e7\u00e3o de coment\u00e1rios abaixo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Google PageSpeed Insights \u00e9 uma das v\u00e1rias ferramentas \u00fateis para medir o desempenho do site. No entanto, algumas das suas sugest\u00f5es &#8211; como o aviso &#8230;<\/p>\n","protected":false},"author":37,"featured_media":36423,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[273,27],"topic":[1021],"class_list":["post-36411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-pagespeed","tag-webperf","topic-erros-site"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como Resolver o Aviso &quot;Leverage Browser Caching&quot; no WordPress<\/title>\n<meta name=\"description\" content=\"Confira este tutorial detalhado sobre como corrigir o aviso Leverage Browser Caching no seu site WordPress que voc\u00ea recebe do Google PageSpeed Insights.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como Resolver o Aviso &quot;Leverage Browser Caching&quot; no WordPress\" \/>\n<meta property=\"og:description\" content=\"Confira este tutorial detalhado sobre como corrigir o aviso Leverage Browser Caching no seu site WordPress que voc\u00ea recebe do Google PageSpeed Insights.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kinstapt\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/jonpenland\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-30T10:23:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-18T09:32:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/aviso-cache-navegador.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1460\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jon Penland\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Confira este tutorial detalhado sobre como corrigir o aviso Leverage Browser Caching no seu site WordPress que voc\u00ea recebe do Google PageSpeed Insights.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/aviso-cache-navegador.png\" \/>\n<meta name=\"twitter:creator\" content=\"@jonrichpen\" \/>\n<meta name=\"twitter:site\" content=\"@kinsta_pt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jon Penland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/\"},\"author\":{\"name\":\"Jon Penland\",\"@id\":\"https:\/\/kinsta.com\/pt\/#\/schema\/person\/dd665169ed69e4c363264e4f56c79d6a\"},\"headline\":\"Como Resolver o Aviso &#8220;Leverage Browser Caching&#8221; no WordPress\",\"datePublished\":\"2020-03-30T10:23:26+00:00\",\"dateModified\":\"2025-02-18T09:32:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/\"},\"wordCount\":1930,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/pt\/#organization\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/aviso-cache-navegador.png\",\"keywords\":[\"pagespeed\",\"webperf\"],\"articleSection\":[\"Tutoriais de Desempenho do WordPress\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/\",\"url\":\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/\",\"name\":\"Como Resolver o Aviso \\\"Leverage Browser Caching\\\" no WordPress\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/aviso-cache-navegador.png\",\"datePublished\":\"2020-03-30T10:23:26+00:00\",\"dateModified\":\"2025-02-18T09:32:00+00:00\",\"description\":\"Confira este tutorial detalhado sobre como corrigir o aviso Leverage Browser Caching no seu site WordPress que voc\u00ea recebe do Google PageSpeed Insights.\",\"breadcrumb\":{\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#primaryimage\",\"url\":\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/aviso-cache-navegador.png\",\"contentUrl\":\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/aviso-cache-navegador.png\",\"width\":1460,\"height\":730,\"caption\":\"Como consertar o Aviso de Cache do Navegador de Alavancagem no WordPress\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kinsta.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erros de Site\",\"item\":\"https:\/\/kinsta.com\/pt\/topicos\/erros-site\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Como Resolver o Aviso &#8220;Leverage Browser Caching&#8221; no WordPress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kinsta.com\/pt\/#website\",\"url\":\"https:\/\/kinsta.com\/pt\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Solu\u00e7\u00f5es de hospedagem Premium, r\u00e1pida e segura\",\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kinsta.com\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kinsta.com\/pt\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kinsta.com\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/kinsta.com\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kinstapt\/\",\"https:\/\/x.com\/kinsta_pt\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kinsta.com\/pt\/#\/schema\/person\/dd665169ed69e4c363264e4f56c79d6a\",\"name\":\"Jon Penland\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/kinsta.com\/pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5a3b3098b301d11bc748055f89d57a0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5a3b3098b301d11bc748055f89d57a0a?s=96&d=mm&r=g\",\"caption\":\"Jon Penland\"},\"description\":\"Jon is the Chief Operating Officer at Kinsta and is involved with Kinsta's sales, customer service, and technical support teams on a daily basis. Jon's a family man. So when he isn't feverishly tapping the keys of his laptop he's usually helping one of his kids fix a bike or setting up Netflix for an impatient preschooler.\",\"sameAs\":[\"http:\/\/www.jonpenland.com\",\"https:\/\/www.facebook.com\/jonpenland\",\"https:\/\/www.linkedin.com\/in\/jonpenland\",\"https:\/\/x.com\/jonrichpen\"],\"url\":\"https:\/\/kinsta.com\/pt\/blog\/author\/jonpenland\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Como Resolver o Aviso \"Leverage Browser Caching\" no WordPress","description":"Confira este tutorial detalhado sobre como corrigir o aviso Leverage Browser Caching no seu site WordPress que voc\u00ea recebe do Google PageSpeed Insights.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/","og_locale":"pt_PT","og_type":"article","og_title":"Como Resolver o Aviso \"Leverage Browser Caching\" no WordPress","og_description":"Confira este tutorial detalhado sobre como corrigir o aviso Leverage Browser Caching no seu site WordPress que voc\u00ea recebe do Google PageSpeed Insights.","og_url":"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/kinstapt\/","article_author":"https:\/\/www.facebook.com\/jonpenland","article_published_time":"2020-03-30T10:23:26+00:00","article_modified_time":"2025-02-18T09:32:00+00:00","og_image":[{"width":1460,"height":730,"url":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/aviso-cache-navegador.png","type":"image\/png"}],"author":"Jon Penland","twitter_card":"summary_large_image","twitter_description":"Confira este tutorial detalhado sobre como corrigir o aviso Leverage Browser Caching no seu site WordPress que voc\u00ea recebe do Google PageSpeed Insights.","twitter_image":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/aviso-cache-navegador.png","twitter_creator":"@jonrichpen","twitter_site":"@kinsta_pt","twitter_misc":{"Escrito por":"Jon Penland","Tempo estimado de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#article","isPartOf":{"@id":"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/"},"author":{"name":"Jon Penland","@id":"https:\/\/kinsta.com\/pt\/#\/schema\/person\/dd665169ed69e4c363264e4f56c79d6a"},"headline":"Como Resolver o Aviso &#8220;Leverage Browser Caching&#8221; no WordPress","datePublished":"2020-03-30T10:23:26+00:00","dateModified":"2025-02-18T09:32:00+00:00","mainEntityOfPage":{"@id":"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/"},"wordCount":1930,"commentCount":0,"publisher":{"@id":"https:\/\/kinsta.com\/pt\/#organization"},"image":{"@id":"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/aviso-cache-navegador.png","keywords":["pagespeed","webperf"],"articleSection":["Tutoriais de Desempenho do WordPress"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/","url":"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/","name":"Como Resolver o Aviso \"Leverage Browser Caching\" no WordPress","isPartOf":{"@id":"https:\/\/kinsta.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#primaryimage"},"image":{"@id":"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/aviso-cache-navegador.png","datePublished":"2020-03-30T10:23:26+00:00","dateModified":"2025-02-18T09:32:00+00:00","description":"Confira este tutorial detalhado sobre como corrigir o aviso Leverage Browser Caching no seu site WordPress que voc\u00ea recebe do Google PageSpeed Insights.","breadcrumb":{"@id":"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#primaryimage","url":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/aviso-cache-navegador.png","contentUrl":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2020\/03\/aviso-cache-navegador.png","width":1460,"height":730,"caption":"Como consertar o Aviso de Cache do Navegador de Alavancagem no WordPress"},{"@type":"BreadcrumbList","@id":"https:\/\/kinsta.com\/pt\/blog\/leverage-browser-cache\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kinsta.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Erros de Site","item":"https:\/\/kinsta.com\/pt\/topicos\/erros-site\/"},{"@type":"ListItem","position":3,"name":"Como Resolver o Aviso &#8220;Leverage Browser Caching&#8221; no WordPress"}]},{"@type":"WebSite","@id":"https:\/\/kinsta.com\/pt\/#website","url":"https:\/\/kinsta.com\/pt\/","name":"Kinsta\u00ae","description":"Solu\u00e7\u00f5es de hospedagem Premium, r\u00e1pida e segura","publisher":{"@id":"https:\/\/kinsta.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinsta.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/kinsta.com\/pt\/#organization","name":"Kinsta","url":"https:\/\/kinsta.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/kinsta.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kinsta.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kinstapt\/","https:\/\/x.com\/kinsta_pt","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kinsta.com\/pt\/#\/schema\/person\/dd665169ed69e4c363264e4f56c79d6a","name":"Jon Penland","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/kinsta.com\/pt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5a3b3098b301d11bc748055f89d57a0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5a3b3098b301d11bc748055f89d57a0a?s=96&d=mm&r=g","caption":"Jon Penland"},"description":"Jon is the Chief Operating Officer at Kinsta and is involved with Kinsta's sales, customer service, and technical support teams on a daily basis. Jon's a family man. So when he isn't feverishly tapping the keys of his laptop he's usually helping one of his kids fix a bike or setting up Netflix for an impatient preschooler.","sameAs":["http:\/\/www.jonpenland.com","https:\/\/www.facebook.com\/jonpenland","https:\/\/www.linkedin.com\/in\/jonpenland","https:\/\/x.com\/jonrichpen"],"url":"https:\/\/kinsta.com\/pt\/blog\/author\/jonpenland\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/posts\/36411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/comments?post=36411"}],"version-history":[{"count":11,"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/posts\/36411\/revisions"}],"predecessor-version":[{"id":57563,"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/posts\/36411\/revisions\/57563"}],"alternate":[{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/36411\/translations\/en"},{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/36411\/translations\/es"},{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/36411\/translations\/it"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/36411\/translations\/pt"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/36411\/translations\/fr"},{"embeddable":true,"hreflang":"nl","title":"Dutch","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/36411\/translations\/nl"},{"embeddable":true,"hreflang":"ja","title":"Japanese","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/36411\/translations\/jp"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/36411\/translations\/de"},{"embeddable":true,"hreflang":"da","title":null,"href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/36411\/translations\/dk"},{"embeddable":true,"hreflang":"sv","title":null,"href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/36411\/translations\/se"},{"href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/36411\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/media\/36423"}],"wp:attachment":[{"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/media?parent=36411"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/tags?post=36411"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/topic?post=36411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}