{"id":46265,"date":"2022-01-27T04:20:22","date_gmt":"2022-01-27T07:20:22","guid":{"rendered":"https:\/\/kinsta.com\/pt\/?p=46265&#038;preview=true&#038;preview_id=46265"},"modified":"2025-02-26T10:40:05","modified_gmt":"2025-02-26T13:40:05","slug":"shopify-para-woocommerce","status":"publish","type":"post","link":"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/","title":{"rendered":"Como Migrar do Shopify para WooCommerce (Em 8 Passos)"},"content":{"rendered":"<p>Shopify \u00e9 uma excelente plataforma para o lan\u00e7amento de sua primeira loja online. Entretanto, conforme sua loja cresce, voc\u00ea provavelmente come\u00e7ar\u00e1 a notar as limita\u00e7\u00f5es que v\u00eam com esta plataforma hospedada. Se voc\u00ea sente que ultrapassou isso, migrar do Shopify para o WooCommerce \u00e9 mais f\u00e1cil do que voc\u00ea imagina.<\/p>\n<p>Com o <a href=\"https:\/\/kinsta.com\/pt\/blog\/tutorial-woocommerce\/\">WooCommerce<\/a>, voc\u00ea tem controle total sobre sua loja. Voc\u00ea pode configurar tudo, desde impostos at\u00e9 a adi\u00e7\u00e3o de m\u00e9todos de envio personalizados. Al\u00e9m disso, voc\u00ea pode publicar centenas ou milhares de produtos, todos de gra\u00e7a.<\/p>\n<p>Este artigo ir\u00e1 discutir o que voc\u00ea precisa saber para migrar o Shopify para o WooCommerce. Mostraremos atrav\u00e9s dos preparativos e o guiaremos passo a passo enquanto voc\u00ea move sua loja. Vamos come\u00e7ar a trabalhar!<\/p>\n<div><\/div><kinsta-auto-toc heading=\"Table of Contents\" exclude=\"last\" list-style=\"arrow\" selector=\"h2\" count-number=\"-1\"><\/kinsta-auto-toc>\n<h3>Confira nosso <a href=\"https:\/\/www.youtube.com\/watch?v=HvP21obqCg4\">guia em v\u00eddeo<\/a> para migrar do Shopify para o WooCommerce<\/h3>\n<kinsta-video src=\"https:\/\/www.youtube.com\/watch?v=HvP21obqCg4\"><\/kinsta-video>\n<h2>Por que voc\u00ea deve considerar migrar o Shopify para WooCommerce<\/h2>\n<p>A principal raz\u00e3o de <a href=\"https:\/\/kinsta.com\/pt\/blog\/woocommerce-vs-shopify\/\">migrar o Shopify para WooCommerce<\/a> \u00e9 que este \u00faltimo \u00e9 constru\u00eddo em cima do <a href=\"https:\/\/kinsta.com\/pt\/blog\/o-que-wordpress\/\">software de c\u00f3digo aberto<\/a>. Ele usa WordPress, permitindo que voc\u00ea <a href=\"https:\/\/kinsta.com\/pt\/blog\/porque-usar-o-wordpress\/\">crie qualquer site<\/a> que voc\u00ea queira em qualquer plataforma de hospedagem de sua escolha. <a href=\"https:\/\/kinsta.com\/pt\/blog\/alternativas-shopify\/\">Ao contr\u00e1rio do Shopify<\/a>, o WooCommerce n\u00e3o lhe cobra para desbloquear recursos. Voc\u00ea tamb\u00e9m n\u00e3o precisar\u00e1 pagar nenhuma taxa de processamento para vender produtos.<\/p>\n<p>Voc\u00ea ainda precisa pagar por hospedagem se voc\u00ea estiver usando WordPress e WooCommerce juntos. No entanto, voc\u00ea n\u00e3o est\u00e1 vinculado a nenhuma plataforma espec\u00edfica. Portanto, voc\u00ea pode escolher o host que mais se encaixa em suas necessidades gerais.<\/p>\n<h2>Considera\u00e7\u00f5es antes de migrar do Shopify para WooCommerce<\/h2>\n<p>Sempre que voc\u00ea planeja migrar um site de uma plataforma para outra, voc\u00ea precisa considerar v\u00e1rios fatores. Por exemplo, voc\u00ea pode precisar pensar em hospedagem, backup de seus dados e muito mais. Vamos passar por cada um desses fatores um a um.<\/p>\n<h3>Encontrando um provedor de hospedagem WordPress amig\u00e1vel<\/h3>\n<p>Se voc\u00ea j\u00e1 est\u00e1 comprometido com o uso do WordPress e WooCommerce, voc\u00ea provavelmente vai querer encontrar um provedor de hospedagem web sob medida para o Sistema de Gerenciamento de Conte\u00fado (CMS &#8211; Content Management System). Devido \u00e0 popularidade da plataforma, voc\u00ea vai encontrar muitas op\u00e7\u00f5es de hospedagem <a href=\"https:\/\/kinsta.com\/pt\/ebooks\/wordpress\/hospedagem-gerenciada-wordpress\/\">projetadas para usu\u00e1rios WordPress<\/a>.<\/p>\n<p><a href=\"https:\/\/kinsta.com\/pt\/comparacao-kinsta\/\">Kinsta \u00e9 um desses web host<\/a>. Oferecemos uma ampla gama de <a href=\"https:\/\/kinsta.com\/pt\/hospedagem-wordpress\/\">planos de hospedagem otimizados para WordPress<\/a> e WooCommerce. Independente do pacote Kinsta que voc\u00ea escolher, voc\u00ea ter\u00e1 acesso aos recursos avan\u00e7ados que voc\u00ea precisa para rodar e expandir sua loja online.<\/p>\n<p>Nossos planos de hospedagem incluem as seguintes caracter\u00edsticas:<\/p>\n<ul>\n<li><a href=\"https:\/\/kinsta.com\/pt\/blog\/o-que-e-ssd\/\">Armazenamento SSD<\/a><\/li>\n<li>Otimiza\u00e7\u00e3o para sites de alto tr\u00e1fego<\/li>\n<li><a href=\"https:\/\/kinsta.com\/docs\/wordpress-hosting\/wordpress-backups\/#wordpress-backup\">Backups di\u00e1rios autom\u00e1ticos<\/a><\/li>\n<li>Suporte 24 horas por dia e remo\u00e7\u00e3o de malware<\/li>\n<li>Funcionalidade de <a href=\"https:\/\/kinsta.com\/pt\/docs\/hospedagem-de-wordpress\/ambiente-de-teste\/\">ambiente de teste<\/a><\/li>\n<li><a href=\"https:\/\/kinsta.com\/pt\/blog\/como-funciona-o-ssl\/\">Certificados SSL<\/a> gratuitos<\/li>\n<\/ul>\n<p>Naturalmente, n\u00f3s recomendamos que voc\u00ea fa\u00e7a sua pesquisa antes de se estabelecer em um provedor de hospedagem para sua loja. Desde que voc\u00ea opte por um web host <a href=\"https:\/\/kinsta.com\/pt\/blog\/hospedagem-wordpress-barata\/\">com boa reputa\u00e7\u00e3o<\/a>, voc\u00ea ainda ter\u00e1 acesso a todos os recursos que o WordPress e o WooCommerce oferecem.<\/p>\n<h3>Fa\u00e7a backup da sua loja Shopify<\/h3>\n<p>Sempre que voc\u00ea fizer mudan\u00e7as significativas em uma loja online, \u00e9 uma \u00f3tima id\u00e9ia fazer backup de<a href=\"https:\/\/kinsta.com\/docs\/wordpress-hosting\/wordpress-backups\/#wordpress-backup\/\"> todos os seus dados<\/a> de antem\u00e3o. Uma das desvantagens de usar o Shopify \u00e9 que a plataforma n\u00e3o oferece funcionalidade de backup.<\/p>\n<p>Shopify permite que voc\u00ea exporte dados de produtos no formato CSV (que vir\u00e1 a calhar durante <a href=\"https:\/\/kinsta.com\/pt\/blog\/migracao-wordpress\/\">o processo de migra\u00e7\u00e3o<\/a>). Entretanto, voc\u00ea n\u00e3o pode fazer backup do resto dos detalhes e do design da sua loja usando as fun\u00e7\u00f5es embutidas da plataforma.<\/p>\n<p>Se voc\u00ea quiser acesso a funcionalidades reais de backup, voc\u00ea precisar\u00e1 recorrer ao <a href=\"https:\/\/apps.shopify.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Shopify App Store<\/a>. Aqui, voc\u00ea encontrar\u00e1 ferramentas que adicionam funcionalidade b\u00e1sica de backup ao Shopify, como o <a href=\"https:\/\/apps.shopify.com\/backup\" target=\"_blank\" rel=\"noopener noreferrer\">Rewind Backups<\/a>:<\/p>\n<figure style=\"width: 1205px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/rewind-backups.png\" alt=\"Rewind Backups\" width=\"1205\" height=\"475\"><figcaption class=\"wp-caption-text\">Rewind Backups<\/figcaption><\/figure>\n<p>\u00c9 importante notar que mesmo com aplicativos como o Rewind Backups, voc\u00ea pode n\u00e3o ser capaz de criar c\u00f3pias completas da sua loja Shopify. Voc\u00ea tamb\u00e9m n\u00e3o pode usar os aplicativos de backup Shopify para migrar a sua loja.<\/p>\n<p>A migra\u00e7\u00e3o do Shopify para o WooCommerce \u00e9 um processo teoricamente livre de riscos para a sua loja existente. Voc\u00ea n\u00e3o perder\u00e1 nenhum dado da sua loja, mas ainda \u00e9 uma boa id\u00e9ia fazer backup dos dados de qualquer site em caso de problemas.<\/p>\n\n<h2>Como migrar do Shopify para WooCommerce (em 8 passos)<\/h2>\n<p>Agora que voc\u00ea tem um web host instalado, \u00e9 hora de come\u00e7ar a mudar sua loja do Shopify para WooCommerce. Esse processo envolve a migra\u00e7\u00e3o de todos os produtos de sua loja e recriar seu layout e design no WooCommerce. No entanto, antes de chegarmos a isso, precisamos configurar o WordPress.<\/p>\n<h3>Passo 1: Configure o WordPress<\/h3>\n<p>O WordPress oferece v\u00e1rios m\u00e9todos de instala\u00e7\u00e3o, dependendo do tipo de web host que voc\u00ea estiver usando. Por exemplo, hospedagens gerenciadas de WordPress frequentemente configuram o CMS automaticamente quando voc\u00ea cria um novo site:<\/p>\n<figure style=\"width: 1016px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/new-website-kinsta-1.png\" alt=\"Instala\u00e7\u00e3o\/Site WordPress no MyKinsta\" width=\"1016\" height=\"508\"><figcaption class=\"wp-caption-text\">Instala\u00e7\u00e3o\/Site WordPress no MyKinsta<\/figcaption><\/figure>\n<p>Se o seu web host n\u00e3o oferece instala\u00e7\u00e3o autom\u00e1tica do WordPress, n\u00f3s recomendamos que voc\u00ea verifique seu painel de controle de hospedagem. Aqui, voc\u00ea pode ter acesso a um instalador de software como o <a href=\"https:\/\/softaculous.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Softaculous<\/a>, que permitir\u00e1 que voc\u00ea configure o WordPress em poucos minutos.<\/p>\n<p>Alternativamente, voc\u00ea tamb\u00e9m pode baixar e <a href=\"https:\/\/kinsta.com\/pt\/docs\/hospedagem-de-wordpress\/como-comecar-wordpress\/instalacao-manual-wordpress\/\">configurar o WordPress manualmente<\/a>, o que \u00e9 mais simples do que poderia parecer. O software est\u00e1 dispon\u00edvel para <a href=\"https:\/\/wordpress.org\/download\/\" target=\"_blank\" rel=\"noopener noreferrer\">download no WordPress.org<\/a>. Ele tamb\u00e9m vem com um famoso <a href=\"https:\/\/kinsta.com\/pt\/docs\/hospedagem-de-wordpress\/como-comecar-wordpress\/instalacao-manual-wordpress\/\">instalador de &#8216;cinco minutos&#8217;<\/a> que o acompanha durante todo o processo uma vez que voc\u00ea carrega os arquivos para o seu servidor.<\/p>\n<h3>Passo 2: Instale o WooCommerce<\/h3>\n<p>Assim que voc\u00ea instalar o WordPress, voc\u00ea ter\u00e1 acesso ao painel de controle. Daqui, voc\u00ea tem controle completo sobre as configura\u00e7\u00f5es, layout e o conte\u00fado que voc\u00ea publica no seu site:<\/p>\n<figure style=\"width: 1260px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/wordpress-dashboard.png\" alt=\"Painel de controle WordPress\" width=\"1260\" height=\"678\"><figcaption class=\"wp-caption-text\">Painel de controle WordPress<\/figcaption><\/figure>\n<p>Como voc\u00ea quer se mudar para uma loja online, primeiro voc\u00ea precisar\u00e1 instalar o WooCommerce. Para fazer isso, v\u00e1 para <strong>Plugins <\/strong><em>&gt;<\/em><strong> Add New <\/strong>e digite &#8220;WooCommerce&#8221; na barra de pesquisa na parte superior da tela.<\/p>\n<p>O WooCommerce deve aparecer como um dos primeiros resultados que voc\u00ea v\u00ea:<\/p>\n<figure style=\"width: 1255px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/install-woocommerce.png\" alt=\"Encontre o plugin do WooCommerce para instal\u00e1-lo\" width=\"1255\" height=\"502\"><figcaption class=\"wp-caption-text\">Encontre o plugin WooCommerce<\/figcaption><\/figure>\n<p>Clique no bot\u00e3o <strong>Install Now<\/strong><strong>\u00a0<\/strong>ao lado da op\u00e7\u00e3o WooCommerce. Em seguida, aguarde o WordPress fazer o download e instale o plugin.<\/p>\n<p>Este processo acontecer\u00e1 em segundo plano, portanto n\u00e3o deixe a p\u00e1gina at\u00e9 que o bot\u00e3o <strong>Activate\u00a0<\/strong>apare\u00e7a ao lado do WooCommerce. Uma vez que isso aconte\u00e7a, clique sobre ele:<\/p>\n<figure style=\"width: 1245px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/activate-woocommerce.png\" alt=\"Ativar o plugin WooCommerce\" width=\"1245\" height=\"431\"><figcaption class=\"wp-caption-text\">Ativar o plugin WooCommerce<\/figcaption><\/figure>\n<p>\u00c9 isso a\u00ed! Agora o WooCommerce est\u00e1 pronto e pronto para usar. Isso significa que voc\u00ea pode <a href=\"https:\/\/kinsta.com\/pt\/blog\/tutorial-woocommerce\/\">come\u00e7ar a publicar e vender produtos<\/a>. Entretanto, voc\u00ea j\u00e1 tem uma lista completa de produtos no Shopify, ent\u00e3o vamos mudar seu cat\u00e1logo para WooCommerce.<\/p>\n<h3>Passo 3: Exporte os produtos do Shopify<\/h3>\n<p>Como mencionamos anteriormente, Shopify permite que voc\u00ea exporte todo o seu cat\u00e1logo de produtos no formato CSV. Este arquivo inclui t\u00edtulos, slugs, tags, variantes e pre\u00e7os para os produtos que voc\u00ea migrar.<\/p>\n<p>Para exportar seus dados de produtos Shopify, v\u00e1 at\u00e9 sua conta e navegue at\u00e9 <strong>Product &gt; All Products<\/strong>. Esta p\u00e1gina mostrar\u00e1 uma lista completa de todos os produtos em sua loja. Ela tamb\u00e9m inclui op\u00e7\u00f5es para importar e exportar dados:<\/p>\n<figure style=\"width: 956px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/export-shopify-products.png\" alt=\"Encontre produtos no Shopify para exportar\" width=\"956\" height=\"564\"><figcaption class=\"wp-caption-text\">Encontre produtos no Shopify para exportar<\/figcaption><\/figure>\n<p>Selecione o bot\u00e3o <strong>Export<\/strong><strong>\u00a0<\/strong>no topo da tela, e o Shopify perguntar\u00e1 quais produtos voc\u00ea quer exportar. Clique em <strong>All products<\/strong><strong>\u00a0<\/strong>e selecione a op\u00e7\u00e3o <strong>CSV for Excel, Numbers, or other spreadsheet programs<\/strong><strong>\u00a0<\/strong>em <strong>Export as<\/strong>:<\/p>\n<figure style=\"width: 1255px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/export-csv-file.png\" alt=\"Exportar como CSV\" width=\"1255\" height=\"811\"><figcaption class=\"wp-caption-text\">Exportar como CSV<\/figcaption><\/figure>\n<p>Uma vez que voc\u00ea clique em <strong>Export products<\/strong>, Shopify compilar\u00e1 um arquivo CSV incluindo todos os dados do seu produto e o enviar\u00e1 para voc\u00ea via e-mail. Esse e-mail pode demorar um pouco para chegar, dependendo do tamanho do seu invent\u00e1rio:<\/p>\n<figure style=\"width: 956px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/shopify-export-email.png\" alt=\"Aguarde que seu arquivo CSV seja compilado\" width=\"956\" height=\"408\"><figcaption class=\"wp-caption-text\">Aguarde que seu arquivo CSV seja compilado<\/figcaption><\/figure>\n<p>O e-mail do Shopify incluir\u00e1 um link para baixar o arquivo CSV que cont\u00e9m todas as informa\u00e7\u00f5es do seu produto. Salve esse arquivo em seu computador porque voc\u00ea vai precisar dele para o pr\u00f3ximo passo.<\/p>\n<h3>Passo 4: Importe seus produtos Shopify para WordPress<\/h3>\n<p>Este passo \u00e9 um dos mais importantes. H\u00e1 duas maneiras de importar produtos Shopify para WooCommerce. P primeiro m\u00e9todo \u00e9 usar o importador de produtos embutido que o WooCommerce usa, e o outro \u00e9 atrav\u00e9s de um servi\u00e7o de migra\u00e7\u00e3o.<\/p>\n<p>Vamos rever as duas abordagens, come\u00e7ando com a op\u00e7\u00e3o manual.<\/p>\n<h4>Use o importador de produtos WooCommerce<\/h4>\n<p>O WooCommerce vem com uma ferramenta que permite que voc\u00ea importe listas de produtos em formato CSV. Voc\u00ea baixou todo o seu cat\u00e1logo Shopify em um \u00fanico arquivo CSV durante o passo anterior, tornando este um processo simples.<\/p>\n<p>O lado negativo desta abordagem \u00e9 que voc\u00ea est\u00e1 importando apenas produtos. Todos os dados da sua loja, tais como clientes, hist\u00f3rico de pedidos, imagens e revis\u00f5es, permanecer\u00e3o no Shopify. Em ess\u00eancia, voc\u00ea est\u00e1 come\u00e7ando de novo usando o WooCommerce com seu estoque existente e um quadro de loja em branco.<\/p>\n<p>Se isso n\u00e3o \u00e9 um quebra-galho, vamos em frente e importe aquele arquivo Shopify CSV no WooCommerce. Acesse o painel do WordPress e v\u00e1 em <strong>Ferramentas &gt; Importar<\/strong>.<\/p>\n<p>Procure a op\u00e7\u00e3o de <strong>produtos WooCommerce (CSV) <\/strong>e clique em <strong>Executar importador<\/strong>:<\/p>\n<figure style=\"width: 1199px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/run-woocommerce-importer.png\" alt=\"Importador de produtos WooCommerce\" width=\"1199\" height=\"459\"><figcaption class=\"wp-caption-text\">Importador de produtos WooCommerce<\/figcaption><\/figure>\n<p>Na pr\u00f3xima p\u00e1gina, o WooCommerce ir\u00e1 pedir que voc\u00ea escolha o arquivo que voc\u00ea quer importar. H\u00e1 tamb\u00e9m uma op\u00e7\u00e3o para atualizar produtos existentes usando os dados de um arquivo CSV. Deixe isso desmarcado j\u00e1 que estamos come\u00e7ando com um invent\u00e1rio limpo:<\/p>\n<figure style=\"width: 943px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/choose-csv-file.png\" alt=\"Escolha os produtos que voc\u00ea quer importar\" width=\"943\" height=\"616\"><figcaption class=\"wp-caption-text\">Escolha os produtos que voc\u00ea quer importar<\/figcaption><\/figure>\n<p>Selecione o arquivo CSV que voc\u00ea baixou durante o terceiro passo e clique em <strong>Continuar<\/strong>. A pr\u00f3xima tela inclui v\u00e1rias op\u00e7\u00f5es para combinar os dados do produto do arquivo CSV com os campos do WooCommerce:<\/p>\n<figure style=\"width: 905px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/map-shopify-data-to-woocommerce.png\" alt=\"Combinar dados de produtos do arquivo CSV com os campos do WooCommerce\" width=\"905\" height=\"696\"><figcaption class=\"wp-caption-text\">Combinar dados de produtos do arquivo CSV com os campos do WooCommerce<\/figcaption><\/figure>\n<p>Percorra essa lista de op\u00e7\u00f5es e decida quais dados voc\u00ea quer importar no WooCommerce e quais voc\u00ea se sente confort\u00e1vel em deixar de fora. Alguns campos, tais como <strong>T\u00edtulo SEO <\/strong>e <strong>Descri\u00e7\u00e3o SEO, <\/strong>n\u00e3o t\u00eam op\u00e7\u00f5es correspondentes no WooCommerce, de modo que voc\u00ea pode exclu\u00ed-los.<\/p>\n<p>Quando voc\u00ea estiver satisfeito com suas escolhas, clique em <strong>Executar importador<\/strong>. O WooCommerce levar\u00e1 um minuto (ou mais) para importar os dados do seu produto Shopify.<\/p>\n<p>Quando o processo terminar, voc\u00ea ver\u00e1 uma mensagem de sucesso que se parece com esta:<\/p>\n<figure style=\"width: 925px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/successful-woocommerce-import.png\" alt=\"O processo de importa\u00e7\u00e3o do produto est\u00e1 completo\" width=\"925\" height=\"595\"><figcaption class=\"wp-caption-text\">O processo de importa\u00e7\u00e3o do produto est\u00e1 completo<\/figcaption><\/figure>\n<p>Se voc\u00ea clicar em <strong>Ver produtos<\/strong>, o WordPress o enviar\u00e1 para a aba <strong>Produtos &gt; Todos os produtos<\/strong>. Aqui, voc\u00ea ver\u00e1 uma vis\u00e3o geral de todos os itens que voc\u00ea acabou de importar:<\/p>\n<figure style=\"width: 1042px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/imported-product-data.png\" alt=\"Vis\u00e3o geral dos produtos importados\" width=\"1042\" height=\"825\"><figcaption class=\"wp-caption-text\">Vis\u00e3o geral dos produtos importados<\/figcaption><\/figure>\n<p>Lembre-se que o WooCommerce n\u00e3o importa imagens de produtos, ent\u00e3o voc\u00ea deve carreg\u00e1-las manualmente. Tamb\u00e9m recomendamos verificar cada entrada de item para garantir que n\u00e3o est\u00e1 faltando nenhuma informa\u00e7\u00e3o cr\u00edtica.<\/p>\n<p>Se faltarem dados do produto, voc\u00ea pode sempre reexecutar o importador e ter certeza de que voc\u00ea est\u00e1 portando os campos corretos para WooCommerce. Em geral, usar o importador manual \u00e9 simples, mas requer alguma microgest\u00e3o em seu lado.<\/p>\n<h4>Use um servi\u00e7o para importar dados do Shopify para WooCommerce<\/h4>\n<p>Migrar do Shopify para WooCommerce \u00e9 comum. Existem plugins e servi\u00e7os completos dedicados para simplificar o processo. A vantagem de usar <a href=\"https:\/\/kinsta.com\/pt\/blog\/plugins-de-migracao-wordpress\/\">as ferramentas de migra\u00e7\u00e3o<\/a> do Shopify \u00e9 que elas automatizam todo o processo <em>e <\/em>permitem voc\u00ea importar dados que voc\u00ea n\u00e3o pode com um simples arquivo CSV.<\/p>\n<p><a href=\"https:\/\/www.shopping-cart-migration.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Cart2Cart<\/a> \u00e9 uma ferramenta \u00fatil. Ele permite que voc\u00ea conecte o WooCommerce com o Shopify, migrando cada ponto de dados de uma plataforma para a outra:<\/p>\n<figure style=\"width: 1158px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/cart2cart.png\" alt=\"Cart2Cart\" width=\"1158\" height=\"516\"><figcaption class=\"wp-caption-text\">Cart2Cart<\/figcaption><\/figure>\n<p>Cart2Cart oferece migra\u00e7\u00f5es gratuitas limitadas que permitem voc\u00ea mover parte do seu invent\u00e1rio Shopify para o WooCommerce. Entretanto, se voc\u00ea quiser ter acesso ao conjunto completo de recursos da ferramenta, voc\u00ea precisar\u00e1 pagar. Os pre\u00e7os variam dependendo de quantos produtos voc\u00ea quer importar e se voc\u00ea deseja incluir dados de clientes e pedidos e postagens no blog.<\/p>\n<p>Cart2Cart oferece uma <a href=\"https:\/\/www.shopping-cart-migration.com\/migration-pricing\" target=\"_blank\" rel=\"noopener noreferrer\">ferramenta de estimativa<\/a> em seu site. Entretanto, para lhe dar uma id\u00e9ia de quanto custa o servi\u00e7o, a migra\u00e7\u00e3o de uma loja Shopify completa com 100 produtos para o WooCommerce lhe daria aproximadamente US$ 120.<\/p>\n<p>Se voc\u00ea quiser usar Cart2Cart, v\u00e1 em frente e inscreva-se para uma conta. Assim que voc\u00ea acessar seu painel de controle, a plataforma lhe pedir\u00e1 para escolher tanto os carros de origem quanto os de destino.<\/p>\n<p>A fonte, neste caso, \u00e9 o Shopify, e o WooCommerce \u00e9 o destino:<\/p>\n<figure style=\"width: 1107px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/cart2cart-source-destination.png\" alt=\"Processo de configura\u00e7\u00e3o do Cart2Cart\" width=\"1107\" height=\"1108\"><figcaption class=\"wp-caption-text\">Processo de configura\u00e7\u00e3o do Cart2Cart<\/figcaption><\/figure>\n<p>Para que o importador Cart2Cart funcione, voc\u00ea precisar\u00e1 gerar uma chave API Shopify. Volte para o painel Shopify e v\u00e1 para a tela <strong>Apps <\/strong>. V\u00e1 at\u00e9 a parte inferior da p\u00e1gina e procure o link que diz <strong>Manage private apps<\/strong>:<\/p>\n<figure style=\"width: 1228px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/manage-private-apps.png\" alt=\"O link de gerenciamento de apps privado.\" width=\"1228\" height=\"556\"><figcaption class=\"wp-caption-text\">O link de gerenciamento de apps privado.<\/figcaption><\/figure>\n<p>Se voc\u00ea n\u00e3o ativou o desenvolvimento de aplicativos privados no Shopify, voc\u00ea ver\u00e1 uma tela que se parece com esta. Clique no bot\u00e3o <strong>Habilitar desenvolvimento de aplicativo privado<\/strong>:<\/p>\n<figure style=\"width: 1178px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/enable-private-app-development.png\" alt=\"Permitir o desenvolvimento de aplicativos privados no Cart2Cart\" width=\"1178\" height=\"689\"><figcaption class=\"wp-caption-text\">Habilitar o desenvolvimento de aplicativos privados.<\/figcaption><\/figure>\n<p>Shopify solicitar\u00e1 que voc\u00ea habilite o desenvolvimento de aplicativos privados. Ele tamb\u00e9m ir\u00e1 avis\u00e1-lo sobre compartilhar sua chave API com partes desconhecidas.<\/p>\n<p>Confirme sua escolha, e agora voc\u00ea ter\u00e1 a op\u00e7\u00e3o de criar um aplicativo privado:<\/p>\n<figure style=\"width: 1178px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/create-private-shopify-app.png\" alt=\"A op\u00e7\u00e3o 'Create private app'\" width=\"1178\" height=\"675\"><figcaption class=\"wp-caption-text\">A op\u00e7\u00e3o &#8216;Create private app&#8217;.<\/figcaption><\/figure>\n<p>Criar um aplicativo privado ir\u00e1 gerar a senha de API que Cart2Cart precisa para acessar Shopify e exportar seus dados.<\/p>\n<p>Primeiramente, defina um nome para seu aplicativo (isto pode ser qualquer coisa) e digite seu e-mail:<\/p>\n<figure style=\"width: 1242px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/shopify-app-details.png\" alt=\"Defina um nome para seu aplicativo e digite um e-mail\" width=\"1242\" height=\"707\"><figcaption class=\"wp-caption-text\">Defina um nome para seu aplicativo e digite um e-mail.<\/figcaption><\/figure>\n<p>V\u00e1 at\u00e9 a se\u00e7\u00e3o de permiss\u00f5es e d\u00ea ao aplicativo acesso a todas as permiss\u00f5es da lista. Voc\u00ea estar\u00e1 usando a op\u00e7\u00e3o <strong>Read and write<\/strong><strong>\u00a0<\/strong>quando dispon\u00edvel ou apenas <strong>Read access<\/strong><strong>\u00a0<\/strong>se o primeiro n\u00e3o aparecer:<\/p>\n<figure style=\"width: 1189px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/active-shopify-app-permissions.png\" alt=\"Entre com as permiss\u00f5es ativas\" width=\"1189\" height=\"668\"><figcaption class=\"wp-caption-text\">Entre com as permiss\u00f5es ativas<\/figcaption><\/figure>\n<p>Tradicionalmente, voc\u00ea n\u00e3o deve dar permiss\u00e3o total para um aplicativo. Entretanto, desde que voc\u00ea n\u00e3o compartilhe a chave API e apague o aplicativo depois, voc\u00ea deve ficar bem.<\/p>\n<p>A seguir, selecione a \u00faltima vers\u00e3o da API do webhook:<\/p>\n<figure style=\"width: 1209px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/latest-webhook-api.png\" alt=\"Webhook API version\" width=\"1209\" height=\"251\"><figcaption class=\"wp-caption-text\">Webhook API version.<\/figcaption><\/figure>\n<p>Clique em <strong>Save <\/strong>para criar o aplicativo e confirmar suas escolhas na tela que ir\u00e1 aparecer. Uma vez que o aplicativo esteja pronto e funcionando, sua senha API ficar\u00e1 dispon\u00edvel na tela de detalhes do aplicativo.<\/p>\n<p>Copie e cole a API no menu de migra\u00e7\u00e3o do Cart2Cart e entre na URL da sua loja ao lado dela:<\/p>\n<figure style=\"width: 1078px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/source-cart-api.png\" alt=\"Copiar e cole a API\" width=\"1078\" height=\"558\"><figcaption class=\"wp-caption-text\">Copiar e cole a API<\/figcaption><\/figure>\n<p>Configurar o carrinho de destino (sua loja WooCommerce) \u00e9 muito mais f\u00e1cil. Tudo que voc\u00ea tem que fazer \u00e9 inserir seus detalhes de login no WordPress (para a conta do administrador), e voc\u00ea est\u00e1 pronto para ir.<\/p>\n<p>Digite esses detalhes e clique em <strong>Escolher Entidades<\/strong>:<\/p>\n<figure style=\"width: 1077px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/target-cart-details.png\" alt=\"Digite os detalhes de login do WordPress\" width=\"1077\" height=\"735\"><figcaption class=\"wp-caption-text\">Digite os detalhes de login do WordPress<\/figcaption><\/figure>\n<p>Cart2Cart vai levar um momento para preparar o processo de migra\u00e7\u00e3o. Se as credenciais estiverem corretas, o programa ir\u00e1 perguntar quais dados voc\u00ea quer mover do Shopify para o WooCommerce:<\/p>\n<figure style=\"width: 1101px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/entities-migration.png\" alt=\"Selecione os dados apropriados que voc\u00ea deseja mover\" width=\"1101\" height=\"899\"><figcaption class=\"wp-caption-text\">Selecione os dados apropriados que voc\u00ea deseja mover.<\/figcaption><\/figure>\n<p>O servi\u00e7o tamb\u00e9m oferecer\u00e1 v\u00e1rios extras pagos para migra\u00e7\u00e3o, incluindo imagens, IDs de pedidos e muito mais. Selecione as op\u00e7\u00f5es que voc\u00ea deseja e inicie a migra\u00e7\u00e3o. Dependendo de quantos dados voc\u00ea precisa para exportar\/importar, o processo pode demorar um pouco.<\/p>\n<p>Depois disso, Cart2Cart mostrar\u00e1 uma tela de sucesso e lhe dar\u00e1 uma op\u00e7\u00e3o para enviar voc\u00ea para sua loja WooCommerce, onde voc\u00ea poder\u00e1 ver os resultados.<\/p>\n<h3>Passo 5: Aponte seu dom\u00ednio para WooCommerce<\/h3>\n<p>Nesta fase, voc\u00ea j\u00e1 deve ter uma loja WooCommerce totalmente funcional que inclua todos os seus produtos Shopify. No entanto, ainda h\u00e1 v\u00e1rias coisas para fazer, incluindo atualizar seus registros de dom\u00ednio para que eles apontem para o seu novo web host.<\/p>\n<p>Atualmente, o seu dom\u00ednio ainda est\u00e1 apontando para a sua loja Shopify. Voc\u00ea provavelmente n\u00e3o quer registrar um novo dom\u00ednio porque isso significa que voc\u00ea precisar\u00e1 come\u00e7ar a construir tr\u00e1fego do zero. Como tal, voc\u00ea pode perder uma porcentagem significativa da sua base de clientes.<\/p>\n<p>O processo da mudan\u00e7a de qual site um dom\u00ednio aponta para variar, dependendo do servi\u00e7o que voc\u00ea usa para gerenci\u00e1-lo. Se voc\u00ea <a href=\"https:\/\/kinsta.com\/pt\/blog\/melhor-registrador-de-dominios\/\">usar um registrador de dom\u00ednio<\/a>, voc\u00ea precisar\u00e1 atualizar seus registros l\u00e1. Esse processo difere de registrador para registrador:<\/p>\n<figure style=\"width: 1012px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/domain-management-1.png\" alt=\"Lista de dom\u00ednios mostrando todos os seus dom\u00ednios registrados.\" width=\"1012\" height=\"351\"><figcaption class=\"wp-caption-text\">Lista de dom\u00ednios mostrando todos os seus dom\u00ednios registrados<\/figcaption><\/figure>\n<p>Se voc\u00ea registrou um dom\u00ednio diretamente do Shopify, voc\u00ea precisaria <a href=\"https:\/\/help.shopify.com\/en\/manual\/domains\/managing-domains\/edit-dns-settings\">editar suas configura\u00e7\u00f5es de DNS<\/a> usando a plataforma. Alternativamente, alguns provedores de hospedagem como a Kinsta permitem que voc\u00ea <a href=\"https:\/\/kinsta.com\/pt\/blog\/o-que-e-um-servidor-de-nomes\/\">atualize seus registros de dom\u00ednio<\/a> a partir do seu painel de controle de hospedagem. MyKinsta, por exemplo, torna f\u00e1cil <a href=\"https:\/\/kinsta.com\/pt\/docs\/hospedagem-de-wordpress\/dominios-wordpress\/\">apontar dom\u00ednios para o seu site<\/a>.<\/p>\n<h3>Passo 6: Configure seus permalinks WordPress<\/h3>\n<p>O WordPress permite que voc\u00ea decida sua estrutura URL, inclusive para produtos WooCommerce. Por padr\u00e3o, as URLs do WordPress parecem algo parecido com isto:<\/p>\n<p><code>yourwoocommercestore.com\/?p=534<\/code><\/p>\n<p>Esse tipo de URL n\u00e3o \u00e9 amig\u00e1vel para o usu\u00e1rio. Ele tamb\u00e9m n\u00e3o favorece do ponto de vista do Search Engine Optimization (SEO).<\/p>\n<p>Para mudar a <a href=\"https:\/\/kinsta.com\/pt\/blog\/o-que-e-uma-url\/\">estrutura URL<\/a> da sua loja, v\u00e1 para <strong>Configura\u00e7\u00f5es &gt; Permalinks &gt; Permalinks de produtos <\/strong>e selecione a op\u00e7\u00e3o que voc\u00ea preferir:<\/p>\n<figure style=\"width: 1177px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/woocommerce-permalinks.png\" alt=\"Alterando a estrutura URL da loja no WordPress\" width=\"1177\" height=\"594\"><figcaption class=\"wp-caption-text\">Alterando a estrutura URL da loja no WordPress<\/figcaption><\/figure>\n<p>Na maioria dos casos, n\u00f3s recomendamos que voc\u00ea use a estrutura <strong>Padr\u00e3o<\/strong>. Com ela, a URL de um produto WooCommerce ser\u00e1 parecida com esta:<\/p>\n<p><code>yourwoocommercestore.com\/product\/sample-name<\/code><\/p>\n<p>Este tipo de URL d\u00e1 aos visitantes informa\u00e7\u00f5es sobre qual produto eles est\u00e3o vendo, for\u00e7ando voc\u00ea a usar slugs descritivas. Uma vez que voc\u00ea selecione uma estrutura permalink, salve as mudan\u00e7as no seu site WordPress.<\/p>\n<p>\u00c9 importante notar que voc\u00ea <em>precisa <\/em> <a href=\"https:\/\/kinsta.com\/pt\/blog\/permalinks-wordpress\/\">escolher uma estrutura permalink<\/a> ao iniciar sua loja WooCommerce. Mudar as estruturas de link em uma data posterior pode impactar o SEO do seu site e causar erros significativos dentro do seu site. Quanto mais cedo voc\u00ea definir uma estrutura permalink, menos dores de cabe\u00e7a voc\u00ea enfrentar\u00e1 no caminho.<\/p>\n<h3>Passo 7: Recrie o design da sua loja Shopify (ou comece de novo)<\/h3>\n<p>Se voc\u00ea verificou qualquer uma das p\u00e1ginas da sua loja WooCommerce, voc\u00ea provavelmente notou que elas n\u00e3o s\u00e3o similares do Shopify. Isso \u00e9 porque voc\u00ea ainda est\u00e1 usando um dos <a href=\"https:\/\/kinsta.com\/pt\/blog\/que-e-u-tema-wordpress\/\">temas padr\u00e3o do WordPress<\/a>.<\/p>\n<p>Nesta fase, voc\u00ea tem duas op\u00e7\u00f5es de como abordar o <a href=\"https:\/\/kinsta.com\/pt\/blog\/design-responsivo-web\/\">design da sua nova loja<\/a>:<\/p>\n<ol>\n<li>Recriando o estilo da sua loja Shopify<\/li>\n<li>Come\u00e7ando de novo com um novo modelo de WooCommerce<\/li>\n<\/ol>\n<p>Ambas as abordagens s\u00e3o v\u00e1lidas, e ambas envolvem a busca pelo <a href=\"https:\/\/kinsta.com\/pt\/blog\/temas-mais-rapidos-woocommerce\/\">tema perfeito do WooCommerce<\/a> para a sua loja. Por um lado, recriar o design da sua loja Shopify pode fazer a transi\u00e7\u00e3o perfeita para os clientes existentes.<\/p>\n<p>Por outro lado, o WordPress oferece significativamente mais <a href=\"https:\/\/kinsta.com\/pt\/blog\/como-personalizar-tema-wordpress\/\">op\u00e7\u00f5es de customiza\u00e7\u00e3o<\/a> do que o Shopify. Com o CMS, voc\u00ea tem acesso a v\u00e1rios <a href=\"https:\/\/kinsta.com\/pt\/blog\/construtores-de-paginas-wordpress\/\">plugins de constru\u00e7\u00e3o de p\u00e1ginas<\/a> que <a href=\"https:\/\/kinsta.com\/pt\/blog\/plugins-woocommerce\/\">funcionam com o WooCommerce<\/a> e permitem que voc\u00ea personalize sua loja da maneira que voc\u00ea achar melhor.<\/p>\n<p>Para personalizar sua loja, voc\u00ea tamb\u00e9m pode <a href=\"https:\/\/kinsta.com\/pt\/blog\/editor-gutenberg-wordpress\/\">usar o Block Editor embutido<\/a> com um <a href=\"https:\/\/kinsta.com\/blog\/wordpress-free-vs-paid-themes\/\">tema amig\u00e1vel ao WooCommerce<\/a>. Qualquer uma das abordagens \u00e9 vi\u00e1vel. Ent\u00e3o, decida o que fazer com todos os recursos que o WordPress e o WooCommerce oferecem a voc\u00ea!<\/p>\n<h3>Passo 8: Configure suas configura\u00e7\u00f5es do WooCommerce<\/h3>\n<p>Importar produtos para o WooCommerce e customizar o estilo da sua loja \u00e9 apenas o come\u00e7o. Antes de voc\u00ea poder come\u00e7ar a vender produtos no WooCommerce, voc\u00ea ainda precisa configurar uma variedade de configura\u00e7\u00f5es, inclusive:<\/p>\n<ul>\n<li>Op\u00e7\u00f5es de pagamento e envio<\/li>\n<li>Configura\u00e7\u00f5es de seguran\u00e7a<\/li>\n<li>Op\u00e7\u00f5es de notifica\u00e7\u00e3o por e-mail<\/li>\n<li>Configura\u00e7\u00f5es do produto<\/li>\n<li>Op\u00e7\u00f5es de impostos<\/li>\n<\/ul>\n<p>Se voc\u00ea se lembrar do processo de configura\u00e7\u00e3o da sua loja Shopify, todas essas configura\u00e7\u00f5es devem soar familiares. Entretanto, o WooCommerce lhe d\u00e1 muito mais controle sobre como voc\u00ea configura a sua loja online:<\/p>\n<figure style=\"width: 1115px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/kinsta.com\/wp-content\/uploads\/2021\/12\/woocommerce-settings.png\" alt=\"Configura\u00e7\u00f5es do WooCommerce.\" width=\"1115\" height=\"453\"><figcaption class=\"wp-caption-text\">Configura\u00e7\u00f5es do WooCommerce.<\/figcaption><\/figure>\n<p>A documenta\u00e7\u00e3o oficial do WooCommerce inclui um guia completo sobre <a href=\"https:\/\/docs.woocommerce.com\/document\/configuring-woocommerce-settings\/\" target=\"_blank\" rel=\"noopener noreferrer\">como configurar suas configura\u00e7\u00f5es<\/a>. Uma vez que voc\u00ea tenha terminado de ajustar as configura\u00e7\u00f5es da sua loja, recomendamos verificar algumas <a href=\"https:\/\/kinsta.com\/pt\/blog\/extensoes-woocommerce\/\">extens\u00f5es do WooCommerce<\/a>.<\/p>\n\n<h2>Resumo<\/h2>\n<p>Migrar do Shopify para WooCommerce envolve muito trabalho. Voc\u00ea n\u00e3o s\u00f3 precisa importar e exportar produtos de uma loja para outra, mas voc\u00ea tamb\u00e9m tem que redesenhar todo o seu site a partir do zero. Felizmente, <a href=\"https:\/\/kinsta.com\/pt\/blog\/aprender-wordpress\/\">o WordPress torna mais f\u00e1cil<\/a> para voc\u00ea ter sua nova loja com a apar\u00eancia que voc\u00ea deseja.<\/p>\n<p>Com o WooCommerce, voc\u00ea tem muito mais controle sobre sua loja do que o Shopify oferece. Isto \u00e9 gra\u00e7as \u00e0 natureza open-source do WordPress e sua popularidade massiva. Portanto, voc\u00ea provavelmente nunca ficar\u00e1 sem novos recursos para experimentar em sua loja.<\/p>\n<p><em>Voc\u00ea tem alguma pergunta sobre como migrar o Shopify para WooCommerce? Pergunte na se\u00e7\u00e3o de coment\u00e1rios abaixo!<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shopify \u00e9 uma excelente plataforma para o lan\u00e7amento de sua primeira loja online. Entretanto, conforme sua loja cresce, voc\u00ea provavelmente come\u00e7ar\u00e1 a notar as limita\u00e7\u00f5es que &#8230;<\/p>\n","protected":false},"author":117,"featured_media":46266,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kinsta_gated_content":false,"_kinsta_gated_content_redirect":"","footnotes":""},"tags":[74,44],"topic":[1026,1027,989],"class_list":["post-46265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-cms","tag-webdev","topic-desenvolvimento-wordpress","topic-ecommerce-no-wordpress","topic-migrar-para-wordpress"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.6 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como Migrar do Shopify para WooCommerce (Em 8 Passos)<\/title>\n<meta name=\"description\" content=\"Voc\u00ea est\u00e1 pronto para mudar sua loja de eCommerce? Aprenda como migrar do Shopify para WooCommerce neste guia detalhado e f\u00e1cil de seguir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como Migrar do Shopify para WooCommerce (Em 8 Passos)\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea est\u00e1 pronto para mudar sua loja de eCommerce? Aprenda como migrar do Shopify para WooCommerce neste guia detalhado e f\u00e1cil de seguir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinsta\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kinstapt\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-27T07:20:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-26T13:40:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/01\/shopify-to-woocommerce.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1460\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Salman Ravoof\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Voc\u00ea est\u00e1 pronto para mudar sua loja de eCommerce? Aprenda como migrar do Shopify para WooCommerce neste guia detalhado e f\u00e1cil de seguir.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/01\/shopify-to-woocommerce.png\" \/>\n<meta name=\"twitter:creator\" content=\"@salmanravoof\" \/>\n<meta name=\"twitter:site\" content=\"@kinsta_pt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Salman Ravoof\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"21 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/\"},\"author\":{\"name\":\"Salman Ravoof\",\"@id\":\"https:\/\/kinsta.com\/pt\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987\"},\"headline\":\"Como Migrar do Shopify para WooCommerce (Em 8 Passos)\",\"datePublished\":\"2022-01-27T07:20:22+00:00\",\"dateModified\":\"2025-02-26T13:40:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/\"},\"wordCount\":3778,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/pt\/#organization\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/01\/shopify-to-woocommerce.png\",\"keywords\":[\"CMS\",\"webdev\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/\",\"url\":\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/\",\"name\":\"Como Migrar do Shopify para WooCommerce (Em 8 Passos)\",\"isPartOf\":{\"@id\":\"https:\/\/kinsta.com\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/01\/shopify-to-woocommerce.png\",\"datePublished\":\"2022-01-27T07:20:22+00:00\",\"dateModified\":\"2025-02-26T13:40:05+00:00\",\"description\":\"Voc\u00ea est\u00e1 pronto para mudar sua loja de eCommerce? Aprenda como migrar do Shopify para WooCommerce neste guia detalhado e f\u00e1cil de seguir.\",\"breadcrumb\":{\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#primaryimage\",\"url\":\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/01\/shopify-to-woocommerce.png\",\"contentUrl\":\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/01\/shopify-to-woocommerce.png\",\"width\":1460,\"height\":730,\"caption\":\"Como Migrar de Shopify para WooCommerce (em 8 Passos)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kinsta.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Migrar para WordPress\",\"item\":\"https:\/\/kinsta.com\/pt\/topicos\/migrar-para-wordpress\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Como Migrar do Shopify para WooCommerce (Em 8 Passos)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kinsta.com\/pt\/#website\",\"url\":\"https:\/\/kinsta.com\/pt\/\",\"name\":\"Kinsta\u00ae\",\"description\":\"Solu\u00e7\u00f5es de hospedagem Premium, r\u00e1pida e segura\",\"publisher\":{\"@id\":\"https:\/\/kinsta.com\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kinsta.com\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kinsta.com\/pt\/#organization\",\"name\":\"Kinsta\",\"url\":\"https:\/\/kinsta.com\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/kinsta.com\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg\",\"contentUrl\":\"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg\",\"width\":500,\"height\":500,\"caption\":\"Kinsta\"},\"image\":{\"@id\":\"https:\/\/kinsta.com\/pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kinstapt\/\",\"https:\/\/x.com\/kinsta_pt\",\"https:\/\/www.instagram.com\/kinstahosting\/\",\"https:\/\/www.linkedin.com\/company\/kinsta\/\",\"https:\/\/www.pinterest.com\/kinstahosting\/\",\"https:\/\/www.youtube.com\/c\/Kinsta\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/kinsta.com\/pt\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987\",\"name\":\"Salman Ravoof\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/kinsta.com\/pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g\",\"caption\":\"Salman Ravoof\"},\"description\":\"Salman Ravoof is a self-taught web developer, writer, creator, and a huge admirer of Free and Open Source Software (FOSS). Besides tech, he's excited by science, philosophy, photography, arts, cats, and food. Learn more about him on his website, and connect with Salman on Twitter.\",\"sameAs\":[\"https:\/\/salmanravoof.com\",\"https:\/\/www.linkedin.com\/in\/salman-ravoof-5a749133\/\",\"https:\/\/x.com\/salmanravoof\"],\"url\":\"https:\/\/kinsta.com\/pt\/blog\/author\/salmanravoof\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Como Migrar do Shopify para WooCommerce (Em 8 Passos)","description":"Voc\u00ea est\u00e1 pronto para mudar sua loja de eCommerce? Aprenda como migrar do Shopify para WooCommerce neste guia detalhado e f\u00e1cil de seguir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/","og_locale":"pt_PT","og_type":"article","og_title":"Como Migrar do Shopify para WooCommerce (Em 8 Passos)","og_description":"Voc\u00ea est\u00e1 pronto para mudar sua loja de eCommerce? Aprenda como migrar do Shopify para WooCommerce neste guia detalhado e f\u00e1cil de seguir.","og_url":"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/","og_site_name":"Kinsta\u00ae","article_publisher":"https:\/\/www.facebook.com\/kinstapt\/","article_published_time":"2022-01-27T07:20:22+00:00","article_modified_time":"2025-02-26T13:40:05+00:00","og_image":[{"width":1460,"height":730,"url":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/01\/shopify-to-woocommerce.png","type":"image\/png"}],"author":"Salman Ravoof","twitter_card":"summary_large_image","twitter_description":"Voc\u00ea est\u00e1 pronto para mudar sua loja de eCommerce? Aprenda como migrar do Shopify para WooCommerce neste guia detalhado e f\u00e1cil de seguir.","twitter_image":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/01\/shopify-to-woocommerce.png","twitter_creator":"@salmanravoof","twitter_site":"@kinsta_pt","twitter_misc":{"Escrito por":"Salman Ravoof","Tempo estimado de leitura":"21 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#article","isPartOf":{"@id":"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/"},"author":{"name":"Salman Ravoof","@id":"https:\/\/kinsta.com\/pt\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987"},"headline":"Como Migrar do Shopify para WooCommerce (Em 8 Passos)","datePublished":"2022-01-27T07:20:22+00:00","dateModified":"2025-02-26T13:40:05+00:00","mainEntityOfPage":{"@id":"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/"},"wordCount":3778,"commentCount":0,"publisher":{"@id":"https:\/\/kinsta.com\/pt\/#organization"},"image":{"@id":"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/01\/shopify-to-woocommerce.png","keywords":["CMS","webdev"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/","url":"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/","name":"Como Migrar do Shopify para WooCommerce (Em 8 Passos)","isPartOf":{"@id":"https:\/\/kinsta.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#primaryimage"},"image":{"@id":"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#primaryimage"},"thumbnailUrl":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/01\/shopify-to-woocommerce.png","datePublished":"2022-01-27T07:20:22+00:00","dateModified":"2025-02-26T13:40:05+00:00","description":"Voc\u00ea est\u00e1 pronto para mudar sua loja de eCommerce? Aprenda como migrar do Shopify para WooCommerce neste guia detalhado e f\u00e1cil de seguir.","breadcrumb":{"@id":"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#primaryimage","url":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/01\/shopify-to-woocommerce.png","contentUrl":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2022\/01\/shopify-to-woocommerce.png","width":1460,"height":730,"caption":"Como Migrar de Shopify para WooCommerce (em 8 Passos)"},{"@type":"BreadcrumbList","@id":"https:\/\/kinsta.com\/pt\/blog\/shopify-para-woocommerce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kinsta.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Migrar para WordPress","item":"https:\/\/kinsta.com\/pt\/topicos\/migrar-para-wordpress\/"},{"@type":"ListItem","position":3,"name":"Como Migrar do Shopify para WooCommerce (Em 8 Passos)"}]},{"@type":"WebSite","@id":"https:\/\/kinsta.com\/pt\/#website","url":"https:\/\/kinsta.com\/pt\/","name":"Kinsta\u00ae","description":"Solu\u00e7\u00f5es de hospedagem Premium, r\u00e1pida e segura","publisher":{"@id":"https:\/\/kinsta.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kinsta.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/kinsta.com\/pt\/#organization","name":"Kinsta","url":"https:\/\/kinsta.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/kinsta.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg","contentUrl":"https:\/\/kinsta.com\/pt\/wp-content\/uploads\/sites\/3\/2023\/12\/kinsta-logo.jpeg","width":500,"height":500,"caption":"Kinsta"},"image":{"@id":"https:\/\/kinsta.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kinstapt\/","https:\/\/x.com\/kinsta_pt","https:\/\/www.instagram.com\/kinstahosting\/","https:\/\/www.linkedin.com\/company\/kinsta\/","https:\/\/www.pinterest.com\/kinstahosting\/","https:\/\/www.youtube.com\/c\/Kinsta"]},{"@type":"Person","@id":"https:\/\/kinsta.com\/pt\/#\/schema\/person\/9cafd2eedd617e640eeea4cf3a5fd987","name":"Salman Ravoof","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/kinsta.com\/pt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c5885f75cb78473fb7408e5e49ad190?s=96&d=mm&r=g","caption":"Salman Ravoof"},"description":"Salman Ravoof is a self-taught web developer, writer, creator, and a huge admirer of Free and Open Source Software (FOSS). Besides tech, he's excited by science, philosophy, photography, arts, cats, and food. Learn more about him on his website, and connect with Salman on Twitter.","sameAs":["https:\/\/salmanravoof.com","https:\/\/www.linkedin.com\/in\/salman-ravoof-5a749133\/","https:\/\/x.com\/salmanravoof"],"url":"https:\/\/kinsta.com\/pt\/blog\/author\/salmanravoof\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/posts\/46265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/comments?post=46265"}],"version-history":[{"count":10,"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/posts\/46265\/revisions"}],"predecessor-version":[{"id":53653,"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/posts\/46265\/revisions\/53653"}],"alternate":[{"embeddable":true,"hreflang":"en","title":"English","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/46265\/translations\/en"},{"embeddable":true,"hreflang":"de","title":"German","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/46265\/translations\/de"},{"embeddable":true,"hreflang":"it","title":"Italian","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/46265\/translations\/it"},{"embeddable":true,"hreflang":"fr","title":"French","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/46265\/translations\/fr"},{"embeddable":true,"hreflang":"pt","title":"Portuguese","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/46265\/translations\/pt"},{"embeddable":true,"hreflang":"es","title":"Spanish","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/46265\/translations\/es"},{"embeddable":true,"hreflang":"nl","title":"Dutch","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/46265\/translations\/nl"},{"embeddable":true,"hreflang":"ja","title":"Japanese","href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/46265\/translations\/jp"},{"href":"https:\/\/kinsta.com\/pt\/wp-json\/kinsta\/v1\/posts\/46265\/tree"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/media\/46266"}],"wp:attachment":[{"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/media?parent=46265"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/tags?post=46265"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/kinsta.com\/pt\/wp-json\/wp\/v2\/topic?post=46265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}